{"id":14732,"date":"2024-11-06T09:23:05","date_gmt":"2024-11-06T08:23:05","guid":{"rendered":"https:\/\/adent.ch\/dentistes\/samara-ruoss\/"},"modified":"2024-11-06T09:27:09","modified_gmt":"2024-11-06T08:27:09","slug":"samara-ruoss","status":"publish","type":"equipe","link":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/","title":{"rendered":"Samara RUOSS"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Samara Ruoss ist Prophylaxeassistentin bei Zahnarztzentrum in <a href=\"https:\/\/adent.ch\/de\/klinik\/luzern\/\">Luzern<\/a>. Sie begleitet die Patienten mit Freundlichkeit und Professionalit\u00e4t, um ihnen zu helfen, eine gute Mundgesundheit zu erhalten. Samara Ruoss ist leidenschaftlich in ihrem Beruf und hat ein offenes Ohr f\u00fcr die Bed\u00fcrfnisse und Sorgen jedes Einzelnen, um einen qualitativ hochwertigen Service und eine angenehme Erfahrung f\u00fcr alle zu bieten.<\/p>\n<p>Da Samara Ruoss mehrere Sprachen beherrscht, darunter Spanisch, Portugiesisch, Deutsch und Englisch, kann sie problemlos mit einem breiten Spektrum von Patienten kommunizieren. Diese Sprachkenntnisse erm\u00f6glichen es ihr, ein Vertrauensverh\u00e4ltnis zu den Patienten aufzubauen, unabh\u00e4ngig von ihrer Muttersprache. Durch die pers\u00f6nliche Erl\u00e4uterung der Zahnpflege stellt Samara Ruoss sicher, dass jeder Patient mit den richtigen Ratschl\u00e4gen f\u00fcr seine Bed\u00fcrfnisse nach Hause geht.<\/p>\n<p>Die Zahngesundheit ist f\u00fcr Samara Ruoss eine Priorit\u00e4t. Sie sieht ihre Rolle nicht nur als Unterst\u00fctzung bei der vorbeugenden Pflege, sondern auch als eine Gelegenheit, die Patienten \u00fcber die Bedeutung der Mundhygiene aufzukl\u00e4ren. Mit Geduld und p\u00e4dagogischem Geschick hilft Samara Ruoss bei der Auswahl der richtigen Produkte und Techniken, um das L\u00e4cheln zu erhalten.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"lightbox lightbox-98-0\" id=\"lightbox-98-0\" data-origin=\"lightbox-98-0\">\n\t\t\t\t\t\t\t\t\t<div class=\"close\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"lightbox-grid\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<h4>FACHGEBIETE<\/h4>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\">Zahnpflege f\u00fcr Kinder<\/a><\/li>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\">Zahnreinigung und Zahnhygiene<\/a><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"lightbox lightbox-98-1\" id=\"lightbox-98-1\" data-origin=\"lightbox-98-1\">\n\t\t\t\t\t\t\t\t\t<div class=\"close\"><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"lightbox-grid\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"col\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>","protected":false},"template":"","langue":[135,101,138,102],"class_list":["post-14732","equipe","type-equipe","status-publish","hentry","langue-deutsch","langue-englisch","langue-portugiesisch","langue-spanisch"],"acf":{"first_name":"Samara","last_name":"RUOSS","job":"Prophylaxeassistentin","short_description":"<p>Prophylaxeassistentin, die Behandlungen oberhalb des Zahnfleisches durchf\u00fchrt und \u00fcber Zahnpr\u00e4vention unterrichtet.<\/p>\n","image":{"ID":14728,"id":14728,"title":"Samara Ruoss_Lucerne","filename":"samara-ruoss_lucerne.png","filesize":2340934,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne.png","link":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/samara-ruoss_lucerne-2\/","alt":"","author":"14","description":"","caption":"","name":"samara-ruoss_lucerne-2","status":"inherit","uploaded_to":14732,"date":"2024-11-06 08:16:16","modified":"2024-11-06 08:27:09","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1880,"height":1410,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne-1307x980.png","large-width":1307,"large-height":980,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne-1536x1152.png","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne.png","2048x2048-width":1880,"2048x2048-height":1410,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/11\/samara-ruoss_lucerne.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"cliniques":[{"ID":4207,"post_author":"14","post_date":"2022-04-20 18:10:15","post_date_gmt":"2022-04-20 16:10:15","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Willkommen bei Adent Luzern\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u00220\\u0022 data-end=\\u0022663\\u0022\\u003eUnser \\u003cstrong data-start=\\u00226\\u0022 data-end=\\u002238\\u0022\\u003eAdent Zahnarztzentrum Luzern\\u003c\/strong\\u003e, ehemals unter dem Namen Cliniodent bekannt, ist seit 2021 Teil der \\u003cstrong data-start=\\u0022107\\u0022 data-end=\\u0022132\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e. Dieser Schritt markierte eine wichtige Weiterentwicklung: Unsere Patientinnen und Patienten profitieren seither von der Expertise eines schweizweiten Netzwerks an Spezialistinnen und Spezialisten, w\u00e4hrend alles erhalten blieb, was unser Zahnarztzentrum auszeichnet \u2013 dasselbe engagierte Team, dieselbe hohe Behandlungsqualit\u00e4t und eine transparente Preisgestaltung. Lediglich das visuelle Erscheinungsbild wurde modernisiert und spiegelt heute mit dem charakteristischen Adent-Gr\u00fcn Vertrauen, Innovation und Nachhaltigkeit wider.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022665\\u0022 data-end=\\u00221165\\u0022\\u003eZentral gelegen, nur wenige Schritte vom Bahnhof entfernt und eingebettet in die historische Altstadt von Luzern, \u00fcberzeugt unser Zahnarztzentrum durch eine ausgezeichnete Erreichbarkeit. Kinder, Jugendliche und Erwachsene werden in einer modernen, stilvollen und zugleich warmen Atmosph\u00e4re empfangen, die Ruhe vermittelt und eine vertrauensvolle Basis schafft. Unser Team spricht Deutsch, Franz\u00f6sisch, Englisch und Italienisch und gew\u00e4hrleistet so eine klare, pers\u00f6nliche und individuelle Betreuung.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221167\\u0022 data-end=\\u00221928\\u0022\\u003eEin interdisziplinaeres Team aus Zahnaerztinnen und Zahnaerzten, Dentalhygienikerinnen und spezialisierten Fachpersonen ermoeglicht eine umfassende und abgestimmte Betreuung. Das Leistungsspektrum reicht von allgemeiner Zahnmedizin ueber Zahnreinigung und Praevention bis hin zu Implantologie, Zahnaufhellung, Zahnersatz und massgeschneiderten Behandlungen fuer aengstliche Patientinnen und Patienten. Durch die enge Zusammenarbeit innerhalb des Teams entstehen individuelle Behandlungskonzepte mit einem ganzheitlichen Blick auf Ihre langfristige Mundgesundheit. Regelmaessige fachliche Austausche und Weiterbildungen innerhalb der Adent Zahnarztzentren stellen sicher, dass neueste Techniken und hoechste Behandlungsstandards in der Schweiz angewendet werden.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221930\\u0022 data-end=\\u00222471\\u0022\\u003eDer Praevention kommt in unserem Zahnarztzentrum eine zentrale Bedeutung zu. Unsere Spezialistinnen und Spezialisten begleiten Sie mit professioneller Zahnreinigung, persoenlicher Beratung zur Mundhygiene und regelmaessiger Kontrolle auf dem Weg zu einem gesunden, aesthetischen und nachhaltigen Laecheln. Gleichzeitig verfuegen unsere Zahnaerzte ueber fundierte Erfahrung in der Implantologie und bieten hochwertige, dauerhafte und aesthetisch anspruchsvolle Loesungen, um Kaufunktion, Komfort und Lebensqualitaet langfristig zu verbessern.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00222473\\u0022 data-end=\\u00222847\\u0022\\u003eBesonders am Herzen liegen uns Patientinnen und Patienten mit Zahnarztangst oder ausgepraegter Unsicherheit. Mit einer einfuelsamen, ruhigen und respektvollen Herangehensweise, moderner Schmerzbehandlung und einer entspannten Umgebung schaffen wir Vertrauen und Sicherheit. Ihr Wohlbefinden steht bei jedem Schritt im Mittelpunkt \u2013 von der ersten Beratung bis zur Nachsorge.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00222849\\u0022 data-end=\\u00223404\\u0022\\u003eDas \\u003cstrong data-start=\\u00222853\\u0022 data-end=\\u00222885\\u0022\\u003eAdent Zahnarztzentrum Luzern\\u003c\/strong\\u003e steht fuer Exzellenz, Innovation und Menschlichkeit. Dank moderner Infrastruktur, fortlaufender Weiterbildung und der Einbindung in ein anerkanntes nationales Netzwerk bieten wir Ihnen Behandlungen auf hoechstem Niveau. Ob Kontrolluntersuchung, aesthetische Zahnmedizin, Implantatversorgung oder regelmaessige Zahnreinigung \u2013 wir begleiten Sie von Montag bis Freitag mit Professionalitaet und Aufmerksamkeit. Bei zahnmedizinischen Notfaellen koennen Sie uns jederzeit kontaktieren oder direkt einen Termin vereinbaren.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"2958\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25019f6eb2\",\"shapes\":\"shape4\",\"_shapes\":\"field_622f5635c8595\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum Luzern\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":\"\",\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 41 420 90 80\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Luzern","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"luzern","to_ping":"","pinged":"","post_modified":"2025-12-31 15:01:02","post_modified_gmt":"2025-12-31 14:01:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/lucerne\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"}],"soins":[{"ID":4134,"post_author":"14","post_date":"2022-01-02 13:50:12","post_date_gmt":"2022-01-02 12:50:12","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Mund, meine Gesundheit\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u0022189\\u0022 data-end=\\u0022603\\u0022\\u003eEin \\u003cstrong data-start=\\u0022193\\u0022 data-end=\\u0022226\\u0022\\u003egesunder, strahlender L\u00e4cheln\\u003c\/strong\\u003e beginnt mit einer regelm\u00e4ssigen \\u003cstrong data-start=\\u0022259\\u0022 data-end=\\u0022276\\u0022\\u003eZahnreinigung\\u003c\/strong\\u003e und einer sorgf\u00e4ltigen \\u003cstrong data-start=\\u0022300\\u0022 data-end=\\u0022315\\u0022\\u003eMundhygiene\\u003c\/strong\\u003e. Der Mund beeinflusst nicht nur unser \\u003cstrong data-start=\\u0022354\\u0022 data-end=\\u0022373\\u0022\\u003eSelbstvertrauen\\u003c\/strong\\u003e und unsere \\u003cstrong data-start=\\u0022385\\u0022 data-end=\\u0022401\\u0022\\u003eAusstrahlung\\u003c\/strong\\u003e, sondern auch unsere \\u003cstrong data-start=\\u0022423\\u0022 data-end=\\u0022440\\u0022\\u003eKommunikation\\u003c\/strong\\u003e, \\u003cstrong data-start=\\u0022442\\u0022 data-end=\\u0022455\\u0022\\u003eErn\u00e4hrung\\u003c\/strong\\u003e und \\u003cstrong data-start=\\u0022460\\u0022 data-end=\\u0022485\\u0022\\u003eallgemeine Gesundheit\\u003c\/strong\\u003e. Bei \\u003cstrong data-start=\\u0022491\\u0022 data-end=\\u0022516\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e begleiten wir Sie dabei, Ihr L\u00e4cheln gesund, gepflegt und selbstbewusst zu erhalten.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022605\\u0022 data-end=\\u00221161\\u0022\\u003e\u00dcber \\u003cstrong data-start=\\u0022610\\u0022 data-end=\\u0022645\\u0022\\u003e600 verschiedene Bakterienarten\\u003c\/strong\\u003e leben in der Mundh\u00f6hle. Ohne gr\u00fcndliche \\u003cstrong data-start=\\u0022686\\u0022 data-end=\\u0022703\\u0022\\u003eZahnreinigung\\u003c\/strong\\u003e k\u00f6nnen diese Bakterien pathologisch werden und zu \\u003cstrong data-start=\\u0022754\\u0022 data-end=\\u0022768\\u0022\\u003eGingivitis\\u003c\/strong\\u003e oder \\u003cstrong data-start=\\u0022774\\u0022 data-end=\\u0022790\\u0022\\u003eParodontitis\\u003c\/strong\\u003e (Zahnlockerung) f\u00fchren. Manche Bakterien gelangen sogar in den Blutkreislauf und wirken sich auf die allgemeine Gesundheit aus. Unsere \\u003cstrong data-start=\\u0022926\\u0022 data-end=\\u0022972\\u0022\\u003eDentalhygienikerinnen und Dentalhygieniker\\u003c\/strong\\u003e sind Expertinnen und Experten f\u00fcr \\u003cstrong data-start=\\u00221007\\u0022 data-end=\\u00221033\\u0022\\u003epr\u00e4ventive Zahnmedizin\\u003c\/strong\\u003e. Sie beraten Sie individuell, zeigen die besten \\u003cstrong data-start=\\u00221082\\u0022 data-end=\\u00221106\\u0022\\u003eMundhygiene-Routinen\\u003c\/strong\\u003e und f\u00fchren professionelle \\u003cstrong data-start=\\u00221133\\u0022 data-end=\\u00221152\\u0022\\u003eZahnreinigungen\\u003c\/strong\\u003e durch.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221163\\u0022 data-end=\\u00221542\\u0022\\u003eMit der richtigen Kombination aus \\u003cstrong data-start=\\u00221197\\u0022 data-end=\\u00221230\\u0022\\u003eprofessioneller Zahnreinigung\\u003c\/strong\\u003e, t\u00e4glichen Pflegeroutinen und den passenden Hilfsmitteln \u2013 wie \\u003cstrong data-start=\\u00221294\\u0022 data-end=\\u00221336\\u0022\\u003eB\u00fcrsten, Interdentalb\u00fcrsten, Zahnseide\\u003c\/strong\\u003e oder \\u003cstrong data-start=\\u00221342\\u0022 data-end=\\u00221360\\u0022\\u003eWasserflossern\\u003c\/strong\\u003e \u2013 sorgen Sie daf\u00fcr, dass Ihr L\u00e4cheln gesund bleibt und Tag f\u00fcr Tag strahlt. Bei \\u003cstrong data-start=\\u00221441\\u0022 data-end=\\u00221466\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e machen wir Ihre Mundgesundheit und Ihr strahlendes L\u00e4cheln zur Priorit\u00e4t.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"\\u003cp data-start=\\u0022181\\u0022 data-end=\\u0022929\\u0022\\u003eEine \\u003cstrong data-start=\\u0022186\\u0022 data-end=\\u0022291\\u0022\\u003eZahnreinigung, die von einer Prophylaxeassistentin oder einem Prophylaxeassistenten durchgef\u00fchrt wird\\u003c\/strong\\u003e, ist eine vorbeugende Behandlung, die dazu dient, Zahnbelag und oberfl\u00e4chliche Verf\u00e4rbungen zu entfernen, ohne unter das Zahnfleisch zu gehen. Diese Art der Zahnreinigung ersetzt keine professionelle Zahnreinigung durch eine Dentalhygienikerin und richtet sich vor allem an Personen ohne Anzeichen einer Zahnfleischentz\u00fcndung. Sie wird besonders f\u00fcr Kinder und Jugendliche empfohlen, um von klein auf eine gute Mundhygiene zu f\u00f6rdern. Die Prophylaxeassistentin oder der Prophylaxeassistent verwendet geeignete Instrumente und gibt individuelle Tipps, um saubere Z\u00e4hne und ein gesundes L\u00e4cheln zwischen den Zahnarztbesuchen zu erhalten.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022931\\u0022 data-end=\\u00221590\\u0022\\u003eEine \\u003cstrong data-start=\\u0022936\\u0022 data-end=\\u00221033\\u0022\\u003eZahnreinigung, die von einer Dentalhygienikerin oder einem Dentalhygieniker durchgef\u00fchrt wird\\u003c\/strong\\u003e, ist eine umfassendere Behandlung, bei der Zahnstein und Belag auch unterhalb des Zahnfleisches entfernt werden. Diese Behandlung ist besonders f\u00fcr Personen mit Anzeichen von Gingivitis oder Parodontitis geeignet, da sie hilft, diese Erkrankungen zu verhindern oder zu behandeln. Die Dentalhygienikerin oder der Dentalhygieniker beurteilt die Gesundheit des Zahnfleisches, f\u00fchrt eine gr\u00fcndliche Reinigung durch und bietet eine individuelle Nachsorge an. Beide Arten der Zahnreinigung tragen gemeinsam dazu bei, die Mundgesundheit langfristig zu erhalten.\\u003c\/p\\u003e\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Mein Zahnarztzentrum finden\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnarztzentren\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/video {\"name\":\"acf\/video\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd1d6224c6\",\"video_preview\":\"\",\"_video_preview\":\"field_67811bb9884ea\",\"type\":\"youtube\",\"_type\":\"field_621c7b47d116a\",\"youtube\":\"\\u003ciframe width=\\u0022560\\u0022 height=\\u0022315\\u0022 src=\\u0022https:\/\/www.youtube-nocookie.com\/embed\/_HwEkrC1wZ4?si=gyi_NdQ7qYhUa8sF\\u0026amp;controls=0\\u0022 title=\\u0022YouTube video player\\u0022 frameborder=\\u00220\\u0022 allow=\\u0022accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\\u0022 allowfullscreen\\u003e\\u003c\/iframe\\u003e\",\"_youtube\":\"field_621c804717694\",\"legend\":\"\",\"_legend\":\"field_621c7e364a19a\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnreinigung und Zahnhygiene\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Rotes, gereiztes oder geschwollenes Zahnfleisch?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Wenden Sie sich an unsere Hygieniker:innen, um vorzubeugen, Zahnstein zu entfernen und Ihre Z\u00e4hne gesund zu erhalten.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Finden Sie Dentalhygieniker\/-innen\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4134\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie k\u00f6nnen Sie Ihre Z\u00e4hne zu Hause gesund erhalten?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16311,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnb\u00fcrste\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Verwenden Sie eine elektrische Zahnb\u00fcrste oder eine Schallzahnb\u00fcrste\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16314,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnzwischenr\u00e4ume\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Reinigen Sie Ihre Zahnzwischenr\u00e4ume mit B\u00fcrstchen, Zahnseide oder Zahnstochern\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16317,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Zahnpasta\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie fluoridhaltige Produkte. Sie sch\u00fctzen Ihre Z\u00e4hne vor S\u00e4ureangriffen\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs\":3,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnsteinentfernung und Zahnhygiene\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Warum sollte man zu einem\/einer Dentalhygieniker\/-in gehen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Vorbeugung und der Schutz vor Zahnerkrankungen stehen im Mittelpunkt der Arbeit der Dentalhygieniker\/-innen. Die Zahnsteinentfernung ist die bekannteste Hygienemassnahme. Sie wird von unseren diplomierten Dentalhygieniker\/-innen durchgef\u00fchrt und besteht in der Entfernung von Zahnstein, der sich auf den Z\u00e4hnen angesammelt hat. Denn selbst wenn Sie sich regelm\u00e4ssig die Z\u00e4hne putzen, kann eine einfache Zahnb\u00fcrste den Zahnstein nicht entfernen. Durch regelm\u00e4ssige Zahnsteinentfernungen, die von unseren Dentalhygienikern\/-hygienikerinnen durchgef\u00fchrt werden, erhalten Sie die Unversehrtheit Ihres Zahnfleisches und Ihrer Z\u00e4hne. Eine halbj\u00e4hrliche Zahnreinigung wird von Fachleuten f\u00fcr Mundgesundheit empfohlen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was ist der Unterschied zwischen einem\/einer Hygieniker\/-in und einem Prophylaxeassistenten\/einer Prophylaxeassistentin?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Bei Adent wird die Zahnpflege von Dentalhygienikern\/-hygienikerinnen und Prophylaxeassistent\/-innen durchgef\u00fchrt. Diese Zahngesundheitsfachleute haben jeweils ihren eigenen Zust\u00e4ndigkeitsbereich. Als Patient\/-in ist es gut, die Unterschiede zwischen ihnen zu kennen. So stellen Sie sicher, dass die Behandlung Ihren Bed\u00fcrfnissen entspricht.\\r\\n\\r\\nDer\/Die Profilaxeassistent\/-in (PA) ist ein diplomierter Dentalassistent\/eine diplomierte Dentalassistentin. Zus\u00e4tzlich zu diesen T\u00e4tigkeiten als Dentalassistent\/-in \u00fcbernimmt der\/die PA folgende Leistungen:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003ePr\u00e4ventivmassnahmen zur Erhaltung der Mundgesundheit\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eInformation und Motivation der Patienten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernung von supragingivalen Plaqueablagerungen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003eBleichen der Z\u00e4hne\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDiese Aufgaben werden immer unter der Aufsicht des Zahnarztes\/der Zahn\u00e4rztin ausgef\u00fchrt. Zus\u00e4tzlich zur Grundausbildung hat er\/sie eine von der SSO geregelte Weiterbildung zur beruflichen Weiterentwicklung absolviert. Diese Weiterbildung erm\u00f6glicht es ihr\/ihm, selbstst\u00e4ndig zu arbeiten.\\r\\n\\r\\nUnsere Prophylaxeassistenten\/\\u002d\\u002dassistentinnen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/\\u0022\\u003ehier\\u003c\/a\\u003e\\r\\n\\r\\nDer\/Die diplomierte Dentalhygieniker\/-in HF (DH) erf\u00fcllt folgende Aufgaben:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eErstellen, \u00dcbernehmen und Interpretieren von Diagnosen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eErstellen von Behandlungspl\u00e4nen in Absprache mit dem Zahnarzt\/der Zahn\u00e4rztin und dem Patienten\/der Patientin\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandeln von Parodontitis\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernen von Zahnstein auf und unter den Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBleichen von Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAnfertigen von R\u00f6ntgenaufnahmen, An\u00e4sthesie\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nUnsere Dentalhygieniker\/-innen finden Sie hier.\\r\\n\\r\\nDie \u00dcberwachung Ihrer Mundhygiene sollte mit Ihrem Zahnarzt\/Ihrer Zahn\u00e4rztin oder Ihres Dentalhygienikers\/Ihrer Dentalhygienikerin besprochen werden.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wer braucht eine Zahnreinigung?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine regelm\u00e4ssige Zahnreinigung wird f\u00fcr jeden empfohlen, der Z\u00e4hne hat, egal ob Erwachsener oder Kind. Kinder k\u00f6nnen unsere Dentalhygieniker\/-innen schon im fr\u00fchen Alter aufsuchen. So erhalten sie professionellen Rat und entwickeln gute Gewohnheiten, sobald sie ihre ersten Z\u00e4hne bekommen. Unsere Dentalhygieniker\/-innen k\u00f6nnen Ihr Kind an den Besuch beim Zahnarzt\/bei der Zahn\u00e4rztin gew\u00f6hnen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Welche Vorteile hat eine regelm\u00e4ssige Zahnreinigung?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine regelm\u00e4ssige Zahnsteinentfernung verhindert, dass sich zu viel Zahnstein auf den Z\u00e4hnen ablagert. Ausserdem werden Verf\u00e4rbungen entfernt, die z. B. durch Teein oder Koffein verursacht werden. Zahnstein und Zahnbelag sind sch\u00e4dlich f\u00fcr die Z\u00e4hne und das Zahnfleisch. Sie f\u00fchren zu Infektionen wie Karies, Zahnlockerung und Zahnfleischentz\u00fcndungen, die als Gingivitis bezeichnet werden. Die Unversehrtheit Ihrer Z\u00e4hne und Ihres Zahnfleischs bleibt erhalten, wenn Sie regelm\u00e4ssig professionelle Zahnreinigungen und Hygienetipps erhalten. Unsere Dentalhygieniker\/-innen beraten Sie auch \u00fcber die richtigen Schritte, um sch\u00f6ne Z\u00e4hne zu erhalten oder wiederzuerlangen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions_4_title\":\"Wie l\u00e4uft eine Zahnhygienesitzung ab?\",\"_accordions_4_title\":\"field_626fdd3ff47be\",\"accordions_4_content\":\"Zun\u00e4chst muss ein medizinischer Fragebogen ausgef\u00fcllt werden. Dann beginnt die Reinigung. Der\/Die Dentalhygieniker\/-in verf\u00fcgt \u00fcber eine Palette moderner Arbeitsinstrumente. Diese werden an die Bed\u00fcrfnisse jedes Patienten\/jeder Patientin angepasst.\\r\\n\\u003col\\u003e\\r\\n \\t\\u003cli\\u003eManuelle Scaler (Zahnsteinentferner). Sie werden nach der Lage des Zahns, der Position des Zahnsteins und danach ausgew\u00e4hlt, ob eine Zahnlockerung vorliegt oder nicht.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eElektronische Scaler mit Ultraschall.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003ePolieren, um Koffein-, Teein- oder Nikotinverf\u00e4rbungen zu entfernen und die Oberfl\u00e4che des Zahnschmelzes zu gl\u00e4tten.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAm Ende gibt er\/sie die patientenspezifischen Gesundheitstipps und -tricks.\\u003c\/li\\u003e\\r\\n\\u003c\/ol\\u003e\\r\\nAlle Dentalhygienikerinnen und Dentalhygieniker bei Adent sind in der GBT-Technik geschult. [GBT] Guided Biofilm Therapy\u00ae ist eine innovative Technik, die von EMS Dental entwickelt wurde, um Biofilm, Verf\u00e4rbungen und Zahnstein von Ihren Z\u00e4hnen zu entfernen. Diese schmerzfreie Technik kann sowohl bei nat\u00fcrlichen Z\u00e4hnen als auch bei Zahnrekonstruktionen und Zahnimplantaten eingesetzt werden.\\r\\n\\r\\n\\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/zahnsteinentfernung-guided-biofilm-technology\/\\u0022\\u003eWeitere Informationen \u00fcber GBT\\u003c\/a\\u003e\",\"_accordions_4_content\":\"field_626fdd46f47bf\",\"accordions_5_title\":\"Ist eine Zahnreinigung schmerzhaft?\",\"_accordions_5_title\":\"field_626fdd3ff47be\",\"accordions_5_content\":\"Bei akuter Empfindlichkeit kann eine \u00f6rtliche Bet\u00e4ubung in Betracht gezogen werden. Dadurch wird Ihr Wohlbefinden w\u00e4hrend der gesamten Zahnreinigung verbessert.\\r\\n\\r\\nF\u00fchlen Sie sich gestresst und nerv\u00f6s, wenn Sie an Ihren n\u00e4chsten Zahnarzttermin denken? Fragen Sie nach einer Behandlung mit Lachgas (MEOPA) oder Hypnose. MEOPA ist ein farb- und geruchloses Gasgemisch aus Sauerstoff und Distickstoffmonoxid. Wenn Sie es einatmen, entspannt es Sie, w\u00e4hrend Sie gleichzeitig beim Bewusstsein sind und Sie wissen was um Sie herum geschieht. Die Sitzung mit dem\/der Dentalhygieniker\/-in wird in aller Ruhe stattfinden.\\r\\n\\r\\nUm mehr \u00fcber die Angst vor dem Zahnarzt\/der Zahn\u00e4rztin zu informieren, haben wir \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/die-zahnarztphobie\/\\u0022\\u003eeinen Artikel\\u003c\/a\\u003e dar\u00fcber verfasst.\",\"_accordions_5_content\":\"field_626fdd46f47bf\",\"accordions\":6,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape3\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/tab {\"name\":\"acf\/tab\",\"data\":{\"anchor\":\"teenager\",\"_anchor\":\"field_635bd13882c1f\",\"tabs_0_name\":\"Kinder\",\"_tabs_0_name\":\"field_624449592e9bd\",\"tabs_0_tab\":13563,\"_tabs_0_tab\":\"field_624449622e9be\",\"tabs_1_name\":\"Teenager\",\"_tabs_1_name\":\"field_624449592e9bd\",\"tabs_1_tab\":4124,\"_tabs_1_tab\":\"field_624449622e9be\",\"tabs_2_name\":\"Erwachsene\",\"_tabs_2_name\":\"field_624449592e9bd\",\"tabs_2_tab\":4128,\"_tabs_2_tab\":\"field_624449622e9be\",\"tabs\":3,\"_tabs\":\"field_624449452e9bc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Sanfte Vorbeugung und Behandlung f\u00fcr Ihre Z\u00e4hne und Ihr Zahnfleisch.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Schlechte Hygiene f\u00fchrt zu Infektionskrankheiten der Z\u00e4hne und des Zahnfleischs. Sie f\u00fchrt auch zu Schmerzen. Diese Erkrankungen k\u00f6nnen sowohl Erwachsene als auch Kinder betreffen. Um das Auftreten von Krankheiten zu verhindern, sind regelm\u00e4ssige Sitzungen bei dem\/der Dentalhygieniker\/-in erforderlich. Der\/Die Dentalhygieniker\/-in entfernt Biofilm und Zahnstein, die sich auf Ihren Z\u00e4hnen festgesetzt haben.\\r\\n\\r\\nDie Zahnarztzentren von Adent passen sich st\u00e4ndig an die Entwicklung der zahnmedizinischen Technologien an. Wir bieten Ihnen eine optimale Pflegequalit\u00e4t und mehr Komfort. Die [GBT] Guided Biofilm Therapy\u00ae ist ein innovativer Ansatz, der von EMS Dental entwickelt wurde. Sie entfernt Biofilm, Verf\u00e4rbungen und Zahnstein. Diese Technik kann bei nat\u00fcrlichen und k\u00fcnstlichen Z\u00e4hnen sowie bei Zahnimplantaten angewendet werden.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Zahnfleisch pflege\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnfleisch pflege\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Profitieren Sie von einer schonenden und umfassenden Zahnreinigung dank der Kompetenzen unserer Fachpersonals. Das Fachwissen in Kombination mit den Technologien, die in den Zahnarztzentren von Adent zum Einsatz kommen, sorgt daf\u00fcr, dass Sie die beste Pflege erhalten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Erfahren Sie mehr \u00fcber die GBT\u00ae\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnstein-Entfernung: Guided Biofilm Technology\",\"url\":\"https:\/\/adent.ch\/de\/info\/zahnsteinentfernung-guided-biofilm-technology\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape1\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnreinigung und Zahnhygiene","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnsteinentfernung-und-zahnhygiene","to_ping":"","pinged":"","post_modified":"2026-01-19 15:14:38","post_modified_gmt":"2026-01-19 14:14:38","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/detartrage-et-hygiene-dentaire\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4140,"post_author":"14","post_date":"2022-01-03 13:50:41","post_date_gmt":"2022-01-03 12:50:41","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Das Beste fu\u0308r kleine La\u0308cheln.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Kinderzahn\u00e4rzte sind in einem kindgerechten psychologischen und p\u00e4dagogischen Ansatz geschult. Ihre Aufgabe ist es, zu beruhigen und mit einem altersgerechten Vokabular zu sprechen, um ein Klima des Vertrauens zu schaffen.\\r\\n\\r\\nWir f\u00fchren alle Arten von Zahnbehandlungen bei Kindern durch.\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eKariesbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eabgebrochener Zahn\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eZahnreinigung\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eTipps zum B\u00fcrsten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":16375,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Kieferorthop\u00e4dische Behandlungen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Zahn\u00e4rzte, die sich auf Kieferorthop\u00e4die spezialisiert haben, bieten kieferorthop\u00e4dische Behandlung f\u00fcr Kinder an. Eine kieferorthop\u00e4dische Behandlung kann in jedem Alter begonnen werden, aber die meisten Eltern w\u00fcnschen sich f\u00fcr ihre Kinder eine fr\u00fchzeitige Behandlung. Je nach Art der erforderlichen Behandlung kann eine erste Phase des Abfangens von Kieferorthop\u00e4den bereits ab dem 4. Lebensjahr stattfinden. In den Adent Zahnarztzentren werden verschiedene kieferorthop\u00e4dische Behandlungen angeboten, die sich an die jeweilige Mundsituation anpassen. Weitere Informationen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eauf unserer Seite \u00fcber Kieferorthop\u00e4de f\u00fcr Kinder\\u003c\/a\\u003e!\\r\\n\\r\\nZus\u00e4tzlich zu diesen zahn\u00e4rztlichen Behandlungen erkl\u00e4ren unsere diplomierten Dentalhygienikerinnen mit p\u00e4dagogischen Methoden, wie Z\u00e4hne und Zahnfleisch gesund erhalten werden k\u00f6nnen. Unsere Fachgebiete f\u00fcr zahn\u00e4rztliche Pr\u00e4vention helfen ihnen, die richtigen Verhaltensweisen zu erlernen, sobald sie die ersten Z\u00e4hne bekommen.\\r\\n\\r\\nHaben Sie Fragen zur Zahnhygiene bei Babys oder Jugendlichen? \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eBesuchen Sie unsere Seite zu diesen Themen\\u003c\/a\\u003e!\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Jeder Zahn muss t\u00e4glich gereinigt werden, egal wie klein er ist. Nach der Nahrungsaufnahme bildet sich ein Biofilm auf der Oberfl\u00e4che des Zahnschmelzes. Dieser Biofilm entwickelt sich weiter, wenn er nicht regelm\u00e4\u00dfig gereinigt wird. Dies f\u00fchrt zu wei\u00dfen, weichen Ablagerungen auf der Oberfl\u00e4che der Z\u00e4hne, die als Plaque bezeichnet werden. Zahnbelag besteht unter anderem aus Bakterien. Bakterien k\u00f6nnen Karies verursachen, wenn die Reinigung nicht regelm\u00e4ssig erfolgt. Plaque kann sich auch zu Zahnstein entwickeln, einem harten, wei\u00dfen Belag, der mit der Zahnb\u00fcrste nicht entfernt werden kann.\\r\\n\\r\\nAuch wenn dies selten vorkommt, kann sich ein Schaden an einem Milchzahn auf einen Erwachsenenzahn auswirken. Die Keime der erwachsenen Z\u00e4hne, die sich unter dem Zahnfleisch bilden, sind empfindlich. Sie k\u00f6nnen besch\u00e4digt werden, wenn ein Milchzahn infiziert wird.\\r\\n\\r\\nHeutzutage gibt es eine breite Palette von Hilfsmitteln f\u00fcr die Zahnreinigung bei Kindern. Sie k\u00f6nnen leicht elektrische Zahnb\u00fcrsten, Zahnseide in Tierform, bunte Kinderzahnb\u00fcrsten usw. erwerben. Diese Hilfsmittel helfen Ihnen dabei, die Mundhygiene Ihres Kindes zu verbessern. Lassen Sie sich von \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eunseren Dentalhygienikerinnen\\u003c\/a\\u003e beraten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Zahnarztangst\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Kind hat Angst vor dem Zahnarzt, was kann ich tun?\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"F\u00fcr Kinder mit Phobie oder Angst vor dem Zahnarzt haben wir L\u00f6sungen! Unsere Zahn\u00e4rzte bieten Lachgas- und Hypnosebehandlungen an, die auch bei Kindern einfach und sicher durchzuf\u00fchren sind. Weitere Informationen finden Sie hier.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie kann ich Zahnprobleme bei meinem Kind vermeiden?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16307,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Geben Sie gute Gewohnheiten weiter!\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Das Z\u00e4hneputzen wird 3x\/Tag empfohlen: Putzen Sie die Z\u00e4hne nach jeder Mahlzeit und vermeiden Sie bei Ihren Kindern das st\u00e4ndige Naschen von S\u00fcssigkeiten, da dies Karies und Schmerzen verursachen kann.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16347,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"B\u00fcrsten ab den ersten Z\u00e4hnen.\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Dies kann eine schwierige Aufgabe sein, aber alle Z\u00e4hne, auch wenn sie noch so klein sind, m\u00fcssen t\u00e4glich gereinigt werden. Tragen Sie ab dem ersten Zahn bis zum Alter von ca. 3 Jahren Zahnpasta in der Gr\u00f6sse eines Reiskorns auf, danach in der Gr\u00f6sse einer Erbse.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16350,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"S\u00fcssigkeiten ja, mit Sympadent\u00ae!\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie \\u003ca href=\\u0022https:\/\/zahnfreundlich.ch\/lassociation-sympadent-sengage-pour-des-dents-denfant-saines\/?lang=fr\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eSympadent\u00ae Bonbons\\u003c\/a\\u003e: Sie wurden getestet und f\u00fcr gut befunden. Diese S\u00fcssigkeiten schonen die Z\u00e4hne von Kindern und Erwachsenen. Sie k\u00f6nnen es in verschiedenen Gesch\u00e4ften in der Schweiz kaufen. Achten Sie auf das Zahnlogo unter dem Regenschirm.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":16562,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Alles miteinander teilen? Ja, aber...\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Vermeiden Sie es, den L\u00f6ffel oder andere Gegenst\u00e4nde in den Mund zu nehmen, bevor Sie sie Ihrem Baby geben: Karies verursachende Bakterien werden \u00fcbertragen.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs_4_image\":16311,\"_blocs_4_image\":\"field_623c222ba627a\",\"blocs_4_title\":\"Eine zus\u00e4tzliche Hilfe f\u00fcr eine optimale Reinigung.\",\"_blocs_4_title\":\"field_623c22c4a627b\",\"blocs_4_description\":\"Elektrische Zahnb\u00fcrsten sind eine gute Hilfe f\u00fcr Ihr Kind. Dies erleichtert das B\u00fcrsten und ermutigt sie. Unsere Dentalhygienikerinnen beraten Sie gerne.\",\"_blocs_4_description\":\"field_623c22cba627c\",\"blocs_4_button_type\":\"none\",\"_blocs_4_button_type\":\"field_623c34377e92d\",\"blocs_5_image\":16353,\"_blocs_5_image\":\"field_623c222ba627a\",\"blocs_5_title\":\"Eine fluoridierte Zahnpasta, die f\u00fcr sein Alter geeignet ist.\",\"_blocs_5_title\":\"field_623c22c4a627b\",\"blocs_5_description\":\"Fluor sch\u00fctzt die Z\u00e4hne vor Karies. Sie finden leicht Zahnpasta f\u00fcr Kinder unter 6 Jahren, f\u00fcr Kinder von 6 bis 12 Jahren und f\u00fcr Erwachsene. Wechseln Sie den Geschmack der Zahnpasta regelm\u00e4ssig: Kinder m\u00f6gen Abwechslung.\",\"_blocs_5_description\":\"field_623c22cba627c\",\"blocs_5_button_type\":\"none\",\"_blocs_5_button_type\":\"field_623c34377e92d\",\"blocs\":6,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnpflege f\u00fcr Kinder\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie unsere Zahn\u00e4rzte, die auf die Behandlung von Kindern spezialisiert sind.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Einen spezialisierten Zahnarzt finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4140\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnpflege f\u00fcr Kinder","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbehandlung-fuer-kinder","to_ping":"","pinged":"","post_modified":"2026-01-19 15:07:44","post_modified_gmt":"2026-01-19 14:07:44","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-pour-les-enfants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Samara RUOSS | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Samara Ruoss praktiziert im Zentrum von Luzern und ist auf Zahnhygiene, Pr\u00e4vention und Zahnreinigungen spezialisiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Samara RUOSS | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Samara Ruoss praktiziert im Zentrum von Luzern und ist auf Zahnhygiene, Pr\u00e4vention und Zahnreinigungen spezialisiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-06T08:27:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/samara-ruoss\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/samara-ruoss\\\/\",\"name\":\"Samara RUOSS | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2024-11-06T08:23:05+00:00\",\"dateModified\":\"2024-11-06T08:27:09+00:00\",\"description\":\"Samara Ruoss praktiziert im Zentrum von Luzern und ist auf Zahnhygiene, Pr\u00e4vention und Zahnreinigungen spezialisiert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/samara-ruoss\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/samara-ruoss\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/samara-ruoss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Team\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Samara RUOSS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Samara RUOSS | Adent Zahnarztzentrum","description":"Samara Ruoss praktiziert im Zentrum von Luzern und ist auf Zahnhygiene, Pr\u00e4vention und Zahnreinigungen spezialisiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/","og_locale":"de_DE","og_type":"article","og_title":"Samara RUOSS | Adent Zahnarztzentrum","og_description":"Samara Ruoss praktiziert im Zentrum von Luzern und ist auf Zahnhygiene, Pr\u00e4vention und Zahnreinigungen spezialisiert.","og_url":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2024-11-06T08:27:09+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/","url":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/","name":"Samara RUOSS | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2024-11-06T08:23:05+00:00","dateModified":"2024-11-06T08:27:09+00:00","description":"Samara Ruoss praktiziert im Zentrum von Luzern und ist auf Zahnhygiene, Pr\u00e4vention und Zahnreinigungen spezialisiert.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/zahnarzt\/samara-ruoss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Team","item":"https:\/\/adent.ch\/de\/team\/"},{"@type":"ListItem","position":2,"name":"Samara RUOSS"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe\/14732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=14732"}],"wp:term":[{"taxonomy":"langue","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/langue?post=14732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}