{"id":16256,"date":"2025-12-09T15:20:24","date_gmt":"2025-12-09T14:20:24","guid":{"rendered":"https:\/\/adent.ch\/dentistes\/victoire-bastide-3\/"},"modified":"2025-12-17T12:32:49","modified_gmt":"2025-12-17T11:32:49","slug":"can-iri","status":"publish","type":"equipe","link":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/","title":{"rendered":"Can IRI"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p data-start=\"0\" data-end=\"600\">Can Iri ist ein erfahrener Zahnarzt, der sich in vielen Bereichen der allgemeinen Zahnmedizin bestens auskennt und stets bestrebt ist, seinen Patienten hochwertige Behandlungen zu bieten. Im Verlauf seiner beruflichen Laufbahn hat er seine Kompetenzen kontinuierlich erweitert und vertieft und absolviert derzeit ein Masterstudium in Kieferorthop\u00e4die, um sein Fachwissen weiter auszubauen. Seine Arbeitsweise verbindet technisches K\u00f6nnen mit einer konsequenten F\u00fcrsorge f\u00fcr das Wohlbefinden jedes einzelnen Patienten, sodass Behandlungen pr\u00e4zise, individuell und vertrauensvoll durchgef\u00fchrt werden.<\/p>\n<p data-start=\"602\" data-end=\"909\">Besonderen Wert legt Can Iri auf die Zahnmedizin f\u00fcr Kinder. Mit viel Einf\u00fchlungsverm\u00f6gen und Geduld schafft er eine beruhigende Atmosph\u00e4re, in der auch die j\u00fcngsten Patienten fr\u00fchzeitig Vertrauen zu den Zahn\u00e4rzten entwickeln und positive Erfahrungen bei Zahnreinigungen und Kontrolluntersuchungen machen.<\/p>\n<p data-start=\"911\" data-end=\"1282\">Seine Motivation, Zahnarzt zu werden, basiert auf dem Wunsch, medizinische Expertise mit einer menschlichen Komponente zu verbinden, um jedem Patienten zu einem gesunden L\u00e4cheln zu verhelfen und ihn dabei einf\u00fchlsam zu begleiten. Diese patientenorientierte Haltung spiegelt sich in jeder Behandlung wider, sei es bei Routinekontrollen oder spezialisierteren Eingriffen.<\/p>\n<p data-start=\"1284\" data-end=\"1617\" data-is-last-node=\"\" data-is-only-node=\"\">Can Iri spricht fliessend Deutsch, Franz\u00f6sisch und T\u00fcrkisch, was ihm erlaubt, mit einer vielf\u00e4ltigen Patientenschaft klar und verst\u00e4ndlich zu kommunizieren. Seine Praxis im Zahnarztzentrum steht f\u00fcr Fachkompetenz, Herzlichkeit und Engagement, wodurch Patienten eine vertrauensvolle und professionelle zahn\u00e4rztliche Betreuung erleben.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>","protected":false},"template":"","langue":[135,101,146],"class_list":["post-16256","equipe","type-equipe","status-publish","hentry","langue-deutsch","langue-englisch","langue-tuerkisch"],"acf":{"job":"Zahnarzt","short_description":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:7c8055f6-18a9-4b19-af7b-43a258344f6a-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"9673ba86-7fe9-4881-abe4-ba31eececeb6\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"1679\" data-end=\"1771\" data-is-last-node=\"\" data-is-only-node=\"\">Erfahrener Zahnarzt bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes L\u00e4cheln.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"pointer-events-none h-px w-px\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n","specialites":[{"label":"\u00dcbliche Zahnpflege","link":"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/"}],"higlight_specialite":"","higlight_specialite_short":"","zawin_codes":false,"first_name":"Can","last_name":"IRI","image":{"ID":16680,"id":16680,"title":"Iri Can Muttenz","filename":"iri-can-muttenz.png","filesize":1981837,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","link":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/iri-can-muttenz-2\/","alt":"","author":"14","description":"","caption":"","name":"iri-can-muttenz-2","status":"inherit","uploaded_to":16256,"date":"2026-02-23 08:54:54","modified":"2026-02-23 08:54:54","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","medium-width":1,"medium-height":1,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","large-width":1,"large-height":1,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","2048x2048-width":1,"2048x2048-height":1,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","gform-image-choice-sm-width":1,"gform-image-choice-sm-height":1,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","gform-image-choice-md-width":1,"gform-image-choice-md-height":1,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/iri-can-muttenz.png","gform-image-choice-lg-width":1,"gform-image-choice-lg-height":1}},"cliniques":[{"ID":4205,"post_author":"14","post_date":"2022-04-20 18:11:36","post_date_gmt":"2022-04-20 16:11:36","post_content":"<!-- wp:acf\/signature-hero {\"name\":\"acf\/signature-hero\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_699c0fd216505\",\"pic\":16517,\"_pic\":\"field_699c0ff058702\",\"title\":\"Ein elegantes, modernes und zeitloses Ambiente\",\"_title\":\"field_699c0fd21650e\",\"text\":\"Bereits beim Betreten \u00fcberzeugt das Zahnarztzentrum mit einem modernen, sorgf\u00e4ltig gestalteten Design. Die R\u00e4ume sind hell, stilvoll und darauf ausgerichtet, eine ruhige und angenehme Atmosph\u00e4re zu schaffen.\\r\\n\\r\\nDas gesamte Umfeld wurde so konzipiert, dass sich Patientinnen und Patienten vom ersten Moment an wohlf\u00fchlen.\\r\\n\\u003cul role=\\u0022list\\u0022\\u003e\\r\\n \\t\\u003cli\\u003eEin ruhiger und komfortabler Wartebereich mit Aussicht f\u00fcr entspanntes Warten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEin diskreter und freundlicher Kinderbereich f\u00fcr Familien\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEin separater Bereich, um sich in Ruhe zu erfrischen oder die Z\u00e4hne zu putzen\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nJeder Bereich spiegelt die Signature-Philosophie von Adent wider: \\u003cstrong\\u003eQualit\u00e4t, Komfort\\u003c\/strong\\u003e und zeitlose \\u003cstrong\\u003eEleganz.\\u003c\/strong\\u003e\",\"_text\":\"field_699c0fe258701\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-text-image {\"name\":\"acf\/signature-text-image\",\"data\":{\"sec_bkg\":\"primary\",\"_sec_bkg\":\"field_69972d6b4b804\",\"is-full\":\"0\",\"_is-full\":\"field_69972e7a4b807\",\"img_dir\":\"start\",\"_img_dir\":\"field_69972dc74b805\",\"img_style\":\"rounded\",\"_img_style\":\"field_69972e264b806\",\"image\":16520,\"_image\":\"field_69972ec24b809\",\"content\":\"\\u003ch2\\u003eModernste Technologien und integriertes 3D-Labor\\u003c\/h2\\u003e\\r\\nDie Zahnklinik Rennbahn by Adent zeichnet sich durch ein integriertes Dentallabor aus: das Labo 3D. Die unmittelbare Zusammenarbeit zwischen Zahn\u00e4rzten und Zahntechnikern erm\u00f6glicht h\u00f6chste Pr\u00e4zision, kurze Produktionszeiten und eine vollst\u00e4ndige Qualit\u00e4tskontrolle \u2013 insbesondere bei komplexen und anspruchsvollen Behandlungen.\\r\\nDie Behandlungsr\u00e4ume sind mit modernster dentaler Technologie ausgestattet. Digitale Bildgebung, pr\u00e4zise Diagnostik und innovative Behandlungsmethoden erm\u00f6glichen zuverl\u00e4ssige Resultate auf h\u00f6chstem funktionellen und \u00e4sthetischen Niveau.\",\"_content\":\"field_69972ece4b80a\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-accordion {\"name\":\"acf\/signature-accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_6997227cd52f3\",\"sec_bkg\":\"primary\",\"_sec_bkg\":\"field_69972c3d39ef9\",\"title\":\"Unsere Fachgebiete\",\"_title\":\"field_6997227cd52fc\",\"accordions_0_title\":\"Zahnimplantate und All-on-4\u2122-Technologie\",\"_accordions_0_title\":\"field_6997227ced542\",\"accordions_0_content\":\"Die Zahn\u00e4rztinnen und Zahn\u00e4rzte des Zahnarztzentrums beherrschen die All-on-4\u2122-Technologie. Diese innovative Methode erm\u00f6glicht es, eine vollst\u00e4ndige Zahnprothese auf nur vier Implantaten zu befestigen.\\r\\n\\r\\nDiese bew\u00e4hrte Behandlung bietet:\\r\\n\\r\\n\\u003cimg class=\\u0022size-medium wp-image-16971 alignright\\u0022 src=\\u0022https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/labels-muttenz-300x300.png\\u0022 alt=\\u0022\\u0022 width=\\u0022300\\u0022 height=\\u0022300\\u0022 \/\\u003e\\r\\n\\u003cul role=\\u0022list\\u0022\\u003e\\r\\n \\t\\u003cli style=\\u0022list-style-type: none\\u0022\\u003e\\r\\n\\u003cul role=\\u0022list\\u0022\\u003e\\r\\n \\t\\u003cli\\u003eEin sofortiges Ergebnis\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eHohen Tragekomfort\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEine nat\u00fcrliche \u00c4sthetik\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEine langfristige und sichere L\u00f6sung\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\n\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\n\\u0026nbsp;\\r\\n\\r\\nSie eignet sich besonders f\u00fcr Patientinnen und Patienten, die rasch wieder ein stabiles, funktionelles und \u00e4sthetisches L\u00e4cheln erhalten m\u00f6chten.\",\"_accordions_0_content\":\"field_6997227ced54c\",\"accordions_1_title\":\"Hochpr\u00e4zise \u00e4sthetische Zahnmedizin\",\"_accordions_1_title\":\"field_6997227ced542\",\"accordions_1_content\":\"Das Zahnarztzentrum bietet ein umfassendes Spektrum moderner \u00e4sthetischer Behandlungen, um das L\u00e4cheln nat\u00fcrlich und harmonisch zu versch\u00f6nern:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eDentale Veneers\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eHochwertige Zahnkronen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eProfessionelles Zahnbleaching\\r\\n(F\u00fcr weitere Informationen kontaktieren Sie bitte direkt das Zahnarztzentrum.)\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nAuch der Austausch alter Amalgamf\u00fcllungen durch biokompatible, langlebige und \u00e4sthetische Materialien geh\u00f6rt zu den angebotenen Leistungen.\",\"_accordions_1_content\":\"field_6997227ced54c\",\"accordions_2_title\":\"Individuell gefertigte Zahnprothesen\",\"_accordions_2_title\":\"field_6997227ced542\",\"accordions_2_content\":\"Dank der engen Zusammenarbeit mit dem internen Labo 3D wird jede Prothese individuell geplant und hergestellt. Dabei stehen h\u00f6chste funktionelle Pr\u00e4zision und eine nat\u00fcrliche \u00c4sthetik im Mittelpunkt.\\r\\n\\r\\nDer kontinuierliche Austausch zwischen Zahn\u00e4rzten, Zahntechnikern und Patientinnen und Patienten erm\u00f6glicht Restaurierungen, die optimal an Morphologie, Okklusion und die nat\u00fcrliche Harmonie des L\u00e4chelns angepasst sind.\",\"_accordions_2_content\":\"field_6997227ced54c\",\"accordions_3_title\":\"Schienen bei schlafbezogenen Atmungsst\u00f6rungen\",\"_accordions_3_title\":\"field_6997227ced542\",\"accordions_3_content\":\"Dr. Andreas Graber, leitender Zahnarzt, ist f\u00fcr die Anwendung von ResMed\u00ae Unterkiefer-Protrusionsschienen zertifiziert.\\r\\n\\r\\nDiese Therapie wird nach einer Diagnose durch einen Schlafmediziner verschrieben und kann dazu beitragen, Schlafapnoe zu reduzieren, die n\u00e4chtliche Atmung zu verbessern und die Lebensqualit\u00e4t deutlich zu steigern.\\r\\n\",\"_accordions_3_content\":\"field_6997227ced54c\",\"accordions\":4,\"_accordions\":\"field_6997227cd530c\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-text-image {\"name\":\"acf\/signature-text-image\",\"data\":{\"sec_bkg\":\"primary-dark\",\"_sec_bkg\":\"field_69972d6b4b804\",\"is-full\":\"1\",\"_is-full\":\"field_69972e7a4b807\",\"img_dir\":\"start\",\"_img_dir\":\"field_69972dc74b805\",\"img_style\":\"half_rounded\",\"_img_style\":\"field_69972e264b806\",\"image\":16541,\"_image\":\"field_69972ec24b809\",\"content\":\"\\u003ch2\\u003eIndividuelle Mundhygiene und Zahnreinigung\\u003c\/h2\\u003e\\r\\nUnsere Dentalhygienikerinnen bieten pr\u00e4ventive Behandlungen f\u00fcr Erwachsene und Kinder an, abgestimmt auf die individuellen Bed\u00fcrfnisse jeder Patientin und jedes Patienten:\\r\\n\\u003cul role=\\u0022list\\u0022\\u003e\\r\\n \\t\\u003cli\\u003eProfessionelle Zahnreinigung und Entfernung von Zahnstein\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eIndividuelle Beratung f\u00fcr eine optimale Mundhygiene\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eProfessionelles Zahnbleaching\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nJede Behandlung tr\u00e4gt dazu bei, die langfristige Gesundheit und Ausstrahlung des L\u00e4chelns zu erhalten.\",\"_content\":\"field_69972ece4b80a\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-text-image {\"name\":\"acf\/signature-text-image\",\"data\":{\"sec_bkg\":\"default\",\"_sec_bkg\":\"field_69972d6b4b804\",\"is-full\":\"0\",\"_is-full\":\"field_69972e7a4b807\",\"img_dir\":\"end\",\"_img_dir\":\"field_69972dc74b805\",\"img_style\":\"half_rounded\",\"_img_style\":\"field_69972e264b806\",\"image\":16544,\"_image\":\"field_69972ec24b809\",\"content\":\"\\u003ch2\\u003eEine menschliche, beruhigende und vertrauensvolle Betreuung\\u003c\/h2\\u003e\\r\\nDa zahnmedizinische Behandlungen bei manchen Menschen Unsicherheit ausl\u00f6sen k\u00f6nnen, legt das Team der Zahnklinik Rennbahn by Adent grossen Wert auf eine einf\u00fchlsame und beruhigende Betreuung.\\r\\nJede Patientin und jeder Patient wird mit Aufmerksamkeit, Respekt und Transparenz begleitet. Ziel ist eine Behandlung ohne Schmerzen und in einem Umfeld des Vertrauens \u2013 besonders auch f\u00fcr Menschen mit Zahnarztangst.\",\"_content\":\"field_69972ece4b80a\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-clinique-head {\"name\":\"acf\/signature-clinique-head\",\"data\":{\"member_id\":14320,\"_member_id\":\"field_69982c49cceaa\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-cta {\"name\":\"acf\/signature-cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_69972a26d38c6\",\"title\":\"Angst, Nervosit\u00e4t, Unsicherheit?\",\"_title\":\"field_69972a26d38df\",\"text\":\"Entdecken Sie unsere Methoden, die Ihnen Behandlungen in vollem? Vertrauen und unter den bestm\u00f6glichen Bedingungen erm\u00f6glichen.\",\"_text\":\"field_69972a26d38e7\",\"cta\":{\"title\":\"RUFEN SIE UNS AN\",\"url\":\"tel:+41618261010\",\"target\":\"\"},\"_cta\":\"field_69972a75e0592\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-members {\"name\":\"acf\/signature-members\",\"data\":{\"title\":\"Zahnklinik Rennbahn by Adent\",\"_title\":\"field_69972a9fcf8f2\",\"text\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_text\":\"field_69972a9fcf8fa\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/signature-cares-list {\"name\":\"acf\/signature-cares-list\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_69972c0308b99\",\"title\":\"Entdecken Sie unsere Pflege\",\"_title\":\"field_69972c0308ba2\",\"description\":\"Unsere Zahn\u00e4rzte und Dentalhygienikerinnen sind dazu da, all Ihre Bed\u00fcrfnisse in Bezug auf die Zahnpflege zu erf\u00fcllen. Bitte kontaktieren Sie uns f\u00fcr weitere Informationen.\",\"_description\":\"field_69972c0308baa\",\"cares\":[\"4138\",\"4140\",\"4134\",\"4132\",\"4136\",\"13554\",\"12151\"],\"_cares\":\"field_69972c0308bb2\"},\"mode\":\"edit\"} \/-->","post_title":"Muttenz","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"muttenz","to_ping":"","pinged":"","post_modified":"2026-04-29 08:53:58","post_modified_gmt":"2026-04-29 06:53:58","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/zahnklinik-rennbahn\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4199,"post_author":"14","post_date":"2022-04-20 18:17:28","post_date_gmt":"2022-04-20 16:17:28","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Ihr Adent-Zahnarzt im Zentrum Sarnen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unser Zahnarztzentrum befindet sich im Herzen von Sarnen, einem charmanten Dorf im Kanton Obwalden. Wir bieten einen multidisziplin\u00e4ren Ansatz in der Zahnheilkunde durch \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/\\u0022\\u003eunser komplettes Team von Zahn\u00e4rzten\\u003c\/a\\u003e. Unser Team besteht aus Zahn\u00e4rzten, Prophylaxeassistentinnen und einem Kieferorthop\u00e4den. Erwachsene und \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\\u0022\\u003eKinder\\u003c\/a\\u003e werden in dem Zahnarztzentrum in Sarnen betreut. Unsere Zahn\u00e4rzte bieten Ihnen alle g\u00e4ngigen zahn\u00e4rztlichen Behandlungen an: \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/die-oralchirurgie\/\\u0022\\u003eWeisheitszahnentfernung\\u003c\/a\\u003e, Wurzelbehandlung, \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/implantat-und-restauration\/\\u0022\\u003eZahnspangen, Zahnimplantate\\u003c\/a\\u003e, aber auch \u00e4sthetische Behandlungen.\\r\\n\\r\\nMit Hilfe eines Kieferorthop\u00e4den k\u00f6nnen Sie Ihre Z\u00e4hne ausrichten und ein gesundes L\u00e4cheln erlangen. Unser \\u003ca href=\\u0022https:\/\/adent.ch\/de\/kieferorthopadie-sarnen\/\\u0022\\u003eKieferorthop\u00e4de in Sarnen\\u003c\/a\\u003e bietet verschiedene Ausrichtungstechniken an. Gemeinsam besprechen Sie das gew\u00fcnschte Ergebnis und die am besten geeignete kieferorthop\u00e4dische Technik.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Neben der normalen Zahnpflege bieten wir auch eine \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnaerztliche-notfaelle\/\\u0022\\u003eNotfallversorgung\\u003c\/a\\u003e an. Sie haben akute Zahnschmerzen oder einen Zahnunfall? Jeden Tag stehen Zeitfenster f\u00fcr Notf\u00e4lle zur Verf\u00fcgung.\\r\\n\\r\\nUnsere Prophylaxeassistentinnen beraten Sie \u00fcber die richtigen Techniken zur Erhaltung gesunder Z\u00e4hne und gesunden Zahnfleisches. Regelm\u00e4\u00dfige Zahnreinigungen tragen zur Erhaltung gesunder Z\u00e4hne und gesunden Zahnfleisches bei. Unsere Prophylaxe-Assistentinnen sind die Fachleute f\u00fcr Mundgesundheit, besuchen Sie sie regelm\u00e4\u00dfig.\\r\\n\\r\\nIn Sarnen begr\u00fc\u00dfen wir Sie von Montag bis Freitag und an einem Samstag im Monat. Das Zentrum ist f\u00fcr Rollstuhlfahrer zug\u00e4nglich.\\r\\n\\r\\n\\u003cstrong\\u003eLeiter des Zahnarztzentrums : \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnarzt\/basem-al-dalfi\/\\u0022\\u003eDr. Basem Al Dalfi \u00a0\\u003c\/a\\u003eSSO-diplomierter Zahnarzt\\u003c\/strong\\u003e\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cem\\u003eSamstag: 1x im Monat nach Absprache\\u003c\/em\\u003e\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"none\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"9397\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25019f6eb2\",\"shapes\":\"shape1\",\"_shapes\":\"field_622f5635c8595\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum in Sarnen\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und freundliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":\"\",\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 41 660 65 55\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Sarnen","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"sarnen","to_ping":"","pinged":"","post_modified":"2025-10-22 16:12:11","post_modified_gmt":"2025-10-22 14:12:11","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/sarnen\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4207,"post_author":"14","post_date":"2022-04-20 18:10:15","post_date_gmt":"2022-04-20 16:10:15","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Willkommen bei Adent Luzern\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u00220\\u0022 data-end=\\u0022663\\u0022\\u003eUnser \\u003cstrong data-start=\\u00226\\u0022 data-end=\\u002238\\u0022\\u003eAdent Zahnarztzentrum Luzern\\u003c\/strong\\u003e, ehemals unter dem Namen Cliniodent bekannt, ist seit 2021 Teil der \\u003cstrong data-start=\\u0022107\\u0022 data-end=\\u0022132\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e. Dieser Schritt markierte eine wichtige Weiterentwicklung: Unsere Patientinnen und Patienten profitieren seither von der Expertise eines schweizweiten Netzwerks an Spezialistinnen und Spezialisten, w\u00e4hrend alles erhalten blieb, was unser Zahnarztzentrum auszeichnet \u2013 dasselbe engagierte Team, dieselbe hohe Behandlungsqualit\u00e4t und eine transparente Preisgestaltung. Lediglich das visuelle Erscheinungsbild wurde modernisiert und spiegelt heute mit dem charakteristischen Adent-Gr\u00fcn Vertrauen, Innovation und Nachhaltigkeit wider.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022665\\u0022 data-end=\\u00221165\\u0022\\u003eZentral gelegen, nur wenige Schritte vom Bahnhof entfernt und eingebettet in die historische Altstadt von Luzern, \u00fcberzeugt unser Zahnarztzentrum durch eine ausgezeichnete Erreichbarkeit. Kinder, Jugendliche und Erwachsene werden in einer modernen, stilvollen und zugleich warmen Atmosph\u00e4re empfangen, die Ruhe vermittelt und eine vertrauensvolle Basis schafft. Unser Team spricht Deutsch, Franz\u00f6sisch, Englisch und Italienisch und gew\u00e4hrleistet so eine klare, pers\u00f6nliche und individuelle Betreuung.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221167\\u0022 data-end=\\u00221928\\u0022\\u003eEin interdisziplinaeres Team aus Zahnaerztinnen und Zahnaerzten, Dentalhygienikerinnen und spezialisierten Fachpersonen ermoeglicht eine umfassende und abgestimmte Betreuung. Das Leistungsspektrum reicht von allgemeiner Zahnmedizin ueber Zahnreinigung und Praevention bis hin zu Implantologie, Zahnaufhellung, Zahnersatz und massgeschneiderten Behandlungen fuer aengstliche Patientinnen und Patienten. Durch die enge Zusammenarbeit innerhalb des Teams entstehen individuelle Behandlungskonzepte mit einem ganzheitlichen Blick auf Ihre langfristige Mundgesundheit. Regelmaessige fachliche Austausche und Weiterbildungen innerhalb der Adent Zahnarztzentren stellen sicher, dass neueste Techniken und hoechste Behandlungsstandards in der Schweiz angewendet werden.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221930\\u0022 data-end=\\u00222471\\u0022\\u003eDer Praevention kommt in unserem Zahnarztzentrum eine zentrale Bedeutung zu. Unsere Spezialistinnen und Spezialisten begleiten Sie mit professioneller Zahnreinigung, persoenlicher Beratung zur Mundhygiene und regelmaessiger Kontrolle auf dem Weg zu einem gesunden, aesthetischen und nachhaltigen Laecheln. Gleichzeitig verfuegen unsere Zahnaerzte ueber fundierte Erfahrung in der Implantologie und bieten hochwertige, dauerhafte und aesthetisch anspruchsvolle Loesungen, um Kaufunktion, Komfort und Lebensqualitaet langfristig zu verbessern.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00222473\\u0022 data-end=\\u00222847\\u0022\\u003eBesonders am Herzen liegen uns Patientinnen und Patienten mit Zahnarztangst oder ausgepraegter Unsicherheit. Mit einer einfuelsamen, ruhigen und respektvollen Herangehensweise, moderner Schmerzbehandlung und einer entspannten Umgebung schaffen wir Vertrauen und Sicherheit. Ihr Wohlbefinden steht bei jedem Schritt im Mittelpunkt \u2013 von der ersten Beratung bis zur Nachsorge.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00222849\\u0022 data-end=\\u00223404\\u0022\\u003eDas \\u003cstrong data-start=\\u00222853\\u0022 data-end=\\u00222885\\u0022\\u003eAdent Zahnarztzentrum Luzern\\u003c\/strong\\u003e steht fuer Exzellenz, Innovation und Menschlichkeit. Dank moderner Infrastruktur, fortlaufender Weiterbildung und der Einbindung in ein anerkanntes nationales Netzwerk bieten wir Ihnen Behandlungen auf hoechstem Niveau. Ob Kontrolluntersuchung, aesthetische Zahnmedizin, Implantatversorgung oder regelmaessige Zahnreinigung \u2013 wir begleiten Sie von Montag bis Freitag mit Professionalitaet und Aufmerksamkeit. Bei zahnmedizinischen Notfaellen koennen Sie uns jederzeit kontaktieren oder direkt einen Termin vereinbaren.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"2958\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25019f6eb2\",\"shapes\":\"shape4\",\"_shapes\":\"field_622f5635c8595\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum Luzern\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":\"\",\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 41 420 90 80\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Luzern","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"luzern","to_ping":"","pinged":"","post_modified":"2025-12-31 15:01:02","post_modified_gmt":"2025-12-31 14:01:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/lucerne\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4195,"post_author":"14","post_date":"2022-05-13 11:01:17","post_date_gmt":"2022-05-13 09:01:17","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Ihr Adent-Zahnarzt im Zentrum Willisau\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Das Team der Zahnarztzentrum in Willisau wurde 2022 in die Adent Gruppe integriert.\u00a0Die hohe Qualit\u00e4t der Behandlungen und die st\u00e4ndige Weiterbildung der Mitarbeiter stehen bei der \\u003ca href=\\u0022https:\/\/adent.ch\/de\/gruppe\/\\u0022\\u003eAdent-Gruppe \\u003c\/a\\u003eim Mittelpunkt. \\u003cspan class=\\u0022fontstyle0\\u0022\\u003eWir bieten die neuesten Behandlungsmethoden in allen Fachgebieten der Zahnheilkunde an und passen unser Behandlungsspektrum st\u00e4ndig an die neuesten Entwicklungen an.\\u003c\/span\\u003e\\r\\n\\r\\nDas Zahnarztzentrum in Willisau verf\u00fcgt \u00fcber sieben Behandlungsr\u00e4ume und empf\u00e4ngt Sie von Montag bis Samstag in einer famili\u00e4ren Umgebung. Wir bieten Ihnen alle wesentlichen Zahnbehandlungen durch unsere diplomierten Zahn\u00e4rzte an.\\r\\n\\r\\nDas Team der Zahn\u00e4rzte wird durch unsere drei Dentalhygieniker erg\u00e4nzt, die sich auf Mundhygiene und Pr\u00e4vention spezialisiert haben. Sie f\u00fchren \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eZahnreinigungen\\u003c\/a\\u003e durch, behandeln Erkrankungen des Zahnhalteapprates (Parodontitis), wenden \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003eprofessionelle Zahnaufhellungen\\u003c\/a\\u003e an und geben Ihnen Ratschl\u00e4ge wie Sie Ihre Mundhygiene verbessern k\u00f6nnen.\\r\\n\\r\\n\\u0026nbsp;\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Unser Team besteht aus 4 Zahn\u00e4rzten, 4 Dentalhygienikern, 5 Dentalassistenten, einer Rezeptionistin und 1 Auszubildenden.\\r\\n\\r\\nUnser Zentrum in Willisau engagiert sich auch in der Schulzahnpflege in den umliegenden Gemeinden.\\r\\n\\r\\nF\u00fcr \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnaerztliche-notfaelle\/\\u0022\\u003ezahn\u00e4rztliche Notf\u00e4lle\\u003c\/a\\u003e steht Ihnen unser \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnaerztliche-notfaelle\/\\u0022\\u003eZahnarztzentrum\\u003c\/a\\u003e w\u00e4hrend seiner \u00d6ffnungszeiten zur Verf\u00fcgung. Ausserhalb dieser Zeiten k\u00f6nnen Sie den Zahnarzt-Notdienst unter 0848 58 24 89 erreichen. Diese Nummer gilt auch am Wochenende und an Feiertagen.\\r\\n\\r\\nDas Zentrum ist mit den \u00f6ffentlichen Verkehrsmitteln leicht zu erreichen (mit dem Bus: Haltestelle Willisau, Chr\u00fczhof). Ausserdem stehen Parkpl\u00e4tze vor der Zahnarztzentrum zur Verf\u00fcgung.\\r\\n\\r\\n\\u003cspan class=\\u0022fontstyle0\\u0022\\u003eWir freuen uns, Sie bei uns begr\u00fcssen zu d\u00fcrfen!\\u003c\/span\\u003e\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"none\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape1\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"13672\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25019f6eb2\",\"shapes\":\"shape1\",\"_shapes\":\"field_622f5635c8595\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum in Willisau\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und freundliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"Alle unsere Praktiker:innen\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":{\"title\":\"\u00c9quipe\",\"url\":\"https:\/\/adent.ch\/equipe\/\",\"target\":\"\"},\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 41 972 70 50\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Willisau","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"willisau","to_ping":"","pinged":"","post_modified":"2025-09-09 17:01:43","post_modified_gmt":"2025-09-09 15:01:43","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/willisau\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"}],"soins":[{"ID":4138,"post_author":"14","post_date":"2022-01-05 10:58:49","post_date_gmt":"2022-01-05 09:58:49","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mundgesundheit f\u00fcr Ihr Wohlbefinden.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Verschiedene Studien zeigen den Zusammenhang zwischen Entz\u00fcndungen im Mund und allgemeinen Gesundheitsproblemen. Mehr als 600 Bakterienarten tummeln sich in unserem Mund. Einige k\u00f6nnen in den Blutkreislauf gelangen und Sch\u00e4den verursachen: Herz-Kreislauf-Probleme, Blutzucker-Diabetes, Atemwegserkrankungen, Gelenkentz\u00fcndungen, Risiko einer Fr\u00fchgeburt.\\r\\n\\r\\nDie zahn\u00e4rztliche Betreuung ist Teil der medizinischen Grundversorgung. Regelm\u00e4\u00dfige Zahnhygiene und regelm\u00e4\u00dfige Kontrollen sind daher der Schl\u00fcssel zu einer guten Zahngesundheit und einem gesunden L\u00e4cheln. Ein L\u00e4cheln verl\u00e4ngert die Lebenserwartung, reduziert Stress und hat eine positive Wirkung auf den Gespr\u00e4chspartner. Ein gesundes L\u00e4cheln gibt Selbstvertrauen und Wohlbefinden im t\u00e4glichen Leben, im Beruf und im Privatleben.\\r\\n\\r\\nEine regelm\u00e4\u00dfige zahn\u00e4rztliche Kontrolle hilft, Probleme, die die Gesundheit Ihrer Z\u00e4hne und Ihres Zahnfleisches beeintr\u00e4chtigen k\u00f6nnen, fr\u00fchzeitig zu erkennen.\\r\\n\\r\\nWir empfehlen einen j\u00e4hrlichen Besuch, um Erkrankungen zu erkennen, zu \u00fcberwachen und zu behandeln.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Die Adent Zahnarztzentren bieten alle g\u00e4ngigen zahn\u00e4rztlichen Behandlungen f\u00fcr Erwachsene und Kinder unter einem Dach an:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eWurzelbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcllungen von abgebrochenen Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernung von Weisheitsz\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandlung von Karies\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eWiederherstellung von Zahnfleischproblemen (Gingivitis, Zahnfleischr\u00fcckgang, Parodontitis, Abszesse usw.).\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003e\u00e4sthetische Behandlungen\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nUnsere Dentalhygienikerinnen helfen Ihnen, eine individuelle Vorsorge zu treffen und k\u00f6nnen Ihnen eine Reihe von Reinigungshilfen empfehlen (B\u00fcrstchen, Zahnstocher, Faden usw.).\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Karies\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Karies: Vorbeugen ist besser als heilen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Hauptursachen f\u00fcr Karies sind eine zuckerhaltige Ern\u00e4hrung, unzureichende Mundpflege oder ein schwaches Immunsystem. Wenn Karies nicht behandelt wird, vergr\u00f6ssert sich der Hohlraum und greift auf das Dentin (die Schicht unter dem Zahnschmelz) oder den Zahnnerv. Es kann zu Schmerzen kommen, insbesondere bei Hitze, K\u00e4lte oder S\u00fcssem. Je gr\u00f6sser der Hohlraum wird, desto st\u00e4rker werden die Schmerzen. Das Zahnr\u00f6ntgenbild, das bei den regelm\u00e4ssigen Kontrollen gemacht wird, kann Anzeichen f\u00fcr eine fr\u00fche Karies erkennen.\\r\\n\\r\\n\\u003cstrong\\u003eWie wird Karies behandelt?\\u003c\/strong\\u003e\\r\\n\\r\\nDie Behandlung von Zahnkaries ist eine sehr h\u00e4ufige allgemeine zahn\u00e4rztliche Behandlung. Karies auf der Oberfl\u00e4che des Zahnschmelzes wird mit einfachen F\u00fcllungen behandelt, die die gleiche Farbe wie Ihr Zahn haben. Bei tieferer Karies kann manchmal eine Wurzelbehandlung und eine Zahnkrone erforderlich sein. Eine Zahnextraktion wird nur dann durchgef\u00fchrt, wenn es sich um eine weit fortgeschrittene Karies handelt, die das tiefe Gewebe des Zahns betrifft. Bei Eingriffen bei Erwachsenen und Kindern k\u00f6nnen wir selbstverst\u00e4ndlich eine An\u00e4sthesie durchf\u00fchren.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3757,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Die Wurzelbehandlung  \",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Bei der Wurzelbehandlung wird der infizierte, besch\u00e4digte oder tote Nerv Ihres Zahns entfernt. Das Herz des Zahns enth\u00e4lt die Nerven und Blutgef\u00e4sse. Sie erm\u00f6glichen es dem Zahn, sich zu entwickeln. Bakterien, die durch Karies, Risse oder besch\u00e4digte F\u00fcllungen in Ihren Zahn eindringen, f\u00fchren zur Bildung eines Abszesses. Dieser Abszess wird durch eine Infektion des Zahnmarks verursacht. In diesem Fall muss das Fruchtfleisch entfernt werden.\\r\\n\\r\\nDer Vorteil der Wurzelbehandlung ist, dass Sie Ihren Zahn behalten k\u00f6nnen, anstatt ihn zu extrahieren. Indem Sie Ihren nat\u00fcrlichen Zahn erhalten, verhindern Sie, dass die anderen Z\u00e4hne ihre Ausrichtung verlieren.\\r\\n\\r\\n\\u003cstrong\\u003eWie l\u00e4uft eine Wurzelbehandlung ab?\\u003c\/strong\\u003e\\r\\n\\r\\nIhr Zahnarzt bet\u00e4ubt den Zahn \u00f6rtlich und legt eine isolierende Membran um den Zahn. Er macht eine kleine \u00d6ffnung in den Zahn, um an den Kanal und die besch\u00e4digte Pulpa (das Herz des Zahns) zu gelangen. Mit Hilfe von Pr\u00e4zisionsinstrumenten entfernt er die Pulpa, reinigt und erweitert den Kanal. Der Zahnarzt f\u00fcllt den Kanal und verschliesst den Zahn mit einer provisorischen oder permanenten F\u00fcllung. Der Zahn ist nicht mehr empfindlich gegen\u00fcber Hitze oder K\u00e4lte, beh\u00e4lt aber seine Eigenschaften. Eine Krone und ein Stift sind in der Regel notwendig, um die Lebensdauer des Zahns zu verl\u00e4ngern.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Zahnfleisch\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Pflege des zahnfleisches\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3761,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Wurzelkanalbehandlung\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Wie wird eine Wurzelkanalbehandlung durchgef\u00fchrt?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Der Zahn wird zun\u00e4chst bet\u00e4ubt und mit einem Gummigewebe (Kofferdam) von der Mundh\u00f6hle isoliert.\\r\\nDer Zahn wird mit einem Bohrer ge\u00f6ffnet und die Eing\u00e4nge des Wurzelkanals dargestellt, die L\u00e4nge des Wurzelkanals wird elektrometrisch gemessen, entz\u00fcndetes und totes Gewebe wird vollst\u00e4ndig entfernt, alle Wurzelkan\u00e4le werden mit desinfizierenden L\u00f6sungen desinfiziert und mit dem Kunststoffmaterial gef\u00fcllt.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Wie lange dauert eine Wurzelkanalbehandlung?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Je nach Anzahl der Zahnwurzeln dauert die Behandlung des Wurzelkanals zwischen einer und zwei Stunden. Dank moderner Behandlungsmethoden f\u00fchren wir die geplante Wurzelbehandlung in der Regel in einer einzigen Sitzung durch, nur in sehr komplizierten F\u00e4llen sind mehrere Sitzungen erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wann ist eine Wurzelkanalbehandlung notwendig?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Bei Entz\u00fcndung oder Nekrose des Zahnnervs (kann mit starken Schmerzen einhergehen oder v\u00f6llig schmerzlos verlaufen), bei tieferer Karies, die bereits bis zum Zahnnerv vorgedrungen ist (meist mit einem oder wenigen Schmerzen verbunden) oder nach einem Unfall.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ist es m\u00f6glich, eine Wurzelbehandlung, die vor langer Zeit erfolglos durchgef\u00fchrt wurde, zu wiederholen?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Selbstverst\u00e4ndlich k\u00f6nnen wir die Wurzelkanalbehandlung in den meisten F\u00e4llen wiederholen und durch den Einsatz der heutigen modernen Behandlungsmethoden hohe Behandlungsergebnisse erzielen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape1\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Entfernung von Weisheitsz\u00e4hnen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Entfernung von Weisheitsz\u00e4hnen ist Teil der Oralchirurgie und der allgemeinen Zahnheilkunde. Es ist ein chirurgischer Eingriff, der regelm\u00e4ssig von Adent durchgef\u00fchrt und beherrscht wird.\\r\\n\\r\\nDie Weisheitsz\u00e4hne wachsen in der Regel zwischen dem 16. und 24. Lebensjahr. Es kann auch vorkommen, dass sie die Weisheitsz\u00e4hne nicht vorhanden sind. In den meisten F\u00e4llen m\u00fcssen sie entfernt werden, da sie nicht in die richtige Richtung wachsen oder unter dem Zahnfleisch \\u0022eingeschlossen\\u0022 sind.\\r\\n\\r\\nInfektionen des umgebenden Gewebes und der Nachbarz\u00e4hne, schwer zu behandelnde Karies oder Verschiebungen von Nachbarz\u00e4hnen k\u00f6nnen die Folge sein.\\r\\n\\r\\n\\u003cstrong\\u003eW\u00fcrden Sie mir empfehlen, meine Weisheitsz\u00e4hne zu entfernen?\\u003c\/strong\\u003e\\r\\n\\r\\nUm die Lage und die Anzahl der vorhandenen Weisheitsz\u00e4hne zu bestimmen, muss der Zahnarzt ein Panoramar\u00f6ntgenaufnahme Ihres Mundes machen. Der Zahnarzt wird Ihnen dann alle notwendigen Informationen geben, um einen Behandlungsplan f\u00fcr die Entfernung eines oder mehrerer Weisheitsz\u00e4hne zu erstellen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Extraktion\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"entfernung von weisheitszaehnen\",\"url\":\"https:\/\/adent.ch\/de\/info\/entfernung-von-weisheitszaehnen\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3792,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column {\"width\":\"100%\"} -->\n<div class=\"wp-block-column\" style=\"flex-basis:100%\"><!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Entz\u00fcndungen und Infektionen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Das St\u00fctzgewebe, das Ihre Z\u00e4hne umgibt, ist wertvoll: Pflegen Sie es!\\r\\n\\r\\n\\u003cstrong\\u003eParodontitis\\u003c\/strong\\u003e (Zahnlockerung) ist eine Krankheit, die das St\u00fctzgewebe betrifft, das Ihren Zahn umgibt und st\u00fctzt. Die Zerst\u00f6rung dieses Gewebes f\u00fchrt zu Beweglichkeit und schliesslich zum Verlust des Zahns. Es gibt verschiedene Stadien der Zahnfleischerkrankung.\\r\\n\\r\\nDas Anfangsstadium ist \\u003cstrong\\u003eGingivitis\\u003c\/strong\\u003e. Sie betrifft nur das Zahnfleisch und ist durch eine Entz\u00fcndung gekennzeichnet: das Zahnfleisch blutet, ist rot und geschwollen.\\r\\n\\r\\nParodontalerkrankungen sind die Hauptursache f\u00fcr Zahnverlust bei Erwachsenen. Etwa 75% der Erwachsenen leiden im Laufe ihres Lebens in unterschiedlichem Ausmass an Zahnfleischproblemen. Die Krankheit kann jedoch auch junge Menschen betreffen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Zahnfleisch\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"pflege des zahnfleisches\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3686,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape5\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/--><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Gef\u00e4hrdete Zahnfleisch: schnell handeln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eWas passiert bei einer Zahnfleischentz\u00fcndung?\\u003c\/strong\\u003e\\r\\n\\r\\nWenn die Gingivitis nicht behandelt wird, breitet sich die Entz\u00fcndung aus und greift auf den Knochen \u00fcber. Der Knochen umgibt Ihre Z\u00e4hne und sorgt daf\u00fcr, dass sie im Kiefer bleiben. Wenn nichts unternommen wird, wird der Knochen, die B\u00e4nder und das gesamte Gewebe, das Ihre Z\u00e4hne st\u00fctzt und umgibt, nach und nach zerst\u00f6rt. Diese Zerst\u00f6rung des Gewebes f\u00fchrt zum Verlust eines oder mehrerer Z\u00e4hne. Dies wird als Parodontitis bezeichnet.\\r\\n\\r\\nZahnlockerung (Parodontitis) ist eine Krankheit, die das Zahnhaltegewebe betrifft. Sie muss von Fachgebieten, die Parodontologen genannt werden, behandelt werden. Eine Zusammenarbeit zwischen Patient, Parodontologe und Dentalhygienikerin ist notwendig, um die Heilung zu optimieren. Um Ihnen die bestm\u00f6gliche Versorgung zu garantieren, bringen wir alle diese Berufe in jedem der Adent Zahnarztzentren zusammen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3764,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\u00dcbliche Zahnpflege\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e250b73f5a9\",\"shapes\":\"shape8\",\"_shapes\":\"field_62149e038cf63\"},\"mode\":\"edit\"} \/-->","post_title":"\u00dcbliche Zahnpflege","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnaerztliche-routineversorgung","to_ping":"","pinged":"","post_modified":"2025-06-04 17:12:12","post_modified_gmt":"2025-06-04 15:12:12","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-courants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4140,"post_author":"14","post_date":"2022-01-03 13:50:41","post_date_gmt":"2022-01-03 12:50:41","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Das Beste fu\u0308r kleine La\u0308cheln.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Kinderzahn\u00e4rzte sind in einem kindgerechten psychologischen und p\u00e4dagogischen Ansatz geschult. Ihre Aufgabe ist es, zu beruhigen und mit einem altersgerechten Vokabular zu sprechen, um ein Klima des Vertrauens zu schaffen.\\r\\n\\r\\nWir f\u00fchren alle Arten von Zahnbehandlungen bei Kindern durch.\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eKariesbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eabgebrochener Zahn\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eZahnreinigung\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eTipps zum B\u00fcrsten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":16375,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Kieferorthop\u00e4dische Behandlungen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Zahn\u00e4rzte, die sich auf Kieferorthop\u00e4die spezialisiert haben, bieten kieferorthop\u00e4dische Behandlung f\u00fcr Kinder an. Eine kieferorthop\u00e4dische Behandlung kann in jedem Alter begonnen werden, aber die meisten Eltern w\u00fcnschen sich f\u00fcr ihre Kinder eine fr\u00fchzeitige Behandlung. Je nach Art der erforderlichen Behandlung kann eine erste Phase des Abfangens von Kieferorthop\u00e4den bereits ab dem 4. Lebensjahr stattfinden. In den Adent Zahnarztzentren werden verschiedene kieferorthop\u00e4dische Behandlungen angeboten, die sich an die jeweilige Mundsituation anpassen. Weitere Informationen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eauf unserer Seite \u00fcber Kieferorthop\u00e4de f\u00fcr Kinder\\u003c\/a\\u003e!\\r\\n\\r\\nZus\u00e4tzlich zu diesen zahn\u00e4rztlichen Behandlungen erkl\u00e4ren unsere diplomierten Dentalhygienikerinnen mit p\u00e4dagogischen Methoden, wie Z\u00e4hne und Zahnfleisch gesund erhalten werden k\u00f6nnen. Unsere Fachgebiete f\u00fcr zahn\u00e4rztliche Pr\u00e4vention helfen ihnen, die richtigen Verhaltensweisen zu erlernen, sobald sie die ersten Z\u00e4hne bekommen.\\r\\n\\r\\nHaben Sie Fragen zur Zahnhygiene bei Babys oder Jugendlichen? \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eBesuchen Sie unsere Seite zu diesen Themen\\u003c\/a\\u003e!\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Jeder Zahn muss t\u00e4glich gereinigt werden, egal wie klein er ist. Nach der Nahrungsaufnahme bildet sich ein Biofilm auf der Oberfl\u00e4che des Zahnschmelzes. Dieser Biofilm entwickelt sich weiter, wenn er nicht regelm\u00e4\u00dfig gereinigt wird. Dies f\u00fchrt zu wei\u00dfen, weichen Ablagerungen auf der Oberfl\u00e4che der Z\u00e4hne, die als Plaque bezeichnet werden. Zahnbelag besteht unter anderem aus Bakterien. Bakterien k\u00f6nnen Karies verursachen, wenn die Reinigung nicht regelm\u00e4ssig erfolgt. Plaque kann sich auch zu Zahnstein entwickeln, einem harten, wei\u00dfen Belag, der mit der Zahnb\u00fcrste nicht entfernt werden kann.\\r\\n\\r\\nAuch wenn dies selten vorkommt, kann sich ein Schaden an einem Milchzahn auf einen Erwachsenenzahn auswirken. Die Keime der erwachsenen Z\u00e4hne, die sich unter dem Zahnfleisch bilden, sind empfindlich. Sie k\u00f6nnen besch\u00e4digt werden, wenn ein Milchzahn infiziert wird.\\r\\n\\r\\nHeutzutage gibt es eine breite Palette von Hilfsmitteln f\u00fcr die Zahnreinigung bei Kindern. Sie k\u00f6nnen leicht elektrische Zahnb\u00fcrsten, Zahnseide in Tierform, bunte Kinderzahnb\u00fcrsten usw. erwerben. Diese Hilfsmittel helfen Ihnen dabei, die Mundhygiene Ihres Kindes zu verbessern. Lassen Sie sich von \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eunseren Dentalhygienikerinnen\\u003c\/a\\u003e beraten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Zahnarztangst\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Kind hat Angst vor dem Zahnarzt, was kann ich tun?\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"F\u00fcr Kinder mit Phobie oder Angst vor dem Zahnarzt haben wir L\u00f6sungen! Unsere Zahn\u00e4rzte bieten Lachgas- und Hypnosebehandlungen an, die auch bei Kindern einfach und sicher durchzuf\u00fchren sind. Weitere Informationen finden Sie hier.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie kann ich Zahnprobleme bei meinem Kind vermeiden?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16307,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Geben Sie gute Gewohnheiten weiter!\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Das Z\u00e4hneputzen wird 3x\/Tag empfohlen: Putzen Sie die Z\u00e4hne nach jeder Mahlzeit und vermeiden Sie bei Ihren Kindern das st\u00e4ndige Naschen von S\u00fcssigkeiten, da dies Karies und Schmerzen verursachen kann.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16347,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"B\u00fcrsten ab den ersten Z\u00e4hnen.\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Dies kann eine schwierige Aufgabe sein, aber alle Z\u00e4hne, auch wenn sie noch so klein sind, m\u00fcssen t\u00e4glich gereinigt werden. Tragen Sie ab dem ersten Zahn bis zum Alter von ca. 3 Jahren Zahnpasta in der Gr\u00f6sse eines Reiskorns auf, danach in der Gr\u00f6sse einer Erbse.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16350,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"S\u00fcssigkeiten ja, mit Sympadent\u00ae!\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie \\u003ca href=\\u0022https:\/\/zahnfreundlich.ch\/lassociation-sympadent-sengage-pour-des-dents-denfant-saines\/?lang=fr\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eSympadent\u00ae Bonbons\\u003c\/a\\u003e: Sie wurden getestet und f\u00fcr gut befunden. Diese S\u00fcssigkeiten schonen die Z\u00e4hne von Kindern und Erwachsenen. Sie k\u00f6nnen es in verschiedenen Gesch\u00e4ften in der Schweiz kaufen. Achten Sie auf das Zahnlogo unter dem Regenschirm.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":16562,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Alles miteinander teilen? Ja, aber...\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Vermeiden Sie es, den L\u00f6ffel oder andere Gegenst\u00e4nde in den Mund zu nehmen, bevor Sie sie Ihrem Baby geben: Karies verursachende Bakterien werden \u00fcbertragen.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs_4_image\":16311,\"_blocs_4_image\":\"field_623c222ba627a\",\"blocs_4_title\":\"Eine zus\u00e4tzliche Hilfe f\u00fcr eine optimale Reinigung.\",\"_blocs_4_title\":\"field_623c22c4a627b\",\"blocs_4_description\":\"Elektrische Zahnb\u00fcrsten sind eine gute Hilfe f\u00fcr Ihr Kind. Dies erleichtert das B\u00fcrsten und ermutigt sie. Unsere Dentalhygienikerinnen beraten Sie gerne.\",\"_blocs_4_description\":\"field_623c22cba627c\",\"blocs_4_button_type\":\"none\",\"_blocs_4_button_type\":\"field_623c34377e92d\",\"blocs_5_image\":16353,\"_blocs_5_image\":\"field_623c222ba627a\",\"blocs_5_title\":\"Eine fluoridierte Zahnpasta, die f\u00fcr sein Alter geeignet ist.\",\"_blocs_5_title\":\"field_623c22c4a627b\",\"blocs_5_description\":\"Fluor sch\u00fctzt die Z\u00e4hne vor Karies. Sie finden leicht Zahnpasta f\u00fcr Kinder unter 6 Jahren, f\u00fcr Kinder von 6 bis 12 Jahren und f\u00fcr Erwachsene. Wechseln Sie den Geschmack der Zahnpasta regelm\u00e4ssig: Kinder m\u00f6gen Abwechslung.\",\"_blocs_5_description\":\"field_623c22cba627c\",\"blocs_5_button_type\":\"none\",\"_blocs_5_button_type\":\"field_623c34377e92d\",\"blocs\":6,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnpflege f\u00fcr Kinder\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie unsere Zahn\u00e4rzte, die auf die Behandlung von Kindern spezialisiert sind.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Einen spezialisierten Zahnarzt finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4140\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnpflege f\u00fcr Kinder","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbehandlung-fuer-kinder","to_ping":"","pinged":"","post_modified":"2026-01-19 15:07:44","post_modified_gmt":"2026-01-19 14:07:44","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-pour-les-enfants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4132,"post_author":"14","post_date":"2022-01-01 13:49:42","post_date_gmt":"2022-01-01 12:49:42","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Ein gesundes L\u00e4cheln f\u00fcr das ganze Leben\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Kieferorthop\u00e4die bietet einen doppelten Nutzen: \u00e4sthetische und funktionelle Vorteile. Denn durch die Korrektur von Fehlstellungen, zu wenig oder zu viel Platz f\u00fcr die Z\u00e4hne, kann die Abnutzung langfristig begrenzt und das Z\u00e4hneputzen erleichtert werden. Ausserdem st\u00e4rkt ein gesundes, harmonisches L\u00e4cheln das Selbstbewusstsein.\\r\\n\\r\\nIn unseren \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnkliniken\/\\u0022\\u003eAdent-Zahnarztzentren\\u003c\/a\\u003e bieten wir massgeschneiderte kieferorthop\u00e4dische Behandlungen f\u00fcr Erwachsene und Kinder an.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Eine pers\u00f6nliche Betreuung erm\u00f6glicht Ihnen, Ihr \u00e4sthetisches L\u00e4cheln und Ihr Wohlbefinden wiederzufinden. Unsere Kieferorthop\u00e4den verwenden \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/die-technologien-der-adent-gruppe\/\\u0022\\u003edie neuesten Technologien\\u003c\/a\\u003e und bieten Ihnen je nach Ausgangssituation und gew\u00fcnschtem Ergebnis verschiedene kieferorthop\u00e4dische Behandlungen an. Diskrete Behandlungen (z. B. die kieferorthop\u00e4dische Methode mit \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\\u0022\\u003eder transparenten Zahnschiene Invisalign\u00ae)\\u003c\/a\\u003e sind f\u00fcr Erwachsene und junge Erwachsene verf\u00fcgbar. Auch die klassische Zahnspange mit Brackets ist eine wirksame, bekannte und anerkannte Behandlungsmethode.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Mein Zentrum finden\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape6\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Welche Techniken gibt es, um meine Z\u00e4hne zu richten?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":3727,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"1. Die vestibul\u00e4ren Brackets\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Unsere Kieferorthop\u00e4den bieten Ihnen festsitzende (sichtbare und unsichtbare) oder herausnehmbare (sichtbare und unsichtbare) Zahnspangen an. Die traditionellen \\u0022Brackets\\u0022 der Zahnspange sind die beliebteste Behandlung. Sie werden einzeln auf jeden Zahn geklebt und ein Metallbogen verbindet die einzelnen Z\u00e4hne miteinander. Zahnspangen (Brackets), die derzeit bekannteste Zahnspange, sind auch in Keramik - zahnfarben - erh\u00e4ltlich. In regelm\u00e4ssigen Abst\u00e4nden werden leichte Spannungen ausge\u00fcbt, die eine sanfte Bewegung der Z\u00e4hne erm\u00f6glichen.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"button\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_0_button_text\":\"Mein Kieferorthop\u00e4de\",\"_blocs_0_button_text\":\"field_623c34767e92e\",\"blocs_0_button_link\":{\"title\":\"\u00c9quipe\",\"url\":\"https:\/\/adent.ch\/de\/team\/\",\"target\":\"_blank\"},\"_blocs_0_button_link\":\"field_623c347f7e92f\",\"blocs_0_is_blank\":\"0\",\"_blocs_0_is_blank\":\"field_623c34b67e930\",\"blocs_1_image\":3734,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"2. Durchsichtige Zahnspange\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Eine kieferorthop\u00e4dische Behandlung ohne Zahnspange ist mit Invisalign\u00ae m\u00f6glich! Bei dieser Technik wird eine Reihe von herausnehmbaren, transparenten Schienen verwendet, um Ihre Z\u00e4hne ohne sichtbaren Dr\u00e4hte oder Brackets auszurichten. Sie tragen jede Serie von Schienen etwa zwei Wochen lang und nehmen sie nur zum Essen, Trinken und Z\u00e4hneputzen heraus. Da Sie jede durchsichtige Schiene durch die n\u00e4chste in der Reihe ersetzen, bewegen sich Ihre Z\u00e4hne Woche f\u00fcr Woche nach und nach, bis sie die endg\u00fcltige Position erreicht haben.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"button\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_1_button_text\":\"Invisalign\u00ae entdecken\",\"_blocs_1_button_text\":\"field_623c34767e92e\",\"blocs_1_button_link\":{\"title\":\"Invisalign Behandlung\",\"url\":\"https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\",\"target\":\"\"},\"_blocs_1_button_link\":\"field_623c347f7e92f\",\"blocs_1_is_blank\":\"0\",\"_blocs_1_is_blank\":\"field_623c34b67e930\",\"blocs_2_image\":3731,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"3. Die Lingualringe (an den Innenseiten)\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Eine linguale Zahnspange ist eine Zahnspange, die hinter den Z\u00e4hnen und vor der Zunge sitzt (daher der Name: \\u0022lingual\\u0022). Gut versteckt und von aussen v\u00f6llig unsichtbar. Die Brackets sind durch einen Metallbogen miteinander verbunden, der den Druck auf die Z\u00e4hne aus\u00fcbt und sie sanft bewegt, bis die gew\u00fcnschte Ausrichtung erreicht ist.\\r\\nSie k\u00f6nnen aus verschiedenen Materialien und Formen hergestellt werden, je nachdem, welche Marke oder welches Modell der Kieferorthop\u00e4de verwendet.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"button\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_2_button_text\":\"Mein Zentrum finden\",\"_blocs_2_button_text\":\"field_623c34767e92e\",\"blocs_2_button_link\":{\"title\":\"Zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_blocs_2_button_link\":\"field_623c347f7e92f\",\"blocs_2_is_blank\":\"0\",\"_blocs_2_is_blank\":\"field_623c34b67e930\",\"blocs\":3,\"_blocs\":\"field_623c21f0a6279\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25104d76c2\",\"shapes\":\"shape1\",\"_shapes\":\"field_623c20cd3ad28\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/tab {\"name\":\"acf\/tab\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd13882c1f\",\"tabs_0_name\":\"Kind\",\"_tabs_0_name\":\"field_624449592e9bd\",\"tabs_0_tab\":13558,\"_tabs_0_tab\":\"field_624449622e9be\",\"tabs_1_name\":\"Erwachsener\",\"_tabs_1_name\":\"field_624449592e9bd\",\"tabs_1_tab\":13559,\"_tabs_1_tab\":\"field_624449622e9be\",\"tabs\":2,\"_tabs\":\"field_624449452e9bc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Kieferorthop\u00e4die f\u00fcr Kinder und Erwachsene\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Weitere Informationen \u00fcber Kieferorthop\u00e4die?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Vereinbaren Sie einen Termin mit einem\/r Kieferorthop\u00e4den\/in, um die M\u00f6glichkeiten der Zahnstellung zu besprechen.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Termin vereinbaren\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Kieferorthop\u00e4die f\u00fcr Kinder und Erwachsene\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Warum sollte man sich f\u00fcr Kieferorthop\u00e4die entscheiden?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"An Kieferorthop\u00e4die denkt man oft zuerst aus \u00e4sthetischen Gr\u00fcnden, doch die Vorteile einer kieferorthop\u00e4dischen Behandlung sind weitaus zahlreicher. Denn Z\u00e4hne und Kiefer in Fehlstellungen k\u00f6nnen zu Funktionsst\u00f6rungen f\u00fchren und sind unter Umst\u00e4nden schwer zu reinigen. Eine schlechte Zahnreinigung f\u00fchrt zu einer Ansammlung von Plaque auf den Z\u00e4hnen und tr\u00e4gt zur Entwicklung von Karies und Zahnfleischerkrankungen (z. B. Zahnfleischschwund) bei. Aufgrund der Schmerzen kann das Kauen beeintr\u00e4chtigt werden und weniger effizient sein, was sich auf Ihre Ern\u00e4hrung und Verdauung auswirkt. Zahnfehlstellungen k\u00f6nnen auch zu \u00fcberm\u00e4ssiger Abnutzung der Z\u00e4hne, Schmerzen im Kiefer, im Kopf, im Nacken und in den Gesichtsmuskeln f\u00fchren.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was sind die Vorteile der Kieferorthop\u00e4die?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Die Vorteile einer kieferorthop\u00e4dischen Behandlung mithilfe einer Zahnspange oder \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\\u0022\\u003eeiner transparenten Invisalign\u00ae-Schiene\\u003c\/a\\u003e (z. B. bei Kindern oder Erwachsenen) sind vielf\u00e4ltig.\\r\\n\\u003col\\u003e\\r\\n \\t\\u003cli\\u003eStellt einen optimalen Biss wieder her: Ein guter Kontakt zwischen den oberen und unteren Z\u00e4hnen f\u00f6rdert das richtige Kauen.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eVerhindert Zahnabnutzung: Wenn die Ausrichtung optimal ist, wird die Zahnabnutzung minimiert. Ihr Zahnschmelz sowie die Form Ihrer Z\u00e4hne bleiben erhalten.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eSorgt f\u00fcr eine bessere Mundgesundheit: Anomalien in der Stellung Ihrer Z\u00e4hne oder Ihres Kiefers k\u00f6nnen zu Schmerzen und Entz\u00fcndungen des Zahnfleisches f\u00fchren. Harmonisch ausgerichtete Z\u00e4hne bieten einen besseren Zugang f\u00fcr die Reinigung.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eStellt ein harmonisches Erscheinungsbild wieder her: Eine optimale Ausrichtung verleiht Selbstvertrauen. Finden Sie zu einem strahlenden L\u00e4cheln zur\u00fcck und steigern Sie Ihr Selbstvertrauen.\\u003c\/li\\u003e\\r\\n\\u003c\/ol\\u003e\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wie viel kostet eine kieferorthop\u00e4dische Behandlung?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Die Kosten f\u00fcr eine kieferorthop\u00e4dische Behandlung k\u00f6nnen erst nach einer umfassenden zahn\u00e4rztlichen Kontrolle bei Ihrem Kieferorthop\u00e4den festgelegt werden. Die Kontrolle wird im Zahnarztzentrum in Anwesenheit der Fachkraft durchgef\u00fchrt. Der Kieferorthop\u00e4de erh\u00e4lt so einen \u00dcberblick \u00fcber Ihren aktuellen Mund- und Zahnstatus und kann sich bei der vollst\u00e4ndigen Untersuchung auf das Vorhandensein von R\u00f6ntgenbildern st\u00fctzen. Sie besprechen die verschiedenen Behandlungsm\u00f6glichkeiten und legen gemeinsam das gew\u00fcnschte Ergebnis fest. Der Preis f\u00fcr eine kieferorthop\u00e4dische Behandlung wird daher erst nach einer Untersuchung durch einen unserer Experten f\u00fcr Kieferorthop\u00e4die festgelegt. Dabei sind mehrere Faktoren zu ber\u00fccksichtigen:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003edie verwendete Technik\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003edie Dauer der Behandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003evorhandene Fehlstellungen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003edas gew\u00fcnschte Endergebnis beeinflusst auch die Kosten der Behandlung\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDiese verschiedenen Aspekte sollten mit unseren Kieferorthop\u00e4den besprochen werden.\\r\\n\\r\\n\\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4132\\u0022\\u003eFinden Sie Ihren Kieferorthop\u00e4den.\\u003c\/a\\u003e\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Wie kann ich w\u00e4hrend meiner Behandlung den Kieferorthop\u00e4den in der Schweiz wechseln?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Den Kieferorthop\u00e4den w\u00e4hrend der Behandlung zu wechseln, ist durchaus m\u00f6glich und kann verschiedene Gr\u00fcnde haben, z. B. einen Umzug, Unzufriedenheit mit der aktuellen Behandlung, Kommunikationsprobleme mit dem aktuellen Behandler oder eine Pr\u00e4ferenz f\u00fcr eine andere Art von Zahnspange.\\r\\n\\r\\nUm den Kieferorthop\u00e4den zu wechseln, m\u00fcssen Sie mehrere wichtige Schritte unternehmen:\\r\\n\\u003col\\u003e\\r\\n \\t\\u003cli\\u003eInformieren Sie Ihren derzeitigen Kieferorthop\u00e4den \u00fcber Ihre Entscheidung. Er ist f\u00fcr die Wartung Ihrer kieferorthop\u00e4dischen Ger\u00e4te und die \u00dcberwachung Ihrer Mundgesundheit verantwortlich und muss Ihre Unterlagen und alle relevanten Informationen an den neuen Zahnarzt weiterleiten.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eVereinbaren Sie einen Termin f\u00fcr eine erste Beratung mit dem neuen Kieferorthop\u00e4den. Dieser Termin erm\u00f6glicht es dem neuen Spezialisten, Ihre Mundgesundheit zu beurteilen und die Komplexit\u00e4t Ihres Falls zu verstehen. Es ist auch sehr wichtig, dass Sie alle Unterlagen \u00fcber Ihre aktuelle Behandlung mitbringen, z. B. R\u00f6ntgenbilder oder Zahnabdr\u00fccke.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eSorgen Sie f\u00fcr eine transparente Kommunikation mit dem neuen Kieferorthop\u00e4den. Erkl\u00e4ren Sie Ihre Erwartungen und die Gr\u00fcnde, warum Sie sich f\u00fcr einen Wechsel des Kieferorthop\u00e4den entschieden haben. Es ist wichtig, dass der neue Kieferorthop\u00e4de Ihre Bed\u00fcrfnisse und Vorlieben versteht, damit die Behandlung erfolgreich fortgesetzt werden kann.\\u003c\/li\\u003e\\r\\n\\u003c\/ol\\u003e\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions_4_title\":\"Wird die Kieferorthop\u00e4die in der Schweiz erstattet?\",\"_accordions_4_title\":\"field_626fdd3ff47be\",\"accordions_4_content\":\"In der Schweiz werden kieferorthop\u00e4dische Behandlungen nicht von der Grundversicherung der Krankenkasse (KVG) gedeckt, die Zahnbehandlungen wird nur dann verg\u00fctet, wenn sie aufgrund einer schweren Krankheit oder eines Unfalls notwendig ist. Um eine Erstattung der Kosten f\u00fcr Kieferorthop\u00e4die zu erhalten, ist es wichtig, eine Zahnzusatzversicherung abzuschliessen.\\r\\n\\r\\nHier sind einige Schl\u00fcsselpunkte zur Erstattung kieferorthop\u00e4discher Behandlungen durch die Zusatzversicherungen in der Schweiz :\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eIn den Vertr\u00e4gen wird der Prozentsatz der Deckung angegeben, der zwischen 50% und 90% liegen kann, und der Restbetrag ist vom Patienten zu tragen.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eDie Versicherungen k\u00f6nnen ein H\u00f6chstalter f\u00fcr die Kosten\u00fcbernahme angeben, das h\u00e4ufig zwischen 18 und 25 Jahren liegt, nach dem sie die Kosten f\u00fcr Kieferorthop\u00e4die nicht mehr \u00fcbernehmen.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEs kann eine Jahres- oder Gesamtobergrenze f\u00fcr die Erstattung der Behandlungskosten geben, die den Betrag begrenzt, den die Versicherung im Jahr oder \u00fcber die gesamte Dauer der Behandlung zahlt.\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nIm Durchschnitt bieten die Zusatzversicherungen eine R\u00fcckerstattung von 75% an, wobei die j\u00e4hrlichen H\u00f6chstgrenzen in der Regel zwischen CHF 1'000 und CHF 15'000 liegen. Es wird empfohlen, eine Versicherung mit einer maximalen Deckungssumme von mindestens CHF 5'000 zu haben, um gut versichert zu sein.\\r\\n\\r\\nBei Kindern k\u00f6nnen die Einzelheiten der Erstattung variieren, und es ist ratsam, die Leistungen der verschiedenen Versicherungsgesellschaften zu vergleichen. In der Regel m\u00fcssen Sie auch mit dem Versicherungsschutz immer einen Teil der Kosten selbst tragen.\",\"_accordions_4_content\":\"field_626fdd46f47bf\",\"accordions\":5,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\"},\"mode\":\"edit\"} \/-->","post_title":"Kieferorthop\u00e4die f\u00fcr Kinder und Erwachsene","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"kieferorthopaedie-fuer-kinder-und-erwachsene","to_ping":"","pinged":"","post_modified":"2026-02-23 10:45:33","post_modified_gmt":"2026-02-23 09:45:33","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/orthodontie-pour-enfants-et-adultes\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Can IRI | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Can Iri, erfahrener Zahnarzt im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Can IRI | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Can Iri, erfahrener Zahnarzt im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T11:32:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/can-iri\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/can-iri\\\/\",\"name\":\"Can IRI | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2025-12-09T14:20:24+00:00\",\"dateModified\":\"2025-12-17T11:32:49+00:00\",\"description\":\"Can Iri, erfahrener Zahnarzt im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/can-iri\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/can-iri\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/can-iri\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Team\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Can IRI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Can IRI | Adent Zahnarztzentrum","description":"Can Iri, erfahrener Zahnarzt im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/","og_locale":"de_DE","og_type":"article","og_title":"Can IRI | Adent Zahnarztzentrum","og_description":"Can Iri, erfahrener Zahnarzt im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.","og_url":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2025-12-17T11:32:49+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/","url":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/","name":"Can IRI | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2025-12-09T14:20:24+00:00","dateModified":"2025-12-17T11:32:49+00:00","description":"Can Iri, erfahrener Zahnarzt im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/zahnarzt\/can-iri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Team","item":"https:\/\/adent.ch\/de\/team\/"},{"@type":"ListItem","position":2,"name":"Can IRI"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe\/16256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=16256"}],"wp:term":[{"taxonomy":"langue","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/langue?post=16256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}