{"id":16268,"date":"2025-12-19T17:06:52","date_gmt":"2025-12-19T16:06:52","guid":{"rendered":"https:\/\/adent.ch\/dentistes\/victoire-bastide-3\/"},"modified":"2025-12-19T17:12:46","modified_gmt":"2025-12-19T16:12:46","slug":"tatevik-gevorgyan","status":"publish","type":"equipe","link":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/","title":{"rendered":"Tatevik GEVORGYAN"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p data-start=\"87\" data-end=\"435\">Tatevik Gevorgyan ist Zahn\u00e4rztin und engagiert sich f\u00fcr eine ganzheitliche Betreuung der Mund- und Zahngesundheit ihrer Patientinnen und Patienten. Sie begleitet Erwachsene und Kinder mit einer professionellen, aufmerksamen und respektvollen Herangehensweise und legt dabei besonderen Wert auf Komfort und Vertrauen w\u00e4hrend der gesamten Behandlung.<\/p>\n<p data-start=\"437\" data-end=\"1003\">Dank einer Praxis, die auf modernen Techniken und hohen Qualit\u00e4tsstandards basiert, bietet Tatevik Gevorgyan Behandlungen an, die auf die spezifischen Bed\u00fcrfnisse jeder Patientin und jedes Patienten abgestimmt sind. Sie hat stets ein offenes Ohr und nimmt sich die Zeit, jeden Behandlungsschritt verst\u00e4ndlich zu erkl\u00e4ren, damit fundierte Entscheidungen in Bezug auf die Mund- und Zahngesundheit getroffen werden k\u00f6nnen. Ihr Ziel ist es, individuelle Behandlungen in einer beruhigenden Atmosph\u00e4re anzubieten und dabei eine langfristige Vertrauensbeziehung aufzubauen.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>","protected":false},"template":"","langue":[103],"class_list":["post-16268","equipe","type-equipe","status-publish","hentry","langue-franzoesisch"],"acf":{"job":"Zahn\u00e4rztin","short_description":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:7c8055f6-18a9-4b19-af7b-43a258344f6a-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"9673ba86-7fe9-4881-abe4-ba31eececeb6\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"1679\" data-end=\"1771\" data-is-last-node=\"\" data-is-only-node=\"\">Erfahrene Zahn\u00e4rztin bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes L\u00e4cheln.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\"><\/div>\n<div class=\"mt-3 w-full empty:hidden\">\n<div class=\"text-center\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"pointer-events-none h-px w-px\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n","specialites":[{"label":"\u00dcbliche Zahnpflege","link":"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/"}],"higlight_specialite":"","higlight_specialite_short":"","zawin_codes":false,"first_name":"Tatevik","last_name":"GEVORGYAN","image":{"ID":16273,"id":16273,"title":"Tatevik Gevorgyan_Acacias","filename":"tatevik-gevorgyan_acacias.png","filesize":2315309,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","link":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/tatevik-gevorgyan_acacias-2\/","alt":"","author":"14","description":"","caption":"","name":"tatevik-gevorgyan_acacias-2","status":"inherit","uploaded_to":16268,"date":"2025-12-19 16:09:24","modified":"2025-12-19 16:09:24","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":0,"height":0,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","thumbnail-width":1,"thumbnail-height":1,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","medium-width":1,"medium-height":1,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","medium_large-width":1,"medium_large-height":1,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","large-width":1,"large-height":1,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","1536x1536-width":1,"1536x1536-height":1,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","2048x2048-width":1,"2048x2048-height":1,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","gform-image-choice-sm-width":1,"gform-image-choice-sm-height":1,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","gform-image-choice-md-width":1,"gform-image-choice-md-height":1,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2025\/12\/tatevik-gevorgyan_acacias.png","gform-image-choice-lg-width":1,"gform-image-choice-lg-height":1}},"cliniques":[{"ID":4241,"post_author":"14","post_date":"2022-04-20 14:35:51","post_date_gmt":"2022-04-20 12:35:51","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Willkommen bei Adent Genf Acacias\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u00220\\u0022 data-end=\\u0022687\\u0022\\u003eIm lebendigen Gesch\u00e4ftsviertel Acacias gelegen, geniesst das \\u003cstrong data-start=\\u002261\\u0022 data-end=\\u002293\\u0022\\u003eZahnarztzentrum Genf Acacias\\u003c\/strong\\u003e einen ausgezeichneten Ruf bei Patientinnen und Patienten, die in der N\u00e4he wohnen oder arbeiten. Dank der zentralen Lage ist es leicht erreichbar und bietet eine angenehme, moderne und vertrauensvolle Atmosph\u00e4re f\u00fcr Erwachsene und Kinder. Seit vielen Jahren in Genf etabliert, setzt das Zahnarztzentrum auf ein erfahrenes Team aus Zahn\u00e4rztinnen, Zahn\u00e4rzten sowie Dentalhygienikerinnen und -hygienikern, die den Menschen und sein Wohlbefinden in den Mittelpunkt stellen. Behandlungen werden auf Franz\u00f6sisch und Englisch angeboten, um auch einer internationalen Patientenschaft gerecht zu werden.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022689\\u0022 data-end=\\u00221241\\u0022\\u003eMit einem multidisziplin\u00e4ren Ansatz und dem Einsatz innovativer Technologien bietet das Zahnarztzentrum Genf Acacias ein umfassendes Spektrum an zahnmedizinischen Behandlungen. Von der Zahnreinigung und Pr\u00e4vention bis hin zu anspruchsvollen Therapien wird jede Situation sorgf\u00e4ltig analysiert, um individuelle, nachhaltige und schonende L\u00f6sungen zu entwickeln. Die fachliche Leitung liegt bei Zentrumsleiter Enguerrand Taillandier, dessen Expertise und Engagement massgeblich zur hohen Qualit\u00e4t und zur Vertrauensbasis des Zahnarztzentrums beitragen.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221243\\u0022 data-end=\\u00221681\\u0022\\u003eEin besonderes Augenmerk gilt der Kinderzahnmedizin, denn Pr\u00e4vention ist bereits ab den ersten Z\u00e4hnen entscheidend. Regelmaessige Termine bei der Dentalhygiene helfen dabei, gute Gewohnheiten fr\u00fchzeitig zu f\u00f6rdern und Karies vorzubeugen. Mit viel Einf\u00fchlungsverm\u00f6gen und p\u00e4dagogischem Geschick begleitet das Team die j\u00fcngsten Patientinnen und Patienten und unterst\u00fctzt Eltern dabei, die Zahngesundheit ihrer Kinder langfristig zu sichern.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221683\\u0022 data-end=\\u00222321\\u0022 data-is-last-node=\\u0022\\u0022 data-is-only-node=\\u0022\\u0022\\u003eDas Zahnarztzentrum Genf Acacias ist von Montag bis Freitag ge\u00f6ffnet und gew\u00e4hrleistet zudem eine rasche Betreuung bei zahnmedizinischen Notf\u00e4llen. Ob akute Schmerzen, ein abgebrochener Zahn oder eine Infektion, t\u00e4glich stehen reservierte Zeitfenster f\u00fcr Notfalltermine zur Verf\u00fcgung, auch f\u00fcr neue Patientinnen und Patienten. Implantologie, Wurzelbehandlungen, professionelle Zahnreinigung, Bleaching sowie moderne kieferorthop\u00e4dische L\u00f6sungen wie Invisalign\u00ae oder die unsichtbare Incognito\u00ae-Technik werden mit Fachkompetenz, Herzlichkeit und einem hohen Anspruch an Qualit\u00e4t durchgef\u00fchrt, damit Sie sich jederzeit gut aufgehoben f\u00fchlen.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"2807\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25019f6eb2\",\"shapes\":\"shape1\",\"_shapes\":\"field_622f5635c8595\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum in Genf - Acacias\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":\"\",\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 22 304 17 50\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Genf Acacias","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"genf-acacias","to_ping":"","pinged":"","post_modified":"2025-12-29 14:07:15","post_modified_gmt":"2025-12-29 13:07:15","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/geneve-acacias\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"}],"soins":[{"ID":4138,"post_author":"14","post_date":"2022-01-05 10:58:49","post_date_gmt":"2022-01-05 09:58:49","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mundgesundheit f\u00fcr Ihr Wohlbefinden.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Verschiedene Studien zeigen den Zusammenhang zwischen Entz\u00fcndungen im Mund und allgemeinen Gesundheitsproblemen. Mehr als 600 Bakterienarten tummeln sich in unserem Mund. Einige k\u00f6nnen in den Blutkreislauf gelangen und Sch\u00e4den verursachen: Herz-Kreislauf-Probleme, Blutzucker-Diabetes, Atemwegserkrankungen, Gelenkentz\u00fcndungen, Risiko einer Fr\u00fchgeburt.\\r\\n\\r\\nDie zahn\u00e4rztliche Betreuung ist Teil der medizinischen Grundversorgung. Regelm\u00e4\u00dfige Zahnhygiene und regelm\u00e4\u00dfige Kontrollen sind daher der Schl\u00fcssel zu einer guten Zahngesundheit und einem gesunden L\u00e4cheln. Ein L\u00e4cheln verl\u00e4ngert die Lebenserwartung, reduziert Stress und hat eine positive Wirkung auf den Gespr\u00e4chspartner. Ein gesundes L\u00e4cheln gibt Selbstvertrauen und Wohlbefinden im t\u00e4glichen Leben, im Beruf und im Privatleben.\\r\\n\\r\\nEine regelm\u00e4\u00dfige zahn\u00e4rztliche Kontrolle hilft, Probleme, die die Gesundheit Ihrer Z\u00e4hne und Ihres Zahnfleisches beeintr\u00e4chtigen k\u00f6nnen, fr\u00fchzeitig zu erkennen.\\r\\n\\r\\nWir empfehlen einen j\u00e4hrlichen Besuch, um Erkrankungen zu erkennen, zu \u00fcberwachen und zu behandeln.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Die Adent Zahnarztzentren bieten alle g\u00e4ngigen zahn\u00e4rztlichen Behandlungen f\u00fcr Erwachsene und Kinder unter einem Dach an:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eWurzelbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcllungen von abgebrochenen Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernung von Weisheitsz\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandlung von Karies\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eWiederherstellung von Zahnfleischproblemen (Gingivitis, Zahnfleischr\u00fcckgang, Parodontitis, Abszesse usw.).\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003e\u00e4sthetische Behandlungen\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nUnsere Dentalhygienikerinnen helfen Ihnen, eine individuelle Vorsorge zu treffen und k\u00f6nnen Ihnen eine Reihe von Reinigungshilfen empfehlen (B\u00fcrstchen, Zahnstocher, Faden usw.).\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Karies\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Karies: Vorbeugen ist besser als heilen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Hauptursachen f\u00fcr Karies sind eine zuckerhaltige Ern\u00e4hrung, unzureichende Mundpflege oder ein schwaches Immunsystem. Wenn Karies nicht behandelt wird, vergr\u00f6ssert sich der Hohlraum und greift auf das Dentin (die Schicht unter dem Zahnschmelz) oder den Zahnnerv. Es kann zu Schmerzen kommen, insbesondere bei Hitze, K\u00e4lte oder S\u00fcssem. Je gr\u00f6sser der Hohlraum wird, desto st\u00e4rker werden die Schmerzen. Das Zahnr\u00f6ntgenbild, das bei den regelm\u00e4ssigen Kontrollen gemacht wird, kann Anzeichen f\u00fcr eine fr\u00fche Karies erkennen.\\r\\n\\r\\n\\u003cstrong\\u003eWie wird Karies behandelt?\\u003c\/strong\\u003e\\r\\n\\r\\nDie Behandlung von Zahnkaries ist eine sehr h\u00e4ufige allgemeine zahn\u00e4rztliche Behandlung. Karies auf der Oberfl\u00e4che des Zahnschmelzes wird mit einfachen F\u00fcllungen behandelt, die die gleiche Farbe wie Ihr Zahn haben. Bei tieferer Karies kann manchmal eine Wurzelbehandlung und eine Zahnkrone erforderlich sein. Eine Zahnextraktion wird nur dann durchgef\u00fchrt, wenn es sich um eine weit fortgeschrittene Karies handelt, die das tiefe Gewebe des Zahns betrifft. Bei Eingriffen bei Erwachsenen und Kindern k\u00f6nnen wir selbstverst\u00e4ndlich eine An\u00e4sthesie durchf\u00fchren.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3757,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Die Wurzelbehandlung  \",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Bei der Wurzelbehandlung wird der infizierte, besch\u00e4digte oder tote Nerv Ihres Zahns entfernt. Das Herz des Zahns enth\u00e4lt die Nerven und Blutgef\u00e4sse. Sie erm\u00f6glichen es dem Zahn, sich zu entwickeln. Bakterien, die durch Karies, Risse oder besch\u00e4digte F\u00fcllungen in Ihren Zahn eindringen, f\u00fchren zur Bildung eines Abszesses. Dieser Abszess wird durch eine Infektion des Zahnmarks verursacht. In diesem Fall muss das Fruchtfleisch entfernt werden.\\r\\n\\r\\nDer Vorteil der Wurzelbehandlung ist, dass Sie Ihren Zahn behalten k\u00f6nnen, anstatt ihn zu extrahieren. Indem Sie Ihren nat\u00fcrlichen Zahn erhalten, verhindern Sie, dass die anderen Z\u00e4hne ihre Ausrichtung verlieren.\\r\\n\\r\\n\\u003cstrong\\u003eWie l\u00e4uft eine Wurzelbehandlung ab?\\u003c\/strong\\u003e\\r\\n\\r\\nIhr Zahnarzt bet\u00e4ubt den Zahn \u00f6rtlich und legt eine isolierende Membran um den Zahn. Er macht eine kleine \u00d6ffnung in den Zahn, um an den Kanal und die besch\u00e4digte Pulpa (das Herz des Zahns) zu gelangen. Mit Hilfe von Pr\u00e4zisionsinstrumenten entfernt er die Pulpa, reinigt und erweitert den Kanal. Der Zahnarzt f\u00fcllt den Kanal und verschliesst den Zahn mit einer provisorischen oder permanenten F\u00fcllung. Der Zahn ist nicht mehr empfindlich gegen\u00fcber Hitze oder K\u00e4lte, beh\u00e4lt aber seine Eigenschaften. Eine Krone und ein Stift sind in der Regel notwendig, um die Lebensdauer des Zahns zu verl\u00e4ngern.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Zahnfleisch\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Pflege des zahnfleisches\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3761,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Wurzelkanalbehandlung\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Wie wird eine Wurzelkanalbehandlung durchgef\u00fchrt?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Der Zahn wird zun\u00e4chst bet\u00e4ubt und mit einem Gummigewebe (Kofferdam) von der Mundh\u00f6hle isoliert.\\r\\nDer Zahn wird mit einem Bohrer ge\u00f6ffnet und die Eing\u00e4nge des Wurzelkanals dargestellt, die L\u00e4nge des Wurzelkanals wird elektrometrisch gemessen, entz\u00fcndetes und totes Gewebe wird vollst\u00e4ndig entfernt, alle Wurzelkan\u00e4le werden mit desinfizierenden L\u00f6sungen desinfiziert und mit dem Kunststoffmaterial gef\u00fcllt.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Wie lange dauert eine Wurzelkanalbehandlung?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Je nach Anzahl der Zahnwurzeln dauert die Behandlung des Wurzelkanals zwischen einer und zwei Stunden. Dank moderner Behandlungsmethoden f\u00fchren wir die geplante Wurzelbehandlung in der Regel in einer einzigen Sitzung durch, nur in sehr komplizierten F\u00e4llen sind mehrere Sitzungen erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wann ist eine Wurzelkanalbehandlung notwendig?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Bei Entz\u00fcndung oder Nekrose des Zahnnervs (kann mit starken Schmerzen einhergehen oder v\u00f6llig schmerzlos verlaufen), bei tieferer Karies, die bereits bis zum Zahnnerv vorgedrungen ist (meist mit einem oder wenigen Schmerzen verbunden) oder nach einem Unfall.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ist es m\u00f6glich, eine Wurzelbehandlung, die vor langer Zeit erfolglos durchgef\u00fchrt wurde, zu wiederholen?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Selbstverst\u00e4ndlich k\u00f6nnen wir die Wurzelkanalbehandlung in den meisten F\u00e4llen wiederholen und durch den Einsatz der heutigen modernen Behandlungsmethoden hohe Behandlungsergebnisse erzielen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape1\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Entfernung von Weisheitsz\u00e4hnen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Entfernung von Weisheitsz\u00e4hnen ist Teil der Oralchirurgie und der allgemeinen Zahnheilkunde. Es ist ein chirurgischer Eingriff, der regelm\u00e4ssig von Adent durchgef\u00fchrt und beherrscht wird.\\r\\n\\r\\nDie Weisheitsz\u00e4hne wachsen in der Regel zwischen dem 16. und 24. Lebensjahr. Es kann auch vorkommen, dass sie die Weisheitsz\u00e4hne nicht vorhanden sind. In den meisten F\u00e4llen m\u00fcssen sie entfernt werden, da sie nicht in die richtige Richtung wachsen oder unter dem Zahnfleisch \\u0022eingeschlossen\\u0022 sind.\\r\\n\\r\\nInfektionen des umgebenden Gewebes und der Nachbarz\u00e4hne, schwer zu behandelnde Karies oder Verschiebungen von Nachbarz\u00e4hnen k\u00f6nnen die Folge sein.\\r\\n\\r\\n\\u003cstrong\\u003eW\u00fcrden Sie mir empfehlen, meine Weisheitsz\u00e4hne zu entfernen?\\u003c\/strong\\u003e\\r\\n\\r\\nUm die Lage und die Anzahl der vorhandenen Weisheitsz\u00e4hne zu bestimmen, muss der Zahnarzt ein Panoramar\u00f6ntgenaufnahme Ihres Mundes machen. Der Zahnarzt wird Ihnen dann alle notwendigen Informationen geben, um einen Behandlungsplan f\u00fcr die Entfernung eines oder mehrerer Weisheitsz\u00e4hne zu erstellen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Extraktion\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"entfernung von weisheitszaehnen\",\"url\":\"https:\/\/adent.ch\/de\/info\/entfernung-von-weisheitszaehnen\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3792,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column {\"width\":\"100%\"} -->\n<div class=\"wp-block-column\" style=\"flex-basis:100%\"><!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Entz\u00fcndungen und Infektionen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Das St\u00fctzgewebe, das Ihre Z\u00e4hne umgibt, ist wertvoll: Pflegen Sie es!\\r\\n\\r\\n\\u003cstrong\\u003eParodontitis\\u003c\/strong\\u003e (Zahnlockerung) ist eine Krankheit, die das St\u00fctzgewebe betrifft, das Ihren Zahn umgibt und st\u00fctzt. Die Zerst\u00f6rung dieses Gewebes f\u00fchrt zu Beweglichkeit und schliesslich zum Verlust des Zahns. Es gibt verschiedene Stadien der Zahnfleischerkrankung.\\r\\n\\r\\nDas Anfangsstadium ist \\u003cstrong\\u003eGingivitis\\u003c\/strong\\u003e. Sie betrifft nur das Zahnfleisch und ist durch eine Entz\u00fcndung gekennzeichnet: das Zahnfleisch blutet, ist rot und geschwollen.\\r\\n\\r\\nParodontalerkrankungen sind die Hauptursache f\u00fcr Zahnverlust bei Erwachsenen. Etwa 75% der Erwachsenen leiden im Laufe ihres Lebens in unterschiedlichem Ausmass an Zahnfleischproblemen. Die Krankheit kann jedoch auch junge Menschen betreffen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Zahnfleisch\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"pflege des zahnfleisches\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3686,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape5\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/--><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Gef\u00e4hrdete Zahnfleisch: schnell handeln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eWas passiert bei einer Zahnfleischentz\u00fcndung?\\u003c\/strong\\u003e\\r\\n\\r\\nWenn die Gingivitis nicht behandelt wird, breitet sich die Entz\u00fcndung aus und greift auf den Knochen \u00fcber. Der Knochen umgibt Ihre Z\u00e4hne und sorgt daf\u00fcr, dass sie im Kiefer bleiben. Wenn nichts unternommen wird, wird der Knochen, die B\u00e4nder und das gesamte Gewebe, das Ihre Z\u00e4hne st\u00fctzt und umgibt, nach und nach zerst\u00f6rt. Diese Zerst\u00f6rung des Gewebes f\u00fchrt zum Verlust eines oder mehrerer Z\u00e4hne. Dies wird als Parodontitis bezeichnet.\\r\\n\\r\\nZahnlockerung (Parodontitis) ist eine Krankheit, die das Zahnhaltegewebe betrifft. Sie muss von Fachgebieten, die Parodontologen genannt werden, behandelt werden. Eine Zusammenarbeit zwischen Patient, Parodontologe und Dentalhygienikerin ist notwendig, um die Heilung zu optimieren. Um Ihnen die bestm\u00f6gliche Versorgung zu garantieren, bringen wir alle diese Berufe in jedem der Adent Zahnarztzentren zusammen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3764,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\u00dcbliche Zahnpflege\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e250b73f5a9\",\"shapes\":\"shape8\",\"_shapes\":\"field_62149e038cf63\"},\"mode\":\"edit\"} \/-->","post_title":"\u00dcbliche Zahnpflege","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnaerztliche-routineversorgung","to_ping":"","pinged":"","post_modified":"2025-06-04 17:12:12","post_modified_gmt":"2025-06-04 15:12:12","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-courants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4140,"post_author":"14","post_date":"2022-01-03 13:50:41","post_date_gmt":"2022-01-03 12:50:41","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Das Beste fu\u0308r kleine La\u0308cheln.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Kinderzahn\u00e4rzte sind in einem kindgerechten psychologischen und p\u00e4dagogischen Ansatz geschult. Ihre Aufgabe ist es, zu beruhigen und mit einem altersgerechten Vokabular zu sprechen, um ein Klima des Vertrauens zu schaffen.\\r\\n\\r\\nWir f\u00fchren alle Arten von Zahnbehandlungen bei Kindern durch.\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eKariesbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eabgebrochener Zahn\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eZahnreinigung\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eTipps zum B\u00fcrsten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":16375,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Kieferorthop\u00e4dische Behandlungen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Zahn\u00e4rzte, die sich auf Kieferorthop\u00e4die spezialisiert haben, bieten kieferorthop\u00e4dische Behandlung f\u00fcr Kinder an. Eine kieferorthop\u00e4dische Behandlung kann in jedem Alter begonnen werden, aber die meisten Eltern w\u00fcnschen sich f\u00fcr ihre Kinder eine fr\u00fchzeitige Behandlung. Je nach Art der erforderlichen Behandlung kann eine erste Phase des Abfangens von Kieferorthop\u00e4den bereits ab dem 4. Lebensjahr stattfinden. In den Adent Zahnarztzentren werden verschiedene kieferorthop\u00e4dische Behandlungen angeboten, die sich an die jeweilige Mundsituation anpassen. Weitere Informationen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eauf unserer Seite \u00fcber Kieferorthop\u00e4de f\u00fcr Kinder\\u003c\/a\\u003e!\\r\\n\\r\\nZus\u00e4tzlich zu diesen zahn\u00e4rztlichen Behandlungen erkl\u00e4ren unsere diplomierten Dentalhygienikerinnen mit p\u00e4dagogischen Methoden, wie Z\u00e4hne und Zahnfleisch gesund erhalten werden k\u00f6nnen. Unsere Fachgebiete f\u00fcr zahn\u00e4rztliche Pr\u00e4vention helfen ihnen, die richtigen Verhaltensweisen zu erlernen, sobald sie die ersten Z\u00e4hne bekommen.\\r\\n\\r\\nHaben Sie Fragen zur Zahnhygiene bei Babys oder Jugendlichen? \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eBesuchen Sie unsere Seite zu diesen Themen\\u003c\/a\\u003e!\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Jeder Zahn muss t\u00e4glich gereinigt werden, egal wie klein er ist. Nach der Nahrungsaufnahme bildet sich ein Biofilm auf der Oberfl\u00e4che des Zahnschmelzes. Dieser Biofilm entwickelt sich weiter, wenn er nicht regelm\u00e4\u00dfig gereinigt wird. Dies f\u00fchrt zu wei\u00dfen, weichen Ablagerungen auf der Oberfl\u00e4che der Z\u00e4hne, die als Plaque bezeichnet werden. Zahnbelag besteht unter anderem aus Bakterien. Bakterien k\u00f6nnen Karies verursachen, wenn die Reinigung nicht regelm\u00e4ssig erfolgt. Plaque kann sich auch zu Zahnstein entwickeln, einem harten, wei\u00dfen Belag, der mit der Zahnb\u00fcrste nicht entfernt werden kann.\\r\\n\\r\\nAuch wenn dies selten vorkommt, kann sich ein Schaden an einem Milchzahn auf einen Erwachsenenzahn auswirken. Die Keime der erwachsenen Z\u00e4hne, die sich unter dem Zahnfleisch bilden, sind empfindlich. Sie k\u00f6nnen besch\u00e4digt werden, wenn ein Milchzahn infiziert wird.\\r\\n\\r\\nHeutzutage gibt es eine breite Palette von Hilfsmitteln f\u00fcr die Zahnreinigung bei Kindern. Sie k\u00f6nnen leicht elektrische Zahnb\u00fcrsten, Zahnseide in Tierform, bunte Kinderzahnb\u00fcrsten usw. erwerben. Diese Hilfsmittel helfen Ihnen dabei, die Mundhygiene Ihres Kindes zu verbessern. Lassen Sie sich von \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eunseren Dentalhygienikerinnen\\u003c\/a\\u003e beraten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Zahnarztangst\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Kind hat Angst vor dem Zahnarzt, was kann ich tun?\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"F\u00fcr Kinder mit Phobie oder Angst vor dem Zahnarzt haben wir L\u00f6sungen! Unsere Zahn\u00e4rzte bieten Lachgas- und Hypnosebehandlungen an, die auch bei Kindern einfach und sicher durchzuf\u00fchren sind. Weitere Informationen finden Sie hier.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie kann ich Zahnprobleme bei meinem Kind vermeiden?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16307,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Geben Sie gute Gewohnheiten weiter!\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Das Z\u00e4hneputzen wird 3x\/Tag empfohlen: Putzen Sie die Z\u00e4hne nach jeder Mahlzeit und vermeiden Sie bei Ihren Kindern das st\u00e4ndige Naschen von S\u00fcssigkeiten, da dies Karies und Schmerzen verursachen kann.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16347,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"B\u00fcrsten ab den ersten Z\u00e4hnen.\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Dies kann eine schwierige Aufgabe sein, aber alle Z\u00e4hne, auch wenn sie noch so klein sind, m\u00fcssen t\u00e4glich gereinigt werden. Tragen Sie ab dem ersten Zahn bis zum Alter von ca. 3 Jahren Zahnpasta in der Gr\u00f6sse eines Reiskorns auf, danach in der Gr\u00f6sse einer Erbse.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16350,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"S\u00fcssigkeiten ja, mit Sympadent\u00ae!\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie \\u003ca href=\\u0022https:\/\/zahnfreundlich.ch\/lassociation-sympadent-sengage-pour-des-dents-denfant-saines\/?lang=fr\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eSympadent\u00ae Bonbons\\u003c\/a\\u003e: Sie wurden getestet und f\u00fcr gut befunden. Diese S\u00fcssigkeiten schonen die Z\u00e4hne von Kindern und Erwachsenen. Sie k\u00f6nnen es in verschiedenen Gesch\u00e4ften in der Schweiz kaufen. Achten Sie auf das Zahnlogo unter dem Regenschirm.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":16562,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Alles miteinander teilen? Ja, aber...\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Vermeiden Sie es, den L\u00f6ffel oder andere Gegenst\u00e4nde in den Mund zu nehmen, bevor Sie sie Ihrem Baby geben: Karies verursachende Bakterien werden \u00fcbertragen.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs_4_image\":16311,\"_blocs_4_image\":\"field_623c222ba627a\",\"blocs_4_title\":\"Eine zus\u00e4tzliche Hilfe f\u00fcr eine optimale Reinigung.\",\"_blocs_4_title\":\"field_623c22c4a627b\",\"blocs_4_description\":\"Elektrische Zahnb\u00fcrsten sind eine gute Hilfe f\u00fcr Ihr Kind. Dies erleichtert das B\u00fcrsten und ermutigt sie. Unsere Dentalhygienikerinnen beraten Sie gerne.\",\"_blocs_4_description\":\"field_623c22cba627c\",\"blocs_4_button_type\":\"none\",\"_blocs_4_button_type\":\"field_623c34377e92d\",\"blocs_5_image\":16353,\"_blocs_5_image\":\"field_623c222ba627a\",\"blocs_5_title\":\"Eine fluoridierte Zahnpasta, die f\u00fcr sein Alter geeignet ist.\",\"_blocs_5_title\":\"field_623c22c4a627b\",\"blocs_5_description\":\"Fluor sch\u00fctzt die Z\u00e4hne vor Karies. Sie finden leicht Zahnpasta f\u00fcr Kinder unter 6 Jahren, f\u00fcr Kinder von 6 bis 12 Jahren und f\u00fcr Erwachsene. Wechseln Sie den Geschmack der Zahnpasta regelm\u00e4ssig: Kinder m\u00f6gen Abwechslung.\",\"_blocs_5_description\":\"field_623c22cba627c\",\"blocs_5_button_type\":\"none\",\"_blocs_5_button_type\":\"field_623c34377e92d\",\"blocs\":6,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnpflege f\u00fcr Kinder\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie unsere Zahn\u00e4rzte, die auf die Behandlung von Kindern spezialisiert sind.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Einen spezialisierten Zahnarzt finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4140\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnpflege f\u00fcr Kinder","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbehandlung-fuer-kinder","to_ping":"","pinged":"","post_modified":"2026-01-19 15:07:44","post_modified_gmt":"2026-01-19 14:07:44","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-pour-les-enfants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4136,"post_author":"14","post_date":"2022-01-06 10:59:42","post_date_gmt":"2022-01-06 09:59:42","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zeigen Sie Ihr strahlendes L\u00e4cheln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unser Mund spielt daher eine wichtige Rolle bei der Kommunikation und Gesundheit.\\r\\n\\r\\nRegelm\u00e4ssige Zahnpflege ist der Schl\u00fcssel zu einer guten Mundgesundheit und tr\u00e4gt wesentlich zur St\u00e4rkung des Selbstbewusstseins bei. Die regelm\u00e4ssige Entfernung von Zahnbelag auf Ihren Z\u00e4hnen verhindert das Wachstum von Bakterien, die Zahnfleischentz\u00fcndungen (Gingivitis) verursachen. Ausserdem h\u00e4lt es Ihre Z\u00e4hne glatt, weiss und gl\u00e4nzend.\\r\\n\\r\\nMit einigen guten Gewohnheiten in Ihrem Alltag und regelm\u00e4ssigen Besuchen bei Ihrem Hygieniker oder Zahnarzt k\u00f6nnen Sie sich ein gesundes, strahlendes L\u00e4cheln und sch\u00f6ne Z\u00e4hne bewahren. Unsere Dentalhygienikerinnen teilen mit Ihnen Gesundheitstipps, um Ihre Z\u00e4hne weiss und Ihr Zahnfleisch gesund zu halten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Wenn Sie die Farbe Ihres Zahnschmelzes aufhellen und weissere Z\u00e4hne haben m\u00f6chten, bieten wir Ihnen eine professionelle Zahnaufhellung an! Wir bieten effektive, einfache, professionelle und nicht-invasive L\u00f6sungen f\u00fcr das Bleichen Ihrer Z\u00e4hne.\\r\\n\\r\\nHaben Sie Fragen zu unseren verschiedenen Zahnaufhellungstechniken? Fragen Sie Ihre \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eDentalhygienikerin\\u003c\/a\\u003e oder Ihren \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4138\\u0022\\u003eZahnarzt\\u003c\/a\\u003e um Rat!\\r\\n\\r\\nEntdecken Sie unten die verschiedenen Zahnaufhellungstechniken und andere \u00e4sthetische Behandlungen, die wir in den Adent Zahnarztzentren anbieten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"none\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung im Zentrum\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eProfessionelles Zahnbleaching: Ein weisseres L\u00e4cheln \u2013 ganz nach Ihren Bed\u00fcrfnissen\\u003c\/strong\\u003e\\r\\n\\r\\nVerleihen Sie Ihrem L\u00e4cheln sofort neue Strahlkraft mit unseren professionellen Zahnbleaching-Behandlungen im Zahnarztzentrum der Groupe Adent. Moderne Technologien, schonende Verfahren und eine individuelle Beratung sorgen f\u00fcr sichtbare und sichere Resultate.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eBlancOne\u00ae: Express-Zahnbleaching f\u00fcr besondere Anl\u00e4sse\\u003c\/strong\\u003e\\r\\n\\r\\nDas BlancOne\u00ae Zahnbleaching ist ideal f\u00fcr einmalige Ereignisse wie eine Hochzeit, ein Fotoshooting oder einen wichtigen Abend. Die Behandlung wird direkt im Zahnarztzentrum von einer speziell ausgebildeten Dentalhygienikerin durchgef\u00fchrt und liefert bereits nach kurzer Zeit sichtbare Ergebnisse (10 bis 30 Minuten, je nach Methode).\\r\\n\\r\\n\ud83d\udc49 \\u003cstrong\\u003eHinweis:\\u003c\/strong\\u003e Die Wirkung ist tempor\u00e4r.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eFl\u00e4sh: Sanftes und nachhaltiges Zahnbleaching (CHF 500.\u2013)\\u003c\/strong\\u003e\\r\\n\\r\\nDas Fl\u00e4sh Zahnbleaching richtet sich an Patientinnen und Patienten, die ein nat\u00fcrliches und langfristiges Ergebnis w\u00fcnschen. Die Behandlung erfolgt \u00fcber mehrere Sitzungen hinweg und erm\u00f6glicht eine kontrollierte, schrittweise Aufhellung der Zahnfarbe.\\r\\n\\r\\n\ud83d\udd0e \\u003cstrong\\u003eWichtig:\\u003c\/strong\\u003e Eine gesunde Dentition ohne Zahnstein oder pathologische Befunde ist Voraussetzung f\u00fcr jedes Zahnbleaching. Eine zahnmedizinische Kontrolle sowie eine Zahnreinigung werden mindestens 3 Monate vor der Behandlung empfohlen.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\ud83d\udccd \\u003cstrong\\u003eUnsere Teams in den Zahnarztzentren beraten Sie gerne\\u003c\/strong\\u003e, um das f\u00fcr Sie passende Zahnbleaching auszuw\u00e4hlen.\\r\\n\\r\\nBitte beachten Sie: Nicht alle Behandlungen sind in allen Zahnarztzentren verf\u00fcgbar. Informieren Sie sich direkt beim Zahnarztzentrum, in dem Sie Ihre Behandlung durchf\u00fchren m\u00f6chten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":7110,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung im Zentrum\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellung im Zentrum: Wie funktioniert das?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Zahnaufhellung wird von unseren ausgebildeten Dentalhygienikerinnen in unserem Zentrum durchgef\u00fchrt. Das Bleichen der Z\u00e4hne wird in einer einzigen Sitzung mit professionellen, bew\u00e4hrten und bekannten Produkten durchgef\u00fchrt. Sie enthalten 16% Carbamidperoxid.\\r\\n\\r\\nIn einem unserer Zentren wird das Bleichgel f\u00fcr 10 bis 30 Minuten auf Ihre Z\u00e4hne aufgetragen. Eine Biophotonenlampe mit einem Bleichbogen (ultraviolettes Licht) wird auf Ihr Gebiss gerichtet und aktiviert das Bleichmittel. Um Empfindlichkeiten zu vermeiden, wird Vitamin D auf das Zahnfleisch aufgetragen.\\r\\n\\r\\nEine Sitzung mit BlancOne\u00ae CLICK dauert 10 Minuten. Die Dentalhygienikerin wendet diese Behandlung direkt nach der Zahnreinigung an. Sie k\u00f6nnen mit dem BlancOne\u00ae CLICK Zahnbleichmittel ein bis zwei Nuancen gewinnen.\\r\\n\\r\\nWir bieten auch BlancOne\u00ae TOUCH Zahnaufhellung an. Die Dauer betr\u00e4gt 30 Minuten, was drei Bleichzyklen entspricht. Mit dieser Behandlung wird Ihr Zahnschmelz um vier bis f\u00fcnf Farbt\u00f6ne aufgehellt. Sie werden mit strahlend weissen Z\u00e4hnen nach Hause gehen!\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was sind die Vorteile des professionellen Zahnbleachings BlancOne\u00ae?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"BlancOne\u00ae Zahnaufhellung ist kurz, effektiv und entspricht den Bed\u00fcrfnissen unserer Patienten durch seine Vorteile:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcr weissere Z\u00e4hne ist nur eine Sitzung erforderlich.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eDie Dauer des Eingriffs ist kurz (ab 10' Minuten Anwendung). Die Zahnaufhellung wird direkt nach Ihrer Zahnreinigung angewendet.\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDie Empfindlichkeit auf den Z\u00e4hnen ist geringer (Tests mit unseren Patienten). Das Ergebnis ist nat\u00fcrlich und dauerhaft.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Was muss ich beachten, bevor ich eine professionelle Zahnaufhellung mit BlancOne\u00ae beginne?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine gute Mundhygiene ist Voraussetzung f\u00fcr eine Zahnaufhellung. Vor der Zahnaufhellung ist ein Kontrolltermin beim Zahnarzt erforderlich. Bevor Sie mit der Behandlung beginnen, m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (wie z.B. Zahnlockerung) ausgeschlossen sein.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ich bin an einer professionellen Zahnaufhellung mit BlancOne\u00ae interessiert. An wen kann ich mich wenden?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Kontaktieren Sie das Zentrum \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnkliniken\/\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eAdent Zahnarztzentrum in Ihrer N\u00e4he\\u003c\/a\\u003e. Unsere Dentalhygienikerinnen sind von Montag bis Samstag, von morgens bis abends in allen unseren Zahnarztzentren f\u00fcr Sie da.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape8\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung mit Schienen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eEin gr\u00fcndliches und lang anhaltendes Ergebnis mit unseren massgeschneiderten Bleaching-Schienen und den professionellen Produkten von \\u003ca href=\\u0022https:\/\/www.philips.ch\/fr\/c-m-pe\/eclaircissement-des-dents\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003ePhilips Zoom\u00ae (400.-)\\u003c\/a\\u003e.\\u003c\/strong\\u003e\\r\\n\\r\\nDiese Zahnaufhellungstechnik ist in verschiedenen Zentren der Adent Gruppe verf\u00fcgbar. Sie liefert signifikante Ergebnisse und garantiert eine zuverl\u00e4ssige Bleichung. Bereits nach einigen Tagen sind Ergebnisse sichtbar und nach nur 2 Wochen ist die Behandlung abgeschlossen. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den Labors des Adent-Netzwerks hergestellt. Gesunde, zahnsteinfreie und pathologiefreie Z\u00e4hne sind eine Voraussetzung f\u00fcr den Beginn einer Zahnaufhellung.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"termin-vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3789,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung mit Schienen\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellungsschienen: Wie funktionieren die Schienen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Dentalhygienikerin oder der Zahnarzt macht einen Abdruck Ihrer Z\u00e4hne und \u00fcbergibt diesen an den Zahntechniker. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den \\u003ca href=\\u0022https:\/\/adent.ch\/de\/gruppe\/dentallabore\/\\u0022\\u003eLabors des Adent-Netzwerks\\u003c\/a\\u003e hergestellt.\\r\\n\\r\\nDie Herstellung der Bleaching-Schiene dauert eine Woche. Nach Ablauf dieser Frist wird ein neuer Termin f\u00fcr die Anprobe, die Beratung und die \u00dcbergabe des Materials (Schiene und Bleichmittel) vereinbart. Die Schienen k\u00f6nnen je nach Vorliebe Tag und Nacht f\u00fcr einige Stunden getragen werden. Bereits nach einigen Tagen sind Ergebnisse sichtbar. Nach nur 2 Wochen ist die Behandlung abgeschlossen und Ihre Z\u00e4hne sind strahlend weiss.\\r\\n\\r\\nIhre Zahnaufhellungsschiene kann gelagert und sp\u00e4ter wieder verwendet werden. So k\u00f6nnen Sie nach Belieben \u00c4nderungen vornehmen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"F\u00fcr wen ist die Zahnaufhellung mit Schienen geeignet?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Die Zahnaufhellung mit Schienen ist f\u00fcr Menschen gedacht, die dauerhaft weissere Z\u00e4hne haben m\u00f6chten. Um f\u00fcr diese Behandlung in Frage zu kommen, d\u00fcrfen Sie keine mundgesundheitlichen Kontraindikationen haben und m\u00fcssen ein gesundes Gebiss haben (kein Zahnstein, keine Karies, keine Zahnlockerung usw.). Der Rat Ihrer Dentalhygienikerin oder Ihres Zahnarztes ist erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Welche Vorteile bietet die professionelle Zahnaufhellung von Philips Zoom\u00ae?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Zahnaufhellung mit massgefertigten Schienen von Philips Zoom\u00ae-Produkten bietet Ihnen eine professionelle, effektive und sichere Zahnaufhellung. Massgefertigte Schienen sind diskret und k\u00f6nnen je nach Wunsch am Tag oder in der Nacht getragen werden. Die innovative Formel des Gels sch\u00fctzt Ihren Zahnschmelz und st\u00e4rkt Ihre Z\u00e4hne, ohne Ihre Gesundheit zu beeintr\u00e4chtigen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Was muss ich beachten, bevor ich mit einer professionellen Philips Zoom\u00ae Zahnaufhellung beginne?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine gute Mundgesundheit ist Voraussetzung f\u00fcr das Bleichen von Z\u00e4hnen. Vor dem Bleichen ist ein Kontrolltermin beim Zahnarzt erforderlich. Vor Beginn der Behandlung m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (z.B. Zahnlockerung) ausgeschlossen werden.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape7\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Invisalign\u00ae\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Invisalign\u00ae ist eine kieferorthop\u00e4dische Behandlung mit durchsichtigen Zahnschienen der Marke Invisalign\u00ae. Bei dieser Behandlung wird eine Reihe von transparenten, herausnehmbaren Alignern f\u00fcr einige Wochen oder Monate getragen, um die Z\u00e4hne auf sanfte und schonende Weise neu auszurichten.\\r\\n\\r\\nDieses transparente und \u00e4sthetisch unauff\u00e4llige System ist nicht nur auf relativ einfache Behandlungen beschr\u00e4nkt, sondern eignet sich auch f\u00fcr komplexere Ausrichtungen. Bei kleinen, un\u00e4sthetischen Zahnfehlstellungen reicht eine mehrmonatige Behandlung mit transparenten Alignern aus. Bei komplexen Behandlungen k\u00f6nnen ein bis zwei Jahre erforderlich sein. Aber keine Sorge, dank der modernen 3D-Bildgebungstechnologie kennen Sie Ihren Behandlungsplan im Voraus, von der Anfangsposition der Z\u00e4hne bis zur gew\u00fcnschten Endposition.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Invisalign\u00ae entdecken\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Invisalign behandlung\",\"url\":\"https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3734,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape7\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnprothesen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Es gibt eine grosse Auswahl an festsitzendem oder herausnehmbarem Zahnersatz, der die \u00c4sthetik und den Komfort Ihres L\u00e4chelns verbessert. Zahnprothesen, die sich leicht an die Bed\u00fcrfnisse jedes Einzelnen anpassen lassen: Zahnkrone, Br\u00fccke, Veneer, herausnehmbare Voll- oder Teilprothese.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Implant et restauration\",\"url\":\"https:\/\/adent.ch\/soin\/implant-et-restauration\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns\":1,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape4\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":3741,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnkrone\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Die Krone ist ein Zahnersatz aus Keramik, der den sichtbaren Teil des Zahns ersetzt, wenn dieser durch Karies oder eine Fraktur stark besch\u00e4digt wurde. Sie sch\u00fctzt den Zahn vor Abnutzung und erm\u00f6glicht die Abdeckung eines Zahnimplantats, das einen fehlenden Zahn ersetzt. Diese Methode vermeidet die vollst\u00e4ndige Extraktion des Zahns. Sie verbessert die \u00c4sthetik und den Komfort Ihres L\u00e4chelns.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":3745,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnbr\u00fccke (oder Bridge)\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Die Br\u00fccke, auch bekannt als Bridge, ist ein Zahnersatz, der einen oder mehrere fehlende Z\u00e4hne ersetzen kann. Mit Zahnbr\u00fccken erhalten Sie \u00c4sthetik und Komfort im Mund zur\u00fcck. Die Pfeiler der Zahnbr\u00fccke befinden sich in der Regel auf beiden Seiten des zahnlosen Kiefers und werden in Form von Implantaten oder gefr\u00e4sten Z\u00e4hnen eingesetzt. Auf diesen Pfeilern ruht die Br\u00fccke. Er ist fest und kann nicht entfernt werden.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":3748,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Veneer\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Das Veneer ist eine hauchd\u00fcnne Keramikschale. Das Veneer ist sehr widerstandsf\u00e4hig und wird auf der Vorderseite der Z\u00e4hne befestigt. Die Farbe passt zu Ihrem L\u00e4cheln, sie wird nach Mass angefertigt und deckt den nat\u00fcrlichen Zahn ab.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":3771,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Vollst\u00e4ndige oder teilweise herausnehmbare Prothese\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Die Zahnprothesen werden nach Mass angefertigt. Sie passen sich der Morphologie Ihrer Mundh\u00f6hle an. Sie sind sehr widerstandsf\u00e4hig und ersetzen einen oder mehrere Z\u00e4hne. Dank der modernen Technologien, die in den Zahnarztzentren eingesetzt werden, bieten sie ein nat\u00fcrliches, \u00e4sthetisches und komfortables Endergebnis.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs\":4,\"_blocs\":\"field_623c21f0a6279\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25104d76c2\",\"shapes\":\"shape5\",\"_shapes\":\"field_623c20cd3ad28\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Bleaching und \u00e4sthetische Behandlungen\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Bleaching und \u00e4sthetische Behandlungen","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbleaching-und-aesthetisch-e-en-behandlungen","to_ping":"","pinged":"","post_modified":"2026-01-22 15:10:05","post_modified_gmt":"2026-01-22 14:10:05","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/blanchiments-et-soins-esthetiques\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tatevik GEVORGYAN | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Tatevik Gevorgyan, erfahrene Zahn\u00e4rztin im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tatevik GEVORGYAN | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Tatevik Gevorgyan, erfahrene Zahn\u00e4rztin im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-19T16:12:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/tatevik-gevorgyan\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/tatevik-gevorgyan\\\/\",\"name\":\"Tatevik GEVORGYAN | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2025-12-19T16:06:52+00:00\",\"dateModified\":\"2025-12-19T16:12:46+00:00\",\"description\":\"Tatevik Gevorgyan, erfahrene Zahn\u00e4rztin im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/tatevik-gevorgyan\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/tatevik-gevorgyan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/tatevik-gevorgyan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Team\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tatevik GEVORGYAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tatevik GEVORGYAN | Adent Zahnarztzentrum","description":"Tatevik Gevorgyan, erfahrene Zahn\u00e4rztin im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/","og_locale":"de_DE","og_type":"article","og_title":"Tatevik GEVORGYAN | Adent Zahnarztzentrum","og_description":"Tatevik Gevorgyan, erfahrene Zahn\u00e4rztin im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.","og_url":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2025-12-19T16:12:46+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/","url":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/","name":"Tatevik GEVORGYAN | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2025-12-19T16:06:52+00:00","dateModified":"2025-12-19T16:12:46+00:00","description":"Tatevik Gevorgyan, erfahrene Zahn\u00e4rztin im Zahnarztzentrum, bietet moderne und einf\u00fchlsame Behandlungen f\u00fcr ein gesundes und sch\u00f6nes L\u00e4cheln.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/zahnarzt\/tatevik-gevorgyan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Team","item":"https:\/\/adent.ch\/de\/team\/"},{"@type":"ListItem","position":2,"name":"Tatevik GEVORGYAN"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe\/16268","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=16268"}],"wp:term":[{"taxonomy":"langue","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/langue?post=16268"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}