{"id":16917,"date":"2026-03-26T10:45:13","date_gmt":"2026-03-26T09:45:13","guid":{"rendered":"https:\/\/adent.ch\/dentistes\/fiona-egli-3\/"},"modified":"2026-03-26T10:51:22","modified_gmt":"2026-03-26T09:51:22","slug":"jiemai-chan","status":"publish","type":"equipe","link":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/","title":{"rendered":"Jiemei CHAN"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<div class=\"flex flex-col text-sm pb-25\">\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-69a54fc0-be90-8396-909d-6bf7c28dce4a-8\" data-testid=\"conversation-turn-26\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:var(--thread-content-margin-xs,calc(var(--spacing)*4))] @w-sm\/main:[--thread-content-margin:var(--thread-content-margin-sm,calc(var(--spacing)*6))] @w-lg\/main:[--thread-content-margin:var(--thread-content-margin-lg,calc(var(--spacing)*16))] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] @w-lg\/main:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col gap-4 grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"516cc2c0-5308-4910-bf9a-032a96df0dae\" data-message-model-slug=\"gpt-5-3\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden\">\n<div class=\"markdown prose dark:prose-invert w-full wrap-break-word light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"520\">Jiemei Chan ist Dentalhygienikerin und stellt ihre Fachkompetenz in den Dienst der Pr\u00e4vention und der langfristigen Mundgesundheit ihrer Patientinnen und Patienten. Im Verlauf ihres beruflichen Werdegangs hat sie fundierte Kenntnisse in der Prophylaxe und in der Mundhygiene entwickelt, die es ihr erm\u00f6glichen, eine pr\u00e4zise, nachhaltige und individuell angepasste Betreuung im Zahnarztzentrum anzubieten. Dabei legt sie grossen Wert auf die Qualit\u00e4t der Behandlung sowie auf den Komfort ihrer Patientinnen und Patienten.<\/p>\n<p data-start=\"522\" data-end=\"979\">In ihrer t\u00e4glichen Arbeit verfolgt Jiemei Chan eine pers\u00f6nliche und aufmerksame Herangehensweise, die sich an den Bed\u00fcrfnissen jedes Einzelnen orientiert. Sie nimmt sich Zeit, zuzuh\u00f6ren, verst\u00e4ndlich zu beraten und ihre Patientinnen und Patienten bei der Umsetzung gesunder Gewohnheiten zu begleiten. Ihr Ziel ist es, Erkrankungen vorzubeugen und durch gezielte Zahnreinigung sowie individuelle Empfehlungen zu einer nachhaltigen Mundgesundheit beizutragen.<\/p>\n<p data-start=\"981\" data-end=\"1335\">Die Entscheidung f\u00fcr diesen Beruf entstand aus ihrem Wunsch, technische Pr\u00e4zision mit menschlichem Kontakt zu verbinden. Patientinnen und Patienten zu betreuen, sie zu begleiten und eine vertrauensvolle Beziehung aufzubauen, ist f\u00fcr sie eine zentrale Motivation. Sie kombiniert fachliche Kompetenz mit einer empathischen und professionellen Arbeitsweise.<\/p>\n<p data-start=\"1337\" data-end=\"1648\" data-is-last-node=\"\" data-is-only-node=\"\">Jiemei Chan spricht Franz\u00f6sisch, Englisch und Italienisch. Dank ihrer Mehrsprachigkeit kann sie im Zahnarztzentrum eine internationale Patientenschaft betreuen und eine klare, vertrauensvolle Kommunikation gew\u00e4hrleisten, sodass sich Patientinnen und Patienten jederzeit gut informiert und gut aufgehoben f\u00fchlen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>","protected":false},"template":"","langue":[101,103,104],"class_list":["post-16917","equipe","type-equipe","status-publish","hentry","langue-englisch","langue-franzoesisch","langue-italienisch"],"acf":{"job":"Dentalhygienikerin","short_description":"<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:7c8055f6-18a9-4b19-af7b-43a258344f6a-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"9673ba86-7fe9-4881-abe4-ba31eececeb6\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"1679\" data-end=\"1771\" data-is-last-node=\"\" data-is-only-node=\"\">Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"pointer-events-none h-px w-px\" aria-hidden=\"true\" data-edge=\"true\"><\/div>\n","specialites":[{"label":"\u00dcbliche Zahnpflege","link":"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/"}],"higlight_specialite":"","higlight_specialite_short":"","zawin_codes":false,"first_name":"Jiemei","last_name":"CHAN","image":{"ID":16922,"id":16922,"title":"Jiemei Chan_Charmilles","filename":"jiemei-chan_charmilles.jpg","filesize":236620,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles.jpg","link":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/jiemei-chan_charmilles-2\/","alt":"","author":"14","description":"","caption":"","name":"jiemei-chan_charmilles-2","status":"inherit","uploaded_to":16917,"date":"2026-03-26 09:49:22","modified":"2026-03-26 09:49:22","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1880,"height":1410,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles-1307x980.jpg","large-width":1307,"large-height":980,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles.jpg","2048x2048-width":1880,"2048x2048-height":1410,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2026\/03\/jiemei-chan_charmilles.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"cliniques":[{"ID":4239,"post_author":"14","post_date":"2022-04-20 14:37:48","post_date_gmt":"2022-04-20 12:37:48","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Willkommen bei Adent Genf Charmilles\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u00220\\u0022 data-end=\\u0022441\\u0022\\u003eDas Adent Zahnarztzentrum Gen\u00e8ve-Charmilles empf\u00e4ngt Erwachsene und Kinder in einer warmen, beruhigenden Umgebung, die ganz auf Wohlbefinden und Vertrauen ausgerichtet ist. Zentral in Genf gelegen, direkt neben dem Einkaufszentrum Plan\u00e8te-Charmilles, ist das Zahnarztzentrum optimal erreichbar und eingebettet in ein lebendiges Quartier mit angenehmer, famili\u00e4rer Atmosph\u00e4re. So lassen sich Zahnarztbesuche einfach in den Alltag integrieren.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022443\\u0022 data-end=\\u0022985\\u0022\\u003eUnter einem Dach bietet das Adent Zahnarztzentrum Gen\u00e8ve-Charmilles das gesamte Spektrum der modernen Zahnmedizin, einschliesslich Kieferorthop\u00e4die f\u00fcr Kinder, Jugendliche und Erwachsene. Ge\u00f6ffnet von Montag bis Samstag passt sich das Team flexibel an individuelle Bed\u00fcrfnisse an und legt grossen Wert auf qualitativ hochwertige, pers\u00f6nliche und sorgf\u00e4ltig durchgef\u00fchrte Behandlungen. Die engagierten Fachpersonen begleiten jede Patientin und jeden Patienten aufmerksam und professionell, in mehreren Sprachen und stets mit einem offenen Ohr.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022987\\u0022 data-end=\\u00221461\\u0022\\u003eEin besonderer Fokus gilt angstbetroffenen Personen, Menschen mit Zahnarztangst sowie Patientinnen und Patienten mit leichten Beeintr\u00e4chtigungen. Dank angepasster Behandlungsmethoden, darunter auch Behandlungen unter Vollnarkose, sorgt das Adent Zahnarztzentrum Gen\u00e8ve-Charmilles f\u00fcr m\u00f6glichst entspannte und komfortable Abl\u00e4ufe. Dieser respektvolle, menschliche Ansatz ist fester Bestandteil der Philosophie des Teams und schafft ein hohes Mass an Sicherheit und Vertrauen.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221463\\u0022 data-end=\\u00222222\\u0022 data-is-last-node=\\u0022\\u0022 data-is-only-node=\\u0022\\u0022\\u003eDie Dentalhygienikerinnen spielen eine zentrale Rolle in der Pr\u00e4vention und der langfristigen Mundgesundheit. Mit moderner Zahnreinigung und der Behandlung von Zahnfleischr\u00fcckgang arbeiten sie unter anderem mit der innovativen GBT\u00ae-Technologie von EMS Dental, um Bel\u00e4ge, Zahnstein und Verf\u00e4rbungen schonend zu entfernen. Erg\u00e4nzend werden professionelle Zahnaufhellungen im Zahnarztzentrum oder f\u00fcr zu Hause angeboten, mit individuell angepassten Schienen und unter fachkundiger Kontrolle. Bei zahnmedizinischen Notf\u00e4llen ist zudem eine schnelle, schmerzfreie Betreuung gew\u00e4hrleistet. Verantwortet wird das Zahnarztzentrum von Dr. Ambrogio Feninno, Orthodontist und Chefarzt, dessen Expertise die Qualit\u00e4t und Verl\u00e4sslichkeit der Behandlungen nachhaltig pr\u00e4gt.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"1685\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"1\",\"_display_shapes\":\"field_62e25019f6eb2\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum in Genf Charmilles\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"Alle unsere Praktiker\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":{\"title\":\"\u00c9quipe\",\"url\":\"https:\/\/adent.ch\/equipe\/\",\"target\":\"\"},\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 22 338 02 00\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Genf Charmilles","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"genf-charmilles","to_ping":"","pinged":"","post_modified":"2026-04-16 16:20:12","post_modified_gmt":"2026-04-16 14:20:12","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/geneve-charmilles\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"}],"soins":[{"ID":4134,"post_author":"14","post_date":"2022-01-02 13:50:12","post_date_gmt":"2022-01-02 12:50:12","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Mund, meine Gesundheit\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u0022189\\u0022 data-end=\\u0022603\\u0022\\u003eEin \\u003cstrong data-start=\\u0022193\\u0022 data-end=\\u0022226\\u0022\\u003egesunder, strahlender L\u00e4cheln\\u003c\/strong\\u003e beginnt mit einer regelm\u00e4ssigen \\u003cstrong data-start=\\u0022259\\u0022 data-end=\\u0022276\\u0022\\u003eZahnreinigung\\u003c\/strong\\u003e und einer sorgf\u00e4ltigen \\u003cstrong data-start=\\u0022300\\u0022 data-end=\\u0022315\\u0022\\u003eMundhygiene\\u003c\/strong\\u003e. Der Mund beeinflusst nicht nur unser \\u003cstrong data-start=\\u0022354\\u0022 data-end=\\u0022373\\u0022\\u003eSelbstvertrauen\\u003c\/strong\\u003e und unsere \\u003cstrong data-start=\\u0022385\\u0022 data-end=\\u0022401\\u0022\\u003eAusstrahlung\\u003c\/strong\\u003e, sondern auch unsere \\u003cstrong data-start=\\u0022423\\u0022 data-end=\\u0022440\\u0022\\u003eKommunikation\\u003c\/strong\\u003e, \\u003cstrong data-start=\\u0022442\\u0022 data-end=\\u0022455\\u0022\\u003eErn\u00e4hrung\\u003c\/strong\\u003e und \\u003cstrong data-start=\\u0022460\\u0022 data-end=\\u0022485\\u0022\\u003eallgemeine Gesundheit\\u003c\/strong\\u003e. Bei \\u003cstrong data-start=\\u0022491\\u0022 data-end=\\u0022516\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e begleiten wir Sie dabei, Ihr L\u00e4cheln gesund, gepflegt und selbstbewusst zu erhalten.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022605\\u0022 data-end=\\u00221161\\u0022\\u003e\u00dcber \\u003cstrong data-start=\\u0022610\\u0022 data-end=\\u0022645\\u0022\\u003e600 verschiedene Bakterienarten\\u003c\/strong\\u003e leben in der Mundh\u00f6hle. Ohne gr\u00fcndliche \\u003cstrong data-start=\\u0022686\\u0022 data-end=\\u0022703\\u0022\\u003eZahnreinigung\\u003c\/strong\\u003e k\u00f6nnen diese Bakterien pathologisch werden und zu \\u003cstrong data-start=\\u0022754\\u0022 data-end=\\u0022768\\u0022\\u003eGingivitis\\u003c\/strong\\u003e oder \\u003cstrong data-start=\\u0022774\\u0022 data-end=\\u0022790\\u0022\\u003eParodontitis\\u003c\/strong\\u003e (Zahnlockerung) f\u00fchren. Manche Bakterien gelangen sogar in den Blutkreislauf und wirken sich auf die allgemeine Gesundheit aus. Unsere \\u003cstrong data-start=\\u0022926\\u0022 data-end=\\u0022972\\u0022\\u003eDentalhygienikerinnen und Dentalhygieniker\\u003c\/strong\\u003e sind Expertinnen und Experten f\u00fcr \\u003cstrong data-start=\\u00221007\\u0022 data-end=\\u00221033\\u0022\\u003epr\u00e4ventive Zahnmedizin\\u003c\/strong\\u003e. Sie beraten Sie individuell, zeigen die besten \\u003cstrong data-start=\\u00221082\\u0022 data-end=\\u00221106\\u0022\\u003eMundhygiene-Routinen\\u003c\/strong\\u003e und f\u00fchren professionelle \\u003cstrong data-start=\\u00221133\\u0022 data-end=\\u00221152\\u0022\\u003eZahnreinigungen\\u003c\/strong\\u003e durch.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221163\\u0022 data-end=\\u00221542\\u0022\\u003eMit der richtigen Kombination aus \\u003cstrong data-start=\\u00221197\\u0022 data-end=\\u00221230\\u0022\\u003eprofessioneller Zahnreinigung\\u003c\/strong\\u003e, t\u00e4glichen Pflegeroutinen und den passenden Hilfsmitteln \u2013 wie \\u003cstrong data-start=\\u00221294\\u0022 data-end=\\u00221336\\u0022\\u003eB\u00fcrsten, Interdentalb\u00fcrsten, Zahnseide\\u003c\/strong\\u003e oder \\u003cstrong data-start=\\u00221342\\u0022 data-end=\\u00221360\\u0022\\u003eWasserflossern\\u003c\/strong\\u003e \u2013 sorgen Sie daf\u00fcr, dass Ihr L\u00e4cheln gesund bleibt und Tag f\u00fcr Tag strahlt. Bei \\u003cstrong data-start=\\u00221441\\u0022 data-end=\\u00221466\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e machen wir Ihre Mundgesundheit und Ihr strahlendes L\u00e4cheln zur Priorit\u00e4t.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"\\u003cp data-start=\\u0022181\\u0022 data-end=\\u0022929\\u0022\\u003eEine \\u003cstrong data-start=\\u0022186\\u0022 data-end=\\u0022291\\u0022\\u003eZahnreinigung, die von einer Prophylaxeassistentin oder einem Prophylaxeassistenten durchgef\u00fchrt wird\\u003c\/strong\\u003e, ist eine vorbeugende Behandlung, die dazu dient, Zahnbelag und oberfl\u00e4chliche Verf\u00e4rbungen zu entfernen, ohne unter das Zahnfleisch zu gehen. Diese Art der Zahnreinigung ersetzt keine professionelle Zahnreinigung durch eine Dentalhygienikerin und richtet sich vor allem an Personen ohne Anzeichen einer Zahnfleischentz\u00fcndung. Sie wird besonders f\u00fcr Kinder und Jugendliche empfohlen, um von klein auf eine gute Mundhygiene zu f\u00f6rdern. Die Prophylaxeassistentin oder der Prophylaxeassistent verwendet geeignete Instrumente und gibt individuelle Tipps, um saubere Z\u00e4hne und ein gesundes L\u00e4cheln zwischen den Zahnarztbesuchen zu erhalten.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022931\\u0022 data-end=\\u00221590\\u0022\\u003eEine \\u003cstrong data-start=\\u0022936\\u0022 data-end=\\u00221033\\u0022\\u003eZahnreinigung, die von einer Dentalhygienikerin oder einem Dentalhygieniker durchgef\u00fchrt wird\\u003c\/strong\\u003e, ist eine umfassendere Behandlung, bei der Zahnstein und Belag auch unterhalb des Zahnfleisches entfernt werden. Diese Behandlung ist besonders f\u00fcr Personen mit Anzeichen von Gingivitis oder Parodontitis geeignet, da sie hilft, diese Erkrankungen zu verhindern oder zu behandeln. Die Dentalhygienikerin oder der Dentalhygieniker beurteilt die Gesundheit des Zahnfleisches, f\u00fchrt eine gr\u00fcndliche Reinigung durch und bietet eine individuelle Nachsorge an. Beide Arten der Zahnreinigung tragen gemeinsam dazu bei, die Mundgesundheit langfristig zu erhalten.\\u003c\/p\\u003e\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Mein Zahnarztzentrum finden\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnarztzentren\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/video {\"name\":\"acf\/video\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd1d6224c6\",\"video_preview\":\"\",\"_video_preview\":\"field_67811bb9884ea\",\"type\":\"youtube\",\"_type\":\"field_621c7b47d116a\",\"youtube\":\"\\u003ciframe width=\\u0022560\\u0022 height=\\u0022315\\u0022 src=\\u0022https:\/\/www.youtube-nocookie.com\/embed\/_HwEkrC1wZ4?si=gyi_NdQ7qYhUa8sF\\u0026amp;controls=0\\u0022 title=\\u0022YouTube video player\\u0022 frameborder=\\u00220\\u0022 allow=\\u0022accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\\u0022 allowfullscreen\\u003e\\u003c\/iframe\\u003e\",\"_youtube\":\"field_621c804717694\",\"legend\":\"\",\"_legend\":\"field_621c7e364a19a\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnreinigung und Zahnhygiene\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Rotes, gereiztes oder geschwollenes Zahnfleisch?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Wenden Sie sich an unsere Hygieniker:innen, um vorzubeugen, Zahnstein zu entfernen und Ihre Z\u00e4hne gesund zu erhalten.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Finden Sie Dentalhygieniker\/-innen\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4134\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie k\u00f6nnen Sie Ihre Z\u00e4hne zu Hause gesund erhalten?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16311,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnb\u00fcrste\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Verwenden Sie eine elektrische Zahnb\u00fcrste oder eine Schallzahnb\u00fcrste\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16314,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnzwischenr\u00e4ume\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Reinigen Sie Ihre Zahnzwischenr\u00e4ume mit B\u00fcrstchen, Zahnseide oder Zahnstochern\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16317,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Zahnpasta\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie fluoridhaltige Produkte. Sie sch\u00fctzen Ihre Z\u00e4hne vor S\u00e4ureangriffen\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs\":3,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnsteinentfernung und Zahnhygiene\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Warum sollte man zu einem\/einer Dentalhygieniker\/-in gehen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Vorbeugung und der Schutz vor Zahnerkrankungen stehen im Mittelpunkt der Arbeit der Dentalhygieniker\/-innen. Die Zahnsteinentfernung ist die bekannteste Hygienemassnahme. Sie wird von unseren diplomierten Dentalhygieniker\/-innen durchgef\u00fchrt und besteht in der Entfernung von Zahnstein, der sich auf den Z\u00e4hnen angesammelt hat. Denn selbst wenn Sie sich regelm\u00e4ssig die Z\u00e4hne putzen, kann eine einfache Zahnb\u00fcrste den Zahnstein nicht entfernen. Durch regelm\u00e4ssige Zahnsteinentfernungen, die von unseren Dentalhygienikern\/-hygienikerinnen durchgef\u00fchrt werden, erhalten Sie die Unversehrtheit Ihres Zahnfleisches und Ihrer Z\u00e4hne. Eine halbj\u00e4hrliche Zahnreinigung wird von Fachleuten f\u00fcr Mundgesundheit empfohlen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was ist der Unterschied zwischen einem\/einer Hygieniker\/-in und einem Prophylaxeassistenten\/einer Prophylaxeassistentin?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Bei Adent wird die Zahnpflege von Dentalhygienikern\/-hygienikerinnen und Prophylaxeassistent\/-innen durchgef\u00fchrt. Diese Zahngesundheitsfachleute haben jeweils ihren eigenen Zust\u00e4ndigkeitsbereich. Als Patient\/-in ist es gut, die Unterschiede zwischen ihnen zu kennen. So stellen Sie sicher, dass die Behandlung Ihren Bed\u00fcrfnissen entspricht.\\r\\n\\r\\nDer\/Die Profilaxeassistent\/-in (PA) ist ein diplomierter Dentalassistent\/eine diplomierte Dentalassistentin. Zus\u00e4tzlich zu diesen T\u00e4tigkeiten als Dentalassistent\/-in \u00fcbernimmt der\/die PA folgende Leistungen:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003ePr\u00e4ventivmassnahmen zur Erhaltung der Mundgesundheit\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eInformation und Motivation der Patienten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernung von supragingivalen Plaqueablagerungen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003eBleichen der Z\u00e4hne\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDiese Aufgaben werden immer unter der Aufsicht des Zahnarztes\/der Zahn\u00e4rztin ausgef\u00fchrt. Zus\u00e4tzlich zur Grundausbildung hat er\/sie eine von der SSO geregelte Weiterbildung zur beruflichen Weiterentwicklung absolviert. Diese Weiterbildung erm\u00f6glicht es ihr\/ihm, selbstst\u00e4ndig zu arbeiten.\\r\\n\\r\\nUnsere Prophylaxeassistenten\/\\u002d\\u002dassistentinnen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/\\u0022\\u003ehier\\u003c\/a\\u003e\\r\\n\\r\\nDer\/Die diplomierte Dentalhygieniker\/-in HF (DH) erf\u00fcllt folgende Aufgaben:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eErstellen, \u00dcbernehmen und Interpretieren von Diagnosen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eErstellen von Behandlungspl\u00e4nen in Absprache mit dem Zahnarzt\/der Zahn\u00e4rztin und dem Patienten\/der Patientin\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandeln von Parodontitis\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernen von Zahnstein auf und unter den Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBleichen von Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAnfertigen von R\u00f6ntgenaufnahmen, An\u00e4sthesie\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nUnsere Dentalhygieniker\/-innen finden Sie hier.\\r\\n\\r\\nDie \u00dcberwachung Ihrer Mundhygiene sollte mit Ihrem Zahnarzt\/Ihrer Zahn\u00e4rztin oder Ihres Dentalhygienikers\/Ihrer Dentalhygienikerin besprochen werden.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wer braucht eine Zahnreinigung?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine regelm\u00e4ssige Zahnreinigung wird f\u00fcr jeden empfohlen, der Z\u00e4hne hat, egal ob Erwachsener oder Kind. Kinder k\u00f6nnen unsere Dentalhygieniker\/-innen schon im fr\u00fchen Alter aufsuchen. So erhalten sie professionellen Rat und entwickeln gute Gewohnheiten, sobald sie ihre ersten Z\u00e4hne bekommen. Unsere Dentalhygieniker\/-innen k\u00f6nnen Ihr Kind an den Besuch beim Zahnarzt\/bei der Zahn\u00e4rztin gew\u00f6hnen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Welche Vorteile hat eine regelm\u00e4ssige Zahnreinigung?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine regelm\u00e4ssige Zahnsteinentfernung verhindert, dass sich zu viel Zahnstein auf den Z\u00e4hnen ablagert. Ausserdem werden Verf\u00e4rbungen entfernt, die z. B. durch Teein oder Koffein verursacht werden. Zahnstein und Zahnbelag sind sch\u00e4dlich f\u00fcr die Z\u00e4hne und das Zahnfleisch. Sie f\u00fchren zu Infektionen wie Karies, Zahnlockerung und Zahnfleischentz\u00fcndungen, die als Gingivitis bezeichnet werden. Die Unversehrtheit Ihrer Z\u00e4hne und Ihres Zahnfleischs bleibt erhalten, wenn Sie regelm\u00e4ssig professionelle Zahnreinigungen und Hygienetipps erhalten. Unsere Dentalhygieniker\/-innen beraten Sie auch \u00fcber die richtigen Schritte, um sch\u00f6ne Z\u00e4hne zu erhalten oder wiederzuerlangen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions_4_title\":\"Wie l\u00e4uft eine Zahnhygienesitzung ab?\",\"_accordions_4_title\":\"field_626fdd3ff47be\",\"accordions_4_content\":\"Zun\u00e4chst muss ein medizinischer Fragebogen ausgef\u00fcllt werden. Dann beginnt die Reinigung. Der\/Die Dentalhygieniker\/-in verf\u00fcgt \u00fcber eine Palette moderner Arbeitsinstrumente. Diese werden an die Bed\u00fcrfnisse jedes Patienten\/jeder Patientin angepasst.\\r\\n\\u003col\\u003e\\r\\n \\t\\u003cli\\u003eManuelle Scaler (Zahnsteinentferner). Sie werden nach der Lage des Zahns, der Position des Zahnsteins und danach ausgew\u00e4hlt, ob eine Zahnlockerung vorliegt oder nicht.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eElektronische Scaler mit Ultraschall.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003ePolieren, um Koffein-, Teein- oder Nikotinverf\u00e4rbungen zu entfernen und die Oberfl\u00e4che des Zahnschmelzes zu gl\u00e4tten.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAm Ende gibt er\/sie die patientenspezifischen Gesundheitstipps und -tricks.\\u003c\/li\\u003e\\r\\n\\u003c\/ol\\u003e\\r\\nAlle Dentalhygienikerinnen und Dentalhygieniker bei Adent sind in der GBT-Technik geschult. [GBT] Guided Biofilm Therapy\u00ae ist eine innovative Technik, die von EMS Dental entwickelt wurde, um Biofilm, Verf\u00e4rbungen und Zahnstein von Ihren Z\u00e4hnen zu entfernen. Diese schmerzfreie Technik kann sowohl bei nat\u00fcrlichen Z\u00e4hnen als auch bei Zahnrekonstruktionen und Zahnimplantaten eingesetzt werden.\\r\\n\\r\\n\\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/zahnsteinentfernung-guided-biofilm-technology\/\\u0022\\u003eWeitere Informationen \u00fcber GBT\\u003c\/a\\u003e\",\"_accordions_4_content\":\"field_626fdd46f47bf\",\"accordions_5_title\":\"Ist eine Zahnreinigung schmerzhaft?\",\"_accordions_5_title\":\"field_626fdd3ff47be\",\"accordions_5_content\":\"Bei akuter Empfindlichkeit kann eine \u00f6rtliche Bet\u00e4ubung in Betracht gezogen werden. Dadurch wird Ihr Wohlbefinden w\u00e4hrend der gesamten Zahnreinigung verbessert.\\r\\n\\r\\nF\u00fchlen Sie sich gestresst und nerv\u00f6s, wenn Sie an Ihren n\u00e4chsten Zahnarzttermin denken? Fragen Sie nach einer Behandlung mit Lachgas (MEOPA) oder Hypnose. MEOPA ist ein farb- und geruchloses Gasgemisch aus Sauerstoff und Distickstoffmonoxid. Wenn Sie es einatmen, entspannt es Sie, w\u00e4hrend Sie gleichzeitig beim Bewusstsein sind und Sie wissen was um Sie herum geschieht. Die Sitzung mit dem\/der Dentalhygieniker\/-in wird in aller Ruhe stattfinden.\\r\\n\\r\\nUm mehr \u00fcber die Angst vor dem Zahnarzt\/der Zahn\u00e4rztin zu informieren, haben wir \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/die-zahnarztphobie\/\\u0022\\u003eeinen Artikel\\u003c\/a\\u003e dar\u00fcber verfasst.\",\"_accordions_5_content\":\"field_626fdd46f47bf\",\"accordions\":6,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape3\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/tab {\"name\":\"acf\/tab\",\"data\":{\"anchor\":\"teenager\",\"_anchor\":\"field_635bd13882c1f\",\"tabs_0_name\":\"Kinder\",\"_tabs_0_name\":\"field_624449592e9bd\",\"tabs_0_tab\":13563,\"_tabs_0_tab\":\"field_624449622e9be\",\"tabs_1_name\":\"Teenager\",\"_tabs_1_name\":\"field_624449592e9bd\",\"tabs_1_tab\":4124,\"_tabs_1_tab\":\"field_624449622e9be\",\"tabs_2_name\":\"Erwachsene\",\"_tabs_2_name\":\"field_624449592e9bd\",\"tabs_2_tab\":4128,\"_tabs_2_tab\":\"field_624449622e9be\",\"tabs\":3,\"_tabs\":\"field_624449452e9bc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Sanfte Vorbeugung und Behandlung f\u00fcr Ihre Z\u00e4hne und Ihr Zahnfleisch.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Schlechte Hygiene f\u00fchrt zu Infektionskrankheiten der Z\u00e4hne und des Zahnfleischs. Sie f\u00fchrt auch zu Schmerzen. Diese Erkrankungen k\u00f6nnen sowohl Erwachsene als auch Kinder betreffen. Um das Auftreten von Krankheiten zu verhindern, sind regelm\u00e4ssige Sitzungen bei dem\/der Dentalhygieniker\/-in erforderlich. Der\/Die Dentalhygieniker\/-in entfernt Biofilm und Zahnstein, die sich auf Ihren Z\u00e4hnen festgesetzt haben.\\r\\n\\r\\nDie Zahnarztzentren von Adent passen sich st\u00e4ndig an die Entwicklung der zahnmedizinischen Technologien an. Wir bieten Ihnen eine optimale Pflegequalit\u00e4t und mehr Komfort. Die [GBT] Guided Biofilm Therapy\u00ae ist ein innovativer Ansatz, der von EMS Dental entwickelt wurde. Sie entfernt Biofilm, Verf\u00e4rbungen und Zahnstein. Diese Technik kann bei nat\u00fcrlichen und k\u00fcnstlichen Z\u00e4hnen sowie bei Zahnimplantaten angewendet werden.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Zahnfleisch pflege\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnfleisch pflege\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Profitieren Sie von einer schonenden und umfassenden Zahnreinigung dank der Kompetenzen unserer Fachpersonals. Das Fachwissen in Kombination mit den Technologien, die in den Zahnarztzentren von Adent zum Einsatz kommen, sorgt daf\u00fcr, dass Sie die beste Pflege erhalten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Erfahren Sie mehr \u00fcber die GBT\u00ae\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnstein-Entfernung: Guided Biofilm Technology\",\"url\":\"https:\/\/adent.ch\/de\/info\/zahnsteinentfernung-guided-biofilm-technology\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape1\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnreinigung und Zahnhygiene","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnsteinentfernung-und-zahnhygiene","to_ping":"","pinged":"","post_modified":"2026-01-19 15:14:38","post_modified_gmt":"2026-01-19 14:14:38","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/detartrage-et-hygiene-dentaire\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4136,"post_author":"14","post_date":"2022-01-06 10:59:42","post_date_gmt":"2022-01-06 09:59:42","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zeigen Sie Ihr strahlendes L\u00e4cheln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unser Mund spielt daher eine wichtige Rolle bei der Kommunikation und Gesundheit.\\r\\n\\r\\nRegelm\u00e4ssige Zahnpflege ist der Schl\u00fcssel zu einer guten Mundgesundheit und tr\u00e4gt wesentlich zur St\u00e4rkung des Selbstbewusstseins bei. Die regelm\u00e4ssige Entfernung von Zahnbelag auf Ihren Z\u00e4hnen verhindert das Wachstum von Bakterien, die Zahnfleischentz\u00fcndungen (Gingivitis) verursachen. Ausserdem h\u00e4lt es Ihre Z\u00e4hne glatt, weiss und gl\u00e4nzend.\\r\\n\\r\\nMit einigen guten Gewohnheiten in Ihrem Alltag und regelm\u00e4ssigen Besuchen bei Ihrem Hygieniker oder Zahnarzt k\u00f6nnen Sie sich ein gesundes, strahlendes L\u00e4cheln und sch\u00f6ne Z\u00e4hne bewahren. Unsere Dentalhygienikerinnen teilen mit Ihnen Gesundheitstipps, um Ihre Z\u00e4hne weiss und Ihr Zahnfleisch gesund zu halten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Wenn Sie die Farbe Ihres Zahnschmelzes aufhellen und weissere Z\u00e4hne haben m\u00f6chten, bieten wir Ihnen eine professionelle Zahnaufhellung an! Wir bieten effektive, einfache, professionelle und nicht-invasive L\u00f6sungen f\u00fcr das Bleichen Ihrer Z\u00e4hne.\\r\\n\\r\\nHaben Sie Fragen zu unseren verschiedenen Zahnaufhellungstechniken? Fragen Sie Ihre \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eDentalhygienikerin\\u003c\/a\\u003e oder Ihren \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4138\\u0022\\u003eZahnarzt\\u003c\/a\\u003e um Rat!\\r\\n\\r\\nEntdecken Sie unten die verschiedenen Zahnaufhellungstechniken und andere \u00e4sthetische Behandlungen, die wir in den Adent Zahnarztzentren anbieten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"none\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung im Zentrum\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eProfessionelles Zahnbleaching: Ein weisseres L\u00e4cheln \u2013 ganz nach Ihren Bed\u00fcrfnissen\\u003c\/strong\\u003e\\r\\n\\r\\nVerleihen Sie Ihrem L\u00e4cheln sofort neue Strahlkraft mit unseren professionellen Zahnbleaching-Behandlungen im Zahnarztzentrum der Groupe Adent. Moderne Technologien, schonende Verfahren und eine individuelle Beratung sorgen f\u00fcr sichtbare und sichere Resultate.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eBlancOne\u00ae: Express-Zahnbleaching f\u00fcr besondere Anl\u00e4sse\\u003c\/strong\\u003e\\r\\n\\r\\nDas BlancOne\u00ae Zahnbleaching ist ideal f\u00fcr einmalige Ereignisse wie eine Hochzeit, ein Fotoshooting oder einen wichtigen Abend. Die Behandlung wird direkt im Zahnarztzentrum von einer speziell ausgebildeten Dentalhygienikerin durchgef\u00fchrt und liefert bereits nach kurzer Zeit sichtbare Ergebnisse (10 bis 30 Minuten, je nach Methode).\\r\\n\\r\\n\ud83d\udc49 \\u003cstrong\\u003eHinweis:\\u003c\/strong\\u003e Die Wirkung ist tempor\u00e4r.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eFl\u00e4sh: Sanftes und nachhaltiges Zahnbleaching (CHF 500.\u2013)\\u003c\/strong\\u003e\\r\\n\\r\\nDas Fl\u00e4sh Zahnbleaching richtet sich an Patientinnen und Patienten, die ein nat\u00fcrliches und langfristiges Ergebnis w\u00fcnschen. Die Behandlung erfolgt \u00fcber mehrere Sitzungen hinweg und erm\u00f6glicht eine kontrollierte, schrittweise Aufhellung der Zahnfarbe.\\r\\n\\r\\n\ud83d\udd0e \\u003cstrong\\u003eWichtig:\\u003c\/strong\\u003e Eine gesunde Dentition ohne Zahnstein oder pathologische Befunde ist Voraussetzung f\u00fcr jedes Zahnbleaching. Eine zahnmedizinische Kontrolle sowie eine Zahnreinigung werden mindestens 3 Monate vor der Behandlung empfohlen.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\ud83d\udccd \\u003cstrong\\u003eUnsere Teams in den Zahnarztzentren beraten Sie gerne\\u003c\/strong\\u003e, um das f\u00fcr Sie passende Zahnbleaching auszuw\u00e4hlen.\\r\\n\\r\\nBitte beachten Sie: Nicht alle Behandlungen sind in allen Zahnarztzentren verf\u00fcgbar. Informieren Sie sich direkt beim Zahnarztzentrum, in dem Sie Ihre Behandlung durchf\u00fchren m\u00f6chten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":7110,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung im Zentrum\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellung im Zentrum: Wie funktioniert das?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Zahnaufhellung wird von unseren ausgebildeten Dentalhygienikerinnen in unserem Zentrum durchgef\u00fchrt. Das Bleichen der Z\u00e4hne wird in einer einzigen Sitzung mit professionellen, bew\u00e4hrten und bekannten Produkten durchgef\u00fchrt. Sie enthalten 16% Carbamidperoxid.\\r\\n\\r\\nIn einem unserer Zentren wird das Bleichgel f\u00fcr 10 bis 30 Minuten auf Ihre Z\u00e4hne aufgetragen. Eine Biophotonenlampe mit einem Bleichbogen (ultraviolettes Licht) wird auf Ihr Gebiss gerichtet und aktiviert das Bleichmittel. Um Empfindlichkeiten zu vermeiden, wird Vitamin D auf das Zahnfleisch aufgetragen.\\r\\n\\r\\nEine Sitzung mit BlancOne\u00ae CLICK dauert 10 Minuten. Die Dentalhygienikerin wendet diese Behandlung direkt nach der Zahnreinigung an. Sie k\u00f6nnen mit dem BlancOne\u00ae CLICK Zahnbleichmittel ein bis zwei Nuancen gewinnen.\\r\\n\\r\\nWir bieten auch BlancOne\u00ae TOUCH Zahnaufhellung an. Die Dauer betr\u00e4gt 30 Minuten, was drei Bleichzyklen entspricht. Mit dieser Behandlung wird Ihr Zahnschmelz um vier bis f\u00fcnf Farbt\u00f6ne aufgehellt. Sie werden mit strahlend weissen Z\u00e4hnen nach Hause gehen!\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was sind die Vorteile des professionellen Zahnbleachings BlancOne\u00ae?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"BlancOne\u00ae Zahnaufhellung ist kurz, effektiv und entspricht den Bed\u00fcrfnissen unserer Patienten durch seine Vorteile:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcr weissere Z\u00e4hne ist nur eine Sitzung erforderlich.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eDie Dauer des Eingriffs ist kurz (ab 10' Minuten Anwendung). Die Zahnaufhellung wird direkt nach Ihrer Zahnreinigung angewendet.\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDie Empfindlichkeit auf den Z\u00e4hnen ist geringer (Tests mit unseren Patienten). Das Ergebnis ist nat\u00fcrlich und dauerhaft.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Was muss ich beachten, bevor ich eine professionelle Zahnaufhellung mit BlancOne\u00ae beginne?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine gute Mundhygiene ist Voraussetzung f\u00fcr eine Zahnaufhellung. Vor der Zahnaufhellung ist ein Kontrolltermin beim Zahnarzt erforderlich. Bevor Sie mit der Behandlung beginnen, m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (wie z.B. Zahnlockerung) ausgeschlossen sein.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ich bin an einer professionellen Zahnaufhellung mit BlancOne\u00ae interessiert. An wen kann ich mich wenden?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Kontaktieren Sie das Zentrum \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnkliniken\/\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eAdent Zahnarztzentrum in Ihrer N\u00e4he\\u003c\/a\\u003e. Unsere Dentalhygienikerinnen sind von Montag bis Samstag, von morgens bis abends in allen unseren Zahnarztzentren f\u00fcr Sie da.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape8\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung mit Schienen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eEin gr\u00fcndliches und lang anhaltendes Ergebnis mit unseren massgeschneiderten Bleaching-Schienen und den professionellen Produkten von \\u003ca href=\\u0022https:\/\/www.philips.ch\/fr\/c-m-pe\/eclaircissement-des-dents\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003ePhilips Zoom\u00ae (400.-)\\u003c\/a\\u003e.\\u003c\/strong\\u003e\\r\\n\\r\\nDiese Zahnaufhellungstechnik ist in verschiedenen Zentren der Adent Gruppe verf\u00fcgbar. Sie liefert signifikante Ergebnisse und garantiert eine zuverl\u00e4ssige Bleichung. Bereits nach einigen Tagen sind Ergebnisse sichtbar und nach nur 2 Wochen ist die Behandlung abgeschlossen. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den Labors des Adent-Netzwerks hergestellt. Gesunde, zahnsteinfreie und pathologiefreie Z\u00e4hne sind eine Voraussetzung f\u00fcr den Beginn einer Zahnaufhellung.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"termin-vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3789,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung mit Schienen\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellungsschienen: Wie funktionieren die Schienen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Dentalhygienikerin oder der Zahnarzt macht einen Abdruck Ihrer Z\u00e4hne und \u00fcbergibt diesen an den Zahntechniker. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den \\u003ca href=\\u0022https:\/\/adent.ch\/de\/gruppe\/dentallabore\/\\u0022\\u003eLabors des Adent-Netzwerks\\u003c\/a\\u003e hergestellt.\\r\\n\\r\\nDie Herstellung der Bleaching-Schiene dauert eine Woche. Nach Ablauf dieser Frist wird ein neuer Termin f\u00fcr die Anprobe, die Beratung und die \u00dcbergabe des Materials (Schiene und Bleichmittel) vereinbart. Die Schienen k\u00f6nnen je nach Vorliebe Tag und Nacht f\u00fcr einige Stunden getragen werden. Bereits nach einigen Tagen sind Ergebnisse sichtbar. Nach nur 2 Wochen ist die Behandlung abgeschlossen und Ihre Z\u00e4hne sind strahlend weiss.\\r\\n\\r\\nIhre Zahnaufhellungsschiene kann gelagert und sp\u00e4ter wieder verwendet werden. So k\u00f6nnen Sie nach Belieben \u00c4nderungen vornehmen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"F\u00fcr wen ist die Zahnaufhellung mit Schienen geeignet?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Die Zahnaufhellung mit Schienen ist f\u00fcr Menschen gedacht, die dauerhaft weissere Z\u00e4hne haben m\u00f6chten. Um f\u00fcr diese Behandlung in Frage zu kommen, d\u00fcrfen Sie keine mundgesundheitlichen Kontraindikationen haben und m\u00fcssen ein gesundes Gebiss haben (kein Zahnstein, keine Karies, keine Zahnlockerung usw.). Der Rat Ihrer Dentalhygienikerin oder Ihres Zahnarztes ist erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Welche Vorteile bietet die professionelle Zahnaufhellung von Philips Zoom\u00ae?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Zahnaufhellung mit massgefertigten Schienen von Philips Zoom\u00ae-Produkten bietet Ihnen eine professionelle, effektive und sichere Zahnaufhellung. Massgefertigte Schienen sind diskret und k\u00f6nnen je nach Wunsch am Tag oder in der Nacht getragen werden. Die innovative Formel des Gels sch\u00fctzt Ihren Zahnschmelz und st\u00e4rkt Ihre Z\u00e4hne, ohne Ihre Gesundheit zu beeintr\u00e4chtigen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Was muss ich beachten, bevor ich mit einer professionellen Philips Zoom\u00ae Zahnaufhellung beginne?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine gute Mundgesundheit ist Voraussetzung f\u00fcr das Bleichen von Z\u00e4hnen. Vor dem Bleichen ist ein Kontrolltermin beim Zahnarzt erforderlich. Vor Beginn der Behandlung m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (z.B. Zahnlockerung) ausgeschlossen werden.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape7\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Invisalign\u00ae\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Invisalign\u00ae ist eine kieferorthop\u00e4dische Behandlung mit durchsichtigen Zahnschienen der Marke Invisalign\u00ae. Bei dieser Behandlung wird eine Reihe von transparenten, herausnehmbaren Alignern f\u00fcr einige Wochen oder Monate getragen, um die Z\u00e4hne auf sanfte und schonende Weise neu auszurichten.\\r\\n\\r\\nDieses transparente und \u00e4sthetisch unauff\u00e4llige System ist nicht nur auf relativ einfache Behandlungen beschr\u00e4nkt, sondern eignet sich auch f\u00fcr komplexere Ausrichtungen. Bei kleinen, un\u00e4sthetischen Zahnfehlstellungen reicht eine mehrmonatige Behandlung mit transparenten Alignern aus. Bei komplexen Behandlungen k\u00f6nnen ein bis zwei Jahre erforderlich sein. Aber keine Sorge, dank der modernen 3D-Bildgebungstechnologie kennen Sie Ihren Behandlungsplan im Voraus, von der Anfangsposition der Z\u00e4hne bis zur gew\u00fcnschten Endposition.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Invisalign\u00ae entdecken\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Invisalign behandlung\",\"url\":\"https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3734,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape7\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnprothesen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Es gibt eine grosse Auswahl an festsitzendem oder herausnehmbarem Zahnersatz, der die \u00c4sthetik und den Komfort Ihres L\u00e4chelns verbessert. Zahnprothesen, die sich leicht an die Bed\u00fcrfnisse jedes Einzelnen anpassen lassen: Zahnkrone, Br\u00fccke, Veneer, herausnehmbare Voll- oder Teilprothese.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Implant et restauration\",\"url\":\"https:\/\/adent.ch\/soin\/implant-et-restauration\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns\":1,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape4\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":3741,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnkrone\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Die Krone ist ein Zahnersatz aus Keramik, der den sichtbaren Teil des Zahns ersetzt, wenn dieser durch Karies oder eine Fraktur stark besch\u00e4digt wurde. Sie sch\u00fctzt den Zahn vor Abnutzung und erm\u00f6glicht die Abdeckung eines Zahnimplantats, das einen fehlenden Zahn ersetzt. Diese Methode vermeidet die vollst\u00e4ndige Extraktion des Zahns. Sie verbessert die \u00c4sthetik und den Komfort Ihres L\u00e4chelns.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":3745,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnbr\u00fccke (oder Bridge)\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Die Br\u00fccke, auch bekannt als Bridge, ist ein Zahnersatz, der einen oder mehrere fehlende Z\u00e4hne ersetzen kann. Mit Zahnbr\u00fccken erhalten Sie \u00c4sthetik und Komfort im Mund zur\u00fcck. Die Pfeiler der Zahnbr\u00fccke befinden sich in der Regel auf beiden Seiten des zahnlosen Kiefers und werden in Form von Implantaten oder gefr\u00e4sten Z\u00e4hnen eingesetzt. Auf diesen Pfeilern ruht die Br\u00fccke. Er ist fest und kann nicht entfernt werden.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":3748,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Veneer\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Das Veneer ist eine hauchd\u00fcnne Keramikschale. Das Veneer ist sehr widerstandsf\u00e4hig und wird auf der Vorderseite der Z\u00e4hne befestigt. Die Farbe passt zu Ihrem L\u00e4cheln, sie wird nach Mass angefertigt und deckt den nat\u00fcrlichen Zahn ab.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":3771,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Vollst\u00e4ndige oder teilweise herausnehmbare Prothese\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Die Zahnprothesen werden nach Mass angefertigt. Sie passen sich der Morphologie Ihrer Mundh\u00f6hle an. Sie sind sehr widerstandsf\u00e4hig und ersetzen einen oder mehrere Z\u00e4hne. Dank der modernen Technologien, die in den Zahnarztzentren eingesetzt werden, bieten sie ein nat\u00fcrliches, \u00e4sthetisches und komfortables Endergebnis.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs\":4,\"_blocs\":\"field_623c21f0a6279\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25104d76c2\",\"shapes\":\"shape5\",\"_shapes\":\"field_623c20cd3ad28\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Bleaching und \u00e4sthetische Behandlungen\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Bleaching und \u00e4sthetische Behandlungen","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbleaching-und-aesthetisch-e-en-behandlungen","to_ping":"","pinged":"","post_modified":"2026-01-22 15:10:05","post_modified_gmt":"2026-01-22 14:10:05","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/blanchiments-et-soins-esthetiques\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jiemei CHAN | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Jiemei Chan, Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jiemei CHAN | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Jiemei Chan, Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T09:51:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/jiemai-chan\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/jiemai-chan\\\/\",\"name\":\"Jiemei CHAN | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2026-03-26T09:45:13+00:00\",\"dateModified\":\"2026-03-26T09:51:22+00:00\",\"description\":\"Jiemei Chan, Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/jiemai-chan\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/jiemai-chan\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/jiemai-chan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Team\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jiemei CHAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jiemei CHAN | Adent Zahnarztzentrum","description":"Jiemei Chan, Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/","og_locale":"de_DE","og_type":"article","og_title":"Jiemei CHAN | Adent Zahnarztzentrum","og_description":"Jiemei Chan, Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.","og_url":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2026-03-26T09:51:22+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/","url":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/","name":"Jiemei CHAN | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2026-03-26T09:45:13+00:00","dateModified":"2026-03-26T09:51:22+00:00","description":"Jiemei Chan, Dentalhygienikerin, spezialisiert auf Mundhygiene f\u00fcr Kinder und Erwachsene.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/zahnarzt\/jiemai-chan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Team","item":"https:\/\/adent.ch\/de\/team\/"},{"@type":"ListItem","position":2,"name":"Jiemei CHAN"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe\/16917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=16917"}],"wp:term":[{"taxonomy":"langue","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/langue?post=16917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}