{"id":4738,"date":"2022-05-30T10:47:50","date_gmt":"2022-05-30T08:47:50","guid":{"rendered":"https:\/\/adent.ch\/dentistes\/klara-chefdeville\/"},"modified":"2024-05-02T15:08:24","modified_gmt":"2024-05-02T13:08:24","slug":"klara-chefdeville","status":"publish","type":"equipe","link":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/","title":{"rendered":"Klara CHEFDEVILLE"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Klara Chefdeville ist Dentalhygienikerin <a href=\"https:\/\/adent.ch\/de\/klinik\/genf-eaux-vives\/\">am Zentrum f\u00fcr Zahnmedizin in Genf, Eaux-Vives<\/a>.<\/p>\n<p>Nach ihrem Abschluss als Dentalhygienikerin in Prag setzte sie ihr Studium in London fort, wo sie einen Master in \u00f6ffentlicher Gesundheit erwarb. Sie hat sich immer stark f\u00fcr den Beruf der Dentalhygienikerin engagiert und verf\u00fcgt heute \u00fcber ein Diplom, das sie zur Durchf\u00fchrung von Lokalan\u00e4sthesien vor Zahnreinigungen und K\u00fcrettagen bef\u00e4higt.<\/p>\n<p>Klara Chefdeville arbeitet auch mit Lupen, die ihr helfen, ihre Handgriffe zu pr\u00e4zisieren. Neben der Vorbeugung von Mundkrankheiten ist sie aufgrund ihrer Erfahrung auch auf die nicht-chirurgische Parodontalbehandlung spezialisiert.<\/p>\n<p>Klara Chefdeville arbeitet regelm\u00e4ssig mit Kindern und verwendet <a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\">Methoden, die auf ihr junges Alter<\/a> zugeschnitten sind.<\/p>\n<p>Ausgebildet in GBT: Guided Biofilm Therapy\u00ae von EMS Dental<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<h4>FACHGEBIETE<\/h4>\n<ul>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\">Zahnreinigung und Zahnhygiene<\/a><\/li>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\">Zahnpflege f\u00fcr Kinder<\/a><\/li>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\">Bleichen und \u00e4sthetische Behandlungen<\/a><\/li>\n<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>","protected":false},"template":"","langue":[101,103,148],"class_list":["post-4738","equipe","type-equipe","status-publish","hentry","langue-englisch","langue-franzoesisch","langue-tschechisch"],"acf":{"first_name":"Klara","last_name":"CHEFDEVILLE","job":"Dentalhygienikerin","short_description":"<p>Dentalhygienikerin, die sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert hat.<\/p>\n","image":{"ID":12234,"id":12234,"title":"Eaux-Vives_Klara Chefdeville","filename":"eaux-vives_klara-chefdeville.png","filesize":2298032,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville.png","link":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/eaux-vives_klara-chefdeville-2\/","alt":"","author":"6","description":"","caption":"","name":"eaux-vives_klara-chefdeville-2","status":"inherit","uploaded_to":4738,"date":"2023-11-24 15:00:06","modified":"2023-11-24 15:00:06","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1880,"height":1410,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville-1307x980.png","large-width":1307,"large-height":980,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville-1536x1152.png","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville.png","2048x2048-width":1880,"2048x2048-height":1410,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/eaux-vives_klara-chefdeville.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"cliniques":[{"ID":4237,"post_author":"14","post_date":"2022-04-20 14:39:35","post_date_gmt":"2022-04-20 12:39:35","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003ch3\\u003eUmfassende Expertise \u2013 auch f\u00fcr komplexe Situationen\\u003c\/h3\\u003e\\r\\nDas Zahnarztzentrum Adent Eaux-Vives vereint erfahrene Zahn\u00e4rztinnen und Zahn\u00e4rzte, die in den modernsten Behandlungstechniken ausgebildet sind. Das Zahnarztzentrum behandelt sowohl pr\u00e4ventive Anliegen als auch hochspezialisierte zahnmedizinische Therapien:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eImplantologie und vollst\u00e4ndige Rehabilitationen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eOral- und Parodontalchirurgie\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eUnsichtbare Kieferorthop\u00e4die und komplexe Zahnkorrekturen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\u00c4sthetische Zahnmedizin (Veneers, Zahnbleaching, keramische Restaurationen)\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eFunktionelle Gesamtrehabilitationen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandlung von Okklusionsst\u00f6rungen und Kiefergelenksproblemen (CMD)\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nJeder Behandlungsplan basiert auf einer umfassenden Diagnose sowie einer ganzheitlichen Analyse der Mundgesundheit. Ziel ist es, langfristige Resultate zu erzielen, die sowohl funktionell als auch \u00e4sthetisch \u00fcberzeugen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:media-text {\"mediaId\":16789,\"mediaLink\":\"https:\/\/adent.ch\/de\/klinik\/genf-eaux-vives\/adent-clinique-dentaires-eaux-vive-62-2-2\/\",\"mediaType\":\"image\"} -->\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/adent-clinique-dentaires-eaux-vive-62-1468x980.jpg\" alt=\"\" class=\"wp-image-16789 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\"><!-- wp:paragraph -->\n<p><strong>Modernste Technologie und digitale Pr\u00e4zision<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><strong><br><\/strong>Als renommiertes Zahnarztzentrum von Adent arbeitet das Zahnarztzentrum Eaux-Vives mit modernster Ausstattung und fortschrittlichen digitalen Behandlungsprotokollen.<br>3D-Bildgebung, digitale Niedrigdosis-Radiologie, softwaregest\u00fctzte Implantatplanung sowie optische Abformungen erm\u00f6glichen eine besonders pr\u00e4zise Analyse und Umsetzung der Behandlungen.<br>Das Zahnarztzentrum arbeitet eng mit f\u00fchrenden Schweizer Dentallaboren zusammen, die f\u00fcr ihre hohen Qualit\u00e4tsstandards, ihre R\u00fcckverfolgbarkeit und ihr handwerkliches K\u00f6nnen bekannt sind. Diese Zusammenarbeit gew\u00e4hrleistet:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>hochpr\u00e4zise, individuell angefertigte Restaurationen<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>sorgf\u00e4ltig ausgew\u00e4hlte Materialien nach h\u00f6chsten Qualit\u00e4tsstandards<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>eine nat\u00fcrliche und langlebige \u00c4sthetik<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>eine perfekte funktionelle Integration<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Die Verbindung aus klinischer Expertise und Schweizer zahntechnischem Know-how bildet eine zentrale Grundlage des therapeutischen Ansatzes.<\/p>\n<!-- \/wp:paragraph --><\/div><\/div>\n<!-- \/wp:media-text -->\n\n<!-- wp:media-text {\"mediaPosition\":\"right\",\"mediaId\":16804,\"mediaLink\":\"https:\/\/adent.ch\/de\/klinik\/genf-eaux-vives\/adent-clinique-dentaires-eaux-vive-6-2\/\",\"mediaType\":\"image\"} -->\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\"><!-- wp:paragraph -->\n<p><strong>Eine individuell abgestimmte Betreuung<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Neben modernster Technologie spielt der menschliche Aspekt eine entscheidende Rolle.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Aufmerksames Zuh\u00f6ren, das Verst\u00e4ndnis der individuellen Erwartungen sowie transparente Erkl\u00e4rungen stehen im Mittelpunkt jeder Behandlung. Therapien werden individuell geplant und bei Bedarf interdisziplin\u00e4r koordiniert.<\/p>\n<!-- \/wp:paragraph --><\/div><figure class=\"wp-block-media-text__media\"><img src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/adent-clinique-dentaires-eaux-vive-6-1-1469x980.jpg\" alt=\"\" class=\"wp-image-16804 size-full\"\/><\/figure><\/div>\n<!-- \/wp:media-text -->\n\n<!-- wp:media-text {\"mediaId\":16795,\"mediaLink\":\"https:\/\/adent.ch\/de\/klinik\/genf-eaux-vives\/adent-clinique-dentaires-eaux-vive-5-2\/\",\"mediaType\":\"image\"} -->\n<div class=\"wp-block-media-text is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/adent-clinique-dentaires-eaux-vive-5-1469x980.jpg\" alt=\"\" class=\"wp-image-16795 size-full\"\/><\/figure><div class=\"wp-block-media-text__content\"><!-- wp:paragraph -->\n<p><strong>Diskretion, Vertrauen und h\u00f6chste Anspr\u00fcche<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Vertraulichkeit und eine hochwertige Patientenerfahrung stehen im Zentrum der Philosophie des Zahnarztzentrums.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>In einem eleganten und zeitgem\u00e4ssen Umfeld basiert jede Konsultation auf:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul class=\"wp-block-list\"><!-- wp:list-item -->\n<li>pr\u00e4ziser Diagnostik<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>transparenter Behandlungsplanung<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>technischer Exzellenz<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item -->\n<li>respektvollem und einf\u00fchlsamem Umgang<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:paragraph -->\n<p>Dieser Anspruch erm\u00f6glicht den Aufbau einer langfristigen Vertrauensbeziehung.<\/p>\n<!-- \/wp:paragraph --><\/div><\/div>\n<!-- \/wp:media-text -->\n\n<!-- wp:media-text {\"mediaPosition\":\"right\",\"mediaId\":16798,\"mediaLink\":\"https:\/\/adent.ch\/de\/klinik\/genf-eaux-vives\/eaux-vives_desk-2\/\",\"mediaType\":\"image\"} -->\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\"><!-- wp:paragraph -->\n<p><strong>Zahnmedizinische Exzellenz in Genf<\/strong><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p><\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Als renommiertes Zahnarztzentrum von Adent positioniert sich das Zahnarztzentrum Eaux-Vives als Referenz f\u00fcr moderne Zahnmedizin in Genf.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph -->\n<p>Im Herzen eines der gefragtesten Quartiere der Stadt bietet das Zahnarztzentrum eine multidisziplin\u00e4re Expertise, modernste Technologien und eine pers\u00f6nliche Betreuung f\u00fcr Patientinnen und Patienten mit h\u00f6chsten Anspr\u00fcchen an Qualit\u00e4t, Pr\u00e4zision und Service.<\/p>\n<!-- \/wp:paragraph --><\/div><figure class=\"wp-block-media-text__media\"><img src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/eaux-vives_desk-1600x980.jpg\" alt=\"\" class=\"wp-image-16798 size-full\"\/><\/figure><\/div>\n<!-- \/wp:media-text -->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"5124\"],\"_members\":\"field_622f5635c857c\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Angst, Nervosit\u00e4t, Unsicherheit?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Entdecken Sie unsere Methoden, die Ihnen Behandlungen in voller Vertrauen und unter den bestm\u00f6glichen Bedingungen erm\u00f6glichen.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"rufen sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"RUFEN SIE UNS AN\",\"url\":\"tel:+41227008100\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum in Genf Eaux-Vives\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":\"\",\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cares-list {\"name\":\"acf\/cares-list\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bc7db53980\",\"title\":\"Entdecken Sie unsere Pflege\",\"_title\":\"field_622f3a593a474\",\"description\":\"Unsere Zahn\u00e4rzte und Dentalhygienikerinnen sind dazu da, all Ihre Bed\u00fcrfnisse in Bezug auf die Zahnpflege zu erf\u00fcllen. Bitte kontaktieren Sie uns f\u00fcr weitere Informationen.\",\"_description\":\"field_6278ccbffdcff\",\"cares\":[\"4138\",\"4140\",\"4134\",\"4132\",\"4136\",\"13554\",\"12151\"],\"_cares\":\"field_622f3a7e3a476\"},\"mode\":\"edit\"} \/-->","post_title":"Genf Eaux-Vives","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"genf-eaux-vives","to_ping":"","pinged":"","post_modified":"2026-04-28 17:15:02","post_modified_gmt":"2026-04-28 15:15:02","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/geneve-eaux-vives\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"}],"soins":[{"ID":4134,"post_author":"14","post_date":"2022-01-02 13:50:12","post_date_gmt":"2022-01-02 12:50:12","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Mund, meine Gesundheit\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u0022189\\u0022 data-end=\\u0022603\\u0022\\u003eEin \\u003cstrong data-start=\\u0022193\\u0022 data-end=\\u0022226\\u0022\\u003egesunder, strahlender L\u00e4cheln\\u003c\/strong\\u003e beginnt mit einer regelm\u00e4ssigen \\u003cstrong data-start=\\u0022259\\u0022 data-end=\\u0022276\\u0022\\u003eZahnreinigung\\u003c\/strong\\u003e und einer sorgf\u00e4ltigen \\u003cstrong data-start=\\u0022300\\u0022 data-end=\\u0022315\\u0022\\u003eMundhygiene\\u003c\/strong\\u003e. Der Mund beeinflusst nicht nur unser \\u003cstrong data-start=\\u0022354\\u0022 data-end=\\u0022373\\u0022\\u003eSelbstvertrauen\\u003c\/strong\\u003e und unsere \\u003cstrong data-start=\\u0022385\\u0022 data-end=\\u0022401\\u0022\\u003eAusstrahlung\\u003c\/strong\\u003e, sondern auch unsere \\u003cstrong data-start=\\u0022423\\u0022 data-end=\\u0022440\\u0022\\u003eKommunikation\\u003c\/strong\\u003e, \\u003cstrong data-start=\\u0022442\\u0022 data-end=\\u0022455\\u0022\\u003eErn\u00e4hrung\\u003c\/strong\\u003e und \\u003cstrong data-start=\\u0022460\\u0022 data-end=\\u0022485\\u0022\\u003eallgemeine Gesundheit\\u003c\/strong\\u003e. Bei \\u003cstrong data-start=\\u0022491\\u0022 data-end=\\u0022516\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e begleiten wir Sie dabei, Ihr L\u00e4cheln gesund, gepflegt und selbstbewusst zu erhalten.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022605\\u0022 data-end=\\u00221161\\u0022\\u003e\u00dcber \\u003cstrong data-start=\\u0022610\\u0022 data-end=\\u0022645\\u0022\\u003e600 verschiedene Bakterienarten\\u003c\/strong\\u003e leben in der Mundh\u00f6hle. Ohne gr\u00fcndliche \\u003cstrong data-start=\\u0022686\\u0022 data-end=\\u0022703\\u0022\\u003eZahnreinigung\\u003c\/strong\\u003e k\u00f6nnen diese Bakterien pathologisch werden und zu \\u003cstrong data-start=\\u0022754\\u0022 data-end=\\u0022768\\u0022\\u003eGingivitis\\u003c\/strong\\u003e oder \\u003cstrong data-start=\\u0022774\\u0022 data-end=\\u0022790\\u0022\\u003eParodontitis\\u003c\/strong\\u003e (Zahnlockerung) f\u00fchren. Manche Bakterien gelangen sogar in den Blutkreislauf und wirken sich auf die allgemeine Gesundheit aus. Unsere \\u003cstrong data-start=\\u0022926\\u0022 data-end=\\u0022972\\u0022\\u003eDentalhygienikerinnen und Dentalhygieniker\\u003c\/strong\\u003e sind Expertinnen und Experten f\u00fcr \\u003cstrong data-start=\\u00221007\\u0022 data-end=\\u00221033\\u0022\\u003epr\u00e4ventive Zahnmedizin\\u003c\/strong\\u003e. Sie beraten Sie individuell, zeigen die besten \\u003cstrong data-start=\\u00221082\\u0022 data-end=\\u00221106\\u0022\\u003eMundhygiene-Routinen\\u003c\/strong\\u003e und f\u00fchren professionelle \\u003cstrong data-start=\\u00221133\\u0022 data-end=\\u00221152\\u0022\\u003eZahnreinigungen\\u003c\/strong\\u003e durch.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221163\\u0022 data-end=\\u00221542\\u0022\\u003eMit der richtigen Kombination aus \\u003cstrong data-start=\\u00221197\\u0022 data-end=\\u00221230\\u0022\\u003eprofessioneller Zahnreinigung\\u003c\/strong\\u003e, t\u00e4glichen Pflegeroutinen und den passenden Hilfsmitteln \u2013 wie \\u003cstrong data-start=\\u00221294\\u0022 data-end=\\u00221336\\u0022\\u003eB\u00fcrsten, Interdentalb\u00fcrsten, Zahnseide\\u003c\/strong\\u003e oder \\u003cstrong data-start=\\u00221342\\u0022 data-end=\\u00221360\\u0022\\u003eWasserflossern\\u003c\/strong\\u003e \u2013 sorgen Sie daf\u00fcr, dass Ihr L\u00e4cheln gesund bleibt und Tag f\u00fcr Tag strahlt. Bei \\u003cstrong data-start=\\u00221441\\u0022 data-end=\\u00221466\\u0022\\u003eAdent Zahnarztzentren\\u003c\/strong\\u003e machen wir Ihre Mundgesundheit und Ihr strahlendes L\u00e4cheln zur Priorit\u00e4t.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"\\u003cp data-start=\\u0022181\\u0022 data-end=\\u0022929\\u0022\\u003eEine \\u003cstrong data-start=\\u0022186\\u0022 data-end=\\u0022291\\u0022\\u003eZahnreinigung, die von einer Prophylaxeassistentin oder einem Prophylaxeassistenten durchgef\u00fchrt wird\\u003c\/strong\\u003e, ist eine vorbeugende Behandlung, die dazu dient, Zahnbelag und oberfl\u00e4chliche Verf\u00e4rbungen zu entfernen, ohne unter das Zahnfleisch zu gehen. Diese Art der Zahnreinigung ersetzt keine professionelle Zahnreinigung durch eine Dentalhygienikerin und richtet sich vor allem an Personen ohne Anzeichen einer Zahnfleischentz\u00fcndung. Sie wird besonders f\u00fcr Kinder und Jugendliche empfohlen, um von klein auf eine gute Mundhygiene zu f\u00f6rdern. Die Prophylaxeassistentin oder der Prophylaxeassistent verwendet geeignete Instrumente und gibt individuelle Tipps, um saubere Z\u00e4hne und ein gesundes L\u00e4cheln zwischen den Zahnarztbesuchen zu erhalten.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022931\\u0022 data-end=\\u00221590\\u0022\\u003eEine \\u003cstrong data-start=\\u0022936\\u0022 data-end=\\u00221033\\u0022\\u003eZahnreinigung, die von einer Dentalhygienikerin oder einem Dentalhygieniker durchgef\u00fchrt wird\\u003c\/strong\\u003e, ist eine umfassendere Behandlung, bei der Zahnstein und Belag auch unterhalb des Zahnfleisches entfernt werden. Diese Behandlung ist besonders f\u00fcr Personen mit Anzeichen von Gingivitis oder Parodontitis geeignet, da sie hilft, diese Erkrankungen zu verhindern oder zu behandeln. Die Dentalhygienikerin oder der Dentalhygieniker beurteilt die Gesundheit des Zahnfleisches, f\u00fchrt eine gr\u00fcndliche Reinigung durch und bietet eine individuelle Nachsorge an. Beide Arten der Zahnreinigung tragen gemeinsam dazu bei, die Mundgesundheit langfristig zu erhalten.\\u003c\/p\\u003e\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Mein Zahnarztzentrum finden\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnarztzentren\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/video {\"name\":\"acf\/video\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd1d6224c6\",\"video_preview\":\"\",\"_video_preview\":\"field_67811bb9884ea\",\"type\":\"youtube\",\"_type\":\"field_621c7b47d116a\",\"youtube\":\"\\u003ciframe width=\\u0022560\\u0022 height=\\u0022315\\u0022 src=\\u0022https:\/\/www.youtube-nocookie.com\/embed\/_HwEkrC1wZ4?si=gyi_NdQ7qYhUa8sF\\u0026amp;controls=0\\u0022 title=\\u0022YouTube video player\\u0022 frameborder=\\u00220\\u0022 allow=\\u0022accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\\u0022 allowfullscreen\\u003e\\u003c\/iframe\\u003e\",\"_youtube\":\"field_621c804717694\",\"legend\":\"\",\"_legend\":\"field_621c7e364a19a\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnreinigung und Zahnhygiene\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Rotes, gereiztes oder geschwollenes Zahnfleisch?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Wenden Sie sich an unsere Hygieniker:innen, um vorzubeugen, Zahnstein zu entfernen und Ihre Z\u00e4hne gesund zu erhalten.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Finden Sie Dentalhygieniker\/-innen\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4134\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie k\u00f6nnen Sie Ihre Z\u00e4hne zu Hause gesund erhalten?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16311,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnb\u00fcrste\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Verwenden Sie eine elektrische Zahnb\u00fcrste oder eine Schallzahnb\u00fcrste\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16314,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnzwischenr\u00e4ume\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Reinigen Sie Ihre Zahnzwischenr\u00e4ume mit B\u00fcrstchen, Zahnseide oder Zahnstochern\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16317,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Zahnpasta\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie fluoridhaltige Produkte. Sie sch\u00fctzen Ihre Z\u00e4hne vor S\u00e4ureangriffen\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs\":3,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnsteinentfernung und Zahnhygiene\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Warum sollte man zu einem\/einer Dentalhygieniker\/-in gehen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Vorbeugung und der Schutz vor Zahnerkrankungen stehen im Mittelpunkt der Arbeit der Dentalhygieniker\/-innen. Die Zahnsteinentfernung ist die bekannteste Hygienemassnahme. Sie wird von unseren diplomierten Dentalhygieniker\/-innen durchgef\u00fchrt und besteht in der Entfernung von Zahnstein, der sich auf den Z\u00e4hnen angesammelt hat. Denn selbst wenn Sie sich regelm\u00e4ssig die Z\u00e4hne putzen, kann eine einfache Zahnb\u00fcrste den Zahnstein nicht entfernen. Durch regelm\u00e4ssige Zahnsteinentfernungen, die von unseren Dentalhygienikern\/-hygienikerinnen durchgef\u00fchrt werden, erhalten Sie die Unversehrtheit Ihres Zahnfleisches und Ihrer Z\u00e4hne. Eine halbj\u00e4hrliche Zahnreinigung wird von Fachleuten f\u00fcr Mundgesundheit empfohlen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was ist der Unterschied zwischen einem\/einer Hygieniker\/-in und einem Prophylaxeassistenten\/einer Prophylaxeassistentin?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Bei Adent wird die Zahnpflege von Dentalhygienikern\/-hygienikerinnen und Prophylaxeassistent\/-innen durchgef\u00fchrt. Diese Zahngesundheitsfachleute haben jeweils ihren eigenen Zust\u00e4ndigkeitsbereich. Als Patient\/-in ist es gut, die Unterschiede zwischen ihnen zu kennen. So stellen Sie sicher, dass die Behandlung Ihren Bed\u00fcrfnissen entspricht.\\r\\n\\r\\nDer\/Die Profilaxeassistent\/-in (PA) ist ein diplomierter Dentalassistent\/eine diplomierte Dentalassistentin. Zus\u00e4tzlich zu diesen T\u00e4tigkeiten als Dentalassistent\/-in \u00fcbernimmt der\/die PA folgende Leistungen:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003ePr\u00e4ventivmassnahmen zur Erhaltung der Mundgesundheit\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eInformation und Motivation der Patienten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernung von supragingivalen Plaqueablagerungen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003eBleichen der Z\u00e4hne\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDiese Aufgaben werden immer unter der Aufsicht des Zahnarztes\/der Zahn\u00e4rztin ausgef\u00fchrt. Zus\u00e4tzlich zur Grundausbildung hat er\/sie eine von der SSO geregelte Weiterbildung zur beruflichen Weiterentwicklung absolviert. Diese Weiterbildung erm\u00f6glicht es ihr\/ihm, selbstst\u00e4ndig zu arbeiten.\\r\\n\\r\\nUnsere Prophylaxeassistenten\/\\u002d\\u002dassistentinnen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/\\u0022\\u003ehier\\u003c\/a\\u003e\\r\\n\\r\\nDer\/Die diplomierte Dentalhygieniker\/-in HF (DH) erf\u00fcllt folgende Aufgaben:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eErstellen, \u00dcbernehmen und Interpretieren von Diagnosen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eErstellen von Behandlungspl\u00e4nen in Absprache mit dem Zahnarzt\/der Zahn\u00e4rztin und dem Patienten\/der Patientin\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandeln von Parodontitis\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernen von Zahnstein auf und unter den Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBleichen von Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAnfertigen von R\u00f6ntgenaufnahmen, An\u00e4sthesie\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nUnsere Dentalhygieniker\/-innen finden Sie hier.\\r\\n\\r\\nDie \u00dcberwachung Ihrer Mundhygiene sollte mit Ihrem Zahnarzt\/Ihrer Zahn\u00e4rztin oder Ihres Dentalhygienikers\/Ihrer Dentalhygienikerin besprochen werden.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wer braucht eine Zahnreinigung?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine regelm\u00e4ssige Zahnreinigung wird f\u00fcr jeden empfohlen, der Z\u00e4hne hat, egal ob Erwachsener oder Kind. Kinder k\u00f6nnen unsere Dentalhygieniker\/-innen schon im fr\u00fchen Alter aufsuchen. So erhalten sie professionellen Rat und entwickeln gute Gewohnheiten, sobald sie ihre ersten Z\u00e4hne bekommen. Unsere Dentalhygieniker\/-innen k\u00f6nnen Ihr Kind an den Besuch beim Zahnarzt\/bei der Zahn\u00e4rztin gew\u00f6hnen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Welche Vorteile hat eine regelm\u00e4ssige Zahnreinigung?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine regelm\u00e4ssige Zahnsteinentfernung verhindert, dass sich zu viel Zahnstein auf den Z\u00e4hnen ablagert. Ausserdem werden Verf\u00e4rbungen entfernt, die z. B. durch Teein oder Koffein verursacht werden. Zahnstein und Zahnbelag sind sch\u00e4dlich f\u00fcr die Z\u00e4hne und das Zahnfleisch. Sie f\u00fchren zu Infektionen wie Karies, Zahnlockerung und Zahnfleischentz\u00fcndungen, die als Gingivitis bezeichnet werden. Die Unversehrtheit Ihrer Z\u00e4hne und Ihres Zahnfleischs bleibt erhalten, wenn Sie regelm\u00e4ssig professionelle Zahnreinigungen und Hygienetipps erhalten. Unsere Dentalhygieniker\/-innen beraten Sie auch \u00fcber die richtigen Schritte, um sch\u00f6ne Z\u00e4hne zu erhalten oder wiederzuerlangen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions_4_title\":\"Wie l\u00e4uft eine Zahnhygienesitzung ab?\",\"_accordions_4_title\":\"field_626fdd3ff47be\",\"accordions_4_content\":\"Zun\u00e4chst muss ein medizinischer Fragebogen ausgef\u00fcllt werden. Dann beginnt die Reinigung. Der\/Die Dentalhygieniker\/-in verf\u00fcgt \u00fcber eine Palette moderner Arbeitsinstrumente. Diese werden an die Bed\u00fcrfnisse jedes Patienten\/jeder Patientin angepasst.\\r\\n\\u003col\\u003e\\r\\n \\t\\u003cli\\u003eManuelle Scaler (Zahnsteinentferner). Sie werden nach der Lage des Zahns, der Position des Zahnsteins und danach ausgew\u00e4hlt, ob eine Zahnlockerung vorliegt oder nicht.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eElektronische Scaler mit Ultraschall.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003ePolieren, um Koffein-, Teein- oder Nikotinverf\u00e4rbungen zu entfernen und die Oberfl\u00e4che des Zahnschmelzes zu gl\u00e4tten.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAm Ende gibt er\/sie die patientenspezifischen Gesundheitstipps und -tricks.\\u003c\/li\\u003e\\r\\n\\u003c\/ol\\u003e\\r\\nAlle Dentalhygienikerinnen und Dentalhygieniker bei Adent sind in der GBT-Technik geschult. [GBT] Guided Biofilm Therapy\u00ae ist eine innovative Technik, die von EMS Dental entwickelt wurde, um Biofilm, Verf\u00e4rbungen und Zahnstein von Ihren Z\u00e4hnen zu entfernen. Diese schmerzfreie Technik kann sowohl bei nat\u00fcrlichen Z\u00e4hnen als auch bei Zahnrekonstruktionen und Zahnimplantaten eingesetzt werden.\\r\\n\\r\\n\\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/zahnsteinentfernung-guided-biofilm-technology\/\\u0022\\u003eWeitere Informationen \u00fcber GBT\\u003c\/a\\u003e\",\"_accordions_4_content\":\"field_626fdd46f47bf\",\"accordions_5_title\":\"Ist eine Zahnreinigung schmerzhaft?\",\"_accordions_5_title\":\"field_626fdd3ff47be\",\"accordions_5_content\":\"Bei akuter Empfindlichkeit kann eine \u00f6rtliche Bet\u00e4ubung in Betracht gezogen werden. Dadurch wird Ihr Wohlbefinden w\u00e4hrend der gesamten Zahnreinigung verbessert.\\r\\n\\r\\nF\u00fchlen Sie sich gestresst und nerv\u00f6s, wenn Sie an Ihren n\u00e4chsten Zahnarzttermin denken? Fragen Sie nach einer Behandlung mit Lachgas (MEOPA) oder Hypnose. MEOPA ist ein farb- und geruchloses Gasgemisch aus Sauerstoff und Distickstoffmonoxid. Wenn Sie es einatmen, entspannt es Sie, w\u00e4hrend Sie gleichzeitig beim Bewusstsein sind und Sie wissen was um Sie herum geschieht. Die Sitzung mit dem\/der Dentalhygieniker\/-in wird in aller Ruhe stattfinden.\\r\\n\\r\\nUm mehr \u00fcber die Angst vor dem Zahnarzt\/der Zahn\u00e4rztin zu informieren, haben wir \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/die-zahnarztphobie\/\\u0022\\u003eeinen Artikel\\u003c\/a\\u003e dar\u00fcber verfasst.\",\"_accordions_5_content\":\"field_626fdd46f47bf\",\"accordions\":6,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape3\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/tab {\"name\":\"acf\/tab\",\"data\":{\"anchor\":\"teenager\",\"_anchor\":\"field_635bd13882c1f\",\"tabs_0_name\":\"Kinder\",\"_tabs_0_name\":\"field_624449592e9bd\",\"tabs_0_tab\":13563,\"_tabs_0_tab\":\"field_624449622e9be\",\"tabs_1_name\":\"Teenager\",\"_tabs_1_name\":\"field_624449592e9bd\",\"tabs_1_tab\":4124,\"_tabs_1_tab\":\"field_624449622e9be\",\"tabs_2_name\":\"Erwachsene\",\"_tabs_2_name\":\"field_624449592e9bd\",\"tabs_2_tab\":4128,\"_tabs_2_tab\":\"field_624449622e9be\",\"tabs\":3,\"_tabs\":\"field_624449452e9bc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Sanfte Vorbeugung und Behandlung f\u00fcr Ihre Z\u00e4hne und Ihr Zahnfleisch.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Schlechte Hygiene f\u00fchrt zu Infektionskrankheiten der Z\u00e4hne und des Zahnfleischs. Sie f\u00fchrt auch zu Schmerzen. Diese Erkrankungen k\u00f6nnen sowohl Erwachsene als auch Kinder betreffen. Um das Auftreten von Krankheiten zu verhindern, sind regelm\u00e4ssige Sitzungen bei dem\/der Dentalhygieniker\/-in erforderlich. Der\/Die Dentalhygieniker\/-in entfernt Biofilm und Zahnstein, die sich auf Ihren Z\u00e4hnen festgesetzt haben.\\r\\n\\r\\nDie Zahnarztzentren von Adent passen sich st\u00e4ndig an die Entwicklung der zahnmedizinischen Technologien an. Wir bieten Ihnen eine optimale Pflegequalit\u00e4t und mehr Komfort. Die [GBT] Guided Biofilm Therapy\u00ae ist ein innovativer Ansatz, der von EMS Dental entwickelt wurde. Sie entfernt Biofilm, Verf\u00e4rbungen und Zahnstein. Diese Technik kann bei nat\u00fcrlichen und k\u00fcnstlichen Z\u00e4hnen sowie bei Zahnimplantaten angewendet werden.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Zahnfleisch pflege\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnfleisch pflege\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Profitieren Sie von einer schonenden und umfassenden Zahnreinigung dank der Kompetenzen unserer Fachpersonals. Das Fachwissen in Kombination mit den Technologien, die in den Zahnarztzentren von Adent zum Einsatz kommen, sorgt daf\u00fcr, dass Sie die beste Pflege erhalten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Erfahren Sie mehr \u00fcber die GBT\u00ae\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnstein-Entfernung: Guided Biofilm Technology\",\"url\":\"https:\/\/adent.ch\/de\/info\/zahnsteinentfernung-guided-biofilm-technology\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape1\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnreinigung und Zahnhygiene","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnsteinentfernung-und-zahnhygiene","to_ping":"","pinged":"","post_modified":"2026-01-19 15:14:38","post_modified_gmt":"2026-01-19 14:14:38","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/detartrage-et-hygiene-dentaire\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4140,"post_author":"14","post_date":"2022-01-03 13:50:41","post_date_gmt":"2022-01-03 12:50:41","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Das Beste fu\u0308r kleine La\u0308cheln.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Kinderzahn\u00e4rzte sind in einem kindgerechten psychologischen und p\u00e4dagogischen Ansatz geschult. Ihre Aufgabe ist es, zu beruhigen und mit einem altersgerechten Vokabular zu sprechen, um ein Klima des Vertrauens zu schaffen.\\r\\n\\r\\nWir f\u00fchren alle Arten von Zahnbehandlungen bei Kindern durch.\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eKariesbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eabgebrochener Zahn\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eZahnreinigung\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eTipps zum B\u00fcrsten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":16375,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Kieferorthop\u00e4dische Behandlungen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Zahn\u00e4rzte, die sich auf Kieferorthop\u00e4die spezialisiert haben, bieten kieferorthop\u00e4dische Behandlung f\u00fcr Kinder an. Eine kieferorthop\u00e4dische Behandlung kann in jedem Alter begonnen werden, aber die meisten Eltern w\u00fcnschen sich f\u00fcr ihre Kinder eine fr\u00fchzeitige Behandlung. Je nach Art der erforderlichen Behandlung kann eine erste Phase des Abfangens von Kieferorthop\u00e4den bereits ab dem 4. Lebensjahr stattfinden. In den Adent Zahnarztzentren werden verschiedene kieferorthop\u00e4dische Behandlungen angeboten, die sich an die jeweilige Mundsituation anpassen. Weitere Informationen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eauf unserer Seite \u00fcber Kieferorthop\u00e4de f\u00fcr Kinder\\u003c\/a\\u003e!\\r\\n\\r\\nZus\u00e4tzlich zu diesen zahn\u00e4rztlichen Behandlungen erkl\u00e4ren unsere diplomierten Dentalhygienikerinnen mit p\u00e4dagogischen Methoden, wie Z\u00e4hne und Zahnfleisch gesund erhalten werden k\u00f6nnen. Unsere Fachgebiete f\u00fcr zahn\u00e4rztliche Pr\u00e4vention helfen ihnen, die richtigen Verhaltensweisen zu erlernen, sobald sie die ersten Z\u00e4hne bekommen.\\r\\n\\r\\nHaben Sie Fragen zur Zahnhygiene bei Babys oder Jugendlichen? \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eBesuchen Sie unsere Seite zu diesen Themen\\u003c\/a\\u003e!\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Jeder Zahn muss t\u00e4glich gereinigt werden, egal wie klein er ist. Nach der Nahrungsaufnahme bildet sich ein Biofilm auf der Oberfl\u00e4che des Zahnschmelzes. Dieser Biofilm entwickelt sich weiter, wenn er nicht regelm\u00e4\u00dfig gereinigt wird. Dies f\u00fchrt zu wei\u00dfen, weichen Ablagerungen auf der Oberfl\u00e4che der Z\u00e4hne, die als Plaque bezeichnet werden. Zahnbelag besteht unter anderem aus Bakterien. Bakterien k\u00f6nnen Karies verursachen, wenn die Reinigung nicht regelm\u00e4ssig erfolgt. Plaque kann sich auch zu Zahnstein entwickeln, einem harten, wei\u00dfen Belag, der mit der Zahnb\u00fcrste nicht entfernt werden kann.\\r\\n\\r\\nAuch wenn dies selten vorkommt, kann sich ein Schaden an einem Milchzahn auf einen Erwachsenenzahn auswirken. Die Keime der erwachsenen Z\u00e4hne, die sich unter dem Zahnfleisch bilden, sind empfindlich. Sie k\u00f6nnen besch\u00e4digt werden, wenn ein Milchzahn infiziert wird.\\r\\n\\r\\nHeutzutage gibt es eine breite Palette von Hilfsmitteln f\u00fcr die Zahnreinigung bei Kindern. Sie k\u00f6nnen leicht elektrische Zahnb\u00fcrsten, Zahnseide in Tierform, bunte Kinderzahnb\u00fcrsten usw. erwerben. Diese Hilfsmittel helfen Ihnen dabei, die Mundhygiene Ihres Kindes zu verbessern. Lassen Sie sich von \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eunseren Dentalhygienikerinnen\\u003c\/a\\u003e beraten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Zahnarztangst\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Kind hat Angst vor dem Zahnarzt, was kann ich tun?\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"F\u00fcr Kinder mit Phobie oder Angst vor dem Zahnarzt haben wir L\u00f6sungen! Unsere Zahn\u00e4rzte bieten Lachgas- und Hypnosebehandlungen an, die auch bei Kindern einfach und sicher durchzuf\u00fchren sind. Weitere Informationen finden Sie hier.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie kann ich Zahnprobleme bei meinem Kind vermeiden?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16307,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Geben Sie gute Gewohnheiten weiter!\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Das Z\u00e4hneputzen wird 3x\/Tag empfohlen: Putzen Sie die Z\u00e4hne nach jeder Mahlzeit und vermeiden Sie bei Ihren Kindern das st\u00e4ndige Naschen von S\u00fcssigkeiten, da dies Karies und Schmerzen verursachen kann.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16347,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"B\u00fcrsten ab den ersten Z\u00e4hnen.\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Dies kann eine schwierige Aufgabe sein, aber alle Z\u00e4hne, auch wenn sie noch so klein sind, m\u00fcssen t\u00e4glich gereinigt werden. Tragen Sie ab dem ersten Zahn bis zum Alter von ca. 3 Jahren Zahnpasta in der Gr\u00f6sse eines Reiskorns auf, danach in der Gr\u00f6sse einer Erbse.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16350,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"S\u00fcssigkeiten ja, mit Sympadent\u00ae!\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie \\u003ca href=\\u0022https:\/\/zahnfreundlich.ch\/lassociation-sympadent-sengage-pour-des-dents-denfant-saines\/?lang=fr\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eSympadent\u00ae Bonbons\\u003c\/a\\u003e: Sie wurden getestet und f\u00fcr gut befunden. Diese S\u00fcssigkeiten schonen die Z\u00e4hne von Kindern und Erwachsenen. Sie k\u00f6nnen es in verschiedenen Gesch\u00e4ften in der Schweiz kaufen. Achten Sie auf das Zahnlogo unter dem Regenschirm.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":16562,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Alles miteinander teilen? Ja, aber...\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Vermeiden Sie es, den L\u00f6ffel oder andere Gegenst\u00e4nde in den Mund zu nehmen, bevor Sie sie Ihrem Baby geben: Karies verursachende Bakterien werden \u00fcbertragen.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs_4_image\":16311,\"_blocs_4_image\":\"field_623c222ba627a\",\"blocs_4_title\":\"Eine zus\u00e4tzliche Hilfe f\u00fcr eine optimale Reinigung.\",\"_blocs_4_title\":\"field_623c22c4a627b\",\"blocs_4_description\":\"Elektrische Zahnb\u00fcrsten sind eine gute Hilfe f\u00fcr Ihr Kind. Dies erleichtert das B\u00fcrsten und ermutigt sie. Unsere Dentalhygienikerinnen beraten Sie gerne.\",\"_blocs_4_description\":\"field_623c22cba627c\",\"blocs_4_button_type\":\"none\",\"_blocs_4_button_type\":\"field_623c34377e92d\",\"blocs_5_image\":16353,\"_blocs_5_image\":\"field_623c222ba627a\",\"blocs_5_title\":\"Eine fluoridierte Zahnpasta, die f\u00fcr sein Alter geeignet ist.\",\"_blocs_5_title\":\"field_623c22c4a627b\",\"blocs_5_description\":\"Fluor sch\u00fctzt die Z\u00e4hne vor Karies. Sie finden leicht Zahnpasta f\u00fcr Kinder unter 6 Jahren, f\u00fcr Kinder von 6 bis 12 Jahren und f\u00fcr Erwachsene. Wechseln Sie den Geschmack der Zahnpasta regelm\u00e4ssig: Kinder m\u00f6gen Abwechslung.\",\"_blocs_5_description\":\"field_623c22cba627c\",\"blocs_5_button_type\":\"none\",\"_blocs_5_button_type\":\"field_623c34377e92d\",\"blocs\":6,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnpflege f\u00fcr Kinder\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie unsere Zahn\u00e4rzte, die auf die Behandlung von Kindern spezialisiert sind.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Einen spezialisierten Zahnarzt finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4140\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnpflege f\u00fcr Kinder","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbehandlung-fuer-kinder","to_ping":"","pinged":"","post_modified":"2026-01-19 15:07:44","post_modified_gmt":"2026-01-19 14:07:44","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-pour-les-enfants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4136,"post_author":"14","post_date":"2022-01-06 10:59:42","post_date_gmt":"2022-01-06 09:59:42","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zeigen Sie Ihr strahlendes L\u00e4cheln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unser Mund spielt daher eine wichtige Rolle bei der Kommunikation und Gesundheit.\\r\\n\\r\\nRegelm\u00e4ssige Zahnpflege ist der Schl\u00fcssel zu einer guten Mundgesundheit und tr\u00e4gt wesentlich zur St\u00e4rkung des Selbstbewusstseins bei. Die regelm\u00e4ssige Entfernung von Zahnbelag auf Ihren Z\u00e4hnen verhindert das Wachstum von Bakterien, die Zahnfleischentz\u00fcndungen (Gingivitis) verursachen. Ausserdem h\u00e4lt es Ihre Z\u00e4hne glatt, weiss und gl\u00e4nzend.\\r\\n\\r\\nMit einigen guten Gewohnheiten in Ihrem Alltag und regelm\u00e4ssigen Besuchen bei Ihrem Hygieniker oder Zahnarzt k\u00f6nnen Sie sich ein gesundes, strahlendes L\u00e4cheln und sch\u00f6ne Z\u00e4hne bewahren. Unsere Dentalhygienikerinnen teilen mit Ihnen Gesundheitstipps, um Ihre Z\u00e4hne weiss und Ihr Zahnfleisch gesund zu halten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Wenn Sie die Farbe Ihres Zahnschmelzes aufhellen und weissere Z\u00e4hne haben m\u00f6chten, bieten wir Ihnen eine professionelle Zahnaufhellung an! Wir bieten effektive, einfache, professionelle und nicht-invasive L\u00f6sungen f\u00fcr das Bleichen Ihrer Z\u00e4hne.\\r\\n\\r\\nHaben Sie Fragen zu unseren verschiedenen Zahnaufhellungstechniken? Fragen Sie Ihre \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eDentalhygienikerin\\u003c\/a\\u003e oder Ihren \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4138\\u0022\\u003eZahnarzt\\u003c\/a\\u003e um Rat!\\r\\n\\r\\nEntdecken Sie unten die verschiedenen Zahnaufhellungstechniken und andere \u00e4sthetische Behandlungen, die wir in den Adent Zahnarztzentren anbieten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"none\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung im Zentrum\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eProfessionelles Zahnbleaching: Ein weisseres L\u00e4cheln \u2013 ganz nach Ihren Bed\u00fcrfnissen\\u003c\/strong\\u003e\\r\\n\\r\\nVerleihen Sie Ihrem L\u00e4cheln sofort neue Strahlkraft mit unseren professionellen Zahnbleaching-Behandlungen im Zahnarztzentrum der Groupe Adent. Moderne Technologien, schonende Verfahren und eine individuelle Beratung sorgen f\u00fcr sichtbare und sichere Resultate.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eBlancOne\u00ae: Express-Zahnbleaching f\u00fcr besondere Anl\u00e4sse\\u003c\/strong\\u003e\\r\\n\\r\\nDas BlancOne\u00ae Zahnbleaching ist ideal f\u00fcr einmalige Ereignisse wie eine Hochzeit, ein Fotoshooting oder einen wichtigen Abend. Die Behandlung wird direkt im Zahnarztzentrum von einer speziell ausgebildeten Dentalhygienikerin durchgef\u00fchrt und liefert bereits nach kurzer Zeit sichtbare Ergebnisse (10 bis 30 Minuten, je nach Methode).\\r\\n\\r\\n\ud83d\udc49 \\u003cstrong\\u003eHinweis:\\u003c\/strong\\u003e Die Wirkung ist tempor\u00e4r.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eFl\u00e4sh: Sanftes und nachhaltiges Zahnbleaching (CHF 500.\u2013)\\u003c\/strong\\u003e\\r\\n\\r\\nDas Fl\u00e4sh Zahnbleaching richtet sich an Patientinnen und Patienten, die ein nat\u00fcrliches und langfristiges Ergebnis w\u00fcnschen. Die Behandlung erfolgt \u00fcber mehrere Sitzungen hinweg und erm\u00f6glicht eine kontrollierte, schrittweise Aufhellung der Zahnfarbe.\\r\\n\\r\\n\ud83d\udd0e \\u003cstrong\\u003eWichtig:\\u003c\/strong\\u003e Eine gesunde Dentition ohne Zahnstein oder pathologische Befunde ist Voraussetzung f\u00fcr jedes Zahnbleaching. Eine zahnmedizinische Kontrolle sowie eine Zahnreinigung werden mindestens 3 Monate vor der Behandlung empfohlen.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\ud83d\udccd \\u003cstrong\\u003eUnsere Teams in den Zahnarztzentren beraten Sie gerne\\u003c\/strong\\u003e, um das f\u00fcr Sie passende Zahnbleaching auszuw\u00e4hlen.\\r\\n\\r\\nBitte beachten Sie: Nicht alle Behandlungen sind in allen Zahnarztzentren verf\u00fcgbar. Informieren Sie sich direkt beim Zahnarztzentrum, in dem Sie Ihre Behandlung durchf\u00fchren m\u00f6chten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":7110,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung im Zentrum\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellung im Zentrum: Wie funktioniert das?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Zahnaufhellung wird von unseren ausgebildeten Dentalhygienikerinnen in unserem Zentrum durchgef\u00fchrt. Das Bleichen der Z\u00e4hne wird in einer einzigen Sitzung mit professionellen, bew\u00e4hrten und bekannten Produkten durchgef\u00fchrt. Sie enthalten 16% Carbamidperoxid.\\r\\n\\r\\nIn einem unserer Zentren wird das Bleichgel f\u00fcr 10 bis 30 Minuten auf Ihre Z\u00e4hne aufgetragen. Eine Biophotonenlampe mit einem Bleichbogen (ultraviolettes Licht) wird auf Ihr Gebiss gerichtet und aktiviert das Bleichmittel. Um Empfindlichkeiten zu vermeiden, wird Vitamin D auf das Zahnfleisch aufgetragen.\\r\\n\\r\\nEine Sitzung mit BlancOne\u00ae CLICK dauert 10 Minuten. Die Dentalhygienikerin wendet diese Behandlung direkt nach der Zahnreinigung an. Sie k\u00f6nnen mit dem BlancOne\u00ae CLICK Zahnbleichmittel ein bis zwei Nuancen gewinnen.\\r\\n\\r\\nWir bieten auch BlancOne\u00ae TOUCH Zahnaufhellung an. Die Dauer betr\u00e4gt 30 Minuten, was drei Bleichzyklen entspricht. Mit dieser Behandlung wird Ihr Zahnschmelz um vier bis f\u00fcnf Farbt\u00f6ne aufgehellt. Sie werden mit strahlend weissen Z\u00e4hnen nach Hause gehen!\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was sind die Vorteile des professionellen Zahnbleachings BlancOne\u00ae?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"BlancOne\u00ae Zahnaufhellung ist kurz, effektiv und entspricht den Bed\u00fcrfnissen unserer Patienten durch seine Vorteile:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcr weissere Z\u00e4hne ist nur eine Sitzung erforderlich.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eDie Dauer des Eingriffs ist kurz (ab 10' Minuten Anwendung). Die Zahnaufhellung wird direkt nach Ihrer Zahnreinigung angewendet.\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDie Empfindlichkeit auf den Z\u00e4hnen ist geringer (Tests mit unseren Patienten). Das Ergebnis ist nat\u00fcrlich und dauerhaft.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Was muss ich beachten, bevor ich eine professionelle Zahnaufhellung mit BlancOne\u00ae beginne?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine gute Mundhygiene ist Voraussetzung f\u00fcr eine Zahnaufhellung. Vor der Zahnaufhellung ist ein Kontrolltermin beim Zahnarzt erforderlich. Bevor Sie mit der Behandlung beginnen, m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (wie z.B. Zahnlockerung) ausgeschlossen sein.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ich bin an einer professionellen Zahnaufhellung mit BlancOne\u00ae interessiert. An wen kann ich mich wenden?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Kontaktieren Sie das Zentrum \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnkliniken\/\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eAdent Zahnarztzentrum in Ihrer N\u00e4he\\u003c\/a\\u003e. Unsere Dentalhygienikerinnen sind von Montag bis Samstag, von morgens bis abends in allen unseren Zahnarztzentren f\u00fcr Sie da.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape8\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung mit Schienen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eEin gr\u00fcndliches und lang anhaltendes Ergebnis mit unseren massgeschneiderten Bleaching-Schienen und den professionellen Produkten von \\u003ca href=\\u0022https:\/\/www.philips.ch\/fr\/c-m-pe\/eclaircissement-des-dents\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003ePhilips Zoom\u00ae (400.-)\\u003c\/a\\u003e.\\u003c\/strong\\u003e\\r\\n\\r\\nDiese Zahnaufhellungstechnik ist in verschiedenen Zentren der Adent Gruppe verf\u00fcgbar. Sie liefert signifikante Ergebnisse und garantiert eine zuverl\u00e4ssige Bleichung. Bereits nach einigen Tagen sind Ergebnisse sichtbar und nach nur 2 Wochen ist die Behandlung abgeschlossen. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den Labors des Adent-Netzwerks hergestellt. Gesunde, zahnsteinfreie und pathologiefreie Z\u00e4hne sind eine Voraussetzung f\u00fcr den Beginn einer Zahnaufhellung.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"termin-vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3789,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung mit Schienen\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellungsschienen: Wie funktionieren die Schienen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Dentalhygienikerin oder der Zahnarzt macht einen Abdruck Ihrer Z\u00e4hne und \u00fcbergibt diesen an den Zahntechniker. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den \\u003ca href=\\u0022https:\/\/adent.ch\/de\/gruppe\/dentallabore\/\\u0022\\u003eLabors des Adent-Netzwerks\\u003c\/a\\u003e hergestellt.\\r\\n\\r\\nDie Herstellung der Bleaching-Schiene dauert eine Woche. Nach Ablauf dieser Frist wird ein neuer Termin f\u00fcr die Anprobe, die Beratung und die \u00dcbergabe des Materials (Schiene und Bleichmittel) vereinbart. Die Schienen k\u00f6nnen je nach Vorliebe Tag und Nacht f\u00fcr einige Stunden getragen werden. Bereits nach einigen Tagen sind Ergebnisse sichtbar. Nach nur 2 Wochen ist die Behandlung abgeschlossen und Ihre Z\u00e4hne sind strahlend weiss.\\r\\n\\r\\nIhre Zahnaufhellungsschiene kann gelagert und sp\u00e4ter wieder verwendet werden. So k\u00f6nnen Sie nach Belieben \u00c4nderungen vornehmen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"F\u00fcr wen ist die Zahnaufhellung mit Schienen geeignet?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Die Zahnaufhellung mit Schienen ist f\u00fcr Menschen gedacht, die dauerhaft weissere Z\u00e4hne haben m\u00f6chten. Um f\u00fcr diese Behandlung in Frage zu kommen, d\u00fcrfen Sie keine mundgesundheitlichen Kontraindikationen haben und m\u00fcssen ein gesundes Gebiss haben (kein Zahnstein, keine Karies, keine Zahnlockerung usw.). Der Rat Ihrer Dentalhygienikerin oder Ihres Zahnarztes ist erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Welche Vorteile bietet die professionelle Zahnaufhellung von Philips Zoom\u00ae?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Zahnaufhellung mit massgefertigten Schienen von Philips Zoom\u00ae-Produkten bietet Ihnen eine professionelle, effektive und sichere Zahnaufhellung. Massgefertigte Schienen sind diskret und k\u00f6nnen je nach Wunsch am Tag oder in der Nacht getragen werden. Die innovative Formel des Gels sch\u00fctzt Ihren Zahnschmelz und st\u00e4rkt Ihre Z\u00e4hne, ohne Ihre Gesundheit zu beeintr\u00e4chtigen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Was muss ich beachten, bevor ich mit einer professionellen Philips Zoom\u00ae Zahnaufhellung beginne?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine gute Mundgesundheit ist Voraussetzung f\u00fcr das Bleichen von Z\u00e4hnen. Vor dem Bleichen ist ein Kontrolltermin beim Zahnarzt erforderlich. Vor Beginn der Behandlung m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (z.B. Zahnlockerung) ausgeschlossen werden.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape7\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Invisalign\u00ae\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Invisalign\u00ae ist eine kieferorthop\u00e4dische Behandlung mit durchsichtigen Zahnschienen der Marke Invisalign\u00ae. Bei dieser Behandlung wird eine Reihe von transparenten, herausnehmbaren Alignern f\u00fcr einige Wochen oder Monate getragen, um die Z\u00e4hne auf sanfte und schonende Weise neu auszurichten.\\r\\n\\r\\nDieses transparente und \u00e4sthetisch unauff\u00e4llige System ist nicht nur auf relativ einfache Behandlungen beschr\u00e4nkt, sondern eignet sich auch f\u00fcr komplexere Ausrichtungen. Bei kleinen, un\u00e4sthetischen Zahnfehlstellungen reicht eine mehrmonatige Behandlung mit transparenten Alignern aus. Bei komplexen Behandlungen k\u00f6nnen ein bis zwei Jahre erforderlich sein. Aber keine Sorge, dank der modernen 3D-Bildgebungstechnologie kennen Sie Ihren Behandlungsplan im Voraus, von der Anfangsposition der Z\u00e4hne bis zur gew\u00fcnschten Endposition.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Invisalign\u00ae entdecken\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Invisalign behandlung\",\"url\":\"https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3734,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape7\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnprothesen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Es gibt eine grosse Auswahl an festsitzendem oder herausnehmbarem Zahnersatz, der die \u00c4sthetik und den Komfort Ihres L\u00e4chelns verbessert. Zahnprothesen, die sich leicht an die Bed\u00fcrfnisse jedes Einzelnen anpassen lassen: Zahnkrone, Br\u00fccke, Veneer, herausnehmbare Voll- oder Teilprothese.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Implant et restauration\",\"url\":\"https:\/\/adent.ch\/soin\/implant-et-restauration\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns\":1,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape4\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":3741,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnkrone\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Die Krone ist ein Zahnersatz aus Keramik, der den sichtbaren Teil des Zahns ersetzt, wenn dieser durch Karies oder eine Fraktur stark besch\u00e4digt wurde. Sie sch\u00fctzt den Zahn vor Abnutzung und erm\u00f6glicht die Abdeckung eines Zahnimplantats, das einen fehlenden Zahn ersetzt. Diese Methode vermeidet die vollst\u00e4ndige Extraktion des Zahns. Sie verbessert die \u00c4sthetik und den Komfort Ihres L\u00e4chelns.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":3745,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnbr\u00fccke (oder Bridge)\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Die Br\u00fccke, auch bekannt als Bridge, ist ein Zahnersatz, der einen oder mehrere fehlende Z\u00e4hne ersetzen kann. Mit Zahnbr\u00fccken erhalten Sie \u00c4sthetik und Komfort im Mund zur\u00fcck. Die Pfeiler der Zahnbr\u00fccke befinden sich in der Regel auf beiden Seiten des zahnlosen Kiefers und werden in Form von Implantaten oder gefr\u00e4sten Z\u00e4hnen eingesetzt. Auf diesen Pfeilern ruht die Br\u00fccke. Er ist fest und kann nicht entfernt werden.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":3748,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Veneer\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Das Veneer ist eine hauchd\u00fcnne Keramikschale. Das Veneer ist sehr widerstandsf\u00e4hig und wird auf der Vorderseite der Z\u00e4hne befestigt. Die Farbe passt zu Ihrem L\u00e4cheln, sie wird nach Mass angefertigt und deckt den nat\u00fcrlichen Zahn ab.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":3771,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Vollst\u00e4ndige oder teilweise herausnehmbare Prothese\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Die Zahnprothesen werden nach Mass angefertigt. Sie passen sich der Morphologie Ihrer Mundh\u00f6hle an. Sie sind sehr widerstandsf\u00e4hig und ersetzen einen oder mehrere Z\u00e4hne. Dank der modernen Technologien, die in den Zahnarztzentren eingesetzt werden, bieten sie ein nat\u00fcrliches, \u00e4sthetisches und komfortables Endergebnis.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs\":4,\"_blocs\":\"field_623c21f0a6279\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25104d76c2\",\"shapes\":\"shape5\",\"_shapes\":\"field_623c20cd3ad28\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Bleaching und \u00e4sthetische Behandlungen\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Bleaching und \u00e4sthetische Behandlungen","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbleaching-und-aesthetisch-e-en-behandlungen","to_ping":"","pinged":"","post_modified":"2026-01-22 15:10:05","post_modified_gmt":"2026-01-22 14:10:05","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/blanchiments-et-soins-esthetiques\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Klara CHEFDEVILLE | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Klara Chefdeville ist Dentalhygienikerin an dem Adent Zahnarztzentrum in Genf, Eaux-Vives und hat sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Klara CHEFDEVILLE | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Klara Chefdeville ist Dentalhygienikerin an dem Adent Zahnarztzentrum in Genf, Eaux-Vives und hat sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T13:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/klara-chefdeville\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/klara-chefdeville\\\/\",\"name\":\"Klara CHEFDEVILLE | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2022-05-30T08:47:50+00:00\",\"dateModified\":\"2024-05-02T13:08:24+00:00\",\"description\":\"Klara Chefdeville ist Dentalhygienikerin an dem Adent Zahnarztzentrum in Genf, Eaux-Vives und hat sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/klara-chefdeville\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/klara-chefdeville\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/klara-chefdeville\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Team\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Klara CHEFDEVILLE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Klara CHEFDEVILLE | Adent Zahnarztzentrum","description":"Klara Chefdeville ist Dentalhygienikerin an dem Adent Zahnarztzentrum in Genf, Eaux-Vives und hat sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/","og_locale":"de_DE","og_type":"article","og_title":"Klara CHEFDEVILLE | Adent Zahnarztzentrum","og_description":"Klara Chefdeville ist Dentalhygienikerin an dem Adent Zahnarztzentrum in Genf, Eaux-Vives und hat sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert.","og_url":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2024-05-02T13:08:24+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/","url":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/","name":"Klara CHEFDEVILLE | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2022-05-30T08:47:50+00:00","dateModified":"2024-05-02T13:08:24+00:00","description":"Klara Chefdeville ist Dentalhygienikerin an dem Adent Zahnarztzentrum in Genf, Eaux-Vives und hat sich auf nicht-chirurgische Parodontalbehandlungen spezialisiert.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/zahnarzt\/klara-chefdeville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Team","item":"https:\/\/adent.ch\/de\/team\/"},{"@type":"ListItem","position":2,"name":"Klara CHEFDEVILLE"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe\/4738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=4738"}],"wp:term":[{"taxonomy":"langue","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/langue?post=4738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}