{"id":5103,"date":"2022-05-31T18:07:19","date_gmt":"2022-05-31T16:07:19","guid":{"rendered":"https:\/\/adent.ch\/dentistes\/thilani-balachandran\/"},"modified":"2024-05-02T14:32:45","modified_gmt":"2024-05-02T12:32:45","slug":"thilani-balachandran","status":"publish","type":"equipe","link":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/","title":{"rendered":"Thilani BALACHANDRAN"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles.<\/p>\n<p>Master in Zahnmedizin an <a href=\"https:\/\/www.unige.ch\/\" target=\"_blank\" rel=\"noopener\">der Universit\u00e4t Genf<\/a> und eidgen\u00f6ssisches Diplom. Thilani Balachandran ist heute Allgemeinzahn\u00e4rztin und kann daher alle Arten von zahn\u00e4rztlichen Behandlungen durchf\u00fchren. Dank ihres Fachwissens kann sie Sie bei allen <a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/\">allgemeinen zahn\u00e4rztlichen<\/a> Behandlungen<a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/\">(Karies<\/a>, <a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\">Bleaching<\/a>, <a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/\">Wurzelbehandlung<\/a>) unterst\u00fctzen.<\/p>\n<p>Sie f\u00fchrt konservierende Behandlungen mit Hilfe von <a href=\"https:\/\/adent.ch\/de\/behandlung\/implantate-und-zahnsanierung\/\">Restaurationstechniken<\/a> durch, die sich st\u00e4ndig weiterentwickeln und die sie in ihrer t\u00e4glichen Praxis anwendet (Onlay, Veneer, etc.). Um mehr \u00fcber die Restaurationstechniken von Adent zu erfahren, <a href=\"https:\/\/adent.ch\/de\/behandlung\/implantate-und-zahnsanierung\/\">klicken Sie bitte hier<\/a>!<\/p>\n<p>Thilani Balachandran und das Zentrum Adent in Genf-Charmilles arbeiten regelm\u00e4ssig mit Kindern und verwenden eine <a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\">auf ihr junges Alter abgestimmte Pflege<\/a>. Sie f\u00fchrt Behandlungen unter Lachgas und Vollnarkose durch, wenn dies erforderlich ist.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<h4>FACHGEBIETE<\/h4>\n<ul>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/\">\u00dcbliche Zahnpflege<\/a><\/li>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\">Zahnpflege f\u00fcr Kinder<\/a><\/li>\n<li><a href=\"https:\/\/adent.ch\/de\/zahnaerztliche-notfaelle\/\">Zahn\u00e4rztliche Notf\u00e4lle<\/a><\/li>\n<li><a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\">Bleichen und \u00e4sthetische Behandlungen<\/a><\/li>\n<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>","protected":false},"template":"","langue":[101,103,156],"class_list":["post-5103","equipe","type-equipe","status-publish","hentry","langue-englisch","langue-franzoesisch","langue-tamilisch"],"acf":{"first_name":"Thilani","last_name":"BALACHANDRAN","job":"Zahn\u00e4rztin","short_description":"<p>Zahn\u00e4rztin, der alle Arten von zahn\u00e4rztlicher Routinebehandlung durchf\u00fchrt.<\/p>\n","image":{"ID":11911,"id":11911,"title":"Vignettes Photo Praticien Site Web(18)","filename":"vignettes-photo-praticien-site-web18.png","filesize":1395820,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18.png","link":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/vignettes-photo-praticien-site-web18-2\/","alt":"","author":"8","description":"","caption":"","name":"vignettes-photo-praticien-site-web18-2","status":"inherit","uploaded_to":5103,"date":"2023-09-26 08:04:37","modified":"2023-09-26 08:04:37","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1880,"height":1410,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18-1307x980.png","large-width":1307,"large-height":980,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18-1536x1152.png","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18.png","2048x2048-width":1880,"2048x2048-height":1410,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web18.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"cliniques":[{"ID":4239,"post_author":"14","post_date":"2022-04-20 14:37:48","post_date_gmt":"2022-04-20 12:37:48","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Willkommen bei Adent Genf Charmilles\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cp data-start=\\u00220\\u0022 data-end=\\u0022441\\u0022\\u003eDas Adent Zahnarztzentrum Gen\u00e8ve-Charmilles empf\u00e4ngt Erwachsene und Kinder in einer warmen, beruhigenden Umgebung, die ganz auf Wohlbefinden und Vertrauen ausgerichtet ist. Zentral in Genf gelegen, direkt neben dem Einkaufszentrum Plan\u00e8te-Charmilles, ist das Zahnarztzentrum optimal erreichbar und eingebettet in ein lebendiges Quartier mit angenehmer, famili\u00e4rer Atmosph\u00e4re. So lassen sich Zahnarztbesuche einfach in den Alltag integrieren.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022443\\u0022 data-end=\\u0022985\\u0022\\u003eUnter einem Dach bietet das Adent Zahnarztzentrum Gen\u00e8ve-Charmilles das gesamte Spektrum der modernen Zahnmedizin, einschliesslich Kieferorthop\u00e4die f\u00fcr Kinder, Jugendliche und Erwachsene. Ge\u00f6ffnet von Montag bis Samstag passt sich das Team flexibel an individuelle Bed\u00fcrfnisse an und legt grossen Wert auf qualitativ hochwertige, pers\u00f6nliche und sorgf\u00e4ltig durchgef\u00fchrte Behandlungen. Die engagierten Fachpersonen begleiten jede Patientin und jeden Patienten aufmerksam und professionell, in mehreren Sprachen und stets mit einem offenen Ohr.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u0022987\\u0022 data-end=\\u00221461\\u0022\\u003eEin besonderer Fokus gilt angstbetroffenen Personen, Menschen mit Zahnarztangst sowie Patientinnen und Patienten mit leichten Beeintr\u00e4chtigungen. Dank angepasster Behandlungsmethoden, darunter auch Behandlungen unter Vollnarkose, sorgt das Adent Zahnarztzentrum Gen\u00e8ve-Charmilles f\u00fcr m\u00f6glichst entspannte und komfortable Abl\u00e4ufe. Dieser respektvolle, menschliche Ansatz ist fester Bestandteil der Philosophie des Teams und schafft ein hohes Mass an Sicherheit und Vertrauen.\\u003c\/p\\u003e\\r\\n\\u003cp data-start=\\u00221463\\u0022 data-end=\\u00222222\\u0022 data-is-last-node=\\u0022\\u0022 data-is-only-node=\\u0022\\u0022\\u003eDie Dentalhygienikerinnen spielen eine zentrale Rolle in der Pr\u00e4vention und der langfristigen Mundgesundheit. Mit moderner Zahnreinigung und der Behandlung von Zahnfleischr\u00fcckgang arbeiten sie unter anderem mit der innovativen GBT\u00ae-Technologie von EMS Dental, um Bel\u00e4ge, Zahnstein und Verf\u00e4rbungen schonend zu entfernen. Erg\u00e4nzend werden professionelle Zahnaufhellungen im Zahnarztzentrum oder f\u00fcr zu Hause angeboten, mit individuell angepassten Schienen und unter fachkundiger Kontrolle. Bei zahnmedizinischen Notf\u00e4llen ist zudem eine schnelle, schmerzfreie Betreuung gew\u00e4hrleistet. Verantwortet wird das Zahnarztzentrum von Dr. Ambrogio Feninno, Orthodontist und Chefarzt, dessen Expertise die Qualit\u00e4t und Verl\u00e4sslichkeit der Behandlungen nachhaltig pr\u00e4gt.\\u003c\/p\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/clinique-head {\"name\":\"acf\/clinique-head\",\"data\":{\"members\":[\"1685\"],\"_members\":\"field_622f5635c857c\",\"display_shapes\":\"1\",\"_display_shapes\":\"field_62e25019f6eb2\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/members {\"name\":\"acf\/members\",\"data\":{\"format\":\"slider\",\"_format\":\"field_65aa873152dbb\",\"subtitle\":\"Zu Ihren Diensten\",\"_subtitle\":\"field_65aa873152dc2\",\"title\":\"Adent Zahnarztzentrum in Genf Charmilles\",\"_title\":\"field_65aa873152dc9\",\"description\":\"Ein professionelles und herzliches Team, das bereit ist, Sie zu empfangen.\",\"_description\":\"field_65aa873152dcf\",\"button_text\":\"Alle unsere Praktiker\",\"_button_text\":\"field_65aa873152dd6\",\"button_link\":{\"title\":\"\u00c9quipe\",\"url\":\"https:\/\/adent.ch\/equipe\/\",\"target\":\"\"},\"_button_link\":\"field_65aa873152ddc\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:block {\"ref\":2108} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Zahnnotfall? \",\"_title\":\"field_62149edd2d388\",\"text\":\"Rufen Sie unser Zentrum jetzt an f\u00fcr eine schnelle Behandlung.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Rufen Sie uns an\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"\",\"url\":\"tel:+41 22 338 02 00\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Genf Charmilles","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"genf-charmilles","to_ping":"","pinged":"","post_modified":"2026-04-16 16:20:12","post_modified_gmt":"2026-04-16 14:20:12","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/clinique\/geneve-charmilles\/","menu_order":0,"post_type":"clinique","post_mime_type":"","comment_count":"0","filter":"raw"}],"soins":[{"ID":4138,"post_author":"14","post_date":"2022-01-05 10:58:49","post_date_gmt":"2022-01-05 09:58:49","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mundgesundheit f\u00fcr Ihr Wohlbefinden.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Verschiedene Studien zeigen den Zusammenhang zwischen Entz\u00fcndungen im Mund und allgemeinen Gesundheitsproblemen. Mehr als 600 Bakterienarten tummeln sich in unserem Mund. Einige k\u00f6nnen in den Blutkreislauf gelangen und Sch\u00e4den verursachen: Herz-Kreislauf-Probleme, Blutzucker-Diabetes, Atemwegserkrankungen, Gelenkentz\u00fcndungen, Risiko einer Fr\u00fchgeburt.\\r\\n\\r\\nDie zahn\u00e4rztliche Betreuung ist Teil der medizinischen Grundversorgung. Regelm\u00e4\u00dfige Zahnhygiene und regelm\u00e4\u00dfige Kontrollen sind daher der Schl\u00fcssel zu einer guten Zahngesundheit und einem gesunden L\u00e4cheln. Ein L\u00e4cheln verl\u00e4ngert die Lebenserwartung, reduziert Stress und hat eine positive Wirkung auf den Gespr\u00e4chspartner. Ein gesundes L\u00e4cheln gibt Selbstvertrauen und Wohlbefinden im t\u00e4glichen Leben, im Beruf und im Privatleben.\\r\\n\\r\\nEine regelm\u00e4\u00dfige zahn\u00e4rztliche Kontrolle hilft, Probleme, die die Gesundheit Ihrer Z\u00e4hne und Ihres Zahnfleisches beeintr\u00e4chtigen k\u00f6nnen, fr\u00fchzeitig zu erkennen.\\r\\n\\r\\nWir empfehlen einen j\u00e4hrlichen Besuch, um Erkrankungen zu erkennen, zu \u00fcberwachen und zu behandeln.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Die Adent Zahnarztzentren bieten alle g\u00e4ngigen zahn\u00e4rztlichen Behandlungen f\u00fcr Erwachsene und Kinder unter einem Dach an:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eWurzelbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcllungen von abgebrochenen Z\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eEntfernung von Weisheitsz\u00e4hnen\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eBehandlung von Karies\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eWiederherstellung von Zahnfleischproblemen (Gingivitis, Zahnfleischr\u00fcckgang, Parodontitis, Abszesse usw.).\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\\u0022\\u003e\u00e4sthetische Behandlungen\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nUnsere Dentalhygienikerinnen helfen Ihnen, eine individuelle Vorsorge zu treffen und k\u00f6nnen Ihnen eine Reihe von Reinigungshilfen empfehlen (B\u00fcrstchen, Zahnstocher, Faden usw.).\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Karies\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Karies: Vorbeugen ist besser als heilen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Hauptursachen f\u00fcr Karies sind eine zuckerhaltige Ern\u00e4hrung, unzureichende Mundpflege oder ein schwaches Immunsystem. Wenn Karies nicht behandelt wird, vergr\u00f6ssert sich der Hohlraum und greift auf das Dentin (die Schicht unter dem Zahnschmelz) oder den Zahnnerv. Es kann zu Schmerzen kommen, insbesondere bei Hitze, K\u00e4lte oder S\u00fcssem. Je gr\u00f6sser der Hohlraum wird, desto st\u00e4rker werden die Schmerzen. Das Zahnr\u00f6ntgenbild, das bei den regelm\u00e4ssigen Kontrollen gemacht wird, kann Anzeichen f\u00fcr eine fr\u00fche Karies erkennen.\\r\\n\\r\\n\\u003cstrong\\u003eWie wird Karies behandelt?\\u003c\/strong\\u003e\\r\\n\\r\\nDie Behandlung von Zahnkaries ist eine sehr h\u00e4ufige allgemeine zahn\u00e4rztliche Behandlung. Karies auf der Oberfl\u00e4che des Zahnschmelzes wird mit einfachen F\u00fcllungen behandelt, die die gleiche Farbe wie Ihr Zahn haben. Bei tieferer Karies kann manchmal eine Wurzelbehandlung und eine Zahnkrone erforderlich sein. Eine Zahnextraktion wird nur dann durchgef\u00fchrt, wenn es sich um eine weit fortgeschrittene Karies handelt, die das tiefe Gewebe des Zahns betrifft. Bei Eingriffen bei Erwachsenen und Kindern k\u00f6nnen wir selbstverst\u00e4ndlich eine An\u00e4sthesie durchf\u00fchren.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3757,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Die Wurzelbehandlung  \",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Bei der Wurzelbehandlung wird der infizierte, besch\u00e4digte oder tote Nerv Ihres Zahns entfernt. Das Herz des Zahns enth\u00e4lt die Nerven und Blutgef\u00e4sse. Sie erm\u00f6glichen es dem Zahn, sich zu entwickeln. Bakterien, die durch Karies, Risse oder besch\u00e4digte F\u00fcllungen in Ihren Zahn eindringen, f\u00fchren zur Bildung eines Abszesses. Dieser Abszess wird durch eine Infektion des Zahnmarks verursacht. In diesem Fall muss das Fruchtfleisch entfernt werden.\\r\\n\\r\\nDer Vorteil der Wurzelbehandlung ist, dass Sie Ihren Zahn behalten k\u00f6nnen, anstatt ihn zu extrahieren. Indem Sie Ihren nat\u00fcrlichen Zahn erhalten, verhindern Sie, dass die anderen Z\u00e4hne ihre Ausrichtung verlieren.\\r\\n\\r\\n\\u003cstrong\\u003eWie l\u00e4uft eine Wurzelbehandlung ab?\\u003c\/strong\\u003e\\r\\n\\r\\nIhr Zahnarzt bet\u00e4ubt den Zahn \u00f6rtlich und legt eine isolierende Membran um den Zahn. Er macht eine kleine \u00d6ffnung in den Zahn, um an den Kanal und die besch\u00e4digte Pulpa (das Herz des Zahns) zu gelangen. Mit Hilfe von Pr\u00e4zisionsinstrumenten entfernt er die Pulpa, reinigt und erweitert den Kanal. Der Zahnarzt f\u00fcllt den Kanal und verschliesst den Zahn mit einer provisorischen oder permanenten F\u00fcllung. Der Zahn ist nicht mehr empfindlich gegen\u00fcber Hitze oder K\u00e4lte, beh\u00e4lt aber seine Eigenschaften. Eine Krone und ein Stift sind in der Regel notwendig, um die Lebensdauer des Zahns zu verl\u00e4ngern.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Zahnfleisch\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Pflege des zahnfleisches\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3761,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Wurzelkanalbehandlung\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Wie wird eine Wurzelkanalbehandlung durchgef\u00fchrt?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Der Zahn wird zun\u00e4chst bet\u00e4ubt und mit einem Gummigewebe (Kofferdam) von der Mundh\u00f6hle isoliert.\\r\\nDer Zahn wird mit einem Bohrer ge\u00f6ffnet und die Eing\u00e4nge des Wurzelkanals dargestellt, die L\u00e4nge des Wurzelkanals wird elektrometrisch gemessen, entz\u00fcndetes und totes Gewebe wird vollst\u00e4ndig entfernt, alle Wurzelkan\u00e4le werden mit desinfizierenden L\u00f6sungen desinfiziert und mit dem Kunststoffmaterial gef\u00fcllt.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Wie lange dauert eine Wurzelkanalbehandlung?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Je nach Anzahl der Zahnwurzeln dauert die Behandlung des Wurzelkanals zwischen einer und zwei Stunden. Dank moderner Behandlungsmethoden f\u00fchren wir die geplante Wurzelbehandlung in der Regel in einer einzigen Sitzung durch, nur in sehr komplizierten F\u00e4llen sind mehrere Sitzungen erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wann ist eine Wurzelkanalbehandlung notwendig?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Bei Entz\u00fcndung oder Nekrose des Zahnnervs (kann mit starken Schmerzen einhergehen oder v\u00f6llig schmerzlos verlaufen), bei tieferer Karies, die bereits bis zum Zahnnerv vorgedrungen ist (meist mit einem oder wenigen Schmerzen verbunden) oder nach einem Unfall.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ist es m\u00f6glich, eine Wurzelbehandlung, die vor langer Zeit erfolglos durchgef\u00fchrt wurde, zu wiederholen?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Selbstverst\u00e4ndlich k\u00f6nnen wir die Wurzelkanalbehandlung in den meisten F\u00e4llen wiederholen und durch den Einsatz der heutigen modernen Behandlungsmethoden hohe Behandlungsergebnisse erzielen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape1\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Entfernung von Weisheitsz\u00e4hnen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Die Entfernung von Weisheitsz\u00e4hnen ist Teil der Oralchirurgie und der allgemeinen Zahnheilkunde. Es ist ein chirurgischer Eingriff, der regelm\u00e4ssig von Adent durchgef\u00fchrt und beherrscht wird.\\r\\n\\r\\nDie Weisheitsz\u00e4hne wachsen in der Regel zwischen dem 16. und 24. Lebensjahr. Es kann auch vorkommen, dass sie die Weisheitsz\u00e4hne nicht vorhanden sind. In den meisten F\u00e4llen m\u00fcssen sie entfernt werden, da sie nicht in die richtige Richtung wachsen oder unter dem Zahnfleisch \\u0022eingeschlossen\\u0022 sind.\\r\\n\\r\\nInfektionen des umgebenden Gewebes und der Nachbarz\u00e4hne, schwer zu behandelnde Karies oder Verschiebungen von Nachbarz\u00e4hnen k\u00f6nnen die Folge sein.\\r\\n\\r\\n\\u003cstrong\\u003eW\u00fcrden Sie mir empfehlen, meine Weisheitsz\u00e4hne zu entfernen?\\u003c\/strong\\u003e\\r\\n\\r\\nUm die Lage und die Anzahl der vorhandenen Weisheitsz\u00e4hne zu bestimmen, muss der Zahnarzt ein Panoramar\u00f6ntgenaufnahme Ihres Mundes machen. Der Zahnarzt wird Ihnen dann alle notwendigen Informationen geben, um einen Behandlungsplan f\u00fcr die Entfernung eines oder mehrerer Weisheitsz\u00e4hne zu erstellen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Extraktion\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"entfernung von weisheitszaehnen\",\"url\":\"https:\/\/adent.ch\/de\/info\/entfernung-von-weisheitszaehnen\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3792,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:columns -->\n<div class=\"wp-block-columns\"><!-- wp:column {\"width\":\"100%\"} -->\n<div class=\"wp-block-column\" style=\"flex-basis:100%\"><!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Entz\u00fcndungen und Infektionen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Das St\u00fctzgewebe, das Ihre Z\u00e4hne umgibt, ist wertvoll: Pflegen Sie es!\\r\\n\\r\\n\\u003cstrong\\u003eParodontitis\\u003c\/strong\\u003e (Zahnlockerung) ist eine Krankheit, die das St\u00fctzgewebe betrifft, das Ihren Zahn umgibt und st\u00fctzt. Die Zerst\u00f6rung dieses Gewebes f\u00fchrt zu Beweglichkeit und schliesslich zum Verlust des Zahns. Es gibt verschiedene Stadien der Zahnfleischerkrankung.\\r\\n\\r\\nDas Anfangsstadium ist \\u003cstrong\\u003eGingivitis\\u003c\/strong\\u003e. Sie betrifft nur das Zahnfleisch und ist durch eine Entz\u00fcndung gekennzeichnet: das Zahnfleisch blutet, ist rot und geschwollen.\\r\\n\\r\\nParodontalerkrankungen sind die Hauptursache f\u00fcr Zahnverlust bei Erwachsenen. Etwa 75% der Erwachsenen leiden im Laufe ihres Lebens in unterschiedlichem Ausmass an Zahnfleischproblemen. Die Krankheit kann jedoch auch junge Menschen betreffen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Alles \u00fcber Zahnfleisch\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"pflege des zahnfleisches\",\"url\":\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3686,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape5\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/--><\/div>\n<!-- \/wp:column --><\/div>\n<!-- \/wp:columns -->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Gef\u00e4hrdete Zahnfleisch: schnell handeln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eWas passiert bei einer Zahnfleischentz\u00fcndung?\\u003c\/strong\\u003e\\r\\n\\r\\nWenn die Gingivitis nicht behandelt wird, breitet sich die Entz\u00fcndung aus und greift auf den Knochen \u00fcber. Der Knochen umgibt Ihre Z\u00e4hne und sorgt daf\u00fcr, dass sie im Kiefer bleiben. Wenn nichts unternommen wird, wird der Knochen, die B\u00e4nder und das gesamte Gewebe, das Ihre Z\u00e4hne st\u00fctzt und umgibt, nach und nach zerst\u00f6rt. Diese Zerst\u00f6rung des Gewebes f\u00fchrt zum Verlust eines oder mehrerer Z\u00e4hne. Dies wird als Parodontitis bezeichnet.\\r\\n\\r\\nZahnlockerung (Parodontitis) ist eine Krankheit, die das Zahnhaltegewebe betrifft. Sie muss von Fachgebieten, die Parodontologen genannt werden, behandelt werden. Eine Zusammenarbeit zwischen Patient, Parodontologe und Dentalhygienikerin ist notwendig, um die Heilung zu optimieren. Um Ihnen die bestm\u00f6gliche Versorgung zu garantieren, bringen wir alle diese Berufe in jedem der Adent Zahnarztzentren zusammen.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3764,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"\u00dcbliche Zahnpflege\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e250b73f5a9\",\"shapes\":\"shape8\",\"_shapes\":\"field_62149e038cf63\"},\"mode\":\"edit\"} \/-->","post_title":"\u00dcbliche Zahnpflege","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnaerztliche-routineversorgung","to_ping":"","pinged":"","post_modified":"2025-06-04 17:12:12","post_modified_gmt":"2025-06-04 15:12:12","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-courants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4140,"post_author":"14","post_date":"2022-01-03 13:50:41","post_date_gmt":"2022-01-03 12:50:41","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Das Beste fu\u0308r kleine La\u0308cheln.\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Kinderzahn\u00e4rzte sind in einem kindgerechten psychologischen und p\u00e4dagogischen Ansatz geschult. Ihre Aufgabe ist es, zu beruhigen und mit einem altersgerechten Vokabular zu sprechen, um ein Klima des Vertrauens zu schaffen.\\r\\n\\r\\nWir f\u00fchren alle Arten von Zahnbehandlungen bei Kindern durch.\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eKariesbehandlung\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eabgebrochener Zahn\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eZahnreinigung\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eTipps zum B\u00fcrsten\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003e\\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eKieferorthop\u00e4de\\u003c\/a\\u003e\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":16375,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Kieferorthop\u00e4dische Behandlungen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unsere Zahn\u00e4rzte, die sich auf Kieferorthop\u00e4die spezialisiert haben, bieten kieferorthop\u00e4dische Behandlung f\u00fcr Kinder an. Eine kieferorthop\u00e4dische Behandlung kann in jedem Alter begonnen werden, aber die meisten Eltern w\u00fcnschen sich f\u00fcr ihre Kinder eine fr\u00fchzeitige Behandlung. Je nach Art der erforderlichen Behandlung kann eine erste Phase des Abfangens von Kieferorthop\u00e4den bereits ab dem 4. Lebensjahr stattfinden. In den Adent Zahnarztzentren werden verschiedene kieferorthop\u00e4dische Behandlungen angeboten, die sich an die jeweilige Mundsituation anpassen. Weitere Informationen finden Sie \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\\u0022\\u003eauf unserer Seite \u00fcber Kieferorthop\u00e4de f\u00fcr Kinder\\u003c\/a\\u003e!\\r\\n\\r\\nZus\u00e4tzlich zu diesen zahn\u00e4rztlichen Behandlungen erkl\u00e4ren unsere diplomierten Dentalhygienikerinnen mit p\u00e4dagogischen Methoden, wie Z\u00e4hne und Zahnfleisch gesund erhalten werden k\u00f6nnen. Unsere Fachgebiete f\u00fcr zahn\u00e4rztliche Pr\u00e4vention helfen ihnen, die richtigen Verhaltensweisen zu erlernen, sobald sie die ersten Z\u00e4hne bekommen.\\r\\n\\r\\nHaben Sie Fragen zur Zahnhygiene bei Babys oder Jugendlichen? \\u003ca href=\\u0022https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\\u0022\\u003eBesuchen Sie unsere Seite zu diesen Themen\\u003c\/a\\u003e!\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin Vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Jeder Zahn muss t\u00e4glich gereinigt werden, egal wie klein er ist. Nach der Nahrungsaufnahme bildet sich ein Biofilm auf der Oberfl\u00e4che des Zahnschmelzes. Dieser Biofilm entwickelt sich weiter, wenn er nicht regelm\u00e4\u00dfig gereinigt wird. Dies f\u00fchrt zu wei\u00dfen, weichen Ablagerungen auf der Oberfl\u00e4che der Z\u00e4hne, die als Plaque bezeichnet werden. Zahnbelag besteht unter anderem aus Bakterien. Bakterien k\u00f6nnen Karies verursachen, wenn die Reinigung nicht regelm\u00e4ssig erfolgt. Plaque kann sich auch zu Zahnstein entwickeln, einem harten, wei\u00dfen Belag, der mit der Zahnb\u00fcrste nicht entfernt werden kann.\\r\\n\\r\\nAuch wenn dies selten vorkommt, kann sich ein Schaden an einem Milchzahn auf einen Erwachsenenzahn auswirken. Die Keime der erwachsenen Z\u00e4hne, die sich unter dem Zahnfleisch bilden, sind empfindlich. Sie k\u00f6nnen besch\u00e4digt werden, wenn ein Milchzahn infiziert wird.\\r\\n\\r\\nHeutzutage gibt es eine breite Palette von Hilfsmitteln f\u00fcr die Zahnreinigung bei Kindern. Sie k\u00f6nnen leicht elektrische Zahnb\u00fcrsten, Zahnseide in Tierform, bunte Kinderzahnb\u00fcrsten usw. erwerben. Diese Hilfsmittel helfen Ihnen dabei, die Mundhygiene Ihres Kindes zu verbessern. Lassen Sie sich von \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eunseren Dentalhygienikerinnen\\u003c\/a\\u003e beraten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Zahnreinigung und Zahnhygiene\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"Zahnarztangst\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Mein Kind hat Angst vor dem Zahnarzt, was kann ich tun?\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"F\u00fcr Kinder mit Phobie oder Angst vor dem Zahnarzt haben wir L\u00f6sungen! Unsere Zahn\u00e4rzte bieten Lachgas- und Hypnosebehandlungen an, die auch bei Kindern einfach und sicher durchzuf\u00fchren sind. Weitere Informationen finden Sie hier.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"none\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns\":1,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Wie kann ich Zahnprobleme bei meinem Kind vermeiden?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":16307,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Geben Sie gute Gewohnheiten weiter!\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Das Z\u00e4hneputzen wird 3x\/Tag empfohlen: Putzen Sie die Z\u00e4hne nach jeder Mahlzeit und vermeiden Sie bei Ihren Kindern das st\u00e4ndige Naschen von S\u00fcssigkeiten, da dies Karies und Schmerzen verursachen kann.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":16347,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"B\u00fcrsten ab den ersten Z\u00e4hnen.\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Dies kann eine schwierige Aufgabe sein, aber alle Z\u00e4hne, auch wenn sie noch so klein sind, m\u00fcssen t\u00e4glich gereinigt werden. Tragen Sie ab dem ersten Zahn bis zum Alter von ca. 3 Jahren Zahnpasta in der Gr\u00f6sse eines Reiskorns auf, danach in der Gr\u00f6sse einer Erbse.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":16350,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"S\u00fcssigkeiten ja, mit Sympadent\u00ae!\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Bevorzugen Sie \\u003ca href=\\u0022https:\/\/zahnfreundlich.ch\/lassociation-sympadent-sengage-pour-des-dents-denfant-saines\/?lang=fr\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eSympadent\u00ae Bonbons\\u003c\/a\\u003e: Sie wurden getestet und f\u00fcr gut befunden. Diese S\u00fcssigkeiten schonen die Z\u00e4hne von Kindern und Erwachsenen. Sie k\u00f6nnen es in verschiedenen Gesch\u00e4ften in der Schweiz kaufen. Achten Sie auf das Zahnlogo unter dem Regenschirm.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":16562,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Alles miteinander teilen? Ja, aber...\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Vermeiden Sie es, den L\u00f6ffel oder andere Gegenst\u00e4nde in den Mund zu nehmen, bevor Sie sie Ihrem Baby geben: Karies verursachende Bakterien werden \u00fcbertragen.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs_4_image\":16311,\"_blocs_4_image\":\"field_623c222ba627a\",\"blocs_4_title\":\"Eine zus\u00e4tzliche Hilfe f\u00fcr eine optimale Reinigung.\",\"_blocs_4_title\":\"field_623c22c4a627b\",\"blocs_4_description\":\"Elektrische Zahnb\u00fcrsten sind eine gute Hilfe f\u00fcr Ihr Kind. Dies erleichtert das B\u00fcrsten und ermutigt sie. Unsere Dentalhygienikerinnen beraten Sie gerne.\",\"_blocs_4_description\":\"field_623c22cba627c\",\"blocs_4_button_type\":\"none\",\"_blocs_4_button_type\":\"field_623c34377e92d\",\"blocs_5_image\":16353,\"_blocs_5_image\":\"field_623c222ba627a\",\"blocs_5_title\":\"Eine fluoridierte Zahnpasta, die f\u00fcr sein Alter geeignet ist.\",\"_blocs_5_title\":\"field_623c22c4a627b\",\"blocs_5_description\":\"Fluor sch\u00fctzt die Z\u00e4hne vor Karies. Sie finden leicht Zahnpasta f\u00fcr Kinder unter 6 Jahren, f\u00fcr Kinder von 6 bis 12 Jahren und f\u00fcr Erwachsene. Wechseln Sie den Geschmack der Zahnpasta regelm\u00e4ssig: Kinder m\u00f6gen Abwechslung.\",\"_blocs_5_description\":\"field_623c22cba627c\",\"blocs_5_button_type\":\"none\",\"_blocs_5_button_type\":\"field_623c34377e92d\",\"blocs\":6,\"_blocs\":\"field_623c21f0a6279\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Zahnpflege f\u00fcr Kinder\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie unsere Zahn\u00e4rzte, die auf die Behandlung von Kindern spezialisiert sind.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Einen spezialisierten Zahnarzt finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Team\",\"url\":\"https:\/\/adent.ch\/de\/team\/?care_id=4140\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Zahnpflege f\u00fcr Kinder","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbehandlung-fuer-kinder","to_ping":"","pinged":"","post_modified":"2026-01-19 15:07:44","post_modified_gmt":"2026-01-19 14:07:44","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/soins-dentaires-pour-les-enfants\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":13554,"post_author":"13","post_date":"2024-05-06 16:49:02","post_date_gmt":"2024-05-06 14:49:02","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnimplantate: Komfort \\u0026 A\u0308sthetik\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Der Ersatz eines fehlenden Zahns durch ein Zahnimplantat bietet erhebliche Vorteile in Bezug auf Gesundheit, Komfort und \u00c4sthetik. In unseren Adent Zahnarztzentren profitieren Sie von der Expertise unserer Zahn\u00e4rzte f\u00fcr Implantologie in Verbindung mit der Qualit\u00e4t der Schweizer Zahnimplantate der Marke \\u003ca href=\\u0022https:\/\/www.straumann.com\/ch\/fr\/professionnels-dentaires.html\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eStraumann\u00ae\\u003c\/a\\u003e, mit denen wir exklusiv zusammenarbeiten.\\r\\n\\r\\nWir haben Dentallabors in unseren R\u00e4umlichkeiten, was eine privilegierte Beziehung zwischen Patient, Zahnarzt und Zahntechniker erm\u00f6glicht und die Herstellung von Zahnimplantaten und Zahnprothesen von \u00e4sthetischer und exzellenter \\u0022Swiss Made\\u0022 Qualit\u00e4t erlaubt.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Formulaire \u2013 Prise de rendez-vous\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"\\u003ch4\\u003eAuf dem neuesten Stand der Technik\\u003c\/h4\\u003e\\r\\nDie Adent Gruppe verf\u00fcgt in ihren Zentren \u00fcber hochmoderne \\u003ca href=\\u0022https:\/\/adent.ch\/de\/info\/die-technologien-der-adent-gruppe\/\\u0022\\u003eIntraoralscanner\\u003c\/a\\u003e und eine Bearbeitungsmaschine f\u00fcr das interne Labor. Die intraoralen Scanner und die Bearbeitungsmaschine erg\u00e4nzen sich und revolutionieren die Herstellungskette von Zahnersatz wie z.B. Zahnprothesen, Zahnkronen und Inlays.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"bouton\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns_1_button_text\":\"Weitere Informationen\",\"_columns_1_button_text\":\"field_6227212165677\",\"columns_1_button_link\":{\"title\":\"Les technologies du groupe Adent\",\"url\":\"https:\/\/adent.ch\/info\/les-technologies-du-groupe-adent\/\",\"target\":\"\"},\"_columns_1_button_link\":\"field_6227212f65678\",\"columns_1_link_is_blank\":\"0\",\"_columns_1_link_is_blank\":\"field_6227213d65679\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Implantate und Restauration\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Was ist ein Zahnimplantat?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Ein Zahnimplantat ist eine k\u00fcnstliche Wurzel - eine Art Schraube aus Titan, Zirkoniumdioxid oder Polymer -, die in den Knochen Ihres Kiefers eingesetzt wird. Das Implantat (die Schraube) ersetzt die Wurzel des fehlenden oder nicht vorhandenen Zahns. Das Implantat dient als Halterung f\u00fcr die Befestigung einer Zahnkrone oder einer Zahnprothese. Bei Tr\u00e4gern von Vollprothesen stabilisiert und verbessert das Implantat den Lebenskomfort erheblich. Das Zahnimplantat bietet einen optimalen Halt f\u00fcr eine untere Prothese und entfernt Plaque vom Gaumen f\u00fcr eine obere Prothese, wodurch der Geschmack wiederentdeckt wird.\\r\\n\\r\\nEin und dasselbe Zahnimplantat kann im Laufe des Lebens auch seine Funktion \u00e4ndern: zun\u00e4chst kann es als Tr\u00e4ger f\u00fcr eine Zahnkrone dienen, sp\u00e4ter kann es das Geschiebe f\u00fcr eine bewegliche Prothese sein.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"F\u00fcr wen ist ein Zahnimplantat geeignet?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Ein Zahnimplantat ist f\u00fcr jeden geeignet, dem Z\u00e4hne fehlen oder nicht vorhanden sind und der gen\u00fcgend Knochen im Kiefer hat, um das Implantat zu tragen. Eine gute Qualit\u00e4t und Quantit\u00e4t des Kieferknochens ist eine der wichtigsten Voraussetzungen f\u00fcr das Einsetzen eines Zahnimplantats. Eine gute allgemeine Gesundheit ist ebenfalls wichtig, und zwar viel wichtiger als das Alter. Das Einsetzen von Zahnimplantaten kann bei bestimmten chronischen Krankheiten kontraindiziert sein. F\u00fcr weitere Informationen wenden Sie sich bitte an \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=13554\\u0022\\u003eunsere Zahn\u00e4rzte f\u00fcr Implantologie.\\u003c\/a\\u003e\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Wie lange dauert die Behandlung?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Die Gesamtdauer der Behandlung f\u00fcr das Einsetzen eines Zahnimplantats h\u00e4ngt von vielen Faktoren ab. Die folgenden Informationen werden daher nur zu Informationszwecken zur Verf\u00fcgung gestellt.\\r\\n\\r\\nIn der Praxis dauert das Einsetzen eines Implantats und die Einheilung durchschnittlich zwischen 3 und 6 Monaten. Wenn die Einheilung des Implantats abgeschlossen ist, kann mit der Herstellung der Zahnkrone oder der endg\u00fcltigen Prothese (Gebiss) begonnen werden. Die Wartezeit h\u00e4ngt von der Komplexit\u00e4t des jeweiligen Falles ab.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Wie hoch ist der Preis f\u00fcr ein Zahnimplantat?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Der Preis f\u00fcr ein Zahnimplantat h\u00e4ngt von vielen Faktoren ab. Um einen Kostenvoranschlag zu erstellen, muss sich der Zahnarzt f\u00fcr Implantologie mit Ihnen treffen und Ihren aktuellen Mundzustand kennenlernen, um die genauen Kosten f\u00fcr das Einsetzen des Zahnimplantats zu bestimmen. Auch die zahn\u00e4rztlichen Behandlungen, die vor dem Einsetzen durchgef\u00fchrt werden m\u00fcssen, sind zu ber\u00fccksichtigen (z.B. die Behandlung von Karies oder Zahnfleischentz\u00fcndungen). Um den Preis festzulegen, ist es daher wichtig, dass der Zahnarzt eine vorl\u00e4ufige Munduntersuchung durchf\u00fchrt, um die Zahnpflege und die Durchf\u00fchrbarkeit des Einsetzens zu beurteilen und Ihnen einen detaillierten Kostenvoranschlag zu unterbreiten. Es ist auch wichtig, dass Sie mit Ihrem Zahnarzt sprechen und ihm alle Fragen \u00fcber die bevorstehende zahn\u00e4rztliche Behandlung stellen k\u00f6nnen.\\r\\n\\r\\nWenn Sie weitere Informationen w\u00fcnschen, vereinbaren Sie einen Termin mit einem Spezialisten in einem \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnkliniken\/\\u0022\\u003eZahnarztzentrum in Ihrer N\u00e4he\\u003c\/a\\u003e.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"Welche Techniken stehen zur Verf\u00fcgung, um einen gebrochenen oder besch\u00e4digten Zahn zu reparieren?\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":3741,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"1. Die Krone\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Ersetzen Sie Ihren Zahn auf \u00e4sthetische, komfortable und nat\u00fcrliche Weise.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":3745,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"2. Die Br\u00fccke\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Stellen Sie Ihre Mundfunktionen und ein harmonisches L\u00e4cheln wieder her.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":3748,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"3. Die Facetten\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Ein ausgewogenes L\u00e4cheln mit Veneers.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":3751,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"4. Die Verbundstoffe\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Minimale Invasion f\u00fcr maximale Wirkung.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs_4_image\":3754,\"_blocs_4_image\":\"field_623c222ba627a\",\"blocs_4_title\":\"5. Onlays \\u0026amp; Inlays\",\"_blocs_4_title\":\"field_623c22c4a627b\",\"blocs_4_description\":\"Eine Alternative f\u00fcr grosse Bauvorhaben.\",\"_blocs_4_description\":\"field_623c22cba627c\",\"blocs_4_button_type\":\"none\",\"_blocs_4_button_type\":\"field_623c34377e92d\",\"blocs\":5,\"_blocs\":\"field_623c21f0a6279\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25104d76c2\",\"shapes\":\"shape1\",\"_shapes\":\"field_623c20cd3ad28\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/one-column {\"name\":\"acf\/one-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd0735637b\",\"title\":\"Die verf\u00fcgbaren Techniken im Detail\",\"_title\":\"field_621cdc025d304\",\"content\":\"\\u003ch4\\u003e1. Die Krone - Ersetzen Sie Ihren Zahn auf \u00e4sthetische, komfortable und nat\u00fcrliche Weise.\\u003c\/h4\\u003e\\r\\nDie Krone ist ein Zahnersatz aus Keramik, der den sichtbaren Teil des Zahns ersetzt, wenn dieser durch Karies oder eine Fraktur stark besch\u00e4digt wurde. Sie sch\u00fctzt den Zahn vor Abnutzung und erm\u00f6glicht die Abdeckung eines Implantats, das einen fehlenden Zahn ersetzt. Diese Methode mit Kronen vermeidet die vollst\u00e4ndige Extraktion des Zahns und verbessert den \u00e4sthetischen Wert und Komfort Ihres L\u00e4chelns. Die Herstellung der Zahnkronen wird von den Handwerkern unseres Dentallabors durchgef\u00fchrt, um die Qualit\u00e4t von Adent zu gew\u00e4hrleisten. Diese Arbeiten sind massgeschneidert und werden in Zusammenarbeit mit dem Patienten, dem Zahnarzt und dem Zahntechniker durchgef\u00fchrt.\\r\\n\\u003ch4\\u003e2. Die Br\u00fccke - Stellen Sie Ihre Mundfunktionen und ein harmonisches L\u00e4cheln wieder her.\\u003c\/h4\\u003e\\r\\nDie Br\u00fccke, auch bekannt als Bridge, ist ein Zahnersatz, der einen oder mehrere fehlende Z\u00e4hne ersetzt. Sie bietet einen \u00e4sthetischen und angenehmen Mundraum. Die Pfeiler der Zahnbr\u00fccke befinden sich in der Regel auf beiden Seiten des zahnlosen Kiefers und werden in Form von Implantaten oder gefr\u00e4sten Z\u00e4hnen eingesetzt. Auf diesen Pfeilern ruht die Br\u00fccke. Die Br\u00fccke ist fest und kann nicht entfernt werden. Eine gute Mundgesundheit ist f\u00fcr die Langlebigkeit dieses Zahnersatzes von entscheidender Bedeutung. Eine regelm\u00e4ssige Kontrolle und Zahnreinigung wird von Fachleuten verlangt.\\r\\n\\u003ch4\\u003e3. Veneers - Ein ausgewogenes L\u00e4cheln mit Veneers\\u003c\/h4\\u003e\\r\\nErleben Sie ein strahlenderes, attraktiveres und dauerhaft weisses L\u00e4cheln mit Veneers. Diese Technik ist g\u00fcltig f\u00fcr :\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eKorrektur der Zahnfarbe (wenn das Bleichmittel nicht ausreicht)\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eAbgenutzte, abgebrochene oder zu kurze Z\u00e4hne\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eLeichte Zahnfehlstellungen (kleine \u00dcberlappungen oder L\u00fccken)\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDas Veneer ist eine kleine, sehr d\u00fcnne, aber sehr starke Keramikschale, die auf der Vorderseite der Z\u00e4hne befestigt wird. Sie hat eine vordefinierte Farbe, die zu Ihrem L\u00e4cheln passt, und deckt den nat\u00fcrlichen Zahn ab. Sie werden auf die sichtbaren Vorderz\u00e4hne gesetzt, um deren Kontur, Farbe und Gr\u00f6sse zu korrigieren, um das Aussehen des L\u00e4chelns zu verbessern. Sie werden nach Mass angefertigt, um Ihnen ein optimales Ergebnis, einen nat\u00fcrlichen Effekt und vor allem eine lange Lebensdauer zu bieten.\\r\\n\\u003ch4\\u003e4. Kompositen - Minimale Invasion f\u00fcr maximale Wirkung\\u003c\/h4\\u003e\\r\\nKompositmaterialien sind Materialien in Form von Pasten oder Fl\u00fcssigkeiten, die unsichtbare Restaurationen von abgebrochenen oder abgenutzten Z\u00e4hnen durch eine Vielzahl von Farbt\u00f6nen erm\u00f6glichen.\\r\\n\\r\\nIn der \u00e4sthetischen Zahnheilkunde werden h\u00e4ufig Kompositf\u00fcllungen verwendet, insbesondere f\u00fcr kleine bis mittelgrosse Restaurationen. Neben dem \u00e4sthetischen Hauptvorteil erm\u00f6glichen Kompositf\u00fcllungen eine F\u00fcllung, ohne dass viel gesunde Zahnsubstanz entfernt werden muss.\\r\\n\\u003ch4\\u003e5. Onlays \\u0026amp; Inlays - Eine Alternative f\u00fcr gro\u00dfe Arbeiten\\u003c\/h4\\u003e\\r\\nOnlays und Inlays sind eine gute Alternative zu grossvolumigen Kompositf\u00fcllungen. Inlays und Onlays sind prothetische Teile, die auf den Zahn aufgesetzt werden, um den Wiederaufbau eines Zahns zu unterst\u00fctzen, der unter Mundhygieneproblemen, Karies oder Rissen gelitten hat. Im Gegensatz zu Kronen, die eine Wurzelbehandlung erfordern, k\u00f6nnen Onlays und Inlays auf einem lebenden Zahn angebracht werden. Inlays und Onlays sind besonders beliebt, weil sie sehr \u00e4sthetisch sind und den besch\u00e4digten Teil des Zahns identisch wiederherstellen k\u00f6nnen.\\r\\n\\r\\nBevor die Inlays und Onlays eingesetzt werden, beschneidet der Zahnarzt den zu rekonstruierenden Zahn und nimmt dann einen Zahnabdruck. Um Ihnen die bestm\u00f6gliche Qualit\u00e4t zu garantieren, werden die Restaurationen in unseren Adent 3D-Laboren und in unseren Partnerlaboren aus verschiedenen Materialien wie Keramik oder einer Kombination aus Komposit und Porzellan individuell angefertigt.\\r\\n\\r\\n\\u003ca href=\\u0022https:\/\/adent.ch\/de\/termin-vereinbaren\/\\u0022\\u003eTermin vereinbaren\\u003c\/a\\u003e\",\"_content\":\"field_621cdc544043f\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Verf\u00fcgbare Techniken\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Die Krone: Wie viel kostet eine Krone?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Kosten f\u00fcr eine Zahnkrone h\u00e4ngen von der Gr\u00f6sse und dem Ort ab, an dem sie angebracht wird. Wenden Sie sich an Ihren Zahnarzt, um eine gr\u00fcndliche Untersuchung durchzuf\u00fchren und einen genauen Kostenvoranschlag zu erstellen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Die Br\u00fccke: An wen richtet sich die Br\u00fccke?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Jeder, der einen oder mehrere Z\u00e4hne verloren hat, kann eine Br\u00fccke verwenden, um die L\u00fccke zu schliessen, sofern der Zahnarzt keine Kontraindikationen angibt.\\r\\nDie Zahnbr\u00fccke repariert besch\u00e4digte Z\u00e4hne oder ersetzt fehlende Z\u00e4hne.\\r\\nDer Zahnersatz verhindert die Verschiebung, die Lockerung und den m\u00f6glichen Verlust der anderen Z\u00e4hne. Das Kauen wird erleichtert, wodurch eine optimale Verdauung gef\u00f6rdert wird. Das L\u00e4cheln ist harmonisiert.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Le pont: Wie lange dauert die Behandlung?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Die Gesamtdauer der Behandlung h\u00e4ngt von vielen Faktoren ab, die Ihnen nur Ihr Zahnarzt mitteilen kann, je nach Ihrer Mundsituation (Fehlen eines oder mehrerer Z\u00e4hne, Einsetzen von Zahnimplantaten usw.). F\u00fcr weitere Informationen wenden Sie sich bitte an einen unserer Zahn\u00e4rzte.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Die Br\u00fccke: Wie viel kostet eine Br\u00fccke?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Der Preis kann erst nach einer gr\u00fcndlichen Untersuchung durch einen unserer qualifizierten Zahn\u00e4rzte festgelegt werden. Er\/Sie wird Ihnen einen detaillierten Kostenvoranschlag gem\u00e4ss dem besprochenen Behandlungsplan vorlegen.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions_4_title\":\"Veneers: Wie viel kostet ein Veneer?\",\"_accordions_4_title\":\"field_626fdd3ff47be\",\"accordions_4_content\":\"Der Preis kann erst nach einer eingehenden Pr\u00fcfung durch einen unserer qualifizierten Zahn\u00e4rzte festgelegt werden. Er\/Sie wird einen detaillierten Kostenvoranschlag gem\u00e4ss dem besprochenen Behandlungsplan vorlegen. Bitte wenden Sie sich an einen unserer Zahn\u00e4rzte, um die verschiedenen M\u00f6glichkeiten zu besprechen.\",\"_accordions_4_content\":\"field_626fdd46f47bf\",\"accordions_5_title\":\"Verbundwerkstoffe: Wie werden Verbundwerkstoffe verwendet?\",\"_accordions_5_title\":\"field_626fdd3ff47be\",\"accordions_5_content\":\"Das Komposit und das Adh\u00e4siv sind feuchtigkeitsempfindlich, so dass der Zahnarzt besondere Massnahmen ergreifen muss, um den Eingriffsbereich trocken zu halten. Manchmal ist eine \u00f6rtliche Bet\u00e4ubung erforderlich, um Schmerzen zu vermeiden. Der Zahnarzt tr\u00e4gt dann eine S\u00e4ure auf, die die Oberfl\u00e4che des Zahns aufraut. Anschliessend wird ein fl\u00fcssiges oder pastenf\u00f6rmiges Komposit aufgetragen, das mit Hilfe einer Polymerisationslampe ausgeh\u00e4rtet wird. Das Modellieren und Polieren des Zahns ist die letzte Phase.\",\"_accordions_5_content\":\"field_626fdd46f47bf\",\"accordions_6_title\":\"Kompositf\u00fcllungen: Wie viel kostet eine Kompositf\u00fcllung?\",\"_accordions_6_title\":\"field_626fdd3ff47be\",\"accordions_6_content\":\"Der Preis h\u00e4ngt von der Gr\u00f6sse und der Oberfl\u00e4che des aufzutragenden Komposits ab. Die Kosten werden auch dadurch beeinflusst, ob R\u00f6ntgenaufnahmen gemacht werden m\u00fcssen oder ob eine An\u00e4sthesie erforderlich ist. Eine gr\u00fcndliche Untersuchung durch einen Zahnarzt ist notwendig, um einen genauen Kostenvoranschlag zu erstellen.\",\"_accordions_6_content\":\"field_626fdd46f47bf\",\"accordions_7_title\":\"Onlays \\u0026amp; Inlays: Wie viel kostet ein Onlay oder ein Inlay?\",\"_accordions_7_title\":\"field_626fdd3ff47be\",\"accordions_7_content\":\"Der Preis h\u00e4ngt von der Gr\u00f6sse des zu behandelnden Gebiets ab. Er kann daher erst nach einer Kontrolle durch Ihren Zahnarzt festgelegt werden. Bitte vereinbaren Sie einen Termin mit einem unserer Zahn\u00e4rzte f\u00fcr eine Informationsberatung.\",\"_accordions_7_content\":\"field_626fdd46f47bf\",\"accordions\":8,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape1\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Implantate und Restauration\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Contactez la clinique dentaire Adent la plus proche de chez vous.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"Cliniques\",\"url\":\"https:\/\/adent.ch\/cliniques\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e250b73f5a9\",\"shapes\":\"shape6\",\"_shapes\":\"field_62149e038cf63\"},\"mode\":\"edit\"} \/-->","post_title":"Implantat und Restauration","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"implantat-und-restauration","to_ping":"","pinged":"","post_modified":"2026-05-06 11:35:38","post_modified_gmt":"2026-05-06 09:35:38","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/implantat-und-restauration\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"},{"ID":4136,"post_author":"14","post_date":"2022-01-06 10:59:42","post_date_gmt":"2022-01-06 09:59:42","post_content":"<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zeigen Sie Ihr strahlendes L\u00e4cheln\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Unser Mund spielt daher eine wichtige Rolle bei der Kommunikation und Gesundheit.\\r\\n\\r\\nRegelm\u00e4ssige Zahnpflege ist der Schl\u00fcssel zu einer guten Mundgesundheit und tr\u00e4gt wesentlich zur St\u00e4rkung des Selbstbewusstseins bei. Die regelm\u00e4ssige Entfernung von Zahnbelag auf Ihren Z\u00e4hnen verhindert das Wachstum von Bakterien, die Zahnfleischentz\u00fcndungen (Gingivitis) verursachen. Ausserdem h\u00e4lt es Ihre Z\u00e4hne glatt, weiss und gl\u00e4nzend.\\r\\n\\r\\nMit einigen guten Gewohnheiten in Ihrem Alltag und regelm\u00e4ssigen Besuchen bei Ihrem Hygieniker oder Zahnarzt k\u00f6nnen Sie sich ein gesundes, strahlendes L\u00e4cheln und sch\u00f6ne Z\u00e4hne bewahren. Unsere Dentalhygienikerinnen teilen mit Ihnen Gesundheitstipps, um Ihre Z\u00e4hne weiss und Ihr Zahnfleisch gesund zu halten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Zahnreinigung und Zahnhygiene\",\"url\":\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"text\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_text\":\"Wenn Sie die Farbe Ihres Zahnschmelzes aufhellen und weissere Z\u00e4hne haben m\u00f6chten, bieten wir Ihnen eine professionelle Zahnaufhellung an! Wir bieten effektive, einfache, professionelle und nicht-invasive L\u00f6sungen f\u00fcr das Bleichen Ihrer Z\u00e4hne.\\r\\n\\r\\nHaben Sie Fragen zu unseren verschiedenen Zahnaufhellungstechniken? Fragen Sie Ihre \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4134\\u0022\\u003eDentalhygienikerin\\u003c\/a\\u003e oder Ihren \\u003ca href=\\u0022https:\/\/adent.ch\/de\/team\/?care_id=4138\\u0022\\u003eZahnarzt\\u003c\/a\\u003e um Rat!\\r\\n\\r\\nEntdecken Sie unten die verschiedenen Zahnaufhellungstechniken und andere \u00e4sthetische Behandlungen, die wir in den Adent Zahnarztzentren anbieten.\",\"_columns_1_text\":\"field_6226294b8a3ea\",\"columns_1_link_type\":\"none\",\"_columns_1_link_type\":\"field_623833b107a07\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung im Zentrum\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eProfessionelles Zahnbleaching: Ein weisseres L\u00e4cheln \u2013 ganz nach Ihren Bed\u00fcrfnissen\\u003c\/strong\\u003e\\r\\n\\r\\nVerleihen Sie Ihrem L\u00e4cheln sofort neue Strahlkraft mit unseren professionellen Zahnbleaching-Behandlungen im Zahnarztzentrum der Groupe Adent. Moderne Technologien, schonende Verfahren und eine individuelle Beratung sorgen f\u00fcr sichtbare und sichere Resultate.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eBlancOne\u00ae: Express-Zahnbleaching f\u00fcr besondere Anl\u00e4sse\\u003c\/strong\\u003e\\r\\n\\r\\nDas BlancOne\u00ae Zahnbleaching ist ideal f\u00fcr einmalige Ereignisse wie eine Hochzeit, ein Fotoshooting oder einen wichtigen Abend. Die Behandlung wird direkt im Zahnarztzentrum von einer speziell ausgebildeten Dentalhygienikerin durchgef\u00fchrt und liefert bereits nach kurzer Zeit sichtbare Ergebnisse (10 bis 30 Minuten, je nach Methode).\\r\\n\\r\\n\ud83d\udc49 \\u003cstrong\\u003eHinweis:\\u003c\/strong\\u003e Die Wirkung ist tempor\u00e4r.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\\u003cstrong\\u003eFl\u00e4sh: Sanftes und nachhaltiges Zahnbleaching (CHF 500.\u2013)\\u003c\/strong\\u003e\\r\\n\\r\\nDas Fl\u00e4sh Zahnbleaching richtet sich an Patientinnen und Patienten, die ein nat\u00fcrliches und langfristiges Ergebnis w\u00fcnschen. Die Behandlung erfolgt \u00fcber mehrere Sitzungen hinweg und erm\u00f6glicht eine kontrollierte, schrittweise Aufhellung der Zahnfarbe.\\r\\n\\r\\n\ud83d\udd0e \\u003cstrong\\u003eWichtig:\\u003c\/strong\\u003e Eine gesunde Dentition ohne Zahnstein oder pathologische Befunde ist Voraussetzung f\u00fcr jedes Zahnbleaching. Eine zahnmedizinische Kontrolle sowie eine Zahnreinigung werden mindestens 3 Monate vor der Behandlung empfohlen.\\r\\n\\r\\n\\u0026nbsp;\\r\\n\\r\\n\ud83d\udccd \\u003cstrong\\u003eUnsere Teams in den Zahnarztzentren beraten Sie gerne\\u003c\/strong\\u003e, um das f\u00fcr Sie passende Zahnbleaching auszuw\u00e4hlen.\\r\\n\\r\\nBitte beachten Sie: Nicht alle Behandlungen sind in allen Zahnarztzentren verf\u00fcgbar. Informieren Sie sich direkt beim Zahnarztzentrum, in dem Sie Ihre Behandlung durchf\u00fchren m\u00f6chten.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Termin vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":7110,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung im Zentrum\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellung im Zentrum: Wie funktioniert das?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Zahnaufhellung wird von unseren ausgebildeten Dentalhygienikerinnen in unserem Zentrum durchgef\u00fchrt. Das Bleichen der Z\u00e4hne wird in einer einzigen Sitzung mit professionellen, bew\u00e4hrten und bekannten Produkten durchgef\u00fchrt. Sie enthalten 16% Carbamidperoxid.\\r\\n\\r\\nIn einem unserer Zentren wird das Bleichgel f\u00fcr 10 bis 30 Minuten auf Ihre Z\u00e4hne aufgetragen. Eine Biophotonenlampe mit einem Bleichbogen (ultraviolettes Licht) wird auf Ihr Gebiss gerichtet und aktiviert das Bleichmittel. Um Empfindlichkeiten zu vermeiden, wird Vitamin D auf das Zahnfleisch aufgetragen.\\r\\n\\r\\nEine Sitzung mit BlancOne\u00ae CLICK dauert 10 Minuten. Die Dentalhygienikerin wendet diese Behandlung direkt nach der Zahnreinigung an. Sie k\u00f6nnen mit dem BlancOne\u00ae CLICK Zahnbleichmittel ein bis zwei Nuancen gewinnen.\\r\\n\\r\\nWir bieten auch BlancOne\u00ae TOUCH Zahnaufhellung an. Die Dauer betr\u00e4gt 30 Minuten, was drei Bleichzyklen entspricht. Mit dieser Behandlung wird Ihr Zahnschmelz um vier bis f\u00fcnf Farbt\u00f6ne aufgehellt. Sie werden mit strahlend weissen Z\u00e4hnen nach Hause gehen!\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"Was sind die Vorteile des professionellen Zahnbleachings BlancOne\u00ae?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"BlancOne\u00ae Zahnaufhellung ist kurz, effektiv und entspricht den Bed\u00fcrfnissen unserer Patienten durch seine Vorteile:\\r\\n\\u003cul\\u003e\\r\\n \\t\\u003cli\\u003eF\u00fcr weissere Z\u00e4hne ist nur eine Sitzung erforderlich.\\u003c\/li\\u003e\\r\\n \\t\\u003cli\\u003eDie Dauer des Eingriffs ist kurz (ab 10' Minuten Anwendung). Die Zahnaufhellung wird direkt nach Ihrer Zahnreinigung angewendet.\\u003c\/li\\u003e\\r\\n\\u003c\/ul\\u003e\\r\\nDie Empfindlichkeit auf den Z\u00e4hnen ist geringer (Tests mit unseren Patienten). Das Ergebnis ist nat\u00fcrlich und dauerhaft.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Was muss ich beachten, bevor ich eine professionelle Zahnaufhellung mit BlancOne\u00ae beginne?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Eine gute Mundhygiene ist Voraussetzung f\u00fcr eine Zahnaufhellung. Vor der Zahnaufhellung ist ein Kontrolltermin beim Zahnarzt erforderlich. Bevor Sie mit der Behandlung beginnen, m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (wie z.B. Zahnlockerung) ausgeschlossen sein.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Ich bin an einer professionellen Zahnaufhellung mit BlancOne\u00ae interessiert. An wen kann ich mich wenden?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Kontaktieren Sie das Zentrum \\u003ca href=\\u0022https:\/\/adent.ch\/de\/zahnkliniken\/\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003eAdent Zahnarztzentrum in Ihrer N\u00e4he\\u003c\/a\\u003e. Unsere Dentalhygienikerinnen sind von Montag bis Samstag, von morgens bis abends in allen unseren Zahnarztzentren f\u00fcr Sie da.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape8\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnaufhellung mit Schienen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"\\u003cstrong\\u003eEin gr\u00fcndliches und lang anhaltendes Ergebnis mit unseren massgeschneiderten Bleaching-Schienen und den professionellen Produkten von \\u003ca href=\\u0022https:\/\/www.philips.ch\/fr\/c-m-pe\/eclaircissement-des-dents\\u0022 target=\\u0022_blank\\u0022 rel=\\u0022noopener\\u0022\\u003ePhilips Zoom\u00ae (400.-)\\u003c\/a\\u003e.\\u003c\/strong\\u003e\\r\\n\\r\\nDiese Zahnaufhellungstechnik ist in verschiedenen Zentren der Adent Gruppe verf\u00fcgbar. Sie liefert signifikante Ergebnisse und garantiert eine zuverl\u00e4ssige Bleichung. Bereits nach einigen Tagen sind Ergebnisse sichtbar und nach nur 2 Wochen ist die Behandlung abgeschlossen. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den Labors des Adent-Netzwerks hergestellt. Gesunde, zahnsteinfreie und pathologiefreie Z\u00e4hne sind eine Voraussetzung f\u00fcr den Beginn einer Zahnaufhellung.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Termin vereinbaren\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"termin-vereinbaren\",\"url\":\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3789,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/accordion {\"name\":\"acf\/accordion\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635ba74f0bd13\",\"title\":\"FAQ - Zahnaufhellung mit Schienen\",\"_title\":\"field_626fdcfcf47bb\",\"description\":\"\",\"_description\":\"field_626fdd05f47bc\",\"accordions_0_title\":\"Zahnaufhellungsschienen: Wie funktionieren die Schienen?\",\"_accordions_0_title\":\"field_626fdd3ff47be\",\"accordions_0_content\":\"Die Dentalhygienikerin oder der Zahnarzt macht einen Abdruck Ihrer Z\u00e4hne und \u00fcbergibt diesen an den Zahntechniker. Ihre individuelle und massgeschneiderte Bleaching-Schiene wird in den \\u003ca href=\\u0022https:\/\/adent.ch\/de\/gruppe\/dentallabore\/\\u0022\\u003eLabors des Adent-Netzwerks\\u003c\/a\\u003e hergestellt.\\r\\n\\r\\nDie Herstellung der Bleaching-Schiene dauert eine Woche. Nach Ablauf dieser Frist wird ein neuer Termin f\u00fcr die Anprobe, die Beratung und die \u00dcbergabe des Materials (Schiene und Bleichmittel) vereinbart. Die Schienen k\u00f6nnen je nach Vorliebe Tag und Nacht f\u00fcr einige Stunden getragen werden. Bereits nach einigen Tagen sind Ergebnisse sichtbar. Nach nur 2 Wochen ist die Behandlung abgeschlossen und Ihre Z\u00e4hne sind strahlend weiss.\\r\\n\\r\\nIhre Zahnaufhellungsschiene kann gelagert und sp\u00e4ter wieder verwendet werden. So k\u00f6nnen Sie nach Belieben \u00c4nderungen vornehmen.\",\"_accordions_0_content\":\"field_626fdd46f47bf\",\"accordions_1_title\":\"F\u00fcr wen ist die Zahnaufhellung mit Schienen geeignet?\",\"_accordions_1_title\":\"field_626fdd3ff47be\",\"accordions_1_content\":\"Die Zahnaufhellung mit Schienen ist f\u00fcr Menschen gedacht, die dauerhaft weissere Z\u00e4hne haben m\u00f6chten. Um f\u00fcr diese Behandlung in Frage zu kommen, d\u00fcrfen Sie keine mundgesundheitlichen Kontraindikationen haben und m\u00fcssen ein gesundes Gebiss haben (kein Zahnstein, keine Karies, keine Zahnlockerung usw.). Der Rat Ihrer Dentalhygienikerin oder Ihres Zahnarztes ist erforderlich.\",\"_accordions_1_content\":\"field_626fdd46f47bf\",\"accordions_2_title\":\"Welche Vorteile bietet die professionelle Zahnaufhellung von Philips Zoom\u00ae?\",\"_accordions_2_title\":\"field_626fdd3ff47be\",\"accordions_2_content\":\"Zahnaufhellung mit massgefertigten Schienen von Philips Zoom\u00ae-Produkten bietet Ihnen eine professionelle, effektive und sichere Zahnaufhellung. Massgefertigte Schienen sind diskret und k\u00f6nnen je nach Wunsch am Tag oder in der Nacht getragen werden. Die innovative Formel des Gels sch\u00fctzt Ihren Zahnschmelz und st\u00e4rkt Ihre Z\u00e4hne, ohne Ihre Gesundheit zu beeintr\u00e4chtigen.\",\"_accordions_2_content\":\"field_626fdd46f47bf\",\"accordions_3_title\":\"Was muss ich beachten, bevor ich mit einer professionellen Philips Zoom\u00ae Zahnaufhellung beginne?\",\"_accordions_3_title\":\"field_626fdd3ff47be\",\"accordions_3_content\":\"Eine gute Mundgesundheit ist Voraussetzung f\u00fcr das Bleichen von Z\u00e4hnen. Vor dem Bleichen ist ein Kontrolltermin beim Zahnarzt erforderlich. Vor Beginn der Behandlung m\u00fcssen Karies, Zahnstein oder andere Erkrankungen (z.B. Zahnlockerung) ausgeschlossen werden.\\r\\n\\r\\nSchwangeren Frauen, starken Rauchern und Jugendlichen bis 18 Jahre wird von einer Zahnaufhellung abgeraten. Ihre Z\u00e4hne sind noch nicht ausgereift, die Wurzeln sind noch offen und empfindlich. Es ist auch zu beachten, dass Zahnkronen und Kompositf\u00fcllungen (allgemein als \\u0022F\u00fcllungen\\u0022 bezeichnet) nicht weiss werden. Wenn sie sich auf den hinteren Z\u00e4hnen befinden, kann das Bleaching problemlos durchgef\u00fchrt werden. Wenn sie jedoch auf den vorderen Z\u00e4hnen vorhanden sind, m\u00fcssen sie nach der Zahnaufhellung ausgetauscht und an die neue Zahnfarbe angepasst werden.\",\"_accordions_3_content\":\"field_626fdd46f47bf\",\"accordions\":4,\"_accordions\":\"field_626fdd1ff47bd\",\"button_button_text\":\"\",\"_button_button_text\":\"field_635b9f5d3ed5e\",\"button_button_link\":\"\",\"_button_button_link\":\"field_635b9f7c3ed5f\",\"button\":\"\",\"_button\":\"field_635b9f2e3ed5d\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e2499085dee\",\"shapes\":\"shape7\",\"_shapes\":\"field_626fd3f41491d\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Invisalign\u00ae\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Invisalign\u00ae ist eine kieferorthop\u00e4dische Behandlung mit durchsichtigen Zahnschienen der Marke Invisalign\u00ae. Bei dieser Behandlung wird eine Reihe von transparenten, herausnehmbaren Alignern f\u00fcr einige Wochen oder Monate getragen, um die Z\u00e4hne auf sanfte und schonende Weise neu auszurichten.\\r\\n\\r\\nDieses transparente und \u00e4sthetisch unauff\u00e4llige System ist nicht nur auf relativ einfache Behandlungen beschr\u00e4nkt, sondern eignet sich auch f\u00fcr komplexere Ausrichtungen. Bei kleinen, un\u00e4sthetischen Zahnfehlstellungen reicht eine mehrmonatige Behandlung mit transparenten Alignern aus. Bei komplexen Behandlungen k\u00f6nnen ein bis zwei Jahre erforderlich sein. Aber keine Sorge, dank der modernen 3D-Bildgebungstechnologie kennen Sie Ihren Behandlungsplan im Voraus, von der Anfangsposition der Z\u00e4hne bis zur gew\u00fcnschten Endposition.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Invisalign\u00ae entdecken\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Invisalign behandlung\",\"url\":\"https:\/\/adent.ch\/de\/info\/invisalign-behandlung\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns_1_column_type\":\"image_video\",\"_columns_1_column_type\":\"field_627221966b517\",\"columns_1_image_video_type\":\"image\",\"_columns_1_image_video_type\":\"field_627222596b51c\",\"columns_1_image\":3734,\"_columns_1_image\":\"field_627222856b51d\",\"columns\":2,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape7\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/two-column {\"name\":\"acf\/two-column\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bd17ffcee6\",\"title\":\"Zahnprothesen\",\"_title\":\"field_622629438a3e9\",\"columns_0_column_type\":\"text\",\"_columns_0_column_type\":\"field_627221966b517\",\"columns_0_text\":\"Es gibt eine grosse Auswahl an festsitzendem oder herausnehmbarem Zahnersatz, der die \u00c4sthetik und den Komfort Ihres L\u00e4chelns verbessert. Zahnprothesen, die sich leicht an die Bed\u00fcrfnisse jedes Einzelnen anpassen lassen: Zahnkrone, Br\u00fccke, Veneer, herausnehmbare Voll- oder Teilprothese.\",\"_columns_0_text\":\"field_6226294b8a3ea\",\"columns_0_link_type\":\"bouton\",\"_columns_0_link_type\":\"field_623833b107a07\",\"columns_0_button_text\":\"Weitere Informationen\",\"_columns_0_button_text\":\"field_6227212165677\",\"columns_0_button_link\":{\"title\":\"Implant et restauration\",\"url\":\"https:\/\/adent.ch\/soin\/implant-et-restauration\/\",\"target\":\"\"},\"_columns_0_button_link\":\"field_6227212f65678\",\"columns_0_link_is_blank\":\"0\",\"_columns_0_link_is_blank\":\"field_6227213d65679\",\"columns\":1,\"_columns\":\"field_6238335007a05\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25403466d9\",\"shapes\":\"shape4\",\"_shapes\":\"field_62262422937e9\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/highlight-image {\"name\":\"acf\/highlight-image\",\"data\":{\"title\":\"\",\"_title\":\"field_623c21dda6278\",\"blocs_0_image\":3741,\"_blocs_0_image\":\"field_623c222ba627a\",\"blocs_0_title\":\"Zahnkrone\",\"_blocs_0_title\":\"field_623c22c4a627b\",\"blocs_0_description\":\"Die Krone ist ein Zahnersatz aus Keramik, der den sichtbaren Teil des Zahns ersetzt, wenn dieser durch Karies oder eine Fraktur stark besch\u00e4digt wurde. Sie sch\u00fctzt den Zahn vor Abnutzung und erm\u00f6glicht die Abdeckung eines Zahnimplantats, das einen fehlenden Zahn ersetzt. Diese Methode vermeidet die vollst\u00e4ndige Extraktion des Zahns. Sie verbessert die \u00c4sthetik und den Komfort Ihres L\u00e4chelns.\",\"_blocs_0_description\":\"field_623c22cba627c\",\"blocs_0_button_type\":\"none\",\"_blocs_0_button_type\":\"field_623c34377e92d\",\"blocs_1_image\":3745,\"_blocs_1_image\":\"field_623c222ba627a\",\"blocs_1_title\":\"Zahnbr\u00fccke (oder Bridge)\",\"_blocs_1_title\":\"field_623c22c4a627b\",\"blocs_1_description\":\"Die Br\u00fccke, auch bekannt als Bridge, ist ein Zahnersatz, der einen oder mehrere fehlende Z\u00e4hne ersetzen kann. Mit Zahnbr\u00fccken erhalten Sie \u00c4sthetik und Komfort im Mund zur\u00fcck. Die Pfeiler der Zahnbr\u00fccke befinden sich in der Regel auf beiden Seiten des zahnlosen Kiefers und werden in Form von Implantaten oder gefr\u00e4sten Z\u00e4hnen eingesetzt. Auf diesen Pfeilern ruht die Br\u00fccke. Er ist fest und kann nicht entfernt werden.\",\"_blocs_1_description\":\"field_623c22cba627c\",\"blocs_1_button_type\":\"none\",\"_blocs_1_button_type\":\"field_623c34377e92d\",\"blocs_2_image\":3748,\"_blocs_2_image\":\"field_623c222ba627a\",\"blocs_2_title\":\"Veneer\",\"_blocs_2_title\":\"field_623c22c4a627b\",\"blocs_2_description\":\"Das Veneer ist eine hauchd\u00fcnne Keramikschale. Das Veneer ist sehr widerstandsf\u00e4hig und wird auf der Vorderseite der Z\u00e4hne befestigt. Die Farbe passt zu Ihrem L\u00e4cheln, sie wird nach Mass angefertigt und deckt den nat\u00fcrlichen Zahn ab.\",\"_blocs_2_description\":\"field_623c22cba627c\",\"blocs_2_button_type\":\"none\",\"_blocs_2_button_type\":\"field_623c34377e92d\",\"blocs_3_image\":3771,\"_blocs_3_image\":\"field_623c222ba627a\",\"blocs_3_title\":\"Vollst\u00e4ndige oder teilweise herausnehmbare Prothese\",\"_blocs_3_title\":\"field_623c22c4a627b\",\"blocs_3_description\":\"Die Zahnprothesen werden nach Mass angefertigt. Sie passen sich der Morphologie Ihrer Mundh\u00f6hle an. Sie sind sehr widerstandsf\u00e4hig und ersetzen einen oder mehrere Z\u00e4hne. Dank der modernen Technologien, die in den Zahnarztzentren eingesetzt werden, bieten sie ein nat\u00fcrliches, \u00e4sthetisches und komfortables Endergebnis.\",\"_blocs_3_description\":\"field_623c22cba627c\",\"blocs_3_button_type\":\"none\",\"_blocs_3_button_type\":\"field_623c34377e92d\",\"blocs\":4,\"_blocs\":\"field_623c21f0a6279\",\"display_shapes\":\"0\",\"_display_shapes\":\"field_62e25104d76c2\",\"shapes\":\"shape5\",\"_shapes\":\"field_623c20cd3ad28\"},\"mode\":\"edit\"} \/-->\n\n<!-- wp:acf\/cta {\"name\":\"acf\/cta\",\"data\":{\"anchor\":\"\",\"_anchor\":\"field_635bcb8d94cbf\",\"type\":\"without_image\",\"_type\":\"field_62149e2d12aaf\",\"subtitle\":\"Bleaching und \u00e4sthetische Behandlungen\",\"_subtitle\":\"field_62149e038cf5c\",\"title\":\"Haben Sie Fragen?\",\"_title\":\"field_62149edd2d388\",\"text\":\"Kontaktieren Sie das Zentrum Adent Zahnarztzentrum in Ihrer N\u00e4he.\",\"_text\":\"field_62149e038cf52\",\"button_text\":\"Mein Zentrum finden\",\"_button_text\":\"field_62149f062d389\",\"button_link\":{\"title\":\"zahnkliniken\",\"url\":\"https:\/\/adent.ch\/de\/zahnkliniken\/\",\"target\":\"\"},\"_button_link\":\"field_62149f112d38a\",\"button_color\":\"primary\",\"_button_color\":\"field_622b41428312a\",\"link_is_blank\":\"0\",\"_link_is_blank\":\"field_62285a3437980\"},\"mode\":\"edit\"} \/-->","post_title":"Bleaching und \u00e4sthetische Behandlungen","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"zahnbleaching-und-aesthetisch-e-en-behandlungen","to_ping":"","pinged":"","post_modified":"2026-01-22 15:10:05","post_modified_gmt":"2026-01-22 14:10:05","post_content_filtered":"","post_parent":0,"guid":"https:\/\/adent.ch\/soin\/blanchiments-et-soins-esthetiques\/","menu_order":0,"post_type":"soin","post_mime_type":"","comment_count":"0","filter":"raw"}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Thilani BALACHANDRAN | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles. Sie f\u00fchrt alle allgemeinen zahn\u00e4rztlichen Behandlungen durch.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Thilani BALACHANDRAN | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles. Sie f\u00fchrt alle allgemeinen zahn\u00e4rztlichen Behandlungen durch.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T12:32:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/thilani-balachandran\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/thilani-balachandran\\\/\",\"name\":\"Thilani BALACHANDRAN | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2022-05-31T16:07:19+00:00\",\"dateModified\":\"2024-05-02T12:32:45+00:00\",\"description\":\"Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles. Sie f\u00fchrt alle allgemeinen zahn\u00e4rztlichen Behandlungen durch.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/thilani-balachandran\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/thilani-balachandran\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/zahnarzt\\\/thilani-balachandran\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Team\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/team\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Thilani BALACHANDRAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Thilani BALACHANDRAN | Adent Zahnarztzentrum","description":"Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles. Sie f\u00fchrt alle allgemeinen zahn\u00e4rztlichen Behandlungen durch.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/","og_locale":"de_DE","og_type":"article","og_title":"Thilani BALACHANDRAN | Adent Zahnarztzentrum","og_description":"Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles. Sie f\u00fchrt alle allgemeinen zahn\u00e4rztlichen Behandlungen durch.","og_url":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2024-05-02T12:32:45+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/","url":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/","name":"Thilani BALACHANDRAN | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2022-05-31T16:07:19+00:00","dateModified":"2024-05-02T12:32:45+00:00","description":"Die Zahn\u00e4rztin Thilani Balachandran praktiziert im Zentrum Adent in Genf-Charmilles. Sie f\u00fchrt alle allgemeinen zahn\u00e4rztlichen Behandlungen durch.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/zahnarzt\/thilani-balachandran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Team","item":"https:\/\/adent.ch\/de\/team\/"},{"@type":"ListItem","position":2,"name":"Thilani BALACHANDRAN"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe\/5103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/equipe"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/equipe"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=5103"}],"wp:term":[{"taxonomy":"langue","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/langue?post=5103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}