{"id":11936,"date":"2024-07-30T12:33:35","date_gmt":"2024-07-30T10:33:35","guid":{"rendered":"https:\/\/adent.ch\/?post_type=news&#038;p=11936"},"modified":"2024-11-25T11:45:03","modified_gmt":"2024-11-25T10:45:03","slug":"dentale-hypersensibilitaet","status":"publish","type":"news","link":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/","title":{"rendered":"Dentale Hypersensibilit\u00e4t"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t<h3 class=\"title\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">Was ist dentale Hypersensibilit\u00e4t ?<\/h3>\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Dentale Hypersensibilit\u00e4t ist ein sehr h\u00e4ufiges und weit verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.<\/p>\n<p>Zahlreiche Menschen leiden unter dentaler Sensibilit\u00e4t. Der akute Schmerz tritt auf, wenn Ihre Z\u00e4hne mit harten, heissen, kalten oder s\u00fcssen Lebensmitteln in Kontakt kommen oder sobald Sie die Zahnb\u00fcrste ansetzen. Die \u00dcberempfindlichkeit ist meist vor\u00fcbergehend und in einigen F\u00e4llen mit blossem Auge nicht erkennbar.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\"  class=\"primary-btn\">Termin vereinbaren<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/06\/adent_metier_medecin-dentiste.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"accordion-block\">\n\t<div class=\"container\">\n\t\t<h3 class=\"h2\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">FAQ &#8211; Dentale Hypersensibilit\u00e4t<\/h3>\n\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"col-lg-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Warum habe ich Zahnschmerzen ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Im Zentrum eines jeden Zahns befindet sich das Dentin, auch Zahnbein genannt. Vom Dentin umschlossen ist die Pulpa, die aus verschiedenen Gef\u00e4ssen und Nerven besteht, die den Zahn am Leben erhalten. Das Dentin wird normalerweise vom Zahnfleisch und dem Zahnschmelz gesch\u00fctzt. Das Zahnbein wird von ganz feinen Dentintubuli durchdrungen, die eine Verbindung zwischen der \u00e4usseren Schicht des Zahnbeins und dem Nerv herstellen. Liegt nun das Dentin aufgrund eines Zahnfleischr\u00fcckgangs oder des Abbaus vom Zahnschmelz frei, senden die Tubuli Reize (K\u00e4lte, W\u00e4rme), die auf die \u00e4ussere Dentinschicht einwirken, direkt an den Nerv, dies l\u00f6st den Schmerz aus.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Was sind die Ursachen von Dentale Hypersensibilit\u00e4t?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Dentale Hypersensibilit\u00e4t kann verschiedene Ursachen haben: eine zu harte Zahnb\u00fcrste, zu starker Druck beim Z\u00e4hneputzen, h\u00e4ufiger Genuss von sauren Lebensmitteln, Z\u00e4hneknirschen oder Risse im Zahn und Zahnfleischr\u00fcckgang. Zusammenfassend kann man sagen: Alles, was Ihren Zahnschmelz angreift und abbaut, kann die Ursache f\u00fcr Ihre dentale Sensibilit\u00e4t sein.<\/p>\n<p>In so einem Fall ist Ihr Zahnschmelz verletzt und l\u00e4sst eine leicht gelbliche Materie hervortreten: das Zahnbein \u2013 eine Schicht, die unterhalb des Zahnschmelzes liegt. Das Zahnbein setzt sich aus winzigen Kan\u00e4len zusammen, den sogenannten Zahntubuli, die zwischen dem Zahnmark und der \u00e4usseren Schicht eine Verbindung herstellt. Geht der Schutz durch den Zahnschmelz verloren, werden aus diesen Kan\u00e4len sehr sensibele Informationen \u00fcbermittelt. Diese Informationen sind Alarmsignale, der den Schmerz ausl\u00f6st.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Wie kann man die dentale Sensibilit\u00e4t vermindern ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Beim Auftreten von dentaler Sensibilit\u00e4t m\u00fcss das Zahnbein gest\u00e4rkt und die Dentintubuli geschlossen werden, um die \u00dcbermittlung des Signals an das Zahnmark zu unterbinden. Auf dem Markt gibt es eine ganze Reihe von nicht verschreibungspflichtigen Produkten, mit denen die dentalen Sensibilit\u00e4ten verbessert werden k\u00f6nnen, manchmal reichen diese allerdings nicht aus. Gew\u00f6hnen Sie sich zudem auch an, Ihre Mundhygiene ernst zu nehmen: Gepflegte Z\u00e4hne sch\u00fctzen vor Sensibilit\u00e4t.<\/p>\n<p>Fluoridhaltige Zahnpasten gegen dentale Sensibilit\u00e4ten.<\/p>\n<p>Kleiner Tipp: Sp\u00fclen Sie Ihren Mund nach dem Z\u00e4hneputzen nicht aus. Mit dem Sp\u00fclen entfernen Sie die in der Zahnpasta enthaltenen Substanzen, die deswegen nicht ihre volle Wirkung entfalten k\u00f6nnen. Spucken Sie nach dem Z\u00e4hneputzen den Schaum aus, ohne anschliessend Ihren Mund auszusp\u00fclen.<\/p>\n<p>W\u00e4hlen Sie eine Zahnpasta mit einem niedrigem RDA-Wert: Die entsprechenden Angaben finden Sie auf dem Tubenr\u00fccken. RDA bedeutet Relative Dentin Abrasion und bezeichnet somit den Grad der Zahn-Scheuerwirkung. Der RDA-Wert gibt Aufschluss \u00fcber die Abrasivit\u00e4t der Zahnpasta. Bei dentaler Sensibilit\u00e4t sollten Sie einen Wert w\u00e4hlen, der nicht \u00fcber 30 liegt.<\/p>\n<p>Die Anwendung von Mundsp\u00fclungen gegen Sensibilit\u00e4ten kann ebenfalls zur Linderung beitragen.<\/p>\n<p>Benutzen Sie eine sanfte Zahnb\u00fcrste mit weichen Borsten und passen Sie Ihre Bewegungen an.<\/p>\n<p>Schr\u00e4nken Sie den Konsum von sauren Lebensmitteln ein und benutzen Sie nach M\u00f6glichkeit einen Trinkhalm. Die Fl\u00fcssigkeit kann dadurch eingenommen werden, ohne dass sie mit Ihren Z\u00e4hnen in Kontakt kommt und verursacht deshalb keine Abnutzung und zus\u00e4tzliche dentale Sensibilisierung.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-3 mt-md-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t<div class=\"cta-block without-image\" >\n\t\t<div class=\"container\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"row justify-content-center\">\n\t\t\t\t<div class=\"col-md-8\">\n\t\t\t\t\t<div class=\"subtitle\"><\/div>\n\t\t\t\t\t<h4 class=\"title\">Falls die dentale Hypersensibilit\u00e4t weiterhin bestehen bleibt, sollten Sie mit Ihrem Zahnarzt oder mit Ihrer Dentalhygienikerin Kontakt aufnehmen<\/h4>\n\t\t\t\t\t<p class=\"text\">Sie k\u00f6nnen Ihnen professionelle L\u00f6sungen vorschlagen, insbesondere die Anwendung eines Lacks oder eines Schutz\u00fcberzugs, die direkt auf die sensible Zone aufgetragen werden. Deren Lebensdauer kann je nach den Verh\u00e4ltnissen in Ihrem Mund begrenzt sein.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/zahnkliniken\/\"  class=\"primary-btn\">Meine Zahnklinik finden<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"template":"","news_categories":[108],"class_list":["post-11936","news","type-news","status-publish","hentry","news_categories-gesundheit"],"acf":{"image":{"ID":5560,"id":5560,"title":"ADENT_Blog_hypersensibilite","filename":"adent_blog_hypersensibilite-1.png","filesize":226679,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1.png","link":"https:\/\/adent.ch\/de\/info\/ueberempfindlichkeit-und-zahnschmerzen\/adent_blog_hypersensibilite-2\/","alt":"","author":"2","description":"","caption":"","name":"adent_blog_hypersensibilite-2","status":"inherit","uploaded_to":13571,"date":"2022-07-06 18:14:59","modified":"2024-05-06 19:05:15","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1920,"height":1440,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1-1307x980.png","large-width":1307,"large-height":980,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1-1536x1152.png","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1.png","2048x2048-width":1920,"2048x2048-height":1440,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_hypersensibilite-1.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"short_description":"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.","related_news_description":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dentale Hypersensibilit\u00e4t | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dentale Hypersensibilit\u00e4t | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T10:45:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/dentale-hypersensibilitaet\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/dentale-hypersensibilitaet\\\/\",\"name\":\"Dentale Hypersensibilit\u00e4t | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2024-07-30T10:33:35+00:00\",\"dateModified\":\"2024-11-25T10:45:03+00:00\",\"description\":\"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/dentale-hypersensibilitaet\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/dentale-hypersensibilitaet\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/dentale-hypersensibilitaet\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dentale Hypersensibilit\u00e4t\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dentale Hypersensibilit\u00e4t | Adent Zahnarztzentrum","description":"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/","og_locale":"de_DE","og_type":"article","og_title":"Dentale Hypersensibilit\u00e4t | Adent Zahnarztzentrum","og_description":"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.","og_url":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2024-11-25T10:45:03+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/","url":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/","name":"Dentale Hypersensibilit\u00e4t | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2024-07-30T10:33:35+00:00","dateModified":"2024-11-25T10:45:03+00:00","description":"Dentale Hypersensibilit\u00e4t ist ein h\u00e4ufiges und verbreitetes Leiden. Die Symptome sind akute und wieder abklingende Zahnschmerzen.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/info\/dentale-hypersensibilitaet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/adent.ch\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"Dentale Hypersensibilit\u00e4t"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/news\/11936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=11936"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/news_categories?post=11936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}