{"id":3943,"date":"2022-05-06T10:49:20","date_gmt":"2022-05-06T08:49:20","guid":{"rendered":"https:\/\/adent.ch\/article\/grossesse-et-hygiene-dentaire\/"},"modified":"2024-11-25T13:31:19","modified_gmt":"2024-11-25T12:31:19","slug":"schwangerschaft-und-zahnhygiene","status":"publish","type":"news","link":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/","title":{"rendered":"Schwangerschaft und Dentalhygienikerin"},"content":{"rendered":"<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t<h3 class=\"title\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">Schwangerschaft und Zahnhygiene: Wie h\u00e4ngt das zusammen?<\/h3>\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Eine Schwangerschaft und die Ankunft eines Kindes sind wichtige Schritte im Leben einer Frau. Der K\u00f6rper ver\u00e4ndert sich, der Organismus wird umgebaut und die Hormone werden gest\u00f6rt. In dieser besonderen Zeit erh\u00e4lt die schwangere Frau viele Ratschl\u00e4ge und Empfehlungen f\u00fcr einen optimalen Verlauf der Schwangerschaft und die Entwicklung des F\u00f6tus.<\/p>\n<p>Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundhygiene zu k\u00fcmmern? Nehmen Sie sich die Zeit, Ihre Dentalhygienikerin oder Ihren Zahnarzt in dieser Zeit zu besuchen, sie k\u00f6nnen Ihnen wertvolle Tipps geben!<\/p>\n<blockquote><p>Informieren Sie Ihren Arzt bei Ihren Besuchen dar\u00fcber, dass Sie schwanger sind.<\/p><\/blockquote>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/grossesse-1470x980.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"accordion-block\">\n\t<div class=\"container\">\n\t\t<h3 class=\"h2\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">FAQ &#8211; Schwangerschaft und Zahnhygiene<\/h3>\n\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"col-lg-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Ungew\u00f6hnlicher Appetit w\u00e4hrend der Schwangerschaft: einige Regeln der Zahnhygiene, die es zu beachten gilt<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Die ber\u00fchmten Hormone, von denen man oft h\u00f6rt, k\u00f6nnen einen ungew\u00f6hnlichen Appetit auf Speisen wecken, die Sie normalerweise nicht in Versuchung gef\u00fchrt h\u00e4tten. Diese Umstellung der Ern\u00e4hrung &#8211; insbesondere auf zuckerhaltige Lebensmittel &#8211; kann das Kariesrisiko erh\u00f6hen. W\u00e4hrend der gesamten Schwangerschaft ist es wichtig, dass Sie Ihre Mundhygiene aufrechterhalten und Ihre Z\u00e4hne regelm\u00e4ssig putzen, damit sich kein Zahnbelag ansammelt. Es wird ausserdem empfohlen, die Zahnzwischenr\u00e4ume zus\u00e4tzlich mit Zahnseide, Zahnstochern, B\u00fcrstchen oder anderen Hilfsmitteln zu reinigen, die von Ihrer Dentalhygienikerin oder Ihrem Zahnarzt empfohlen werden.<\/p>\n<p>W\u00e4hrend der Schwangerschaft empfehlen wir zwei Zahnreinigungen, um die Gesundheit Ihres Zahnfleisches und Ihrer Z\u00e4hne zu gew\u00e4hrleisten. Die Dentalhygienikerin entfernt alle Ablagerungen auf Ihren Z\u00e4hnen (Plaque, Zahnstein, Verf\u00e4rbungen). Wenn das Zahnfleisch Anzeichen einer Entz\u00fcndung aufweist, gibt Ihnen die Dentalhygienikerin diese auf Ihre pers\u00f6nliche Situation abgestimmten Mundreinigungstipps, um Ihr L\u00e4cheln gesund zu erhalten.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Schwangerschafts\u00fcbelkeit: Die richtigen Massnahmen zum Schutz Ihrer Z\u00e4hne<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>\u00dcbelkeit kann zum Alltag einer schwangeren Frau geh\u00f6ren. Dies f\u00fchrt zu einer Ansammlung von S\u00e4ure in Ihrem Mund, einer Senkung des pH-Wertes im Speichel und zu Entkalkungen auf der Oberfl\u00e4che des Zahnschmelzes. Um die Auswirkungen der S\u00e4ure auf Ihre Z\u00e4hne zu verringern, wird empfohlen, den Mund mit Wasser auszusp\u00fclen und eine fluoridhaltige Mundsp\u00fclung zu verwenden. Fluorid remineralisiert die Oberfl\u00e4che Ihres Zahnschmelzes und st\u00e4rkt ihn dadurch. Wir empfehlen Ihnen, nach dem Erbrechen den Mund gr\u00fcndlich mit Wasser oder Mundwasser auszusp\u00fclen. Der pH-Wert wird neutralisiert und Ihr Zahnschmelz vor S\u00e4ureangriffen gesch\u00fctzt.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Gingivitis in der Schwangerschaft oder Schwangerschaftsgingivitis: Was ist das?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Schwangerschaftsgingivitis, ist eine Folge des hormonellen Ungleichgewichts, das w\u00e4hrend der Schwangerschaft auftritt. Das hormonelle Ungleichgewicht macht die Mundschleimhaut anf\u00e4lliger f\u00fcr Angriffe von Bakterien im Mund. Eine erh\u00f6hte Empfindlichkeit des Zahnfleisches, eine Entz\u00fcndung des Zahnfleischgewebes und unregelm\u00e4ssige Konturen des Zahnfleisches sind einige Symptome einer Schwangerschaftsgingivitis. Andere sichtbare Symptome wie R\u00f6tung, Schwellung und spontane Blutungen sollten Sie auf den Zustand Ihres Zahnfleischs aufmerksam machen.<\/p>\n<p>Wenn Sie diese Symptome beobachten, sollten Sie einen <a href=\"https:\/\/adent.ch\/de\/termin-vereinbaren\/\">Termin<\/a> bei Ihrer Dentalhygienikerin vereinbaren, die eine sanfte Zahnreinigung durchf\u00fchren wird.<\/p>\n<p>In einigen F\u00e4llen ist <a href=\"https:\/\/adent.ch\/de\/info\/pflege-des-zahnfleisches\/\">Parodontitis <\/a>(eine Krankheit, die das Zahnfleisch und den Knochen um Ihre Z\u00e4hne herum zerst\u00f6rt) ein Faktor, der das Risiko einer Fr\u00fchgeburt signifikant erh\u00f6ht. Zahlreiche Studien haben gezeigt, dass eine Parodontitis bei einer schwangeren Frau das Risiko erh\u00f6ht, dass das Kind vor der 37. Toxine und Bakterien, die bei Parodontitis auftreten, werden mit Fr\u00fchgeburten in Verbindung gebracht.<\/p>\n<p>Um ein gesundes Zahnfleisch und gesunde Z\u00e4hne zu erhalten, empfehlen wir Ihnen in jedem Fall regelm\u00e4ssige Zahnreinigungen und Kontrollen, noch bevor Sie schwanger werden!<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">&#8220;Eine Schwangerschaft, ein Zahn&#8221;: Mythos oder Realit\u00e4t?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Schwangere Frauen beschuldigen ihr Baby f\u00e4lschlicherweise, ihnen &#8220;Kalzium zu entziehen&#8221;, was zum Verlust eines Zahnes pro Schwangerschaft f\u00fchren k\u00f6nnte. W\u00e4hrend fr\u00fcher eine Schwangerschaft zu Mangelerscheinungen f\u00fchrte, insbesondere an Kalzium, kann man heute nicht mehr von Unterern\u00e4hrung sprechen.<\/p>\n<p>Die einzige Auswirkung ist der Hormonhaushalt mit dem Risiko einer akuten Gingivitis, die zu empfindlichem Zahnfleisch, Blutungen und Schwellungen f\u00fchrt, kurzum zu Schmerzen, die das Putzen erschweren. Naschen und zuckerhaltige Lebensmittel sind ebenfalls zwei Risikofaktoren f\u00fcr die Z\u00e4hne.<\/p>\n<p>Um Zahnschmerzen und -probleme w\u00e4hrend der Schwangerschaft zu vermeiden, sollten Sie gute Ern\u00e4hrungsgewohnheiten, regelm\u00e4ssige Zahnpflege und Besuche bei Ihrer Dentalhygienikerin oder Ihrem Zahnarzt beibehalten. So bleiben Ihre Z\u00e4hne und Ihr Zahnfleisch gesund.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-3 mt-md-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t<div class=\"cta-block without-image\" >\n\t\t<div class=\"container\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"row justify-content-center\">\n\t\t\t\t<div class=\"col-md-8\">\n\t\t\t\t\t<div class=\"subtitle\"><\/div>\n\t\t\t\t\t<h4 class=\"title\">Haben Sie Fragen? Schmerzt Ihr Zahnfleisch?<\/h4>\n\t\t\t\t\t<p class=\"text\">Kontaktieren Sie ein Zahnarztzentrum in Ihrer N\u00e4he oder vereinbaren Sie einen Termin \u00fcber unser Kontaktformular.<br \/>\r\n<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/zahnkliniken\/\"  class=\"primary-btn\">Mein Zentrum finden<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n","protected":false},"template":"","news_categories":[106],"class_list":["post-3943","news","type-news","status-publish","hentry","news_categories-ratschlaege"],"acf":{"related_news_description":"","short_description":"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?","image":{"ID":5563,"id":5563,"title":"ADENT_Blog_grossesse","filename":"adent_blog_grossesse-1.png","filesize":128896,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1.png","link":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/adent_blog_grossesse-2\/","alt":"","author":"2","description":"","caption":"","name":"adent_blog_grossesse-2","status":"inherit","uploaded_to":3943,"date":"2022-07-06 18:15:04","modified":"2022-07-06 19:05:28","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1920,"height":1440,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1-1307x980.png","large-width":1307,"large-height":980,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1-1536x1152.png","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1.png","2048x2048-width":1920,"2048x2048-height":1440,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_blog_grossesse-1.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schwangerschaft und Dentalhygienikerin | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schwangerschaft und Dentalhygienikerin | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-25T12:31:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/schwangerschaft-und-zahnhygiene\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/schwangerschaft-und-zahnhygiene\\\/\",\"name\":\"Schwangerschaft und Dentalhygienikerin | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"datePublished\":\"2022-05-06T08:49:20+00:00\",\"dateModified\":\"2024-11-25T12:31:19+00:00\",\"description\":\"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/schwangerschaft-und-zahnhygiene\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/schwangerschaft-und-zahnhygiene\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/info\\\/schwangerschaft-und-zahnhygiene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schwangerschaft und Dentalhygienikerin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schwangerschaft und Dentalhygienikerin | Adent Zahnarztzentrum","description":"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/","og_locale":"de_DE","og_type":"article","og_title":"Schwangerschaft und Dentalhygienikerin | Adent Zahnarztzentrum","og_description":"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?","og_url":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2024-11-25T12:31:19+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/","url":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/","name":"Schwangerschaft und Dentalhygienikerin | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"datePublished":"2022-05-06T08:49:20+00:00","dateModified":"2024-11-25T12:31:19+00:00","description":"Das Wohlbefinden einer schwangeren Frau w\u00e4hrend der Schwangerschaft ist von entscheidender Bedeutung. Aber wussten Sie, dass es auch wichtig ist, sich um die Mundgesundheit zu k\u00fcmmern?","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/info\/schwangerschaft-und-zahnhygiene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/adent.ch\/de\/blog\/"},{"@type":"ListItem","position":2,"name":"Schwangerschaft und Dentalhygienikerin"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/news\/3943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/news"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=3943"}],"wp:term":[{"taxonomy":"news_categories","embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/news_categories?post=3943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}