{"id":12031,"date":"2023-11-06T13:44:08","date_gmt":"2023-11-06T12:44:08","guid":{"rendered":"https:\/\/adent.ch\/dentiste-lausanne-2-2\/"},"modified":"2025-04-23T17:00:54","modified_gmt":"2025-04-23T15:00:54","slug":"orthodontiste-lausanne","status":"publish","type":"page","link":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/","title":{"rendered":"Nos cliniques orthodontiques \u00e0 Lausanne"},"content":{"rendered":"\n<div class=\"content-type-selector-block\" data-id=\"content-type-selector-block-90\" id=\"content-type-selector-block-90\">\n\t<div class=\"container\">\n\t\t<div class=\"block-heading\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t<h3 class=\"block-heading__title h2\">Nos cabinets d&#8217;orthodontie \u00e0 Lausanne<\/h3>\n\t\t\t<div class=\"block-heading__description\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"content-type-grid\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"content-wrapper\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card \">\n\t\t\t\t\t\t\t<div class=\"clinique-card__pic\">\n\t\t\t\t\t\t\t\t<div class=\"card-tags\">\n\t\t\t\t\t\t\t\t\t<div class=\"card-tag\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1.781 10.172a9 9 0 1 0 18 0 9 9 0 0 0-18 0Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M10.781 5.172v5l3 3\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t<span>Ouvert<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_lausanne-gare_1_banner_1920x980-1920x980.jpg\" alt=\"\" loading=\"lazy\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"clinique-card__caption\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__contact\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__phone\">\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"25\" fill=\"none\" viewBox=\"0 0 25 25\">\n\t\t\t\t\t\t\t\t\t\t\t\t<path fill=\"currentColor\" d=\"M21.346 13.603c-.262 0-.537-.084-.799-.143a12 12 0 0 1-1.562-.467 2.38 2.38 0 0 0-2.956 1.196l-.262.55a15.7 15.7 0 0 1-3.183-2.39A15.7 15.7 0 0 1 10.2 9.156l.548-.25a2.39 2.39 0 0 0 1.192-2.965 13 13 0 0 1-.465-1.577 9 9 0 0 1-.143-.8 3.6 3.6 0 0 0-1.24-2.15A3.57 3.57 0 0 0 7.756.588H4.167a3.57 3.57 0 0 0-3.54 4.064 22.8 22.8 0 0 0 6.45 13.146 22.7 22.7 0 0 0 13.112 6.465q.233.018.465 0a3.57 3.57 0 0 0 3.577-3.585v-3.585a3.6 3.6 0 0 0-.823-2.26 3.58 3.58 0 0 0-2.062-1.23m.584 7.17a1.197 1.197 0 0 1-1.371 1.184 20.44 20.44 0 0 1-11.766-5.785 20.53 20.53 0 0 1-5.818-11.83 1.198 1.198 0 0 1 1.192-1.375h3.577a1.19 1.19 0 0 1 1.192.932c0 .323.107.657.179.98q.206.94.548 1.84l-1.669.79a1.2 1.2 0 0 0-.62.668 1.2 1.2 0 0 0 0 .909 17.3 17.3 0 0 0 8.345 8.365c.29.12.616.12.906 0 .296-.11.536-.334.668-.621l.75-1.673a14.8 14.8 0 0 0 2.85.729 1.19 1.19 0 0 1 .93 1.195l.107 3.693ZM14.896.458h-.834a1.196 1.196 0 0 0-1.09 1.297 1.2 1.2 0 0 0 1.293 1.093h.631c1.898 0 3.717.756 5.058 2.1a7.18 7.18 0 0 1 2.095 5.07v.634a1.197 1.197 0 0 0 1.085 1.29h.095a1.19 1.19 0 0 0 1.193-1.087v-.836a9.57 9.57 0 0 0-2.79-6.756A9.53 9.53 0 0 0 14.896.457Zm2.385 9.56a1.196 1.196 0 0 0 1.192 1.196 1.19 1.19 0 0 0 1.192-1.195 4.79 4.79 0 0 0-1.397-3.38 4.76 4.76 0 0 0-3.372-1.4 1.19 1.19 0 0 0-1.192 1.194 1.197 1.197 0 0 0 1.192 1.196c.633 0 1.24.251 1.686.7.447.448.699 1.056.699 1.69Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41 21 331 40 00\" class=\"phone h5\">+41 21 331 40 00<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"clinique-card__marker\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"23\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path fill=\"#fff\" d=\"M8.063 22.55a356.86 356.86 0 0 0-3.141-4.312c-1.563-2.156-2.594-3.608-3.094-4.357C1.11 12.803.625 11.897.375 11.163S0 9.583 0 8.625C0 7.068.406 5.63 1.219 4.312A8.99 8.99 0 0 1 4.5 1.168C5.875.389 7.375 0 9 0s3.125.39 4.5 1.168a8.99 8.99 0 0 1 3.281 3.144A8.062 8.062 0 0 1 18 8.625c0 .958-.125 1.804-.375 2.538-.25.734-.734 1.64-1.453 2.718-.5.749-1.531 2.201-3.094 4.357l-3.14 4.313c-.22.3-.532.449-.938.449-.406 0-.719-.15-.938-.45ZM9 12.22c1.031 0 1.914-.352 2.648-1.056.735-.704 1.102-1.55 1.102-2.538 0-.988-.367-1.834-1.102-2.538C10.914 5.383 10.031 5.03 9 5.03c-1.031 0-1.914.352-2.648 1.056-.735.704-1.102 1.55-1.102 2.538 0 .988.367 1.834 1.102 2.538.734.704 1.617 1.056 2.648 1.056Z\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__title h4\">Lausanne Bahnhof<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__info\">\n\t\t\t\t\t\t\t\t\t<div class=\"reviews\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rating\">4.8<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stars\"><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews-count\">138 reviews<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"more-info\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/klinik\/lausanne-gare\/\" class=\"inline-link inline-link--dark\">Mehr Infos<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/formulaire-zawin\/?id=4225&#038;code=https:\/\/oa.zawin.ch\/k4185_01\" class=\"primary-btn book\">Termin vereinbaren<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card \">\n\t\t\t\t\t\t\t<div class=\"clinique-card__pic\">\n\t\t\t\t\t\t\t\t<div class=\"card-tags\">\n\t\t\t\t\t\t\t\t\t<div class=\"card-tag\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1.781 10.172a9 9 0 1 0 18 0 9 9 0 0 0-18 0Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M10.781 5.172v5l3 3\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t<span>Ouvert<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/blecherette5-1470x980.jpg\" alt=\"\" loading=\"lazy\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"clinique-card__caption\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__contact\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__phone\">\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"25\" fill=\"none\" viewBox=\"0 0 25 25\">\n\t\t\t\t\t\t\t\t\t\t\t\t<path fill=\"currentColor\" d=\"M21.346 13.603c-.262 0-.537-.084-.799-.143a12 12 0 0 1-1.562-.467 2.38 2.38 0 0 0-2.956 1.196l-.262.55a15.7 15.7 0 0 1-3.183-2.39A15.7 15.7 0 0 1 10.2 9.156l.548-.25a2.39 2.39 0 0 0 1.192-2.965 13 13 0 0 1-.465-1.577 9 9 0 0 1-.143-.8 3.6 3.6 0 0 0-1.24-2.15A3.57 3.57 0 0 0 7.756.588H4.167a3.57 3.57 0 0 0-3.54 4.064 22.8 22.8 0 0 0 6.45 13.146 22.7 22.7 0 0 0 13.112 6.465q.233.018.465 0a3.57 3.57 0 0 0 3.577-3.585v-3.585a3.6 3.6 0 0 0-.823-2.26 3.58 3.58 0 0 0-2.062-1.23m.584 7.17a1.197 1.197 0 0 1-1.371 1.184 20.44 20.44 0 0 1-11.766-5.785 20.53 20.53 0 0 1-5.818-11.83 1.198 1.198 0 0 1 1.192-1.375h3.577a1.19 1.19 0 0 1 1.192.932c0 .323.107.657.179.98q.206.94.548 1.84l-1.669.79a1.2 1.2 0 0 0-.62.668 1.2 1.2 0 0 0 0 .909 17.3 17.3 0 0 0 8.345 8.365c.29.12.616.12.906 0 .296-.11.536-.334.668-.621l.75-1.673a14.8 14.8 0 0 0 2.85.729 1.19 1.19 0 0 1 .93 1.195l.107 3.693ZM14.896.458h-.834a1.196 1.196 0 0 0-1.09 1.297 1.2 1.2 0 0 0 1.293 1.093h.631c1.898 0 3.717.756 5.058 2.1a7.18 7.18 0 0 1 2.095 5.07v.634a1.197 1.197 0 0 0 1.085 1.29h.095a1.19 1.19 0 0 0 1.193-1.087v-.836a9.57 9.57 0 0 0-2.79-6.756A9.53 9.53 0 0 0 14.896.457Zm2.385 9.56a1.196 1.196 0 0 0 1.192 1.196 1.19 1.19 0 0 0 1.192-1.195 4.79 4.79 0 0 0-1.397-3.38 4.76 4.76 0 0 0-3.372-1.4 1.19 1.19 0 0 0-1.192 1.194 1.197 1.197 0 0 0 1.192 1.196c.633 0 1.24.251 1.686.7.447.448.699 1.056.699 1.69Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41 21 644 20 00\" class=\"phone h5\">+41 21 644 20 00<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"clinique-card__marker\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"23\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path fill=\"#fff\" d=\"M8.063 22.55a356.86 356.86 0 0 0-3.141-4.312c-1.563-2.156-2.594-3.608-3.094-4.357C1.11 12.803.625 11.897.375 11.163S0 9.583 0 8.625C0 7.068.406 5.63 1.219 4.312A8.99 8.99 0 0 1 4.5 1.168C5.875.389 7.375 0 9 0s3.125.39 4.5 1.168a8.99 8.99 0 0 1 3.281 3.144A8.062 8.062 0 0 1 18 8.625c0 .958-.125 1.804-.375 2.538-.25.734-.734 1.64-1.453 2.718-.5.749-1.531 2.201-3.094 4.357l-3.14 4.313c-.22.3-.532.449-.938.449-.406 0-.719-.15-.938-.45ZM9 12.22c1.031 0 1.914-.352 2.648-1.056.735-.704 1.102-1.55 1.102-2.538 0-.988-.367-1.834-1.102-2.538C10.914 5.383 10.031 5.03 9 5.03c-1.031 0-1.914.352-2.648 1.056-.735.704-1.102 1.55-1.102 2.538 0 .988.367 1.834 1.102 2.538.734.704 1.617 1.056 2.648 1.056Z\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__title h4\">Lausanne Bl\u00e9cherette<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__info\">\n\t\t\t\t\t\t\t\t\t<div class=\"reviews\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rating\">4.6<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stars\"><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-half\"><\/use><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews-count\">254 reviews<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"more-info\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/klinik\/lausanne-blecherette-2\/\" class=\"inline-link inline-link--dark\">Mehr Infos<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/formulaire-zawin\/?id=4227&#038;code=https:\/\/oa.zawin.ch\/k1530_01\" class=\"primary-btn book\">Termin vereinbaren<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card is-signature\">\n\t\t\t\t\t\t\t<div class=\"clinique-card__pic\">\n\t\t\t\t\t\t\t\t<div class=\"card-tags\">\n\t\t\t\t\t\t\t\t\t<div class=\"card-tag\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1.781 10.172a9 9 0 1 0 18 0 9 9 0 0 0-18 0Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M10.781 5.172v5l3 3\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t<span>Ouvert<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card-tag card-tag--signature\">Signature<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/cdsf_page_clinique_signature-784x980.jpg\" alt=\"\" loading=\"lazy\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"clinique-card__caption\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__contact\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__phone\">\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"25\" fill=\"none\" viewBox=\"0 0 25 25\">\n\t\t\t\t\t\t\t\t\t\t\t\t<path fill=\"currentColor\" d=\"M21.346 13.603c-.262 0-.537-.084-.799-.143a12 12 0 0 1-1.562-.467 2.38 2.38 0 0 0-2.956 1.196l-.262.55a15.7 15.7 0 0 1-3.183-2.39A15.7 15.7 0 0 1 10.2 9.156l.548-.25a2.39 2.39 0 0 0 1.192-2.965 13 13 0 0 1-.465-1.577 9 9 0 0 1-.143-.8 3.6 3.6 0 0 0-1.24-2.15A3.57 3.57 0 0 0 7.756.588H4.167a3.57 3.57 0 0 0-3.54 4.064 22.8 22.8 0 0 0 6.45 13.146 22.7 22.7 0 0 0 13.112 6.465q.233.018.465 0a3.57 3.57 0 0 0 3.577-3.585v-3.585a3.6 3.6 0 0 0-.823-2.26 3.58 3.58 0 0 0-2.062-1.23m.584 7.17a1.197 1.197 0 0 1-1.371 1.184 20.44 20.44 0 0 1-11.766-5.785 20.53 20.53 0 0 1-5.818-11.83 1.198 1.198 0 0 1 1.192-1.375h3.577a1.19 1.19 0 0 1 1.192.932c0 .323.107.657.179.98q.206.94.548 1.84l-1.669.79a1.2 1.2 0 0 0-.62.668 1.2 1.2 0 0 0 0 .909 17.3 17.3 0 0 0 8.345 8.365c.29.12.616.12.906 0 .296-.11.536-.334.668-.621l.75-1.673a14.8 14.8 0 0 0 2.85.729 1.19 1.19 0 0 1 .93 1.195l.107 3.693ZM14.896.458h-.834a1.196 1.196 0 0 0-1.09 1.297 1.2 1.2 0 0 0 1.293 1.093h.631c1.898 0 3.717.756 5.058 2.1a7.18 7.18 0 0 1 2.095 5.07v.634a1.197 1.197 0 0 0 1.085 1.29h.095a1.19 1.19 0 0 0 1.193-1.087v-.836a9.57 9.57 0 0 0-2.79-6.756A9.53 9.53 0 0 0 14.896.457Zm2.385 9.56a1.196 1.196 0 0 0 1.192 1.196 1.19 1.19 0 0 0 1.192-1.195 4.79 4.79 0 0 0-1.397-3.38 4.76 4.76 0 0 0-3.372-1.4 1.19 1.19 0 0 0-1.192 1.194 1.197 1.197 0 0 0 1.192 1.196c.633 0 1.24.251 1.686.7.447.448.699 1.056.699 1.69Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41 21 312 39 42\" class=\"phone h5\">+41 21 312 39 42<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"clinique-card__marker\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"23\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path fill=\"#fff\" d=\"M8.063 22.55a356.86 356.86 0 0 0-3.141-4.312c-1.563-2.156-2.594-3.608-3.094-4.357C1.11 12.803.625 11.897.375 11.163S0 9.583 0 8.625C0 7.068.406 5.63 1.219 4.312A8.99 8.99 0 0 1 4.5 1.168C5.875.389 7.375 0 9 0s3.125.39 4.5 1.168a8.99 8.99 0 0 1 3.281 3.144A8.062 8.062 0 0 1 18 8.625c0 .958-.125 1.804-.375 2.538-.25.734-.734 1.64-1.453 2.718-.5.749-1.531 2.201-3.094 4.357l-3.14 4.313c-.22.3-.532.449-.938.449-.406 0-.719-.15-.938-.45ZM9 12.22c1.031 0 1.914-.352 2.648-1.056.735-.704 1.102-1.55 1.102-2.538 0-.988-.367-1.834-1.102-2.538C10.914 5.383 10.031 5.03 9 5.03c-1.031 0-1.914.352-2.648 1.056-.735.704-1.102 1.55-1.102 2.538 0 .988.367 1.834 1.102 2.538.734.704 1.617 1.056 2.648 1.056Z\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__title h4\">Lausanne Zentrum<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__info\">\n\t\t\t\t\t\t\t\t\t<div class=\"reviews\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rating\">4.6<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stars\"><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-half\"><\/use><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews-count\">93 reviews<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"more-info\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/klinik\/lausanne-centre\/\" class=\"inline-link inline-link--dark\">Mehr Infos<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/formulaire-zawin\/?id=4229&#038;code=https:\/\/oa.zawin.ch\/fr-CH\/k6155_01\" class=\"primary-btn book\">Termin vereinbaren<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card \">\n\t\t\t\t\t\t\t<div class=\"clinique-card__pic\">\n\t\t\t\t\t\t\t\t<div class=\"card-tags\">\n\t\t\t\t\t\t\t\t\t<div class=\"card-tag\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1.781 10.172a9 9 0 1 0 18 0 9 9 0 0 0-18 0Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M10.781 5.172v5l3 3\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t<span>Ouvert<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/04\/adent-clinique-dentaire-ecublens-septembre-2019-106-1469x980.jpg\" alt=\"\" loading=\"lazy\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"clinique-card__caption\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__contact\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__phone\">\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"25\" fill=\"none\" viewBox=\"0 0 25 25\">\n\t\t\t\t\t\t\t\t\t\t\t\t<path fill=\"currentColor\" d=\"M21.346 13.603c-.262 0-.537-.084-.799-.143a12 12 0 0 1-1.562-.467 2.38 2.38 0 0 0-2.956 1.196l-.262.55a15.7 15.7 0 0 1-3.183-2.39A15.7 15.7 0 0 1 10.2 9.156l.548-.25a2.39 2.39 0 0 0 1.192-2.965 13 13 0 0 1-.465-1.577 9 9 0 0 1-.143-.8 3.6 3.6 0 0 0-1.24-2.15A3.57 3.57 0 0 0 7.756.588H4.167a3.57 3.57 0 0 0-3.54 4.064 22.8 22.8 0 0 0 6.45 13.146 22.7 22.7 0 0 0 13.112 6.465q.233.018.465 0a3.57 3.57 0 0 0 3.577-3.585v-3.585a3.6 3.6 0 0 0-.823-2.26 3.58 3.58 0 0 0-2.062-1.23m.584 7.17a1.197 1.197 0 0 1-1.371 1.184 20.44 20.44 0 0 1-11.766-5.785 20.53 20.53 0 0 1-5.818-11.83 1.198 1.198 0 0 1 1.192-1.375h3.577a1.19 1.19 0 0 1 1.192.932c0 .323.107.657.179.98q.206.94.548 1.84l-1.669.79a1.2 1.2 0 0 0-.62.668 1.2 1.2 0 0 0 0 .909 17.3 17.3 0 0 0 8.345 8.365c.29.12.616.12.906 0 .296-.11.536-.334.668-.621l.75-1.673a14.8 14.8 0 0 0 2.85.729 1.19 1.19 0 0 1 .93 1.195l.107 3.693ZM14.896.458h-.834a1.196 1.196 0 0 0-1.09 1.297 1.2 1.2 0 0 0 1.293 1.093h.631c1.898 0 3.717.756 5.058 2.1a7.18 7.18 0 0 1 2.095 5.07v.634a1.197 1.197 0 0 0 1.085 1.29h.095a1.19 1.19 0 0 0 1.193-1.087v-.836a9.57 9.57 0 0 0-2.79-6.756A9.53 9.53 0 0 0 14.896.457Zm2.385 9.56a1.196 1.196 0 0 0 1.192 1.196 1.19 1.19 0 0 0 1.192-1.195 4.79 4.79 0 0 0-1.397-3.38 4.76 4.76 0 0 0-3.372-1.4 1.19 1.19 0 0 0-1.192 1.194 1.197 1.197 0 0 0 1.192 1.196c.633 0 1.24.251 1.686.7.447.448.699 1.056.699 1.69Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41 21 694 20 00\" class=\"phone h5\">+41 21 694 20 00<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"clinique-card__marker\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"23\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path fill=\"#fff\" d=\"M8.063 22.55a356.86 356.86 0 0 0-3.141-4.312c-1.563-2.156-2.594-3.608-3.094-4.357C1.11 12.803.625 11.897.375 11.163S0 9.583 0 8.625C0 7.068.406 5.63 1.219 4.312A8.99 8.99 0 0 1 4.5 1.168C5.875.389 7.375 0 9 0s3.125.39 4.5 1.168a8.99 8.99 0 0 1 3.281 3.144A8.062 8.062 0 0 1 18 8.625c0 .958-.125 1.804-.375 2.538-.25.734-.734 1.64-1.453 2.718-.5.749-1.531 2.201-3.094 4.357l-3.14 4.313c-.22.3-.532.449-.938.449-.406 0-.719-.15-.938-.45ZM9 12.22c1.031 0 1.914-.352 2.648-1.056.735-.704 1.102-1.55 1.102-2.538 0-.988-.367-1.834-1.102-2.538C10.914 5.383 10.031 5.03 9 5.03c-1.031 0-1.914.352-2.648 1.056-.735.704-1.102 1.55-1.102 2.538 0 .988.367 1.834 1.102 2.538.734.704 1.617 1.056 2.648 1.056Z\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__title h4\">Ecublens<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__info\">\n\t\t\t\t\t\t\t\t\t<div class=\"reviews\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rating\">4.5<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stars\"><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-half\"><\/use><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews-count\">290 reviews<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"more-info\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/klinik\/ecublens\/\" class=\"inline-link inline-link--dark\">Mehr Infos<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/formulaire-zawin\/?id=4243&#038;code=https:\/\/oa.zawin.ch\/k1538_01\t\t\t\" class=\"primary-btn book\">Termin vereinbaren<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card \">\n\t\t\t\t\t\t\t<div class=\"clinique-card__pic\">\n\t\t\t\t\t\t\t\t<div class=\"card-tags\">\n\t\t\t\t\t\t\t\t\t<div class=\"card-tag\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"21\" height=\"21\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M1.781 10.172a9 9 0 1 0 18 0 9 9 0 0 0-18 0Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<path stroke=\"#69BE28\" stroke-linecap=\"round\" stroke-linejoin=\"round\" stroke-width=\"2\" d=\"M10.781 5.172v5l3 3\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t<span>Ouvert<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/11\/b07a0254_v2-866x980.jpg\" alt=\"\" loading=\"lazy\">\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"clinique-card__caption\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__contact\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"clinique-card__phone\">\n\t\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"25\" fill=\"none\" viewBox=\"0 0 25 25\">\n\t\t\t\t\t\t\t\t\t\t\t\t<path fill=\"currentColor\" d=\"M21.346 13.603c-.262 0-.537-.084-.799-.143a12 12 0 0 1-1.562-.467 2.38 2.38 0 0 0-2.956 1.196l-.262.55a15.7 15.7 0 0 1-3.183-2.39A15.7 15.7 0 0 1 10.2 9.156l.548-.25a2.39 2.39 0 0 0 1.192-2.965 13 13 0 0 1-.465-1.577 9 9 0 0 1-.143-.8 3.6 3.6 0 0 0-1.24-2.15A3.57 3.57 0 0 0 7.756.588H4.167a3.57 3.57 0 0 0-3.54 4.064 22.8 22.8 0 0 0 6.45 13.146 22.7 22.7 0 0 0 13.112 6.465q.233.018.465 0a3.57 3.57 0 0 0 3.577-3.585v-3.585a3.6 3.6 0 0 0-.823-2.26 3.58 3.58 0 0 0-2.062-1.23m.584 7.17a1.197 1.197 0 0 1-1.371 1.184 20.44 20.44 0 0 1-11.766-5.785 20.53 20.53 0 0 1-5.818-11.83 1.198 1.198 0 0 1 1.192-1.375h3.577a1.19 1.19 0 0 1 1.192.932c0 .323.107.657.179.98q.206.94.548 1.84l-1.669.79a1.2 1.2 0 0 0-.62.668 1.2 1.2 0 0 0 0 .909 17.3 17.3 0 0 0 8.345 8.365c.29.12.616.12.906 0 .296-.11.536-.334.668-.621l.75-1.673a14.8 14.8 0 0 0 2.85.729 1.19 1.19 0 0 1 .93 1.195l.107 3.693ZM14.896.458h-.834a1.196 1.196 0 0 0-1.09 1.297 1.2 1.2 0 0 0 1.293 1.093h.631c1.898 0 3.717.756 5.058 2.1a7.18 7.18 0 0 1 2.095 5.07v.634a1.197 1.197 0 0 0 1.085 1.29h.095a1.19 1.19 0 0 0 1.193-1.087v-.836a9.57 9.57 0 0 0-2.79-6.756A9.53 9.53 0 0 0 14.896.457Zm2.385 9.56a1.196 1.196 0 0 0 1.192 1.196 1.19 1.19 0 0 0 1.192-1.195 4.79 4.79 0 0 0-1.397-3.38 4.76 4.76 0 0 0-3.372-1.4 1.19 1.19 0 0 0-1.192 1.194 1.197 1.197 0 0 0 1.192 1.196c.633 0 1.24.251 1.686.7.447.448.699 1.056.699 1.69Z\" \/>\n\t\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41 21 653 55 50\" class=\"phone h5\">+41 21 653 55 50<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\" class=\"clinique-card__marker\">\n\t\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"23\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t\t<path fill=\"#fff\" d=\"M8.063 22.55a356.86 356.86 0 0 0-3.141-4.312c-1.563-2.156-2.594-3.608-3.094-4.357C1.11 12.803.625 11.897.375 11.163S0 9.583 0 8.625C0 7.068.406 5.63 1.219 4.312A8.99 8.99 0 0 1 4.5 1.168C5.875.389 7.375 0 9 0s3.125.39 4.5 1.168a8.99 8.99 0 0 1 3.281 3.144A8.062 8.062 0 0 1 18 8.625c0 .958-.125 1.804-.375 2.538-.25.734-.734 1.64-1.453 2.718-.5.749-1.531 2.201-3.094 4.357l-3.14 4.313c-.22.3-.532.449-.938.449-.406 0-.719-.15-.938-.45ZM9 12.22c1.031 0 1.914-.352 2.648-1.056.735-.704 1.102-1.55 1.102-2.538 0-.988-.367-1.834-1.102-2.538C10.914 5.383 10.031 5.03 9 5.03c-1.031 0-1.914.352-2.648 1.056-.735.704-1.102 1.55-1.102 2.538 0 .988.367 1.834 1.102 2.538.734.704 1.617 1.056 2.648 1.056Z\" \/>\n\t\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__title h4\">Epalinges<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__info\">\n\t\t\t\t\t\t\t\t\t<div class=\"reviews\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rating\">4.6<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"stars\"><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-half\"><\/use><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews-count\">10 reviews<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"more-info\">\n\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/klinik\/epalinges\/\" class=\"inline-link inline-link--dark\">Mehr Infos<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"clinique-card__footer\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/formulaire-zawin\/?id=9799&#038;code=https:\/\/oa.zawin.ch\/fr-CH\/k4096_01\" class=\"primary-btn book\">Termin vereinbaren<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t\t\t\t<\/div>\n<\/div>\n\n<div class=\"one-column-block\" >\n\t<div class=\"container\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-md-8\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"h2\">Vous \u00eates \u00e0 la recherche d&#8217;un orthodontiste \u00e0 Lausanne ?<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"content\"><p>Nos cabinets d&#8217;orthodontie \u00e0 Lausanne vous re\u00e7oivent 6 jours sur 7 pour une gamme compl\u00e8te de traitements orthodontiques. Chacune de nos cliniques est ais\u00e9ment accessible par les transports en commun et b\u00e9n\u00e9ficie de places de stationnement \u00e0 proximit\u00e9.<\/p>\n<p>R\u00e9parties dans le district de Lausanne, choisissez la clinique d&#8217;orthodontie la plus accessible, que cela soit \u00e0 <a href=\"https:\/\/adent.ch\/clinique\/lausanne-gare\/\">Lausanne Gare<\/a>, <a href=\"https:\/\/adent.ch\/clinique\/lausanne-centre\/\">Lausanne Saint-Fran\u00e7ois<\/a>, <a href=\"https:\/\/adent.ch\/clinique\/lausanne-blecherette-2\/\">Lausanne Bl\u00e9cherette<\/a>, <a href=\"https:\/\/adent.ch\/clinique\/epalinges\/\">Epalinges<\/a>, <a href=\"https:\/\/adent.ch\/clinique\/ecublens\/\">Ecublens<\/a>, chaque orthodontiste et expert.e en soins dentaires offre des traitements adapt\u00e9s, assurant la sant\u00e9 et l&#8217;\u00e9clat de votre sourire, pour enfants et adultes.<\/p>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"accordion-block\">\n\t<div class=\"container\">\n\t\t<h3 class=\"h2\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">Quelles pathologies n\u00e9cessitent un traitement orthodontique ?<\/h3>\n\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"col-lg-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Malocclusions dentaires<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Il s&#8217;agit d&#8217;une mauvaise position des dents lorsque les arcades dentaires ne s&#8217;embo\u00eetent pas correctement. Non trait\u00e9es, elles peuvent augmenter le risque de d\u00e9velopper des douleurs articulaires et avoir un impact n\u00e9gatif sur la mastication et la phon\u00e9tique. Les malocclusions sont class\u00e9es en plusieurs types :<\/p>\n<ul>\n<li>Malocclusion de classe 1 : Occlusion normale mais avec des probl\u00e8mes d&#8217;alignement comme l&#8217;encombrement dentaire ou le diast\u00e8me.<\/li>\n<li>Malocclusion de classe 2 : La m\u00e2choire sup\u00e9rieure est trop avanc\u00e9e et\/ou la m\u00e2choire inf\u00e9rieure est trop recul\u00e9e.<\/li>\n<li>Malocclusion de classe 3 : La m\u00e2choire sup\u00e9rieure est trop recul\u00e9e ou la m\u00e2choire inf\u00e9rieure est trop avanc\u00e9e.<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Probl\u00e8mes d&#8217;espace et de croissance des m\u00e2choires<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Une m\u00e2choire trop \u00e9troite peut mener \u00e0 plusieurs probl\u00e9matiques : espace insuffisant pour l&#8217;\u00e9ruption des dents d\u00e9finitives, fermeture incorrecte de la bouche qui peut mener \u00e0 des probl\u00e9matiques \u00e0 la respiration (respiration orale) et \u00e0 la d\u00e9glutition (d\u00e9glutition atypique).<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Probl\u00e8mes comportementaux<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Sucer son pouce ou pousser ses dents avec la langue peut alt\u00e9rer la position des dents et la forme de la m\u00e2choire\u200b.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Traumatismes et anomalies g\u00e9n\u00e9tiques<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Des accidents affectant les dents ou la m\u00e2choire, ou des anomalies h\u00e9rit\u00e9es des parents peuvent \u00e9galement n\u00e9cessiter un traitement orthodontique.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Autres probl\u00e9matiques orthodontiques<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><ul>\n<li><strong>B\u00e9ances<\/strong> : Situation o\u00f9 il n&#8217;y a pas de contact entre les dents sup\u00e9rieures et inf\u00e9rieures lorsqu&#8217;on ferme la bouche.<\/li>\n<li><strong>Manque de place et malpositions dentaires<\/strong> : Quand il n&#8217;y a pas assez d&#8217;espace dans la m\u00e2choire pour toutes les dents, ce qui entra\u00eene un alignement incorrect.<\/li>\n<li><strong>Exc\u00e8s d&#8217;espace entre les dents<\/strong> : Contraire au manque de place, trop d&#8217;espace peut \u00eatre pr\u00e9sent entre les dents.<\/li>\n<li><strong>Supraclusion s\u00e9v\u00e8re<\/strong> : Les dents sup\u00e9rieures recouvrent trop les dents inf\u00e9rieures lors de la fermeture de la bouche.<\/li>\n<li><strong>Canines incluses<\/strong> : Canines qui ne peuvent pas \u00e9merger normalement et restent bloqu\u00e9es dans la m\u00e2choire.<\/li>\n<li><strong>Espaces excessifs<\/strong> : Grands espaces entre les dents qui emp\u00eachent l&#8217;\u00e9ruption normale des canines.<\/li>\n<li><strong>Molaires d\u00e9finitives bloqu\u00e9es<\/strong> : Quand une molaire adulte ne peut pas \u00e9merger car une molaire de lait n&#8217;est pas tomb\u00e9e.<\/li>\n<li><strong>Ag\u00e9n\u00e9sies dentaires<\/strong> : Absence cong\u00e9nitale d&#8217;une ou plusieurs dents.<\/li>\n<li><strong>Dents surnum\u00e9raires<\/strong> : Pr\u00e9sence de dents en exc\u00e8s dans la m\u00e2choire.<\/li>\n<\/ul>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-3 mt-md-5\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-content\">\n\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/professionnels\/nos-metiers-specialises\/\" class=\"primary-btn\">En savoir plus sur nos dentistes<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"one-column-block\" >\n\t<div class=\"container\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t<div class=\"row justify-content-center\">\n\t\t\t<div class=\"col-md-8\">\n\t\t\t\t\t\t\t\t\t<h3 class=\"h2\">Besoin d&#8217;un cabinet d&#8217;orthodontie \u00e0 Lausanne ?<\/h3>\n\t\t\t\t\t\t\t\t<div class=\"content\"><p>Chez Adent Cliniques Dentaires, nous consid\u00e9rons l&#8217;orthodontie non seulement comme une porte vers un sourire esth\u00e9tiquement plaisant mais \u00e9galement comme un moyen essentiel d&#8217;am\u00e9liorer la sant\u00e9 bucco-dentaire sur le long terme. Notre approche est fond\u00e9e sur un accompagnement personnalis\u00e9 et l&#8217;usage des technologies les plus pointues pour assurer des r\u00e9sultats qui vont bien au-del\u00e0 de l&#8217;esth\u00e9tique.<\/p>\n<h4>L&#8217;Orthodontie pour enfants \u00e0 Lausanne<\/h4>\n<p>Pour les plus jeunes, un parcours orthodontique pr\u00e9coce s&#8217;av\u00e8re souvent b\u00e9n\u00e9fique. D\u00e8s l&#8217;\u00e2ge de 6 ans, nous accueillons les enfants pour un premier examen orthodontique. Cette \u00e9valuation anticip\u00e9e permet d&#8217;identifier et de traiter les malocclusions naissantes, profitant ainsi de la croissance pour guider le d\u00e9veloppement d&#8217;un sourire harmonieux. Cette prise en charge en amont facilite les corrections futures et soutient un d\u00e9veloppement sain des dents et des m\u00e2choires.<\/p>\n<p>Les traitements chez les enfants peuvent varier de simples appareils amovibles pour corriger des habitudes orales, \u00e0 des dispositifs plus complexes pour redresser les dents et les m\u00e2choires. Chaque solution est choisie avec soin pour son efficacit\u00e9 et son impact positif sur la confiance de l&#8217;enfant.<\/p>\n<h4>L&#8217;orthodontie pour adultes \u00e0 Lausanne<\/h4>\n<p>Les adultes b\u00e9n\u00e9ficient eux aussi de notre expertise en orthodontie. Avec des solutions comme la technique Invisalign\u00ae, l&#8217;orthodontie adulte se fait discr\u00e8te et s&#8217;int\u00e8gre parfaitement au style de vie de chacun. Ces m\u00e9thodes avanc\u00e9es permettent de corriger les sourires de mani\u00e8re presque imperceptible, offrant ainsi une nouvelle assurance \u00e0 ceux qui souhaitent harmoniser leur sourire sans compromettre leur apparence.<\/p>\n<p>Que ce soit pour rectifier une m\u00e2choire trop avanc\u00e9e ou aligner des dents qui se chevauchent, nos sp\u00e9cialistes \u00e9laborent des plans de traitement sur mesure. Ainsi, chaque patient adulte retrouve non seulement l&#8217;esth\u00e9tique souhait\u00e9e mais aussi une fonctionnalit\u00e9 am\u00e9lior\u00e9e, essentielle pour une mastication correcte et une meilleure sant\u00e9 bucco-dentaire.<\/p>\n<h4>Les bienfaits de l&#8217;orthodontie<\/h4>\n<p>L&#8217;orthodontie va bien au-del\u00e0 d&#8217;un sourire &#8220;parfait&#8221;. Un alignement correct des dents facilite le nettoyage, r\u00e9duit le risque de caries et de maladies parodontales, et permet une mastication plus efficace. Ces am\u00e9liorations se traduisent par une r\u00e9duction de la plaque dentaire, une meilleure digestion et une diminution des douleurs li\u00e9es aux mauvaises positions dentaires ou \u00e0 la m\u00e2choire.<\/p>\n<p>Notre engagement est de fournir un service qui refl\u00e8te la qualit\u00e9, l&#8217;attention et le soin que m\u00e9rite votre sourire. Chez Adent, chaque sourire est le d\u00e9but d&#8217;une histoire de bien-\u00eatre et de confiance en soi.<\/p>\n<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t<div class=\"cta-block without-image\" >\n\t\t<div class=\"container\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"row justify-content-center\">\n\t\t\t\t<div class=\"col-md-8\">\n\t\t\t\t\t<div class=\"subtitle\"><\/div>\n\t\t\t\t\t<h4 class=\"title\">Sublimez votre sourire, osez l&#8217;excellence en orthodontie \u00e0 Lausanne<\/h4>\n\t\t\t\t\t<p class=\"text\">Prenez rendez-vous avec un.e orthodontiste \u00e0 Lausanne et discutez ensemble des soins possibles pour aligner vos dents.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/dentiste-lausanne-2\/\"  class=\"primary-btn\">Contactez-nous<\/a>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n<div class=\"accordion-block\">\n\t<div class=\"container\">\n\t\t<h3 class=\"h2\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">FAQ &#8211; Orthodontie \u00e0 Lausanne<\/h3>\n\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"col-lg-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Combien co\u00fbte un traitement orthodontique \u00e0 Lausanne ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>La d\u00e9termination pr\u00e9cise du tarif d&#8217;un soin orthodontique s&#8217;effectue suite \u00e0 une consultation d\u00e9taill\u00e9e au cabinet d&#8217;orthodontie Adent \u00e0 Lausanne. Co\u00fbt de la premi\u00e8re consultation : d\u00e8s CH 119-.<\/p>\n<p>Cette \u00e9valuation compl\u00e8te est r\u00e9alis\u00e9e dans nos locaux, sous le regard expert de nos sp\u00e9cialistes. Votre orthodontiste ou m\u00e9decin dentiste sp\u00e9cialis\u00e9 en orthodontie \u00e9value la situation globale de votre sant\u00e9 buccale, appuy\u00e9 par des images radiographiques si n\u00e9cessaires, afin d&#8217;\u00e9laborer un diagnostic exhaustif.<\/p>\n<p>Lors de cet \u00e9change, les diff\u00e9rentes options th\u00e9rapeutiques sont explor\u00e9es et un objectif de traitement est \u00e9tabli conjointement. C&#8217;est sur la base de cette consultation approfondie que le co\u00fbt de votre parcours orthodontique sera \u00e9tabli, en prenant en compte des \u00e9l\u00e9ments tels que la m\u00e9thode de traitement choisie, la dur\u00e9e envisag\u00e9e du traitement, l&#8217;\u00e9tat actuel de vos dents et la vision de l&#8217;aboutissement souhait\u00e9.<\/p>\n<p>L&#8217;\u00e9laboration du plan financier fait partie int\u00e9grante de la discussion avec votre orthodontiste Adent, assurant une transparence et une personnalisation du traitement.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Quel d\u00e9lai pour un rendez-vous avec un orthodontiste \u00e0 Lausanne ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Peu importe votre emploi du temps, notre \u00e9quipe d&#8217;accueil s&#8217;engage \u00e0 vous proposer un cr\u00e9neau pour une consultation, profitant de l&#8217;ouverture de notre clinique six jours sur sept.<\/p>\n<p>Gr\u00e2ce \u00e0 cette amplitude horaire \u00e9tendue, nous sommes en mesure de r\u00e9pondre efficacement et rapidement \u00e0 toute situation.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-3 mt-md-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"content-type-selector-block\" data-id=\"content-type-selector-block-70\" id=\"content-type-selector-block-70\">\n\t<div class=\"container\">\n\t\t<div class=\"block-heading\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t<h3 class=\"block-heading__title h2\">Nos orthodontistes \u00e0 Lausanne<\/h3>\n\t\t\t<div class=\"block-heading__description\">Une \u00e9quipe professionnelle et chaleureuse pr\u00eate \u00e0 vous accueillir dans l&#8217;une de nos cabinets d&#8217;orthodontie Adent de Lausanne.<\/div>\n\t\t<\/div>\n\t\t<div class=\"content-type-slider\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"swiper\"><div class=\"swiper-wrapper\">\t\t\t\t\t\t\t<div class=\"swiper-slide\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"equipe-card\">\n\t\t\t\t\t\t\t<div class=\"equipe-card__caption\">\n\t\t\t\t\t\t\t\t<div class=\"equipe-card__job\">Kieferorthop\u00e4de<\/div>\n\t\t\t\t\t\t\t\t<h6 class=\"equipe-card__name h3\">Kenan DIAB<\/h6>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"equipe-card__description\"><p>Zahnarzt, der kieferorthop\u00e4dische Behandlung in vollem Umfang anbietet.<\/p>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"equipe-card__pic\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/05\/vignettes-photo-praticien-site-web-12-1307x980.png\" alt=\"Kenan Diab\" loading=\"lazy\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"equipe-card__footer\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/zahnarzt\/kenan-diab\/\" class=\"primary-btn\">Profil ansehen<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\t\t\t\t\t\t<\/div><\/div><div class=\"swiper-button-prev\"><\/div><div class=\"swiper-button-next\"><\/div>\t\t<\/div>\n\t\t<div class=\"content-type-slider-slider-pagination\"><\/div>\t\t\t<\/div>\n<\/div>\n\n\t<div class=\"pics-gallery\" id=\"gallery-3\" data-id=\"gallery-3\">\n\t\t<div class=\"pics-slider\">\n\t\t\t<div class=\"swiper\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure class=\"pics-slider__item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"image\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_lausanne-gare_2_map_1024x768.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure class=\"pics-slider__item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"image\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_lausanne_centre_2_banner.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure class=\"pics-slider__item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"image\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_lausanne-blecherette_1_map_1024x768.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure class=\"pics-slider__item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"image\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_thoune_map_1024x768.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure class=\"pics-slider__item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"image\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2023\/01\/adent-clinique-dentaire-ecublens-septembre-2019-54-1-1467x980.jpg\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t<figure class=\"pics-slider__item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"pics-slider-pagination\"><\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<div class=\"cares-list-block\" >\n\t<div class=\"container\">\n\t\t<div class=\"row\">\n\t\t\t<div class=\"col-md-4\">\n\t\t\t\t<h2 class=\"title h3\">Entdecken Sie unsere Pflege<\/h2>\n\t\t\t\t<div class=\"text-lg is-dark\">Unsere Zahn\u00e4rzte und Dentalhygienikerinnen sind dazu da, all Ihre Bed\u00fcrfnisse in Bezug auf die Zahnpflege zu erf\u00fcllen. Bitte kontaktieren Sie uns f\u00fcr weitere Informationen.<\/div>\n\t\t\t\t<div class=\"cares-list-slider-pagination\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"col-md-8\">\n\t\t\t\t<div class=\"cares-list-slider\">\n\t\t\t\t\t<div class=\"swiper\">\n\t\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">Kieferorthop\u00e4die f\u00fcr Kinder und Erwachsene<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Verwandeln Sie Ihr L\u00e4cheln<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/kieferorthopaedie-fuer-kinder-und-erwachsene\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">Zahnreinigung und Zahnhygiene<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Ein gesund aussehendes L\u00e4cheln<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnsteinentfernung-und-zahnhygiene\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">Bleaching und \u00e4sthetische Behandlungen<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Ein noch strahlenderes L\u00e4cheln f\u00fcr maximales Selbstvertrauen<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbleaching-und-aesthetisch-e-en-behandlungen\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">\u00dcbliche Zahnpflege<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Ein umfassendes Kompetenzzentrum f\u00fcr Sie und Ihre Kinder<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnaerztliche-routineversorgung\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">Zahnpflege f\u00fcr Kinder<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Angepasstes Know-how<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/zahnbehandlung-fuer-kinder\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">Zahnprothese<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Geben Sie Ihrem L\u00e4cheln seinen Glanz zur\u00fcck mit unseren massgeschneiderten Zahnprothesen.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/implantate-und-zahnsanierung\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"care-slide\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__title h4\">Implantat und Restauration<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__desc\">Komfort und \u00c4sthetik dank Zahnimplantaten<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"care-slide__link\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/de\/behandlung\/implantat-und-restauration\/\" class=\"inline-link\">Weiterlesen<\/a>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":10607,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12031","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":{"short_description":"Nos cliniques dentaires de Lausanne accueillent 6j\/7 adultes et enfants en 14 langues. ","display_banner":true,"banner_bgd_type":"empty","banner_buttons":false,"banner_subtitle":"Adent Cliniques Dentaires","banner_title":"Nos cliniques orthodontiques \u00e0 Lausanne","banner_title_color":"white","banner_details":"<p>Le Groupe Adent vous accueille au sein de ces 5 cliniques \u00e0 Lausanne, tous accessibles via les transports en commun. Choisissez la localisation qui vous convient le mieux, que ce soit en centre-ville ou en p\u00e9riph\u00e9rie.<\/p>\n","display_shapes":false},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orthodondistes \u00e0 Lausanne | Adent Zahnarztzentrum<\/title>\n<meta name=\"description\" content=\"5 cliniques d\u2019orthodondistes Adent \u00e0 Lausanne 6j\/7. Transformez votre sourire ! Orthondondiste enfants et adultes. RDV rapide en ligne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orthodondistes \u00e0 Lausanne | Adent Zahnarztzentrum\" \/>\n<meta property=\"og:description\" content=\"5 cliniques d\u2019orthodondistes Adent \u00e0 Lausanne 6j\/7. Transformez votre sourire ! Orthondondiste enfants et adultes. RDV rapide en ligne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Zahnarztzentrum\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-23T15:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2023\/01\/adent-clinique-dentaire-ecublens-septembre-2019-54-1467x980.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1467\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/\",\"name\":\"Orthodondistes \u00e0 Lausanne | Adent Zahnarztzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/adent-clinique-dentaire-ecublens-septembre-2019-54.jpg\",\"datePublished\":\"2023-11-06T12:44:08+00:00\",\"dateModified\":\"2025-04-23T15:00:54+00:00\",\"description\":\"5 cliniques d\u2019orthodondistes Adent \u00e0 Lausanne 6j\\\/7. Transformez votre sourire ! Orthondondiste enfants et adultes. RDV rapide en ligne.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/adent-clinique-dentaire-ecublens-septembre-2019-54.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/adent-clinique-dentaire-ecublens-septembre-2019-54.jpg\",\"width\":2246,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/orthodontiste-lausanne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adent.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos cliniques orthodontiques \u00e0 Lausanne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"name\":\"Adent Zahnarztzentrum\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orthodondistes \u00e0 Lausanne | Adent Zahnarztzentrum","description":"5 cliniques d\u2019orthodondistes Adent \u00e0 Lausanne 6j\/7. Transformez votre sourire ! Orthondondiste enfants et adultes. RDV rapide en ligne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/","og_locale":"de_DE","og_type":"article","og_title":"Orthodondistes \u00e0 Lausanne | Adent Zahnarztzentrum","og_description":"5 cliniques d\u2019orthodondistes Adent \u00e0 Lausanne 6j\/7. Transformez votre sourire ! Orthondondiste enfants et adultes. RDV rapide en ligne.","og_url":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/","og_site_name":"Adent Zahnarztzentrum","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2025-04-23T15:00:54+00:00","og_image":[{"width":1467,"height":980,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2023\/01\/adent-clinique-dentaire-ecublens-septembre-2019-54-1467x980.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/","url":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/","name":"Orthodondistes \u00e0 Lausanne | Adent Zahnarztzentrum","isPartOf":{"@id":"https:\/\/adent.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/#primaryimage"},"image":{"@id":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/#primaryimage"},"thumbnailUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2023\/01\/adent-clinique-dentaire-ecublens-septembre-2019-54.jpg","datePublished":"2023-11-06T12:44:08+00:00","dateModified":"2025-04-23T15:00:54+00:00","description":"5 cliniques d\u2019orthodondistes Adent \u00e0 Lausanne 6j\/7. Transformez votre sourire ! Orthondondiste enfants et adultes. RDV rapide en ligne.","breadcrumb":{"@id":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/de\/orthodontiste-lausanne\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/#primaryimage","url":"https:\/\/adent.ch\/wp-content\/uploads\/2023\/01\/adent-clinique-dentaire-ecublens-septembre-2019-54.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2023\/01\/adent-clinique-dentaire-ecublens-septembre-2019-54.jpg","width":2246,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/de\/orthodontiste-lausanne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adent.ch\/de\/"},{"@type":"ListItem","position":2,"name":"Nos cliniques orthodontiques \u00e0 Lausanne"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/de\/#website","url":"https:\/\/adent.ch\/de\/","name":"Adent Zahnarztzentrum","description":"","publisher":{"@id":"https:\/\/adent.ch\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Organization","@id":"https:\/\/adent.ch\/de\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/pages\/12031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/comments?post=12031"}],"version-history":[{"count":5,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/pages\/12031\/revisions"}],"predecessor-version":[{"id":15467,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/pages\/12031\/revisions\/15467"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media\/10607"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/de\/wp-json\/wp\/v2\/media?parent=12031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}