{"id":13016,"date":"2024-07-03T16:24:15","date_gmt":"2024-07-03T14:24:15","guid":{"rendered":"https:\/\/adent.ch\/?page_id=13016"},"modified":"2024-11-26T15:42:14","modified_gmt":"2024-11-26T14:42:14","slug":"vevey","status":"publish","type":"page","link":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/","title":{"rendered":"Urgences dentaires Vevey"},"content":{"rendered":"\n<div class=\"clinique-datas\" id=\"clinique-datas\">\n\t<div class=\"flex-content\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\n\t\t<div class=\"datas\">\n\t\t\t\t\t\t\t<div class=\"address-container\">\n\t\t\t\t\t<svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#pin\"><\/use><\/svg>\t\t\t\t\t<div class=\"address\">\n\t\t\t\t\t\tRue du Panorama 16<br\/>1800 Vevey\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"phone-container\">\n\t\t\t\t\t<svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#phone\"><\/use><\/svg>\t\t\t\t\t<a href=\"tel:+41 21 921 55 88\" class=\"phone\">+41 21 921 55 88<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"email-container\">\n\t\t\t\t\t<svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#envelop\"><\/use><\/svg>\t\t\t\t\t<a href=\"mailto:vevey@adent.ch\" class=\"email\">vevey@adent.ch<\/a>\n\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"buttons\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/en\/formulaire-zawin\/?id=8158&#038;code=https:\/\/oa.zawin.ch\/fr-CH\/k4355_01\" class=\"primary-btn white\">Appointment<\/a>\n\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/en\/dental-emergencies\/?location=228\" class=\"secondary-btn\">Emergencies<\/a>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"separator\"><\/div>\n\n\t\t\t<div class=\"access-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"access bus\">\n\t\t\t\t\t\t<svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#bus\"><\/use><\/svg>\t\t\t\t\t\t<div class=\"access-content\">\n\t\t\t\t\t\t\tVMCV bus, stop &#8220;H\u00f4tel de Ville&#8221;\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"access train\">\n\t\t\t\t\t\t<svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#subway\"><\/use><\/svg>\t\t\t\t\t\t<div class=\"access-content\">\n\t\t\t\t\t\t\t5 min walk from Vevey train station\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"access parking\">\n\t\t\t\t\t\t<svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#parking\"><\/use><\/svg>\t\t\t\t\t\t<div class=\"access-content\">\n\t\t\t\t\t\t\tParking Vieille Ville or parking du Simplon\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"separator second\"><\/div>\n\n\t\t\t\t\t<div class=\"schedule-container\">\n\t\t\t\t\t\t<div class=\"title\">Opening hours<\/div>\n\t\t\t\t\t\t<div class=\"description\"><\/div>\n\t\t\t\t\t\t<div class=\"schedule\">\n\t\t\t\t\t\t\t<b>monday<\/b> : 08:00 &#8211; 18:00<br><b>tuesday<\/b> : 08:00 &#8211; 18:00<br><b>wednesday<\/b> : 08:00 &#8211; 18:00<br><b>thursday<\/b> : 08:00 &#8211; 18:00<br><b>friday<\/b> : 08:00 &#8211; 18:00<br><b>saturday<\/b> : Closed<br><b>sunday<\/b> : Closed<br>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t<div class=\"google-map-container\">\n\t\t\t<div class=\"google-map\"><\/div>\n\t\t\t<div class=\"google-map-markers\">\n\t\t\t\t<div class=\"marker active\" data-lat=\"46.4601529\" data-lng=\"6.8473123\">\n\t\t\t\t\t<div class=\"marker-content\">\n\t\t\t\t\t\t<div class=\"marker-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"image\" style=\"background-image: url(https:\/\/adent.ch\/wp-content\/uploads\/2022\/08\/adent-clinique-dentaire-ecublens-septembre-2019-59-e1659446198707-300x200.jpg)\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"rating\">4.3<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"stars\"><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-full\"><\/use><\/svg><svg class=\"icon\" aria-hidden=\"true\"><use href=\"https:\/\/adent.ch\/wp-content\/themes\/adent\/assets\/icons\/dist\/sprite.svg?v=5.0.1#star-half\"><\/use><\/svg><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"reviews-count\">24 reviews<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"marker-right\">\n\t\t\t\t\t\t\t<div class=\"subtitle\">Adent Dental Clinic<\/div>\n\t\t\t\t\t\t\t<div class=\"name\">Vevey<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+41 21 921 55 88\" class=\"phone\">\n\t\t\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"25\" fill=\"none\">\n\t\t\t\t\t\t\t\t\t\t<path fill=\"#69BE28\" d=\"M21.344 13.604c-.262 0-.537-.084-.799-.144a11.737 11.737 0 0 1-1.562-.466 2.379 2.379 0 0 0-2.956 1.195l-.262.55a15.706 15.706 0 0 1-3.183-2.39 15.738 15.738 0 0 1-2.384-3.191l.548-.251a2.396 2.396 0 0 0 1.192-2.964 12.525 12.525 0 0 1-.465-1.578 9.377 9.377 0 0 1-.143-.8 3.587 3.587 0 0 0-1.24-2.15A3.57 3.57 0 0 0 7.754.59H4.165a3.569 3.569 0 0 0-3.54 4.063 22.812 22.812 0 0 0 6.45 13.146 22.712 22.712 0 0 0 13.113 6.466c.154.012.31.012.465 0a3.571 3.571 0 0 0 3.576-3.585v-3.586a3.59 3.59 0 0 0-.823-2.26 3.575 3.575 0 0 0-2.062-1.23Zm.584 7.17a1.199 1.199 0 0 1-1.37 1.183A20.437 20.437 0 0 1 8.79 16.173 20.528 20.528 0 0 1 2.973 4.342a1.198 1.198 0 0 1 1.192-1.375h3.577a1.19 1.19 0 0 1 1.192.932c0 .323.107.658.179.98.138.626.32 1.242.548 1.84l-1.669.79c-.287.132-.51.372-.62.669-.119.29-.119.617 0 .908a17.296 17.296 0 0 0 8.345 8.366c.29.12.616.12.906 0 .296-.11.536-.334.668-.622l.75-1.673a14.758 14.758 0 0 0 2.85.73 1.193 1.193 0 0 1 .93 1.194l.107 3.693ZM14.894.458h-.834a1.195 1.195 0 0 0-1.09 1.296 1.2 1.2 0 0 0 1.293 1.094h.632c1.896 0 3.716.755 5.057 2.1a7.18 7.18 0 0 1 2.095 5.07v.634a1.198 1.198 0 0 0 1.085 1.29h.095a1.19 1.19 0 0 0 1.192-1.087v-.837a9.573 9.573 0 0 0-2.788-6.756A9.525 9.525 0 0 0 14.895.458Zm2.385 9.56a1.197 1.197 0 0 0 1.192 1.195 1.19 1.19 0 0 0 1.192-1.195 4.786 4.786 0 0 0-1.397-3.38 4.762 4.762 0 0 0-3.371-1.4 1.19 1.19 0 0 0-1.193 1.195 1.196 1.196 0 0 0 1.193 1.195c.632 0 1.238.252 1.685.7.448.448.699 1.056.699 1.69Z\"><\/path>\n\t\t\t\t\t\t\t\t\t<\/svg>\n\t\t\t\t\t\t\t\t\t<span>+41 21 921 55 88<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"buttons\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/en\/clinic\/vevey\/\" class=\"primary-btn\">Infos<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.google.com\/maps\/dir\/\/Adent+%7C+Dentiste+Vevey,+Rue+du+Panorama,+Vevey,+Suisse\/@46.4602717,6.7649741,19224m\/data=!3m2!1e3!5s0x478ebceef4127ae9:0x963722fd8f2e670!4m8!4m7!1m0!1m5!1m1!1s0x478e9cce885258d3:0xfac9590cb2a60e0b!2m2!1d6.847375!2d46.460183?entry=ttu&#038;g_ep=EgoyMDI1MDQyOC4wIKXMDSoJLDEwMjExNDUzSAFQAw%3D%3D\" title=\"Google Maps route planner\" target=\"_blank\" class=\"primary-btn\">Itinerary<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/en\/formulaire-zawin\/?id=8158&#038;code=https:\/\/oa.zawin.ch\/fr-CH\/k4355_01\" class=\"primary-btn\">Appointment<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"two-column-block\" >\n\t<div class=\"container\">\n\t\t\t\t\t<h3 class=\"title\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">Quels sympt\u00f4mes signalent qu&#8217;une urgence dentaire doit \u00eatre trait\u00e9e imm\u00e9diatement ?<\/h3>\n\t\t\t\t\t\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Face \u00e0 une <a href=\"https:\/\/adent.ch\/urgences-dentaires\/\">urgence dentaire<\/a>, une action rapide est indispensable pour att\u00e9nuer les douleurs aigu\u00ebs ou pr\u00e9venir d&#8217;\u00e9ventuelles complications. Adent Cliniques Dentaires met l&#8217;accent sur l&#8217;importance de ne pas n\u00e9gliger ces alertes :<\/p>\n<ul>\n<li><strong>Douleur aigu\u00eb<\/strong> : Un soin imm\u00e9diat est essentiel pour soulager la douleur.<\/li>\n<li><strong>Traumatisme dentaire<\/strong> : Une dent endommag\u00e9e par un impact ou d\u00e9tach\u00e9e n\u00e9cessite une intervention rapide pour r\u00e9duire les dommages ou essayer de la r\u00e9tablir.<\/li>\n<li><strong>Infection ou abc\u00e8s<\/strong> : Une inflammation signalant une infection pr\u00e8s d&#8217;une dent ou des gencives requiert un traitement urgent pour stopper l&#8217;infection.<\/li>\n<li><strong>Saignement important<\/strong> : Une v\u00e9rification s&#8217;impose suite \u00e0 une extraction dentaire ou une l\u00e9sion pour pr\u00e9venir les complications.<\/li>\n<li><strong>Probl\u00e8mes de proth\u00e8ses dentaires<\/strong> : Il est n\u00e9cessaire de corriger les proth\u00e8ses ab\u00eem\u00e9es pour \u00e9viter le malaise et maintenir leur efficacit\u00e9.<\/li>\n<\/ul>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-6\">\n\t\t\t\t\t\t\t<div class=\"text-lg\">\n\t\t\t\t\t\t\t\t<p>Face \u00e0 ces signes, contacter sans tarder un professionnel des urgences dentaires est vital.<\/p>\n<p>Adent Cliniques Dentaires dispose des moyens n\u00e9cessaires pour une prise en charge rapide de toute urgence dentaire, visant \u00e0 all\u00e9ger la douleur et l&#8217;inconfort gr\u00e2ce \u00e0 notre approche minutieuse et \u00e0 notre savoir-faire pr\u00e9cis.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"highlight-image-block\" data-id=\"highlight-image-91\" id=\"highlight-image-91\">\n\t<div class=\"container\">\n\t\t\t\t\t<div class=\"h2 title\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">Que faire en situation d&#8217;urgence dentaire ?<\/div>\n\t\t\t\t\t\t\t<div class=\"cards-slider\">\n\t\t\t\t<div class=\"swiper count-4\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"card\">\n\t\t\t\t\t\t\t\t\t<div class=\"card__caption\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"card__title\">Dent cass\u00e9e<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__read-more\" data-read-more>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__desc\"><span data-read-more-short>En cas de dent cass\u00e9e, r\u00e9cup\u00e9rez le fragment et contactez imm\u00e9diatement votre dentiste. Conservez-le dans<span data-read-more-dots>&#8230;<\/span><\/span><span data-read-more-full style=\"display: none;\"> du s\u00e9rum physiologique, votre salive ou du lait. Selon le type de fracture, il est possible de r\u00e9parer la dent. M\u00eame si une fracture ne provoque pas toujours de douleur, il est essentiel de consulter rapidement. Un service d&#8217;urgence dentaire peut intervenir sans d\u00e9lai.\n<\/span>\n                <button class=\"read-more-btn\" data-read-more-toggle data-read-more-less=\"Lire moins\">Read more<\/button><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__pic\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/dent_casser_bleu.svg\" alt=\"Dent cass\u00e9e\" loading=\"lazy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"card\">\n\t\t\t\t\t\t\t\t\t<div class=\"card__caption\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"card__title\">Dent perdue<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__read-more\" data-read-more>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__desc\"><span data-read-more-short>Si vous perdez une dent, cherchez-la imm\u00e9diatement, car une r\u00e9implantation est souvent r\u00e9alisable. Contactez sans<span data-read-more-dots>&#8230;<\/span><\/span><span data-read-more-full style=\"display: none;\"> attendre votre dentiste ou un service d&#8217;urgence, tout en \u00e9vitant de toucher les racines. Mettez la dent dans du s\u00e9rum physiologique, de la salive ou du lait. La perte d&#8217;une dent n\u00e9cessite une prise en charge rapide. Un dentiste d&#8217;Adent \u00e0 Vevey est disponible pour intervenir rapidement, accordant une importance majeure \u00e0 ces cas.\n<\/span>\n                <button class=\"read-more-btn\" data-read-more-toggle data-read-more-less=\"Lire moins\">Read more<\/button><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__pic\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/sourire_dent_perdu_bleu.svg\" alt=\"Dent perdue\" loading=\"lazy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"card\">\n\t\t\t\t\t\t\t\t\t<div class=\"card__caption\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"card__title\">Dent d\u00e9plac\u00e9e<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__read-more\" data-read-more>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__desc\"><span data-read-more-short>Ne manipulez pas la dent et appelez votre dentiste imm\u00e9diatement. Si vous saignez, appliquez une<span data-read-more-dots>&#8230;<\/span><\/span><span data-read-more-full style=\"display: none;\"> compresse sur la zone affect\u00e9e. En cas de douleur forte, appelez tout de suite votre clinique dentaire \u00e0 Vevey pour des recommandations professionnelles. Un dentiste vous guidera durant cette situation difficile. Agir promptement augmente les possibilit\u00e9s de r\u00e9paration et gu\u00e9rison, et notre \u00e9quipe est pr\u00eate \u00e0 vous offrir le soutien requis avec soin.\n<\/span>\n                <button class=\"read-more-btn\" data-read-more-toggle data-read-more-less=\"Lire moins\">Read more<\/button><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__pic\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/sourire_dent_deplacer_bleu.svg\" alt=\"Dent d\u00e9plac\u00e9e\" loading=\"lazy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<div class=\"card\">\n\t\t\t\t\t\t\t\t\t<div class=\"card__caption\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"card__title\">Il n&#8217;y a rien de visible<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__read-more\" data-read-more>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__desc\"><span data-read-more-short>Il est avis\u00e9 de consulter un dentiste m\u00eame sans dommages apparents apr\u00e8s un choc dentaire,<span data-read-more-dots>&#8230;<\/span><\/span><span data-read-more-full style=\"display: none;\"> car des complications peuvent survenir ult\u00e9rieurement. Il est sage de noter les circonstances de l&#8217;accident pour une \u00e9ventuelle couverture d&#8217;assurance. Les urgences dentaires ne se r\u00e9sument pas aux fractures dentaires ou aux abc\u00e8s ; seul un professionnel qualifi\u00e9 chez Adent peut rep\u00e9rer les cons\u00e9quences moins \u00e9videntes d&#8217;un traumatisme dentaire.\n<\/span>\n                <button class=\"read-more-btn\" data-read-more-toggle data-read-more-less=\"Lire moins\">Read more<\/button><\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"card__pic\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/dent_accident_bleu.svg\" alt=\"Il n'y a rien de visible\" loading=\"lazy\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"cards-slider-pagination\"><\/div>\n\t\t\t<\/div>\n<\/div>\n\n<div class=\"accordion-block\">\n\t<div class=\"container\">\n\t\t<h3 class=\"h2\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">FAQ &#8211; Urgences dentaires \u00e0 Vevey<\/h3>\n\t\t<div class=\"row justify-content-between\" data-sal=\"slide-up\" data-sal-delay=\"200\" data-sal-easing=\"ease-in-out\" data-sal-duration=\"300\">\n\t\t\t<div class=\"col-lg-8\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\">Quel est le prix d&#8217;une consultation d&#8217;urgence dentaire \u00e0 Vevey ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Le prix d&#8217;une consultation d&#8217;urgence dentaire \u00e0 Vevey peut fluctuer en fonction de divers \u00e9l\u00e9ments, notamment la nature de l&#8217;urgence, les soins requis et le choix de la clinique. Pour obtenir une estimation pr\u00e9cise, il est pr\u00e9f\u00e9rable de contacter directement la clinique Adent appropri\u00e9e.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\"> Comment trouver un dentiste de garde \u00e0 Vevey en dehors des heures de la clinique ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>Il est est possible d&#8217;obtenir un rendez-vous avec un dentiste de garde \u00e0 Vevey en dehors des heures normales, nos cliniques r\u00e9servent des cr\u00e9neaux sp\u00e9cifiques pour les urgences.<\/p>\n<p>Le service d&#8217;urgence de la Soci\u00e9t\u00e9 Vaudoise des M\u00e9decins dentistes assure une permanence t\u00e9l\u00e9phonique et redirection chez un dentiste de garde 24h\/24<\/p>\n<p><a href=\"tel:0848 13 31 33\">0848 13 31 33<\/a><\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"accordion\">\n\t\t\t\t\t\t\t<h2 class=\"accordion__title\"> Mon dentiste r\u00e9gulier Adent me prendra-t-il en charge en cas d&#8217;urgence dentaire ?<\/h2>\n\t\t\t\t\t\t\t<div class=\"content\"><p>En tant que patient chez Adent, nous nous efforcerons de faire intervenir votre dentiste habituel en cas d&#8217;urgence. Si cela n&#8217;est pas possible, un autre professionnel vous fournira rapidement des soins, tout en assurant le suivi avec votre dentiste r\u00e9gulier.<\/p>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"col-lg-3 mt-md-5\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"button-content\">\n\t\t\t\t\t\t<a href=\"https:\/\/adent.ch\/prise-de-rendez-vous\/\" class=\"primary-btn\">Prendre rendez-vous<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":13,"featured_media":5600,"parent":3162,"menu_order":8,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-13016","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":{"display_banner":true,"banner_title_color":"green","banner_bgd_type":"image","banner_buttons":false,"banner_urgences":{"titre":"Urgences dentaires Gen\u00e8ve","description":"<p>Face \u00e0 une urgence dentaire \u00e0 Gen\u00e8ve, chaque minute pass\u00e9e avec un mal de dent peut sembler une \u00e9ternit\u00e9. Chez Adent Cliniques Dentaires, nous comprenons l&#8217;anxi\u00e9t\u00e9 que peut provoquer une douleur dentaire soudaine ou un accident. C&#8217;est pourquoi notre \u00e9quipe d\u00e9di\u00e9e de professionnels de la sant\u00e9 dentaire \u00e0 Gen\u00e8ve est pr\u00eate \u00e0 intervenir avec efficacit\u00e9 et compassion. Disponibles du lundi au samedi, nous vous garantissons une prise en charge imm\u00e9diate tout en douceur, pour que votre probl\u00e8me de dent soit solutionn\u00e9 sans d\u00e9lai.<\/p>\n","message_info":"<p>Une dent fractur\u00e9e, une infection soudaine ? Gardez votre calme, car la douleur n&#8217;a pas \u00e0 dominer votre quotidien. \u00c0 Gen\u00e8ve, un dentiste de garde est pr\u00eat \u00e0 intervenir pour toute urgence dentaire. Soyez tranquille, prendre en main les urgences dentaires rapidement et efficacement, c&#8217;est le c\u0153ur de notre m\u00e9tier.<\/p>\n<p>&nbsp;<\/p>\n"},"short_description":"","display_shapes":false,"banner_shapes_type":"main_b","banner_subtitle":"","banner_title":"Urgences dentaires Vevey","banner_details":"<p style=\"font-size: 22px;\">En cas d&#8217;urgence dentaire \u00e0 Vevey, chaque instant d&#8217;attente peut sembler interminable. Chez Adent Cliniques Dentaires, nous sommes l\u00e0 pour vous soulager rapidement. Nous sommes disponibles du lundi au samedi pour une intervention imm\u00e9diate.<\/p>\n","banner_image":false,"banner_image_mobile":{"ID":6483,"id":6483,"title":"ADENT_Clinique_Willisau_map_1024x768","filename":"adent_clinique_wilisau_map_1024x768.jpg","filesize":67042,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","link":"https:\/\/adent.ch\/en\/clinic\/willisau\/adent_clinique_wilisau_map_1024x768-2\/","alt":"","author":"2","description":"","caption":"","name":"adent_clinique_wilisau_map_1024x768-2","status":"inherit","uploaded_to":4194,"date":"2022-07-10 11:20:58","modified":"2022-07-11 10:21:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/adent.ch\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/adent_clinique_wilisau_map_1024x768.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"title":"","subtitle":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Urgences Dentaires Vevey | Prise en charge rapide<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez nos services dentaires d&#039;urgence pour toute la famille \u00e0 Vevey. Prenez rendez-vous en ligne avec nos dentistes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Urgences Dentaires Vevey | Prise en charge rapide\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez nos services dentaires d&#039;urgence pour toute la famille \u00e0 Vevey. Prenez rendez-vous en ligne avec nos dentistes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/\" \/>\n<meta property=\"og:site_name\" content=\"Adent Dental Clinics\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/adentcliniquesdentaires\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T14:42:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1619\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/\",\"name\":\"Urgences Dentaires Vevey | Prise en charge rapide\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/dent_casser_bleu.svg\",\"datePublished\":\"2024-07-03T14:24:15+00:00\",\"dateModified\":\"2024-11-26T14:42:14+00:00\",\"description\":\"D\u00e9couvrez nos services dentaires d'urgence pour toute la famille \u00e0 Vevey. Prenez rendez-vous en ligne avec nos dentistes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/dent_casser_bleu.svg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/dent_casser_bleu.svg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/vevey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adent.ch\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Urgences dentaires\",\"item\":\"https:\\\/\\\/adent.ch\\\/en\\\/urgences-dentaires\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Urgences dentaires Vevey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/adent.ch\\\/en\\\/\",\"name\":\"Adent Dental Clinics\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adent.ch\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/#organization\",\"name\":\"Adent Cliniques Dentaires\",\"url\":\"https:\\\/\\\/adent.ch\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adent.ch\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg\",\"width\":2880,\"height\":750,\"caption\":\"Adent Cliniques Dentaires\"},\"image\":{\"@id\":\"https:\\\/\\\/adent.ch\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/adentcliniquesdentaires\\\/\",\"https:\\\/\\\/www.instagram.com\\\/adent.ch\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCPd5UjY-ipuq3MhW6m0W-wg\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/adent-cliniques-dentaires\\\/?originalSubdomain=ch\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Urgences Dentaires Vevey | Prise en charge rapide","description":"D\u00e9couvrez nos services dentaires d'urgence pour toute la famille \u00e0 Vevey. Prenez rendez-vous en ligne avec nos dentistes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/","og_locale":"en_US","og_type":"article","og_title":"Urgences Dentaires Vevey | Prise en charge rapide","og_description":"D\u00e9couvrez nos services dentaires d'urgence pour toute la famille \u00e0 Vevey. Prenez rendez-vous en ligne avec nos dentistes.","og_url":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/","og_site_name":"Adent Dental Clinics","article_publisher":"https:\/\/www.facebook.com\/adentcliniquesdentaires\/","article_modified_time":"2024-11-26T14:42:14+00:00","og_image":[{"width":1619,"height":1080,"url":"https:\/\/adent.ch\/wp-content\/uploads\/2024\/04\/adent-aubonne-mai-2022-igor-laski-web-hd-srvb-48.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/","url":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/","name":"Urgences Dentaires Vevey | Prise en charge rapide","isPartOf":{"@id":"https:\/\/adent.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/#primaryimage"},"image":{"@id":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/#primaryimage"},"thumbnailUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/dent_casser_bleu.svg","datePublished":"2024-07-03T14:24:15+00:00","dateModified":"2024-11-26T14:42:14+00:00","description":"D\u00e9couvrez nos services dentaires d'urgence pour toute la famille \u00e0 Vevey. Prenez rendez-vous en ligne avec nos dentistes.","breadcrumb":{"@id":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/#primaryimage","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/dent_casser_bleu.svg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/07\/dent_casser_bleu.svg"},{"@type":"BreadcrumbList","@id":"https:\/\/adent.ch\/en\/urgences-dentaires\/vevey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adent.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Urgences dentaires","item":"https:\/\/adent.ch\/en\/urgences-dentaires\/"},{"@type":"ListItem","position":3,"name":"Urgences dentaires Vevey"}]},{"@type":"WebSite","@id":"https:\/\/adent.ch\/en\/#website","url":"https:\/\/adent.ch\/en\/","name":"Adent Dental Clinics","description":"","publisher":{"@id":"https:\/\/adent.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adent.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/adent.ch\/en\/#organization","name":"Adent Cliniques Dentaires","url":"https:\/\/adent.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/adent.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","contentUrl":"https:\/\/adent.ch\/wp-content\/uploads\/2022\/09\/adent-habefast-logo-2018-fr-05032019-rvb-scaled.jpg","width":2880,"height":750,"caption":"Adent Cliniques Dentaires"},"image":{"@id":"https:\/\/adent.ch\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/adentcliniquesdentaires\/","https:\/\/www.instagram.com\/adent.ch\/","https:\/\/www.youtube.com\/channel\/UCPd5UjY-ipuq3MhW6m0W-wg","https:\/\/www.linkedin.com\/company\/adent-cliniques-dentaires\/?originalSubdomain=ch"]}]}},"_links":{"self":[{"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/pages\/13016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/comments?post=13016"}],"version-history":[{"count":4,"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/pages\/13016\/revisions"}],"predecessor-version":[{"id":14893,"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/pages\/13016\/revisions\/14893"}],"up":[{"embeddable":true,"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/pages\/3162"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/media\/5600"}],"wp:attachment":[{"href":"https:\/\/adent.ch\/en\/wp-json\/wp\/v2\/media?parent=13016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}